{"id":10204,"date":"2016-01-04T17:22:21","date_gmt":"2016-01-04T20:22:21","guid":{"rendered":"http:\/\/pcb.org.br\/portal2\/?p=10204"},"modified":"2016-02-02T18:07:21","modified_gmt":"2016-02-02T21:07:21","slug":"118-anos-de-nascimento-de-luiz-carlos-prestes","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/10204","title":{"rendered":"118 anos de nascimento de Luiz Carlos Prestes"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"imagem\" title=\"imagem\" src=\"https:\/\/i0.wp.com\/www.cartacapital.com.br\/cultura\/biografia-restaura-trajetoria-politica-de-luiz-carlos-prestes-4499.html\/luiz-carlos-prestes\/%40%40images\/62475641-3422-49fd-9d9b-889ce2194e5a.jpeg?w=747\" alt=\"imagem\" \/>Hoje fazem 118 anos de nascimento de Luiz Carlos Prestes. Um dos mais expressivos patriotas brasileiros. Ele que dedicou 70\u00a0 dos seus 92 anos de vida \u00e0 luta do povo brasileiro pela transforma\u00e7\u00e3o da sociedade. Enfrentou de armas nas m\u00e3os os governantes,\u00a0 de 1924 a 1927,\u00a0 atrav\u00e9s da Invicta Coluna Prestes. Participou, como Presidente de honra da ALN, na luta antifascista em 1935, foi preso durante 9 anos, teve sua mulher e companheira, Olga Benario Prestes entregue aos nazistas alem\u00e3es, gr\u00e1vida de 7 meses. Deste casamento nasceu Anita Leocadia Prestes, que hoje \u00e9 historiadora e j\u00e1 escreveu mais de dez livros destacando grandes momentos da vida do Prestes e da hist\u00f3ria pol\u00edtica do Brasil.<!--more--><\/p>\n<p>Anita preside o Instituto Luiz Carlos Prestes, que det\u00e9m grande acervo da trajet\u00f3ria deste her\u00f3i do povo oprimido e explorado do Brasil. Logo que saiu da pris\u00e3o com a Anistia em 1945,\u00a0 ele se elege o senador mais votado e ainda em paralelo se elege deputado federal constituinte.\u00a0 Foi um dos mais destacados parlamentares da hist\u00f3ria do parlamento brasileiro, liderou a quarta maior bancada de 1945,\u00a0 depois teve o PCB cassado seu registro e todos os mandatos parlamentares cassados, perseguidos, presos e assassinados, tudo em nome da chamada &#8220;democracia burguesa&#8221;.<\/p>\n<p>Era o Brasil fazendo a op\u00e7\u00e3o pelo imperialismo estadunidense, durante os anos da guerra fria. Mas o Cavaleiro\u00a0 da Esperan\u00e7a foi para\u00a0 a luta na clandestinidade, de onde dirigia as dif\u00edceis lutas de reorganiza\u00e7\u00e3o do PCB e dos trabalhadores.\u00a0 Luiz Carlos Prestes lutou sempre,\u00a0 at\u00e9 seus \u00faltimos dias de vida,\u00a0 enfrentou novos tempos dif\u00edceis p\u00f3s ditadura civil-militar de 1964, ficando mais uma vez na dureza da luta clandestina, realizando Congresso, organizando\u00a0 a resist\u00eancia popular e democr\u00e1tica,\u00a0 depois\u00a0 por decis\u00e3o do Comit\u00ea Central do PCB, foi para o ex\u00edlio, de onde\u00a0 continuou a luta contra\u00a0 a ditadura e pelas liberdades democr\u00e1ticas.<\/p>\n<p>Voltou do ex\u00edlio com a Anistia, em 1979. Enfrentou\u00a0 novos embates no PCB,\u00a0 divergiu da maioria do CC, mas continuou sua luta como comunista e como revolucion\u00e1rio,\u00a0 participando das lutas pelas diretas, nas campanhas eleitorais de\u00a0 Brizola para presidente e de Lula em 1989. Faleceu em 1990, deixando um legado de hero\u00edsmo,\u00a0 firmeza ideol\u00f3gica,\u00a0 honradez e honestidade com os princ\u00edpios e ideais que construiu nos seus 92 anos de vida. Sua vida e trajet\u00f3ria pol\u00edtica se somam \u00e0 rica hist\u00f3ria\u00a0 de lutas proporcionadas pelo Partido Comunista Brasileiro,\u00a0 o PCB,\u00a0 onde Prestes militou e o dirigiu por cerca de 50 anos de sua vida. No final do ano passado sua filha e historiadora escreveu a sua biografia pol\u00edtica,\u00a0 editada pela Editora Boitempo,\u00a0 num trabalho de pesquisa primoroso e uma edi\u00e7\u00e3o muito especial.<\/p>\n<p>Viva Luiz Carlos Prestes! Viva os seus 118 anos de nascimento! Para que sua hist\u00f3ria continue inspirando as atuais e futuras gera\u00e7\u00f5es na luta pelo Socialismo!<\/p>\n<p>Roberto Arrais &#8211; Militante e dirigente do PCB .<\/p>\n","protected":false},"excerpt":{"rendered":"Hoje fazem 118 anos de nascimento de Luiz Carlos Prestes. Um dos mais expressivos patriotas brasileiros. Ele que dedicou 70\u00a0 dos seus 92 \n<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/10204\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[50],"tags":[],"class_list":["post-10204","post","type-post","status-publish","format-standard","hentry","category-c61-cultura-revolucionaria"],"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p659gw-2EA","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/10204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=10204"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/10204\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=10204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=10204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=10204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}