{"id":10657,"date":"2016-03-19T17:41:15","date_gmt":"2016-03-19T20:41:15","guid":{"rendered":"http:\/\/pcb.org.br\/portal2\/?p=10657"},"modified":"2016-04-16T12:20:07","modified_gmt":"2016-04-16T15:20:07","slug":"colombia-o-paramilitarismo-continua-sendo-o-principal-assassino-das-organizacoes-sociais-e-da-populacao","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/10657","title":{"rendered":"Col\u00f4mbia: O paramilitarismo continua sendo o principal assassino das organiza\u00e7\u00f5es sociais e da popula\u00e7\u00e3o"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" height=\"400\" width=\"600\" decoding=\"async\" class=\"imagem\" title=\"imagem\" src=\"https:\/\/i0.wp.com\/www.resumenlatinoamericano.org\/wp-content\/uploads\/2016\/03\/paras-600x400.jpg?resize=600%2C400\" alt=\"imagem\" \/>Resumen Latinoamericano \/ 13 de mar\u00e7o de 2016 \u2013 MARCHA PATRI\u00d3TICA<\/p>\n<p>No momento em que mais se aproxima a possibilidade de celebrarmos um acordo de paz, essa paz que foi nossa raz\u00e3o de ser como organiza\u00e7\u00f5es sociais e pela qual trabalhamos arduamente para que seja com justi\u00e7a social, \u00e9 quando voltamos a receber o ataque daqueles que historicamente tentam nos calar.<!--more--><\/p>\n<p>Cada dia se recrudesce e aumenta a viol\u00eancia contra os defensores de direitos humanos em Magdalena Medio, Nordeste Antioquense, sul de Bol\u00edvar e sob o Cauca antioquense, por\u00e9m persistimos na luta para dignificar a vida e garantir a perman\u00eancia neste territ\u00f3rio.<\/p>\n<p>Como AHERAMIGUA, ACVC e CAHUCOPANA celebramos os di\u00e1logos em Havana desenvolvidos pelas FARC-EP e o governo nacional, o que permitiu diminuir em nossos territ\u00f3rios os conflitos b\u00e9licos, por\u00e9m hoje nos vemos confrontados por diversos riscos em nosso trabalho organizativo ante o aumento e recrudescimento da a\u00e7\u00e3o dos grupos paramilitares nas regi\u00f5es.<\/p>\n<p>A presen\u00e7a de atores armados ilegais, a disputa pelo territ\u00f3rio e os interesses pelas riquezas que se encontram nestas zonas, elevaram a confronta\u00e7\u00e3o militar tendo como consequ\u00eancia enfrentamentos armados entre os pr\u00f3prios grupos ilegais. Tudo isso se soma \u00e0 classifica\u00e7\u00e3o e acusa\u00e7\u00e3o das comunidades por parte destes grupos, que alegam que as comunidades s\u00e3o ajudantes das guerrilhas colocando os l\u00edderes em alto risco, por serem eles que denunciam e visibilizam os fatos, sem contarem com as garantias necess\u00e1rias por parte do Estado pelo exerc\u00edcio da defesa dos direitos humanos.<\/p>\n<p>Estas acusa\u00e7\u00f5es v\u00eam se dando por meio de panfletos e mensagens (em grafites, mensagens de texto para celulares ou recados atrav\u00e9s da pr\u00f3pria comunidade), que geram ansiedade e temor por parte dos l\u00edderes e dos habitantes. Dessa maneira, a presen\u00e7a e hostilidades realizadas contra a popula\u00e7\u00e3o, somadas aos desaparecimentos for\u00e7ados e assassinatos de povoados, levaram ao deslocamento para a \u00e1rea urbana da cidade de Puerto Claver, munic\u00edpio de Bagre \u2013 Antioquia, no m\u00eas de janeiro deste ano, onde estivemos como organiza\u00e7\u00f5es defensoras de direitos humanos, realizando a jornada de verifica\u00e7\u00e3o ante esta arremetida paramilitar. Hoje, as comunidades deslocadas ainda se encontram em um ref\u00fagio na ponta da cidade por medo de regressar a suas fazendas ante esta situa\u00e7\u00e3o.<\/p>\n<p>Al\u00e9m disso, nas \u00faltimas semanas, no munic\u00edpio de Segovia, ocorreu um massacre, em que estiveram envolvidos membros do Cl\u00e3 Usuga ou tamb\u00e9m chamados de Urabe\u00f1os. Ao mesmo tempo, no nordeste antioquense e no sul da Bol\u00edvia permanecem sendo distribu\u00eddos panfletos de intimida\u00e7\u00e3o e continuam os assassinatos seletivos. Finalmente, hoje com tristeza, novamente as organiza\u00e7\u00f5es campesinas s\u00e3o v\u00edtimas diretas, dado o assassinato de um de nossos dirigentes e amigo, William Castill e as constantes amea\u00e7as contra nossa companheira Mar\u00eda Diana Arrieta P\u00e9rez, da AHERAMIGUA.<\/p>\n<p>N\u00e3o ignoramos o fato acontecido em 6 de mar\u00e7o passado, no munic\u00edpio de Montecristo, sul de Bol\u00edvar, onde um soldado em estado de embriaguez, pertencente \u00e0 Segunda Brigada do Ex\u00e9rcito Nacional, assassinou tr\u00eas pessoas e feriu gravemente outras tr\u00eas em um incidente com sua carteira. Mais um fato que envolve a popula\u00e7\u00e3o e a converte em v\u00edtima da viol\u00eancia e do abuso da autoridade.<\/p>\n<p>As organiza\u00e7\u00f5es que trabalham na defesa da vida repudiam estes acontecimentos terr\u00edveis, que visam deslegitimar nosso trabalho e dar in\u00edcio a uma onda de deslocamentos e viol\u00eancia generalizada.<\/p>\n<p>Por isso, fazemos um chamado urgente \u00e0s institui\u00e7\u00f5es governamentais para enfrentar um dos maiores problemas dos quais continuamos sendo v\u00edtimas. Tal situa\u00e7\u00e3o que n\u00e3o nos permitir\u00e1 avan\u00e7ar para a consecu\u00e7\u00e3o de uma paz est\u00e1vel e duradoura. \u00c9 necess\u00e1rio tomar as a\u00e7\u00f5es pertinentes contra os grupos paramilitares que hoje rondam livremente as \u00e1reas urbanas dos munic\u00edpios. Al\u00e9m de amea\u00e7ar a popula\u00e7\u00e3o e gerar terror, assassinam, deslocam e formam alian\u00e7as entre suas estruturas para desarticular o trabalho das organiza\u00e7\u00f5es.<\/p>\n<p>Por nossos mortos nem um minuto de sil\u00eancio!<\/p>\n<p>Asociaci\u00f3n de Hermandades Agroecol\u00f3gicas y Mineras de Guamoco \u2013 AHERAMIGUA<\/p>\n<p>Asociaci\u00f3n Campesina del Valle del R\u00edo Cimitarra \u2013 Red Agroecol\u00f3gica<br \/>\nNacional \u2013 ACVC RAN<\/p>\n<p>Corporaci\u00f3n Acci\u00f3n Humanitaria por la Convivencia y la Paz del Nordeste<br \/>\nAntioque\u00f1o \u2013 CAHUCOPANA<\/p>\n<p>Foto: tirada por Radio Macondo<\/p>\n<p>Fonte: <a href=\"http:\/\/www.resumenlatinoamericano.org\/2016\/03\/13\/colombia-el-paramilitarismo-sigue-siendo-el-principal-victimario-de-las-organizaciones-sociales-y-la-poblacion\/\" target=\"_blank\">http:\/\/www.<wbr \/>resumenlatinoamericano.org\/<wbr \/>2016\/03\/13\/colombia-el-<wbr \/>paramilitarismo-sigue-siendo-<wbr \/>el-principal-victimario-de-<wbr \/>las-organizaciones-sociales-y-<wbr \/>la-poblacion\/<\/a><\/p>\n<p>Tradu\u00e7\u00e3o: Partido Comunista Brasileiro (PCB)<\/p>\n","protected":false},"excerpt":{"rendered":"Resumen Latinoamericano \/ 13 de mar\u00e7o de 2016 \u2013 MARCHA PATRI\u00d3TICA No momento em que mais se aproxima a possibilidade de celebrarmos um \n<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/10657\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[34],"tags":[],"class_list":["post-10657","post","type-post","status-publish","format-standard","hentry","category-c39-colombia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-2LT","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/10657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=10657"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/10657\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=10657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=10657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=10657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}