{"id":109,"date":"2009-09-08T23:26:45","date_gmt":"2009-09-08T23:26:45","guid":{"rendered":"http:\/\/pcb.org.br\/portal2\/?p=109"},"modified":"2009-09-08T23:26:45","modified_gmt":"2009-09-08T23:26:45","slug":"ser-comunista","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/109","title":{"rendered":"Ser Comunista"},"content":{"rendered":"\n<p>4. Ser comunista \u00e9 defender a exist\u00eancia das diferen\u00e7as e suas ricas manifesta\u00e7\u00f5es, mas jamais aceitar as desigualdades sociais;<\/p>\n<p>5. Ser comunista \u00e9 apostar na capacidade de supera\u00e7\u00e3o do ser humano na busca incessante do bem-estar-social e, sobretudo, na utopia eterna da igualdade entre os homens;<\/p>\n<p>6. Ser comunista hoje, mais do que nunca, \u00e9 acreditar que as conquistas da ci\u00eancia e da tecnologia s\u00f3 fazem sentido se forem para o benef\u00edcio de todos;<\/p>\n<p>7. Ser comunista \u00e9 combater a exclus\u00e3o social e promover a fraternidade dos povos, assim como a coexist\u00eancia das culturas e dos saberes populares;<\/p>\n<p>8. Ser comunista \u00e9 sustentar a id\u00e9ia de que a vida pode e deve ser cada vez mais bem vivida por todos em igualdade de condi\u00e7\u00f5es;<\/p>\n<p>9. Ser comunista \u00e9 nunca desistir das convic\u00e7\u00f5es herdadas pela tradi\u00e7\u00e3o das lutas dos povos da Terra, renovando-as a cada momento atrav\u00e9s de novos ensinamentos e novos est\u00edmulos;<\/p>\n<p>10.Ser comunista \u00e9 cuidar de seu semelhante como parte integrante de seu ser.<\/p>\n","protected":false},"excerpt":{"rendered":"Lincoln de Abreu Penna\n1. Ser comunista \u00e9 estar atento \u00e0 vida, proteg\u00ea-la e tornar sua exist\u00eancia n\u00e3o s\u00f3 poss\u00edvel como plena;\n2. Ser comunista \u00e9 cultivar a fonte de saber aonde quer que ela se manifeste, na tradi\u00e7\u00e3o dos costumes simples da boa conviv\u00eancia ou nos processos de elabora\u00e7\u00e3o do conhecimento produzido pela humanidade;\n3. Ser comunista \u00e9 contemplar as in\u00fameras situa\u00e7\u00f5es que possibilitem a amplia\u00e7\u00e3o dos horizontes do ser humano, preservando a rela\u00e7\u00e3o e a diversidade entre as esp\u00e9cies, os g\u00eaneros e as etnias;\n<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/109\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[42],"tags":[],"class_list":["post-109","post","type-post","status-publish","format-standard","hentry","category-c47-lincoln-penna"],"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p659gw-1L","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=109"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/109\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}