{"id":11375,"date":"2016-06-21T16:46:15","date_gmt":"2016-06-21T19:46:15","guid":{"rendered":"http:\/\/pcb.org.br\/portal2\/?p=11375"},"modified":"2016-07-18T18:08:34","modified_gmt":"2016-07-18T21:08:34","slug":"bases-da-otan-na-europa-e-a-ameaca-das-armas-nucleares","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/11375","title":{"rendered":"Bases da OTAN na Europa e a amea\u00e7a das armas nucleares"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"imagem\" src=\"https:\/\/i0.wp.com\/www.odiario.info\/b2-img\/NATO1.jpg?w=747\" alt=\"\" \/>Rui Namorado Rosa<\/p>\n<p>Num fundamentado texto como \u00e9 sempre uso, Rui Namorado Rosa diz no texto que hoje publicamos por que raz\u00e3o \u00aba NATO \u00e9 argumento e instrumento para, primeiro, duas grandes pot\u00eancias nucleares, e depois, uma s\u00f3 delas, terem efetivamente decidido sobre a defesa e a seguran\u00e7a no continente Europeu\u00bb; e <!--more-->acrescenta que n\u00e3o foi com a integra\u00e7\u00e3o na NATO que Estados Europeus \u00abadquiriram parte ativa na negocia\u00e7\u00e3o e garantia de seguran\u00e7a e Paz na Europa. Antes por isso mesmo a perderam, e tornaram-se correspons\u00e1veis pela militariza\u00e7\u00e3o na Europa e pela escalada de conflitos dram\u00e1ticos no continente e na bacia do Mediterr\u00e2neo, de que todos somos v\u00edtimas\u00bb.<br \/>\n\u00abMuitos pa\u00edses europeus foram capturados para a vis\u00e3o estrat\u00e9gica da NATO e como instrumentos de influ\u00eancia pol\u00edtica e militar da NATO sobre o nosso continente e para al\u00e9m dele. A Uni\u00e3o Europeia tem facilitado o avan\u00e7o de tal vis\u00e3o militarista e percurso guerreiro\u00bb.<\/p>\n<p><b>A NATO NA EUROPA HOJE [1]<\/b><\/p>\n<p>A NATO det\u00eam forte presen\u00e7a na Europa, em todos os azimutes. A sua infraestrutura compreende cerca de 50 bases militares norte-americanas dispersas por 12 pa\u00edses, mas muitas mais a n\u00edvel de detalhe mais fino. A n\u00edvel mais elevado, o comando global est\u00e1 cometido ao Comando Operacional Aliado (ACO) em Bruxelas. Outras estruturas de comando est\u00e3o localizadas na Noruega (Joint Warfare Centre), Pol\u00f3nia (Joint Force Training Centre), Portugal (Joint Analysis and Lessons Learned Centre), It\u00e1lia (Undersea Research Centre), Pa\u00edses Baixos (Joint Force Command), Alemanha (Airborn Warning Control System), etc.<\/p>\n<p>A partir da cimeira de Praga (2002), EUA prosseguiram arranjos bilaterais, designadamente com a Pol\u00f3nia e a Rep\u00fablica Checa, para o projeto de instalar um sistema de rastreamento conjugado com um sistema de lan\u00e7amento de m\u00edsseis intercetores de longo alcance. Na cimeira de Bucareste (2008) foi assumida a inten\u00e7\u00e3o de refor\u00e7ar os meios existentes com ativos estado-unidense e europeus para instalar um sistema antim\u00edssil bal\u00edstico integrado, abarcando todo o espa\u00e7o NATO. Em Setembro de 2009, a Ag\u00eancia dos EUA <i>Missile Defense Agency (MDA) anunciou um programa para implementa\u00e7\u00e3o de um sistema antim\u00edssil na Europa, denominado European Phased Adaptive Approach for European BMD<\/i> \u2013 EPAA, que veio a ser adotado pela NATO na cimeira de Lisboa (2010).<\/p>\n<p>Em Setembro de 2011 foram sucessivamente anunciadas a instala\u00e7\u00e3o de bases terrestres de m\u00edsseis intercetores SM-3 na Rom\u00e9nia e na Pol\u00f3nia; e uma esta\u00e7\u00e3o de rastreamento radar na Turquia. Entretanto, o sistema antim\u00edssil compreende j\u00e1 um ramo naval, com quatro destroyers dotados de sistema Aegis baseados em Espanha, e ainda, uma base de comando e controlo localizada na Alemanha (Ramstein Air Base). Este sistema antim\u00edssil bal\u00edstico (ABM) inscreve-se no quadro do referido programa <i>European Phased Adaptive Approach,<\/i> e visa antecipar um hipot\u00e9tico ataque sobre estados europeus da NATO por m\u00edsseis de curto e m\u00e9dio alcance (at\u00e9 5000 km).<\/p>\n<p>Em Outubro de 2015 ao largo da Esc\u00f3cia, meios aeronavais e m\u00edsseis, da NATO e de dez estados membros, realizou pela primeira vez e com anunciado \u00eaxito um exerc\u00edcio de fogo real em \u201cdefesa bal\u00edstica mar\u00edtima\u201d que, segundo o representante da Marinha norte-americana, dever\u00e1 tornar-se rotina anual.<\/p>\n<p><b>PELO DESARMAMENTO NUCLEAR GERAL E CONTROLADO [2]<\/b><\/p>\n<p>O Tratado de n\u00e3o-Prolifera\u00e7\u00e3o de armas Nucleares &#8211; NPT, assinado em 1968, visa prevenir a prolifera\u00e7\u00e3o (vertical e horizontal) de armas nucleares, alcan\u00e7ar o desarmamento, e promover o acesso \u00e0s aplica\u00e7\u00f5es pac\u00edficas da energia nuclear, estabelecendo salvaguardas sob a responsabilidade da AIEA, entretanto j\u00e1 constitu\u00edda por decis\u00e3o da Assembleia Geral das Na\u00e7\u00f5es Unidas em 1956. Esse tratado \u00e9 uma pe\u00e7a fundamental na ordem e para a Paz mundial. Designa cinco estados detentores de armas nucleares, os mesmos que t\u00eam assento permanente no Conselho de Seguran\u00e7a. Embora a ado\u00e7\u00e3o quase universal deste Tratado, quatro estados n\u00e3o aderiram e desenvolveram no entretanto armas nucleares \u2013 India, Paquist\u00e3o, Coreia do Norte e Israel.<\/p>\n<p>A par do NPT, o Tratado para a Interdi\u00e7\u00e3o de Testes nucleares \u00e9 um instrumento fundamental para conter a amea\u00e7a nuclear. Em 1963 o Tratado para a Interdi\u00e7\u00e3o Parcial de Testes nucleares (PTBT) proibiu testes de armas nucleares na atmosfera e subaqu\u00e1ticos, com vasta ades\u00e3o e duradouro impacto pol\u00edtico, militar e ambiental. Em 1996, a Assembleia Geral das Na\u00e7\u00f5es Unidas adotou por ampla maioria a atualiza\u00e7\u00e3o do PTBT em vigor por um Tratado para a Interdi\u00e7\u00e3o Completa de Testes nucleares (CTBT), alargando a proibi\u00e7\u00e3o \u00e0 realiza\u00e7\u00e3o de testes subterr\u00e2neos. Foi constitu\u00edda com sede em Viena a Organiza\u00e7\u00e3o (CTBTO) com mandato para verificar o seu cumprimento, estabelecer rede de esta\u00e7\u00f5es de monitoriza\u00e7\u00e3o e centro de recolha de dados, e desenvolver meios de inspe\u00e7\u00e3o; mais de trezentos dispositivos integram essa rede \u00e0 volta do mundo, sendo os dados processados e facultado aos estados signat\u00e1rios. Mais de 180 estados subscreveram este Tratado. Em seu anexo 2 nomeia os 45 estados que o negociaram e s\u00e3o detentores de tecnologia nuclear, estados cuja ades\u00e3o \u00e9 condi\u00e7\u00e3o necess\u00e1ria \u00e0 sua entrada em vigor, o que ainda n\u00e3o aconteceu, posto que tr\u00eas deles ainda n\u00e3o o subscreveram \u2013 India, Paquist\u00e3o, Coreia do Norte \u2013 e cinco n\u00e3o o ratificaram \u2013 EUA, China, Ir\u00e3o, Israel, Egipto. Todos os estados Europeus, de Leste a Oeste, o ratificaram; no quadro da NATO, os EUA destacam-se por serem o \u00fanico a n\u00e3o o ter ratificado.<\/p>\n<p><b>ESFOR\u00c7OS PELO DESARMAMENTO, COMPROMETIMENTOS PARA A GUERRA [3]<\/b><\/p>\n<p>A redu\u00e7\u00e3o dos ativos nucleares acumulados durante a guerra fria s\u00e3o uma outra via necess\u00e1ria para alcan\u00e7ar o desarmamento nuclear. Ao longo das d\u00e9cadas de 70 e 80, EUA e URSS mantiveram negocia\u00e7\u00f5es no sentido da limita\u00e7\u00e3o coordenada dos respetivos meios ofensivos nucleares, quando os ativos das duas grandes pot\u00eancias somavam j\u00e1 30 mil ogivas nucleares. O processo negocial (SALT I) conseguiu em 1972 um Acordo Interino para limita\u00e7\u00e3o de armas ofensivas e um Tratado para limita\u00e7\u00e3o de sistemas antim\u00edssil bal\u00edstico (ABM). Em 1979 foi alcan\u00e7ado o Tratado para a limita\u00e7\u00e3o de armas ofensivas estrat\u00e9gicas (SALT II), este j\u00e1 consagrando a redu\u00e7\u00e3o do n\u00famero de ogivas e de ve\u00edculos lan\u00e7adores, restri\u00e7\u00e3o do uso de ve\u00edculos de reentrada com ogivas e alvos m\u00faltiplos (MIRV), e medidas de verifica\u00e7\u00e3o. Todavia este tratado, embora contribuindo para manter abertas as vias de negocia\u00e7\u00e3o e antecipando resultados futuros, n\u00e3o chegou a ser ratificado pelos EUA.<\/p>\n<p>Um Tratado para a redu\u00e7\u00e3o e limita\u00e7\u00e3o de armas ofensivas estrat\u00e9gicas (START I) foi finalmente acordado em 1991. No entretanto, com a dissolu\u00e7\u00e3o da URSS, e na perspetiva da preval\u00eancia da ordem internacional no que respeitava \u00e0 n\u00e3o prolifera\u00e7\u00e3o nuclear, a R\u00fassia assumiu a heran\u00e7a dos ativos e responsabilidades da URSS no \u00e2mbito do TNP, enquanto Bielorr\u00fassia, Ucr\u00e2nia e Cazaquist\u00e3o destru\u00edram ou transferiram seus ativos nucleares e assumiram a condi\u00e7\u00e3o de estados n\u00e3o detentores de armas nucleares, nos temos do Protocolo de Lisboa (1992). Os pressupostos do START foram cumpridos, e este Tratado entrou em vigor em 1994, devendo expirar em 2009. Traduziu-se na remo\u00e7\u00e3o de 80% dos efetivos estrat\u00e9gicos nucleares ent\u00e3o existentes, para menos de 6000 ogivas e menos de 1600 ve\u00edculos de lan\u00e7amento, de um e outro lado.<\/p>\n<p>O processo de negocia\u00e7\u00e3o START foi retomado logo em 1992, por\u00e9m um novo Tratado (New START) s\u00f3 veio a ser finalmente ratificado em 2011. A ser implementado at\u00e9 2018 e vigorar at\u00e9 2021, visa manter o contacto e a confian\u00e7a entre os EUA e Federa\u00e7\u00e3o Russa, renovar o sistema de verifica\u00e7\u00e3o, e prosseguir a trajet\u00f3ria de redu\u00e7\u00e3o de n\u00famero de lan\u00e7adores estrat\u00e9gicos e de ogivas. As metas fixadas para o armamento instalado pronto \u00e9 1.550 ogivas nucleares estrat\u00e9gicas e 800 ve\u00edculos de lan\u00e7amento (<i>Inter Continental Ballistic Missiles &#8211; ICBM, Submarine Launched Ballistic Missiles &#8211; SLBM, <\/i>e avi\u00f5es bombardeiros). Estes meios continuam a exceder, de longe, os ativos nucleares de alguns outros pa\u00edses tamb\u00e9m detentores de ogivas, lan\u00e7adores e sistemas nucleares defensivos ou ofensivos, designadamente R.P. China e \u00cdndia, bem como Fran\u00e7a e Reino Unido na pr\u00f3pria Europa.<\/p>\n<p>Foram quase duas d\u00e9cadas de negocia\u00e7\u00f5es laboriosas e penosas, em vista da complexidade de inova\u00e7\u00f5es t\u00e9cnicas supervenientes, mas sobretudo resultado dos jogos diplom\u00e1ticos e da intromiss\u00e3o militar de que o espa\u00e7o Europeu foi quer alvo quer pretexto, por parte de pa\u00edses terceiros e da NATO em particular. Notar que esse per\u00edodo de negocia\u00e7\u00f5es entre EUA e Federa\u00e7\u00e3o Russa abrange, no espa\u00e7o da Uni\u00e3o Europeia, o per\u00edodo que decorre desde 1992 &#8211; com o Tratado de Maastricht (que incorpora a Pol\u00edtica Comum Externa e Seguran\u00e7a na funda\u00e7\u00e3o da Uni\u00e3o) e a formula\u00e7\u00e3o pela Uni\u00e3o da Europa Ocidental das metas ofensivas designadas por \u201cPetersberg Tasks\u201d &#8211; passando pelas cimeiras de Saint-Malo, Col\u00f3nia e Hels\u00ednquia, at\u00e9 \u00e0 ratifica\u00e7\u00e3o do Tratado de Lisboa em 2009 &#8211; quando a Pol\u00edtica Comum de Seguran\u00e7a e Defesa e a velha Uni\u00e3o da Europa Ocidental foram formalmente assimiladas na Uni\u00e3o Europeia. Em paralelo, prosseguiu o alagamento e integra\u00e7\u00e3o das duas Organiza\u00e7\u00f5es: dos 28 estados membros da Uni\u00e3o e dos 28 membros da NATO, 22 pertencem a ambas.<\/p>\n<p>Nas cimeiras de Lisboa, Chicago e Wales, a NATO reafirmou partilhar com a Uni\u00e3o Europeia valores comuns e interesses estrat\u00e9gicos, ao ponto de indiscern\u00edvel identidade. Incluindo facultar acesso a meios de planeamento e apoios para opera\u00e7\u00f5es militares lideradas pela Uni\u00e3o fora do quadro da pr\u00f3pria NATO. Assim sendo, tropas europeias, suportada em recursos da NATO, poder\u00e3o ent\u00e3o atuar para al\u00e9m da esfera de a\u00e7\u00e3o da NATO, no cumprimento de miss\u00f5es por esta aprovadas; em poucas palavras, soldados europeus est\u00e3o \u00e0s ordens de um diret\u00f3rio liderado pelos EUA, para cumprir objetivos em qualquer parte do mundo \u2013 no Iraque, S\u00edria, L\u00edbia, I\u00e9men, N\u00edger, Chade, Nig\u00e9ria, etc.<\/p>\n<p><b>PROLIFERA\u00c7\u00c3O NUCLEAR NA EUROPA [4]<\/b><\/p>\n<p>Graves infra\u00e7\u00f5es ao TNP emergem na regi\u00e3o \u00c1sia-Pac\u00edfico e outras foram cometidas e persistem em territ\u00f3rio europeu. Na Europa, na sequ\u00eancia de negocia\u00e7\u00f5es no \u00e2mbito da NATO, B\u00e9lgica, Pa\u00edses Baixos, Alemanha, It\u00e1lia e Turquia, que \u00e0 luz do TNP s\u00e3o pa\u00edses n\u00e3o detentores de armas nucleares, aceitaram partilhar com os EUA o armazenamento e instala\u00e7\u00e3o de armas nucleares nos respetivos territ\u00f3rios. Gr\u00e9cia e Reino Unido, tendo tamb\u00e9m j\u00e1 partilhado armas nucleares com os EUA, cr\u00ea-se ter\u00e3o deixado de o fazer. Presentemente calcula-se sejam duzentas as ogivas nucleares norte-americanas por essa via estacionadas em bases de estados Europeus. Tais delega\u00e7\u00f5es de meios e responsabilidades violam os artigos I e II do TNP. Essa \u201cpartilha\u201d adv\u00e9m de acordos bilaterais anteriores ao Tratado de N\u00e3o-Prolifera\u00e7\u00e3o, enquanto este veio a proibir explicitamente qualquer transfer\u00eancia de armas nucleares a partir de um estado detentor de armas nucleares e a sua rece\u00e7\u00e3o por um outro estado que o n\u00e3o seja, Tratado a que todas essas partes aderiram, mas cuja letra e esp\u00edrito subvertem.<\/p>\n<p>As armas em quest\u00e3o s\u00e3o bombas de gravidade da s\u00e9rie B-61. Est\u00e1 anunciada a sua substitui\u00e7\u00e3o pela vers\u00e3o B61-12, que exibe v\u00e1rias val\u00eancias inovadoras neste tipo de armas: condu\u00e7\u00e3o de elevada precis\u00e3o para o alvo, pot\u00eancia ajust\u00e1vel, e capacidade de penetra\u00e7\u00e3o no subsolo e fortifica\u00e7\u00f5es. Essas especificidades t\u00e9cnicas maximizam o efeito \u201c\u00fatil\u201d relativamente aos efeitos colaterais, o que amea\u00e7a tornar a op\u00e7\u00e3o pelo seu uso perigosamente mais tolerado ou aceite, inclusive em opera\u00e7\u00f5es t\u00e1ticas. Com efeito, as for\u00e7as a\u00e9reas alem\u00e3, italiana, belga, holandesa e turca anunciam estar em vias de adquirir novos avi\u00f5es norte-americanos para acomodar as novas bombas para opera\u00e7\u00e3o t\u00e1tica.<\/p>\n<p>Em sentido contr\u00e1rio, o governo alem\u00e3o j\u00e1 em 2009 expressara apoio \u00e0 retirada das armas nucleares norte-americanas do seu territ\u00f3rio e da Europa, no que foi secundado pelos governos belga e holand\u00eas; enquanto os parlamentos holand\u00eas e alem\u00e3o tamb\u00e9m j\u00e1 tomaram posi\u00e7\u00e3o contra a continuidade destas mesmas armas. No quadro acad\u00e9mico, pol\u00edtico e social, multiplicam-se as vozes que clamam pela elimina\u00e7\u00e3o destas armas. Receamos que focos de conflito diplom\u00e1tico ou militar estejam a ser suscitados e manipulados para continuar a fazer crer e impor a vontade de estrategas militares e os interesses do complexo militar-industrial norte-americano e europeu sobre os povos europeus.<\/p>\n<p><b>A NATO COMPROMETE A EUROPA PARA A GUERRA [5] <\/b><\/p>\n<p>A NATO \u00e9 argumento e instrumento para, primeiro, duas grandes pot\u00eancias nucleares, e depois, uma s\u00f3 delas, terem efetivamente decidido sobre a defesa e a seguran\u00e7a no continente Europeu. Estados Europeus detentores de armamento nuclear reconhecidos pelo TNP (Reino Unido e Fran\u00e7a), e ainda outros que, n\u00e3o o sendo, acolhem e partilham em seu territ\u00f3rio armamento nuclear dos EUA (pelo menos B\u00e9lgica, Holanda, Alemanha, It\u00e1lia e Turquia), n\u00e3o foi por terem integrado a NATO que adquiriram parte ativa na negocia\u00e7\u00e3o e garantia de seguran\u00e7a e Paz na Europa. Antes por isso mesmo a perderam, e tornaram-se correspons\u00e1veis pela militariza\u00e7\u00e3o na Europa e pela escalada de conflitos dram\u00e1ticos no continente e na bacia do Mediterr\u00e2neo, de que todos somos v\u00edtimas.<\/p>\n<p>Os povos europeus n\u00e3o t\u00eam de ser conduzidos a escolher entre Ocidente e Oriente. A constitui\u00e7\u00e3o da NATO precedeu a constru\u00e7\u00e3o europeia e a sua influ\u00eancia tem sido um constrangimento permanente \u00e0s livres escolhas dos povos europeus desde ent\u00e3o. Muitos pa\u00edses europeus foram capturados para a vis\u00e3o estrat\u00e9gica da NATO e como instrumentos de influ\u00eancia pol\u00edtica e militar da NATO sobre o nosso continente e para al\u00e9m dele. A Uni\u00e3o Europeia tem facilitado o avan\u00e7o de tal vis\u00e3o militarista e percurso guerreiro. A NATO n\u00e3o \u00e9 um instrumento de constru\u00e7\u00e3o da Paz, mas sim de subjuga\u00e7\u00e3o pol\u00edtica e militar, e instrumento de guerra para que os seus membros europeus t\u00eam sido convocados a combater na Jugosl\u00e1via, Afeganist\u00e3o, Iraque, L\u00edbia, etc.<\/p>\n<p>O quadro de confronto diplom\u00e1tico e militar n\u00e3o se desanuviou com o desaparecimento da cortina de ferro, que seria a suposta raz\u00e3o de ser da NATO. Talvez esta tenha sido respons\u00e1vel pela queda da cortina de ferro; mas seguramente \u00e9 correspons\u00e1vel pelo ulterior prosseguimento e at\u00e9 aprofundamento do clima de confronto e agress\u00e3o concreta.<\/p>\n<p>As negocia\u00e7\u00f5es para o desarmamento na Europa e sua vizinhan\u00e7a n\u00e3o conseguiram abolir o confronto estrat\u00e9gico com armas nucleares. Os bombardeiros, os submarinos e destroyers, os sistemas bal\u00edsticos terrestres (fixos e m\u00f3veis); os m\u00edsseis guiados de alta precis\u00e3o, alta velocidade, alta ou baixa altitude, de curto a muito longo alcance; os dispositivos de dete\u00e7\u00e3o, rastreamento e alerta; as redes de comunica\u00e7\u00e3o e os centros de processamento e comando; as telecomunica\u00e7\u00f5es e a teledete\u00e7\u00e3o via sat\u00e9lite; s\u00e3o elementos que convergem para complexos, mas sobretudo perigos\u00edssimos, conflitos militares, potencialmente com armas nucleares.<\/p>\n<p>A corrida armamentista serve objetivos de dom\u00ednio pol\u00edtico e econ\u00f3mico mundial, de submiss\u00e3o de vastas popula\u00e7\u00f5es \u00e0 oferta de for\u00e7a de trabalho e \u00e0 procura de mercados de consumo, incluindo os interesses dos complexos militares-industriais que produzem as inova\u00e7\u00f5es t\u00e9cnicas, depois propagandeadas como virtuosamente necess\u00e1rias, defensivas e vitoriosas. A discrimina\u00e7\u00e3o entre sistemas m\u00edssil e antim\u00edssil, ou ofensivos e defensivos, bem como entre armas estrat\u00e9gicas e t\u00e1ticas, perde significado neste quadro de ampla diversidade e sofistica\u00e7\u00e3o t\u00e9cnica. A insist\u00eancia em implementar a defesa antibal\u00edstica ou designado escudo antim\u00edssil e contemplar o lan\u00e7amento de primeiro ataque designado preventivo, ou em atingir capacidade dissuasora e preservar capacidade de retalia\u00e7\u00e3o, n\u00e3o servem a promo\u00e7\u00e3o da confian\u00e7a e o desarmamento. O caminho contra a prolifera\u00e7\u00e3o nuclear n\u00e3o pode negar ou protelar o caminho para a desarmamento nuclear, como o TNP igualmente consagra, e a que comunidade internacional se obrigou.<\/p>\n<p>Qualquer conflito militar cont\u00e9m em si a perspetiva de escalada, mas uma escalada nuclear \u00e9 um cen\u00e1rio apocal\u00edptico. Os presentes arsenais de nucleares somam mais de 15 mil ogivas, e a sua pot\u00eancia soma um milh\u00e3o de vezes a potencia das bombas nucleares lan\u00e7adas sobre Hiroxima ou Nagas\u00e1qui. Quando apenas 30 megacidades abrigam 500 milh\u00f5es habitantes e j\u00e1 mais de metade da popula\u00e7\u00e3o mundial habita \u00e1reas urbanas, a sua vulnerabilidade a armas de destrui\u00e7\u00e3o massiva \u00e9 uma enorme amea\u00e7a. Na realidade, uma guerra nuclear global desencadearia um \u201cinverno nuclear\u201d, uma cat\u00e1strofe de escala planet\u00e1ria com efeitos s\u00f3 compar\u00e1veis a raros fen\u00f3menos, como o impacto de um grande meteoro ou uma vasta crise vulc\u00e2nica, que na hist\u00f3ria geol\u00f3gica j\u00e1 foram respons\u00e1veis por assinalados eventos de extin\u00e7\u00e3o de vida na Terra.<\/p>\n<p>\u00c9 pois tamb\u00e9m em nome da vida na Terra e da sobreviv\u00eancia da humanidade que o movimento pela Paz apela \u00e0 ren\u00fancia \u00e0 corrida armamentista, incluindo a interdi\u00e7\u00e3o de novas armas, a militariza\u00e7\u00e3o do \u00c1rtico e do espa\u00e7o exterior, e a interdi\u00e7\u00e3o completa e definitiva das armas nucleares.<\/p>\n<p>2 de Junho de 2016<\/p>\n<p><b>In &#8211; THERE IS AN ALTERNATIVE \u2013 NO TO NATO<br \/>\nGUE\/NGL \u2013 Peace and Anti-NATO &#8211; Conference \/ Brussels 2&amp;3 June 2016<\/b><\/p>\n<p>\u2026\u2026\u2026<\/p>\n<p><b>Bibliografia <\/b><br \/>\n[1]<br \/>\n<a href=\"http:\/\/militarybases.com\/\" target=\"_blank\">http:\/\/militarybases.com\/<\/a><br \/>\n<a href=\"http:\/\/beta.mimmer.com\/articles\/sm-3-bmd-in-from-the-sea-epaa-aegis-ashore\" target=\"_blank\">http:\/\/beta.mimmer.com\/articles\/sm-3-bmd-in-from-the-sea-epaa-aegis-ashore <\/a><br \/>\n<a href=\"http:\/\/www.state.gov\/t\/avc\/rls\/162447.htm\" target=\"_blank\">http:\/\/www.state.gov\/t\/avc\/rls\/162447.htm <\/a><br \/>\n<a href=\"http:\/\/www.globalsecurity.org\/military\/facility\/sites.htm\" target=\"_blank\">http:\/\/www.globalsecurity.org\/military\/facility\/sites.htm <\/a><br \/>\n<a href=\"http:\/\/www.janes.com\/article\/55425\/sm-3-achieves-intercept-in-asd15-coalition-test\" target=\"_blank\">http:\/\/www.janes.com\/article\/55425\/sm-3-achieves-intercept-in-asd15-coalition-test <\/a><br \/>\n<a href=\"https:\/\/news.usni.org\/2015\/10\/26\/nato-hopes-to-boost-collective-maritime-bmd-capability-through-exercises-investments\" target=\"_blank\">https:\/\/news.usni.org\/2015\/10\/26\/nato-hopes-to-boost-collective-maritime-bmd-capability-through-exercises-investments<\/a><br \/>\n<a href=\"http:\/\/fpc.state.gov\/documents\/organization\/142710.pdf\" target=\"_blank\">http:\/\/fpc.state.gov\/documents\/organization\/142710.pdf <\/a><\/p>\n<p>[2]<br \/>\n<a href=\"https:\/\/www.iaea.org\/publications\/documents\/treaties\/npt\" target=\"_blank\">https:\/\/www.iaea.org\/publications\/documents\/treaties\/npt<\/a><br \/>\n<a href=\"http:\/\/www.un.org\/en\/conf\/npt\/2015\/\" target=\"_blank\">http:\/\/www.un.org\/en\/conf\/npt\/2015\/ <\/a><br \/>\n<a href=\"https:\/\/www.ctbto.org\/the-treaty\/status-of-signature-and-ratification\/\" target=\"_blank\">https:\/\/www.ctbto.org\/the-treaty\/status-of-signature-and-ratification\/<\/a><\/p>\n<p>[3]<br \/>\n<a href=\"http:\/\/large.stanford.edu\/courses\/2016\/ph241\/long2\/\" target=\"_blank\">http:\/\/large.stanford.edu\/courses\/2016\/ph241\/long2\/<\/a><br \/>\n<a href=\"https:\/\/www.armscontrol.org\/factsheets\" target=\"_blank\">https:\/\/www.armscontrol.org\/factsheets <\/a><br \/>\n<a href=\"https:\/\/www.armscontrol.org\/ACT\/2015_11\/Features\/Chinese-Strategic-Missile-Defense-Will-It-Happen-and-What-Would-It-Mean\" target=\"_blank\">https:\/\/www.armscontrol.org\/ACT\/2015_11\/Features\/Chinese-Strategic-Missile-Defense-Will-It-Happen-and-What-Would-It-Mean<\/a><br \/>\n<a href=\"https:\/\/www.armscontrol.org\/factsheets\/INFtreaty\" target=\"_blank\">https:\/\/www.armscontrol.org\/factsheets\/INFtreaty <\/a><br \/>\n<a href=\"http:\/\/www.europeaninstitute.org\/index.php\/eu-facts\/897-european-defence-timeline\" target=\"_blank\">http:\/\/www.europeaninstitute.org\/index.php\/eu-facts\/897-european-defence-timeline <\/a><br \/>\n<a href=\"http:\/\/www.nato.int\/cps\/en\/natohq\/topics_49217.htm\" target=\"_blank\">http:\/\/www.nato.int\/cps\/en\/natohq\/topics_49217.htm <\/a><br \/>\n<a href=\"http:\/\/www.icanw.org\/the-facts\/nuclear-arsenals\/\" target=\"_blank\">http:\/\/www.icanw.org\/the-facts\/nuclear-arsenals\/ <\/a><br \/>\n<a href=\"https:\/\/www.wsws.org\/en\/articles\/2015\/02\/17\/boko-f17.html\" target=\"_blank\">https:\/\/www.wsws.org\/en\/articles\/2015\/02\/17\/boko-f17.html<\/a><\/p>\n<p>[4]<br \/>\n<a href=\"http:\/\/www.nti.org\/analysis\/articles\/nato-nuclear-disarmament\/\" target=\"_blank\">http:\/\/www.nti.org\/analysis\/articles\/nato-nuclear-disarmament\/ <\/a><br \/>\n<a href=\"http:\/\/www.bits.de\/public\/articles\/sda-05-01.htm\" target=\"_blank\">http:\/\/www.bits.de\/public\/articles\/sda-05-01.htm<\/a><br \/>\n<a href=\"https:\/\/www.armscontrol.org\/factsheets\/Nuclearweaponswhohaswhat\" target=\"_blank\">https:\/\/www.armscontrol.org\/factsheets\/Nuclearweaponswhohaswhat <\/a><br \/>\n<a href=\"https:\/\/fas.org\/blogs\/security\/2016\/01\/b61-12_earth-penetration\/\" target=\"_blank\">https:\/\/fas.org\/blogs\/security\/2016\/01\/b61-12_earth-penetration\/<\/a><br \/>\n<a href=\"http:\/\/nationalinterest.org\/blog\/the-buzz\/the-most-dangerous-nuclear-weapon-americas-arsenal-13433\" target=\"_blank\">http:\/\/nationalinterest.org\/blog\/the-buzz\/the-most-dangerous-nuclear-weapon-americas-arsenal-13433 <\/a><br \/>\n<a href=\"http:\/\/belfercenter.ksg.harvard.edu\/files\/us-tactical-nuclearweapons-in-europe.pdf\" target=\"_blank\">http:\/\/belfercenter.ksg.harvard.edu\/files\/us-tactical-nuclearweapons-in-europe.pdf <\/a><br \/>\n<a href=\"https:\/\/www.opendemocracy.net\/can-europe-make-it\/xanthe-hall\/time-for-nuclear-sharing-to-end\" target=\"_blank\">https:\/\/www.opendemocracy.net\/can-europe-make-it\/xanthe-hall\/time-for-nuclear-sharing-to-end<\/a><\/p>\n<p>[5]<br \/>\n<a href=\"http:\/\/www.un.org\/en\/development\/desa\/news\/population\/world-urbanization-prospects-2014.html\" target=\"_blank\">http:\/\/www.un.org\/en\/development\/desa\/news\/population\/world-urbanization-prospects-2014.html <\/a><br \/>\n<a href=\"http:\/\/es.rice.edu\/projects\/Poli378\/Nuclear\/\" target=\"_blank\">http:\/\/es.rice.edu\/projects\/Poli378\/Nuclear\/ <\/a><br \/>\n<a href=\"http:\/\/es.rice.edu\/projects\/Poli378\/Nuclear\/f04.stratg_invent.html\" target=\"_blank\">http:\/\/es.rice.edu\/projects\/Poli378\/Nuclear\/f04.stratg_invent.html <\/a><br \/>\n<a href=\"http:\/\/es.rice.edu\/projects\/Poli378\/Nuclear\/f13.stratg_invent.html\" target=\"_blank\">http:\/\/es.rice.edu\/projects\/Poli378\/Nuclear\/f13.stratg_invent.html <\/a><br \/>\n<a href=\"http:\/\/index.heritage.org\/military\/2016\/assessments\/\" target=\"_blank\">http:\/\/index.heritage.org\/military\/2016\/assessments\/<\/a><\/p>\n<p>http:\/\/www.odiario.info\/index.php\/bases-da-nato-na-europa-e\/<\/p>\n","protected":false},"excerpt":{"rendered":"Rui Namorado Rosa Num fundamentado texto como \u00e9 sempre uso, Rui Namorado Rosa diz no texto que hoje publicamos por que raz\u00e3o \u00aba \n<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/11375\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[38],"tags":[],"class_list":["post-11375","post","type-post","status-publish","format-standard","hentry","category-c43-imperialismo"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-2Xt","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/11375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=11375"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/11375\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=11375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=11375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=11375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}