{"id":11732,"date":"2016-08-02T00:42:39","date_gmt":"2016-08-02T03:42:39","guid":{"rendered":"https:\/\/pcb.org.br\/portal2\/?p=11732"},"modified":"2016-08-19T20:06:03","modified_gmt":"2016-08-19T23:06:03","slug":"cerca-de-100-movimentos-e-organizacoes-juntos-no-rj-para-protestar-nos-jogos-da-exclusao","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/11732","title":{"rendered":"Cerca de 100 movimentos e organiza\u00e7\u00f5es juntos no RJ para protestar nos Jogos da Exclus\u00e3o"},"content":{"rendered":"<p><b><img data-recalc-dims=\"1\" decoding=\"async\" class=\"imagem\" title=\"imagem\" src=\"https:\/\/i0.wp.com\/lh3.googleusercontent.com\/-5jb51ygb_x0\/V6AWQRuzIyI\/AAAAAAAAMXI\/j2SBUHvsb0o447PXprcauBvvRI-kAiC0gCCo\/s912\/mapa.png?w=747&#038;ssl=1\" alt=\"imagem\" \/>Marcha dos atletas, vig\u00edlia pelo respeito aos direitos humanos e ato no dia da abertura das olimp\u00edadas s\u00e3o alguns destaques das atividades<\/b><!--more--><\/p>\n<p>Quem vive no Rio de Janeiro percebe que, ao contr\u00e1rio do que mostra\u00a0a propaganda oficial, o legado das Olimp\u00edadas inclui problemas no\u00a0transporte, na sa\u00fade, \u00a0na educa\u00e7\u00e3o, na moradia, impactos aos direitos das mulheres e nas quest\u00f5es ambientais, dentre outros. A\u00a0cidade est\u00e1 cada vez mais cara e\u00a0violenta, <a href=\"http:\/\/fase.org.br\/pt\/informe-se\/noticias\/violencia-bate-recordes-na-cidade-olimpica\/\" target=\"_blank\">em especial para a popula\u00e7\u00e3o das favelas e periferias<\/a>. Para debater e protestar contra essa realidade, organiza\u00e7\u00f5es, movimentos e coletivos v\u00e3o estar na \u201cJornada de Lutas Rio 2016 \u2013 os Jogos da Exclus\u00e3o\u201d, de 1\u00ba a 5 de agosto.<\/p>\n<p>O evento vai abordar o colapso financeiro do estado, a repress\u00e3o aos camel\u00f4s e a outros trabalhadores, a militariza\u00e7\u00e3o e a viol\u00eancia policial, al\u00e9m do desrespeito ao direito \u00e0 moradia e outros. Na <a href=\"https:\/\/medium.com\/@jogosdaexclusao\/jogos-da-exclus%C3%A3o-programa%C3%A7%C3%A3o-ifcs-95d04f374ae2#.e7keqo2o1\" target=\"_blank\">programa\u00e7\u00e3o da Jornada<\/a>\u00a0de Lutas, s\u00e3o destaques atividades como: a Vig\u00edlia da Dignidade, que acontece na segunda-feira (1\u00ba), na Cinel\u00e2ndia, das 14h \u00e0s 21h, no Centro da cidade; e a Marcha dos Atletas, na ter\u00e7a-feira (2), reunindo usu\u00e1rios de equipamentos esportivos fechados ou\u00a0sucateados na \u201ccidade ol\u00edmpica\u201d.<\/p>\n<p>Est\u00e3o previstos ainda debates e oficinas no\u00a0Instituto de Filosofia e Ci\u00eancias Sociais (IFCS\/UFRJ), de 2 a 4 de agosto, no Largo de S\u00e3o Francisco, tamb\u00e9m no Centro.\u00a0Para o dia\u00a05 de agosto, \u00e0s 14h, os\u00a0mais de 100 movimentos sociais, organiza\u00e7\u00f5es e coletivos que integram a Jornada de Lutas convidam a todas e a todos\u00a0a se somarem a\u00a0<a href=\"https:\/\/www.facebook.com\/events\/818049904962891\/\" target=\"_blank\">uma manifesta\u00e7\u00e3o na Pra\u00e7a Saens Pe\u00f1a<\/a>, na Tijuca, zona norte do Rio.\u00a0\u201cQueremos mostrar que a popula\u00e7\u00e3o do Rio est\u00e1 organizada na resist\u00eancia contra os efeitos desse megaevento\u201d, explicou Larissa Larcerda, da campanha Jogos da Exclus\u00e3o.<\/p>\n<p><strong>Mapa da Exclus\u00e3o<\/strong><strong>\u00a0<\/strong><\/p>\n<p>Para fazer contraponto \u00e0 vis\u00e3o de \u201ccidade ol\u00edmpica\u201d, a campanha produziu o \u201c<a href=\"https:\/\/medium.com\/@jogosdaexclusao\/o-rio-de-janeiro-dos-jogos-da-exclus%C3%A3o-104624e70#.j9c3o1kn3\" target=\"_blank\">mapa da exclus\u00e3o<\/a>\u201d do Rio de Janeiro. De acordo com informa\u00e7\u00f5es do documento, pelo menos 77 mil pessoas perderam suas casas desde que o Rio foi escolhido como sede das Olimp\u00edadas 2016, em 2009. Tamb\u00e9m fica evidente a atua\u00e7\u00e3o policial em diferentes \u00e1reas da cidade, revelando de forma espacial o racismo do Estado contra regi\u00f5es perif\u00e9ricas e favelas em prol da mercantiliza\u00e7\u00e3o da vida.<\/p>\n<p>A campanha destaca tamb\u00e9m que nenhuma meta de despolui\u00e7\u00e3o foi cumprida para os Jogos. No caso da Ba\u00eda de Guanabara, a promessa era de que 80% do esgoto jogado nela estaria sendo tratado at\u00e9 2016, mas se\u00a0chegou nem a 50% do total. \u00a0\u201cO Rio vem lutando contra os efeitos dos megaeventos desde os Jogos Panamericanos de 2007. Agora, chegamos ao fim de um ciclo de quase uma d\u00e9cada. A Jornada de Lutas, assim, \u00e9 a chance de debater tudo que aconteceu no Rio e, em alguma medida, no pa\u00eds, mas tamb\u00e9m de fortalecer a resist\u00eancia contra esse modelo de cidade segregado\u201d, explica Giselle Tanaka,\u00a0que tamb\u00e9m integra\u00a0a campanha Jogos da Exclus\u00e3o.<\/p>\n<p><strong>FASE na\u00a0jornada de lutas\u00a0<\/strong><\/p>\n<p>Na <a href=\"https:\/\/www.facebook.com\/somosdignidade\/?fref=ts\" target=\"_blank\">Vig\u00edlia da Dignidade<\/a>, a FASE exibir\u00e1\u00a0v\u00eddeos sobre causas como direito \u00e0 cidade e justi\u00e7a ambiental. Tamb\u00e9m estar\u00e1 em um\u00a0espa\u00e7o de\u00a0troca de conhecimentos e distribui\u00e7\u00e3o de publica\u00e7\u00f5es. Na\u00a0pr\u00f3xima ter\u00e7a-feira (2), a partir das 10h, debater\u00e1\u00a0junto a outras organiza\u00e7\u00f5es e movimentos sociais a \u201chist\u00f3ria de mulheres na cidade ol\u00edmpica\u201d. \u201cAs resist\u00eancias e a auto-organiza\u00e7\u00e3o das mulheres\u201d tamb\u00e9m ser\u00e3o temas em roda de\u00a0conversa, \u00e0s 14h, com a presen\u00e7a de moradoras de Manguinhos, do Complexo do Alem\u00e3o, de ativistas transfeministas e de agricultoras urbanas.<\/p>\n<p>Aercio de Oliveira, coordenador do programa da FASE no Rio de Janeiro, ressalta que \u00e9 preciso olhar para o modelo de cidade fortalecido pelos Jogos. Como exemplo, cita o \u201c<a href=\"http:\/\/fase.org.br\/pt\/informe-se\/artigos\/porto-maravilha-violacoes-e-resistencias-onde-nasceu-o-rio\/\" target=\"_blank\">Porto Maravilha<\/a>\u201d, que \u201cse ajusta \u00e0 crescente financeiriza\u00e7\u00e3o da economia em escala global\u201d.\u00a0\u201cInicialmente, no per\u00edmetro do projeto, estaria a vila dos \u00e1rbitros e de profissionais da m\u00eddia que v\u00e3o atuar\u00a0nas olimp\u00edadas. Mas, a partir da altera\u00e7\u00e3o, a regi\u00e3o portu\u00e1ria n\u00e3o ter\u00e1 mais equipamentos ligados diretamente aos jogos. O impacto visual da arquitetura moderna das obras na regi\u00e3o, no entanto, aumentou as dificuldades para que as pessoas compreendam o quanto os investimentos foram extremamente seletivos, privilegiando os \u201cneg\u00f3cios\u201d. Na regi\u00e3o\u00a0permanece a <a href=\"http:\/\/fase.org.br\/pt\/informe-se\/noticias\/bairro-caju-excluido-de-plano-de-habitacao-para-zona-portuaria-do-rio\/\" target=\"_blank\">precariedade de servi\u00e7os p\u00fablico essenciais<\/a> \u201c, afirma, lembrando o caso das<a href=\"http:\/\/fase.org.br\/pt\/acervo\/biblioteca\/cartografia-social-urbana-transformacoes-e-resistencias-na-regiao-portuaria-do-rio-de-janeiro\/\" target=\"_blank\"> remo\u00e7\u00f5es no Morro da Provid\u00eanci<\/a>a.<\/p>\n<p>Nesse contexto, na quarta-feira (3), entram em pauta os \u201c<a href=\"https:\/\/www.facebook.com\/events\/502041453326701\/\" target=\"_blank\">desafios da luta por moradia no Rio de Janeiro<\/a>\u201c. \u00a0Estar\u00e3o presentes grupos de resist\u00eancia que emergiram em meio \u00e0 realiza\u00e7\u00e3o de megaeventos, criando novos la\u00e7os e estrat\u00e9gias na luta contra as remo\u00e7\u00f5es. O objetivo da atividade \u00e9 compor um painel de perspectivas sobre o tema ao final desse ciclo de viola\u00e7\u00f5es. Participar\u00e3o movimentos nacionais e internacionais de luta por moradia, ativistas, pesquisadores, coletivos e outras organiza\u00e7\u00f5es que se mobilizam por uma cidade justa e democr\u00e1tica.<\/p>\n<p>Saiba mais pela <a href=\"https:\/\/medium.com\/@jogosdaexclusao\/jogos-da-exclus%C3%A3o-programa%C3%A7%C3%A3o-ifcs-95d04f374ae2#.guwjhxkbv\" target=\"_blank\">programa\u00e7\u00e3o completa da Rio 2016 \u2013 Os Jogos da Exclus\u00e3o<\/a>.<\/p>\n<blockquote data-secret=\"g5Cxg4VYqb\" class=\"wp-embedded-content\"><p><a href=\"https:\/\/fase.org.br\/pt\/informe-se\/noticias\/mais-de-60-movimentos-e-organizacoes-juntas-no-rj-para-protestar-nas-olimpiadas\/\">Cerca de 100 movimentos e organiza\u00e7\u00f5es juntos no RJ para protestar nos Jogos da Exclus\u00e3o<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/fase.org.br\/pt\/informe-se\/noticias\/mais-de-60-movimentos-e-organizacoes-juntas-no-rj-para-protestar-nas-olimpiadas\/embed\/#?secret=g5Cxg4VYqb\" data-secret=\"g5Cxg4VYqb\" width=\"600\" height=\"338\" title=\"&#8220;Cerca de 100 movimentos e organiza\u00e7\u00f5es juntos no RJ para protestar nos Jogos da Exclus\u00e3o&#8221; &#8212; FASE\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"Marcha dos atletas, vig\u00edlia pelo respeito aos direitos humanos e ato no dia da abertura das olimp\u00edadas s\u00e3o alguns destaques das atividades\n<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/11732\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[7],"tags":[],"class_list":["post-11732","post","type-post","status-publish","format-standard","hentry","category-s8-brasil"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-33e","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/11732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=11732"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/11732\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=11732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=11732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=11732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}