{"id":12110,"date":"2016-09-19T02:25:49","date_gmt":"2016-09-19T05:25:49","guid":{"rendered":"https:\/\/pcb.org.br\/portal2\/?p=12110"},"modified":"2016-10-06T15:49:00","modified_gmt":"2016-10-06T18:49:00","slug":"humboldt-e-o-descobrimento-da-natureza","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/12110","title":{"rendered":"Humboldt e o descobrimento da natureza"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"imagem\" title=\"imagem\" src=\"https:\/\/i0.wp.com\/www.odiario.info\/b2-img\/123d.jpg?w=747\" alt=\"imagem\" \/>Miguel Urbano Rodrigues<\/p>\n<p>Pouco conhecido hoje fora dos meios acad\u00e9micos, Alexander Humboldt foi um dos \u00faltimos grandes humanistas com uma cultura integrada, aberto a m\u00faltiplos ramos do pensamento cient\u00edfico. Eminentes naturalistas identificam no s\u00e1bio prussiano um precursor do darwinismo. Foi amigo de Goethe, Schiller, Jefferson e Bol\u00edvar.<!--more--><\/p>\n<p>Foi em Berlim Leste, na RDA, que, ao passar frente \u00e0 Universidade que tem o seu nome, tomei consci\u00eancia em 1978 da minha ignor\u00e2ncia sobre Humboldt.<\/p>\n<p>Mas somente muitos anos depois, quando residia em Cuba, li pela primeira vez um livro seu. Humboldt era muito popular entre os intelectuais da Ilha. Fidel admirava-o, citava-o com frequ\u00eancia, e fizera traduzir muitos dos seus livros.<\/p>\n<p>Quase esquecido hoje fora dos meios acad\u00e9micos, Humboldt foi um dos \u00faltimos humanistas de cultura integrada, aberta a todos ramos do conhecimento cient\u00edfico. Eminentes naturalistas identificam nele um percursor do darwinismo.<\/p>\n<p>Segundo The Economist, os atuais ecologistas \u00abdevem tudo\u00bb a Humboldt. E na opini\u00e3o da The New York Review of Books, \u00abas suas teorias nunca estiveram t\u00e3o vivas\u00bb.<\/p>\n<p>INF\u00c2NCIA, ADOLESCENCIA E JUVENTUDE<\/p>\n<p>Alexander Von Humboldt (1769-1859) nasceu numa fam\u00edlia abastada da aristocracia prussiana. N\u00e3o teve uma inf\u00e2ncia feliz. O pai faleceu quando tinha cinco anos e a m\u00e3e, uma senhora muito religiosa e de mentalidade convencional, n\u00e3o revelou muito afeto pelos filhos.<\/p>\n<p>Alexander e o irm\u00e3o Wilhelm tiveram uma educa\u00e7\u00e3o privilegiada com os melhores professores. Mas n\u00e3o tinham di\u00e1logo com a m\u00e3e. Os dois irmaos, ligados por uma amizade profunda, eram muito diferentes. Wilhelm, estudioso, adorava a Hist\u00f3ria e a mitologia e cedo manifestou um grande interesse pela lingu\u00edstica.<\/p>\n<p>Alexander preferia o campo a Berlim. Durante as f\u00e9rias no castelo de Tegel, propriedade familiar, dava longas caminhadas. Os animais, as plantas, o c\u00e9u, as rochas, as montanhas e os rios, a Natureza em geral, exerciam sobre ele fasc\u00ednio.<\/p>\n<p>Ao contr\u00e1rio do irm\u00e3o, era um solit\u00e1rio e os seus poucos amigos n\u00e3o o compreendiam.<\/p>\n<p>Formou-se, sem brilho especial, em engenharia. Do seu primeiro emprego como inspetor de minas, apreciou sobretudo a oportunidade de viajar muito pelo pa\u00eds.<\/p>\n<p>Mas o seu interesse n\u00e3o era profissional: dirigia-se sobretudo aos cen\u00e1rios, aos fen\u00f3menos da Natureza e aos homens. Os mineiros eram sobrexplorados,o que o indignava. O iluminismo era satanizado na monarquia prussiana de \u00abdireito divino\u00bb.<\/p>\n<p>Datam dessa \u00e9poca as suas experi\u00eancias com a chamada eletricidade animal. Sem ler Feuerbach e Marx foi desde a juventude um materialista convicto.<\/p>\n<p>Aos 21 anos, com um amigo, Georg Forster, que acompanhara Cook numa das suas viagens, visitou durante quatro meses a Inglaterra, a Holanda e a Fran\u00e7a.<\/p>\n<p>Essa perambula\u00e7\u00e3o europeia contribuiu para refor\u00e7ar a sua avers\u00e3o pela atmosfera obscurantista da Pr\u00fassia. Amava a liberdade, era um liberal.<\/p>\n<p>Ao visitar o irm\u00e3o, j\u00e1 casado e com filhos, em Iena onde ent\u00e3o residia, teve a oportunidade de conhecer dois gigantes da literatura: Goethe e Schiller. Desenvolveu uma solida amizade com ambos. Ele e Goethe descobriram uma paix\u00e3o comum pela bot\u00e2nica, pelas transforma\u00e7\u00f5es clim\u00e1ticas, pelo regime de ventos, pela capacidade das \u00e1rvores para enriquecer a atmosfera com humidade.<\/p>\n<p>Juntos lamentaram a forma como o homem perturbava o equil\u00edbrio harmonioso da Natureza, a sua tend\u00eancia a destruir o ambiente.<\/p>\n<p>Sem disso tomar consci\u00eancia, o jovem Humboldt foi o pai do movimento ambientalista.<\/p>\n<p>AM\u00c9RICA LATINA: AVENTURA E CI\u00caNCIA<\/p>\n<p>Em junho de 1799, acompanhado do m\u00e9dico e bot\u00e2nico franc\u00eas Aim\u00e9 Bonpland, embarcou na Corunha para a Venezuela. O rei de Espanha, Carlos IV, autorizara-o a visitar as suas colonias da Am\u00e9rica, privilegio rar\u00edssimas vezes concedido a um estrangeiro.<\/p>\n<p>Humboldt era um jovem naturalista de 22 anos, admirado por Goethe, mas desconhecido na Europa.<\/p>\n<p>Ao regressar cinco anos depois foi recebido em Paris e na Alemanha como figura proeminente da comunidade cient\u00edfica.<\/p>\n<p>Ele pr\u00f3prio teve dificuldade em compreender a sua vertiginosa eleva\u00e7\u00e3o aos p\u00edncaros da fama. A sua obra monumental somente seria publicada no regresso ao longo de mais de cinco d\u00e9cadas.<\/p>\n<p>Mas textos seus, enviados de pa\u00edses que percorrera, haviam sido amplamente divulgados na Europa e nos Estados Unidos suscitando surpresa e admira\u00e7\u00e3o.<\/p>\n<p>Humboldt rompera como naturalistas fronteiras tradicionais da ci\u00eancia.<\/p>\n<p>Ao desembarcar em Cuman\u00e1 no oriente venezuelano, teve a sensa\u00e7\u00e3o de que chegar a outro planeta. Tudo era diferente e n\u00e3o imaginado: as plantas, as \u00e1rvores, o clima, o mar, os rios, as montanhas, as plan\u00edcies. Tudo o encantou, exceto o sistema colonial e a escravatura.<\/p>\n<p>Desceu o Orenoco, atravessou a estepe dos LLanos, conheceu a amaz\u00f3nia equatoriana, escalou o Chimborazo, o gigante andino que na \u00e9poca, erradamente, era tido como a montanha mais alta do mundo.<\/p>\n<p>Conviveu com tribos de \u00edndios e impressionou-o o conhecimento que tinha das \u00e1rvores floresta de todos os animais da selva. Reagiu aos estere\u00f3tipos europeus sobre a barb\u00e1rie dos selvagens.<\/p>\n<p>Nos Andes esbo\u00e7ou aquilo a que chamou Naturgemalde, palavra que pode designar um quadro da natureza que aponta para totalidade.<\/p>\n<p>\u00abA Natureza &#8211; afirmou &#8211; \u00e9 uma totalidade viva, n\u00e3o um agregado morto\u00bb. E desenhou o Naturgemalde, representando em corte transversal como uma rede em que tudo estava ligado. As plantas distribu\u00edam-se segundo a latitude desde os l\u00edquenes da linha das neves aos carvalhos e j\u00e1 na base as palmeiras tropicais.<\/p>\n<p>O Naturgemalde condensava&lt; num estranho quadro de 90 por 60 cm a s\u00edntese das teses revolucion\u00e1rias de Humboldt sobre a integra\u00e7\u00e3o da Natureza.<\/p>\n<p>Depois de visitar o Peru e estudar ruinas da civiliza\u00e7\u00e3o incaica embarcou no Equador para o M\u00e9xico onde permaneceu um ano. Na \u00e9poca a arqueologia ainda n\u00e3o realizara as escava\u00e7\u00f5es que iluminaram a hist\u00f3ria de Tenochtitlan e da sua destrui\u00e7\u00e3o por Cortez. Mas o que viu foi suficiente para Humboldt sentir deslumbramento pela cultura dos antigos mexicanos. A sua avers\u00e3o pela coloniza\u00e7\u00e3o espanhola aumentou<\/p>\n<p>Apos uma breve passagem por Cuba viajou para os Estados Unidos. Mantinha h\u00e1 muito correspond\u00eancia com Jefferson que o admirava muito.<\/p>\n<p>A empatia entre ambos foi imediata. Humboldt era um falador excepcional.Emitia por minuto o dobro de palavras de uma pessoa normal, Mas Jefferson escutava-o embevecido. Convidou-o para a Casa Branca onde o s\u00e1bio prussiano conviveu com intelectuais e pol\u00edticos, incluindo o futuro presidente Madison.<\/p>\n<p>Teve uma despedida triunfal quando embarcou para Fran\u00e7a em junho de 1804.<\/p>\n<p>A OBRA FOI ESCRITA EM PARIS E BERLIM<\/p>\n<p>Uma biografia de um n\u00edvel excecional reavivou no mundo da cultura, nos \u00faltimos anos, o interesse pelo genial cientista: A Inven\u00e7\u00e3o da Natureza- As aventuras de Alexander Von Humboldt, o her\u00f3i esquecido da ci\u00eancia.*<br \/>\nA autora, Andrea Wulf, dedicou anos a esse trabalho, definido pelo Finantial Times como \u00abuma fascinante hist\u00f3ria das ideias\u00bb<\/p>\n<p>Humbolt fixou resid\u00eancia em Paris. A Academia das Ci\u00eancias e o Jardin des Plantes eram para ele indispens\u00e1veis para as suas pesquisas.<\/p>\n<p>Achava Berlim uma cidade provinciana, insipida sem uma universidade.<\/p>\n<p>Mas o rei da Pr\u00fassia, Frederico Guilherme III seu grande admirador, atribui-lhe uma generosa pens\u00e3o. Tinha gasto grande parte da fortuna pessoal nas viagens e na prepara\u00e7\u00e3o da sua obra.<\/p>\n<p>Paris aparecia-lhe como o polo da cultura europeia que deslocava as fronteiras do pensamento cient\u00edfico. Ali desenvolveu amizades com cientistas famosos como Gay Lussac, Cuvier, Lamarck.<\/p>\n<p>Teve grandes amigos, mas nunca se interessou por mulheres.<\/p>\n<p>Ao iniciar a escrita de Viagem \u00e0s Regi\u00f5es Equatoriais do Novo Continente n\u00e3o imaginava que essa obra teria 34 volumes e lhe exigiria muitos anos de um trabalho exaustivo. O primeiro tomo teve por t\u00edtulo Ensaio sobre Geografia das Plantas. Nele defendia uma compreens\u00e3o revolucion\u00e1ria da natureza incompat\u00edvel com a de Lineu, o celebre bot\u00e2nico sueco. Goethe ao ler o livro afirmou numa confer\u00eancia que Humboldt iluminara a ciencia com \u00abuma brilhante chama\u00bb.<\/p>\n<p>Quando Napole\u00e3o esmagou a Pr\u00fassia reduzindo-a a pot\u00eancia de segunda classe, o rei for\u00e7ou Humboldt a mudar-se para Berlim. Ai escreveu Perspectivas da Natureza, traduzido em onze l\u00ednguas.<\/p>\n<p>Era uma obra simultaneamente cient\u00edfica e liter\u00e1ria, acess\u00edvel a m\u00faltiplas classes sociais. Descrevia a Natureza, lembra Andrea Wulf, \u00abcomo rede de vida com plantas e animais dependentes uns dos outros\u201d, sublinhando as liga\u00e7\u00f5es internas das for\u00e7as naturais.<\/p>\n<p>\u00abComparava os desertos da \u00c1frica com os LLanos da Venezuela e as charnecas do Norte da Europa, paisagens muito afastadas umas das outras, mas agora combinadas num retrato \u00fanico da Natureza\u00bb<\/p>\n<p>Goethe, fascinado, escreveu uma carta ao amigo expressando o seu entusiasmo. Chateaubriand afirmou achar aquela escrita t\u00e3o extraordin\u00e1ria que \u00abse acredita estar a deslizar nas ondas com ele, a perdermo-nos com ele nas profundezas dos bosques\u00bb.<\/p>\n<p>De volta a Paris com autoriza\u00e7\u00e3o do rei (escreveu parte da sua obra em franc\u00eas) retomou a correspond\u00eancia com Jefferson e Bolivar. O libertador das col\u00f3nias espanholas admirava o s\u00e1bio prussiano. Orgulhava se da influ\u00eancia que exercera na sua luta. Via nele \u00abo descobridor do Novo Mundo\u00bb.7<\/p>\n<p>Charles Darwin visitou-o em Paris. Era ent\u00e3o um jovem naturalista quase desconhecido. Nao escondia aos amigos que fora A Narrativa Pessoal que o decidira a embarcar no Beagle para a viagem que lhe permitiu escrever A Origem das Esp\u00e9cies, o livro que o imortalizaria.<br \/>\nNuma das suas idas a Londres tentou mais uma vez obter autoriza\u00e7\u00e3o da Companhia da India Oriental para visitar o subcontinente. O ministro Canning e o pr\u00f3prio rei de Inglaterra intercederam por ele. A sua aspira\u00e7\u00e3o era escalar os Himalaias, Mas a Companhia, que ent\u00e3o tinha um poder absoluto na India, n\u00e3o atendeu o seu pedido. Conhecia os textos anti-colonialistas de Humboldt.<\/p>\n<p>No seu regresso definitivo a Berlim, obteve junto do czar Nicolau I da R\u00fassia autoriza\u00e7\u00e3o para visitar a Sib\u00e9ria.<\/p>\n<p>Foi a sua \u00faltima grande aventura. Desceu at\u00e9 a Cordilheira do Altai entre o Cazaquist\u00e3o, a R\u00fassia, a Mong\u00f3lia e China. Percorreu 16 000 quil\u00f3metros em seis meses. Tinha 60 anos, mas aguentou bem m os gelos siberianos e os calores abrasadores das estepes russas. No regresso, foi recebido em Petersburgo, na Academia Imperial das Ci\u00eancias como um her\u00f3i.<\/p>\n<p>Puskin dele disse ao escut\u00e1-lo: \u00abCativantes discursos jorravam da sua boca\u00bb.<\/p>\n<p>A viagem permitiu-lhe confirmar a sua teoria sobre conex\u00f5es que ligavam todos os fen\u00f3menos e for\u00e7as da Natureza.<\/p>\n<p>O COSMO, SINTESE DO SEU PENSAMENTO<\/p>\n<p>Humboldt tinha mais de 65 nos quando concebeu a ideia de um livro que, escreve Andrea Wulf, representasse numa \u00ab\u00fanica obra todo o mundo material\u00bb.<\/p>\n<p>Foi, inesperadamente, o mais famoso dos seus livros: Cosmo, Um Esbo\u00e7o da Descri\u00e7\u00e3o F\u00edsica do Universo.<br \/>\nO primeiro tomo foi publicado na Alemanha em 1845,seis anos depois de iniciado.<br \/>\nHumboldt transporta os leitores &#8211; comenta Wulf &#8211; numa viagem desde o espa\u00e7o exterior at\u00e9 \u00e1 Terra\u00bb.<br \/>\nO segundo tomo foi publicado dois anos mais tarde em 1847-Nele conduz o leitor-esclarece a bi\u00f3grafa &#8211; \u00abnuma viagem do espirito pela hist\u00f3ria humana desde antigas civiliza\u00e7\u00f5es at\u00e9 aos tempos modernos\u00bb.<br \/>\nEm 1850\/51 publicou o terceiro tomo. Na introdu\u00e7\u00e3o informou que seria o ultimo e nele tentava superar defici\u00eancias dos anteriores.<\/p>\n<p>Mas afinal escreveu mais dois tomos. O quarto, em 1857, incidia sobre o geomagnetismo, os vulc\u00f5es e os terramotos.<\/p>\n<p>Humboldt, muito debilitado apos uma apoplexia, continuou a escrever com a paix\u00e3o de um jovem. Segundo Andrea Wulf, recebia aproximadamente 4 000 cartas por ano e respondia ainda a mais de 2000.<br \/>\nDesde a morte do irm\u00e3o sua tend\u00eancia para a solid\u00e3o acentuou-se. Wilhelm e ele eram muito diferentes. O irm\u00e3o era tamb\u00e9m um s\u00e1bio, mas tamb\u00e9m um diplomata. Foi embaixador na It\u00e1lia, na Inglaterra e na \u00c1ustria e fundador da Universidade de Berlim, quando ministro da Educa\u00e7\u00e3o. Desde meninos uma amizade indestrut\u00edvel os uniu.<br \/>\nEscreveu o quinto tomo j\u00e1 muito doente. Enviou o manuscrito ao editor semanas antes de morrer e foi publicado postumamente.<\/p>\n<p>Quando faleceu, a 6 de maio de 1959, tinha 89 anos.<\/p>\n<p>Em toda a Europa, na Am\u00e9rica e na \u00c1sia foram escritas milhares de p\u00e1ginas sobre o cientista e o homem.<\/p>\n<p>Para o reio Guilherme IV da Pr\u00fassia, Alexander Von Humboldt foi \u00abo maior homem desde o Dil\u00favio\u00bb.<\/p>\n<p>*Andrea Wulf, A Inven\u00e7\u00e3o da Natureza-As Aventuras de Alexander Von Humboldt, o her\u00f3i esquecido da ci\u00eancia, 544 p\u00e1ginas, Circulo de Leitores, Lisboa<\/p>\n<p>http:\/\/www.odiario.info\/humboldt-e-o-descobrimento-da-natureza\/<\/p>\n","protected":false},"excerpt":{"rendered":"Miguel Urbano Rodrigues Pouco conhecido hoje fora dos meios acad\u00e9micos, Alexander Humboldt foi um dos \u00faltimos grandes humanistas com uma cultura integrada, aberto \n<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/12110\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[50],"tags":[],"class_list":["post-12110","post","type-post","status-publish","format-standard","hentry","category-c61-cultura-revolucionaria"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-39k","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/12110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=12110"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/12110\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=12110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=12110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=12110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}