{"id":12303,"date":"2016-10-10T18:06:41","date_gmt":"2016-10-10T21:06:41","guid":{"rendered":"https:\/\/pcb.org.br\/portal2\/?p=12303"},"modified":"2016-11-04T16:08:18","modified_gmt":"2016-11-04T19:08:18","slug":"premiam-o-inventor-dos-falsos-positivos-com-o-premio-nobel-da-paz","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/12303","title":{"rendered":"Premiam o inventor dos \u201cFALSOS POSITIVOS\u201d com o Pr\u00eamio Nobel da Paz"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" height=\"400\" width=\"620\" decoding=\"async\" class=\"imagem\" title=\"imagem\" src=\"https:\/\/i0.wp.com\/www.resumenlatinoamericano.org\/wp-content\/uploads\/2016\/10\/santos_y_fuerzas_militares_0-620x400.jpg?resize=620%2C400\" alt=\"imagem\" \/><strong><b>Por Dick Emanuelsson,<\/b><\/strong> Resumen Latinoamericano, 7 de outubro de 2016 \u2013 O mandat\u00e1rio colombiano \u00e9 premiado pelo Comit\u00ea da OTAN em Oslo. \u00c9 realmente indignante, por\u00e9m n\u00e3o surpreendente.<!--more--><\/p>\n<p>O comit\u00ea se destacou anteriormente por outorgar o pr\u00eamio a reconhecidos genocidas, como Henry Kissinger, Menachem Begin e, para coroar sua lista, outorgou a Obama o pr\u00eamio manchado de sangue dos povos em luta.<\/p>\n<p>Quando o Ex\u00e9rcito colombiano tinha o comandante Alfonso Cano ante os fuzis, indefeso e cego por ter perdido seus \u00f3culos, os militares se comunicaram com Santos e perguntaram o que fariam. Apesar das primeiras negocia\u00e7\u00f5es secretas entre as FARC e o governo de Santos j\u00e1 terem iniciado para preparar o Processo de Paz em Havana, Santos n\u00e3o hesitou um segundo. \u201cMATEM!\u201d foi a ordem desse senhor que, ante o rev\u00e9s do resultado do plebiscito no domingo passado, revogou o Cessar-fogo Bilateral para a data de 31 de outubro, ano em curso, ao inv\u00e9s de formalizar juridicamente o Acordo Final da Paz com as FARC.<\/p>\n<p>Dois dias depois, o Comit\u00ea noruegu\u00eas tomou a decis\u00e3o de outorgar-lhe o pr\u00eamio.<\/p>\n<p>N\u00e3o \u00e9 s\u00f3 isso. Quem inventou a ins\u00f3lita frase \u201cFalsos Positivos\u201d? Foi o senhor Santos, na qualidade de Ministro da Guerra do narcopresidente \u00c1lvaro Uribe V\u00e9lez. \u201cFalsos Positivos\u201d n\u00e3o \u00e9 outra coisa que \u201cExecu\u00e7\u00f5es extrajudiciais\u201d, ou na boca do povo: fuzilamento do advers\u00e1rio.<\/p>\n<p>Porem, os \u201cadvers\u00e1rios\u201d eram civis, n\u00e3o guerrilheiros. Jovens sem trabalho, deficientes e gente inocente. A ordem da dupla Uribe&amp;Santos a seus generais era \u201cPRODUZIR O RESULTADO EM LITROS DE SANGUE!\u201d.<\/p>\n<p>N\u00e3o nos estranha que lhe deem o pr\u00eamio porque o pa\u00eds que receber\u00e1 a medalha \u00e9 membro da OTAN, a mesma alian\u00e7a de guerra que agora se prepara para converter o conflito na S\u00edria em uma guerra final contra toda a oposi\u00e7\u00e3o do planeta e da humanidade \u00e0 pol\u00edtica de exterm\u00ednio das lutas populares. N\u00e3o nos enganemos!<\/p>\n<p>Os verdadeiros lutadores pela paz na Col\u00f4mbia se encontram nas fileiras do povo, aqueles que nunca duvidaram por um segundo em entregar seu peito e sua vida para acabar com uma classe de assassinos e exploradores que s\u00e3o capazes de exterminar seu pr\u00f3prio povo para preservar seus privil\u00e9gios.<\/p>\n<p>Fonte: http:\/\/www.resumenlatinoamericano.org\/2016\/10\/07\/premian-el-inventor-de-los-falsos-positivos-con-el-premio-nobel-de-paz\/<\/p>\n<p>Tradu\u00e7\u00e3o: Partido Comunista Brasileiro (PCB)<\/p>\n","protected":false},"excerpt":{"rendered":"Por Dick Emanuelsson, Resumen Latinoamericano, 7 de outubro de 2016 \u2013 O mandat\u00e1rio colombiano \u00e9 premiado pelo Comit\u00ea da OTAN em Oslo. \u00c9 \n<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/12303\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[34],"tags":[],"class_list":["post-12303","post","type-post","status-publish","format-standard","hentry","category-c39-colombia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-3cr","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/12303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=12303"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/12303\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=12303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=12303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=12303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}