{"id":13228,"date":"2017-01-15T17:14:17","date_gmt":"2017-01-15T20:14:17","guid":{"rendered":"https:\/\/pcb.org.br\/portal2\/?p=13228"},"modified":"2017-01-29T15:08:13","modified_gmt":"2017-01-29T18:08:13","slug":"pais-negligencia-o-crime-organizado-e-combate-o-inimigo-errado-afirma-pesquisadora","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/13228","title":{"rendered":"Pa\u00eds negligencia o crime organizado e combate o inimigo errado, afirma pesquisadora"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"imagem\" title=\"imagem\" src=\"https:\/\/i0.wp.com\/farm1.staticflickr.com\/621\/32108302161_2e04b340f4_z.jpg?w=747&#038;ssl=1\" alt=\"imagem\" \/>N\u00e3o se pode combater organiza\u00e7\u00f5es e fluxos ilegais sem mexer em articula\u00e7\u00f5es pol\u00edticas e econ\u00f4micas<\/p>\n<p>Luciano Velleda<\/p>\n<p>Rede Brasil Atual, 10 de Janeiro de 2017 \u00e0s 10:20<!--more--><\/p>\n<p>Nos \u00faltimos dias diversos especialistas explicaram que as matan\u00e7as ocorridas nos pres\u00eddios em Manaus e Boa Vista n\u00e3o s\u00f3 n\u00e3o foram um \u201cacidente\u201d, como definiu o presidente Michel Temer, como eram previs\u00edveis desde o an\u00fancio da ruptura, em outubro de 2016, da rela\u00e7\u00e3o entre Comando Vermelho (CV) e Primeiro Comando da Capital (PCC).<\/p>\n<p>Para a pesquisadora Jacqueline Sinhoretto, professora da Universidade Federal de S\u00e3o Carlos (UFScar) e coordenadora do Grupo de Estudos sobre Viol\u00eancia e Administra\u00e7\u00e3o de Conflitos da institui\u00e7\u00e3o, as 99 mortes de presos demonstram que o sistema penal do Brasil luta contra o inimigo errado. Organizadora do Mapa do Encarceramento, lan\u00e7ado em 2015, Jacqueline avalia que todo o empenho da seguran\u00e7a p\u00fablica do pa\u00eds est\u00e1 voltado para crimes de menor import\u00e2ncia, enquanto a verdadeira estrutura do crime organizado n\u00e3o \u00e9 combatida.<\/p>\n<p>\u201cO tipo de controle que se faz no Brasil de organiza\u00e7\u00f5es criminais e dos fluxos dos mercados ilegais tem pouca efetividade. N\u00e3o tem como combater organiza\u00e7\u00f5es criminais sem mexer com as articula\u00e7\u00f5es pol\u00edticas e econ\u00f4micas que elas t\u00eam. E \u00e9 exatamente isso que n\u00e3o se faz no Brasil, onde queremos enfrentar o narcotr\u00e1fico com o encarceramento de pequenos traficantes\u201d, afirma a pesquisadora.<\/p>\n<p>Nessa entrevista, ela destaca que os programas de metas e de bonifica\u00e7\u00f5es policiais, em vigor em v\u00e1rios estados do pa\u00eds, colaboram para o caos do sistema carcer\u00e1rio. \u201cO sucesso da atividade policial \u00e9 medido pelo n\u00famero de pris\u00f5es e de apreens\u00f5es realizadas. Vemos claramente que essas pris\u00f5es ocorrem numa magnitude que est\u00e1 relacionada a essa ideia de bonificar policiais pelo n\u00famero de pris\u00f5es e flagrantes feitos.\u201d<\/p>\n<p>O problema, explica, \u00e9 que o foco dessas pris\u00f5es est\u00e1 no tr\u00e1fico de drogas e crimes contra o patrim\u00f4nio, enquanto outros delitos mais graves n\u00e3o s\u00e3o enfrentados. \u201cHomic\u00eddio \u00e9 prioridade, feminic\u00eddio \u00e9 prioridade, crimes graves que envolvem amea\u00e7as \u00e0 vida, como estupro e sequestro, crimes que envolvem viol\u00eancia f\u00edsica devem ser as prioridades.\u201d<\/p>\n<p>Para ela, n\u00e3o h\u00e1 d\u00favida: o Brasil enfrenta de modo equivocado o crime. \u201cH\u00e1 pouca efic\u00e1cia no combate ao crime em dimens\u00e3o macro, que s\u00e3o realmente as redes criminais, como elas lavam dinheiro, como se organizam, quem s\u00e3o as lideran\u00e7as principais e como ela corrompe o sistema. Se investe pouco nisso que \u00e9 a sustenta\u00e7\u00e3o da economia criminal.\u201d<\/p>\n<p><strong>O que significou o rompimento entre o PCC e o CV?<\/strong><\/p>\n<p>Quando houve o rompimento, ficou bem claro que iria mudar a l\u00f3gica de conviv\u00eancia das a\u00e7\u00f5es criminais. \u00c9 uma disputa de hegemonia, de poder e de mercado dentro das penitenci\u00e1rias, mas n\u00e3o s\u00f3. \u00c9 poss\u00edvel, como tem acontecido em algumas capitais e outras cidades m\u00e9dias, toda uma reorganiza\u00e7\u00e3o desses fluxos e de uma economia pol\u00edtica do crime. Depois que houve a explicita\u00e7\u00e3o de que acabou o acordo entre PCC e CV, ficou o alerta de que havia a possibilidade de conflitos violentos dentro das cadeias, onde a presen\u00e7a \u00e9 importante, mas tamb\u00e9m transbordando. O crescimento de homic\u00eddios em Natal, em 2016, j\u00e1 responde a essa tens\u00e3o de grupos ligados de alguma forma ao CV ou ao PCC. Cada localidade tem uma combina\u00e7\u00e3o pr\u00f3pria, com quadrilhas locais que se articulam nesses mercados ilegais e que podem ou n\u00e3o gerar viol\u00eancia.<\/p>\n<p><strong>Diante desses avisos, o que poderia ou deveria ter sido feito?<\/strong><\/p>\n<p>\u00c9 muito dif\u00edcil falar agora, \u00e9 uma quest\u00e3o complexa que emerge de l\u00f3gicas complexas. Todos os pa\u00edses que enfrentaram problemas com organiza\u00e7\u00f5es criminais tiveram muita dificuldade. O tipo de controle que se faz no Brasil de organiza\u00e7\u00f5es criminais e dos fluxos dos mercados ilegais tem pouca efetividade. Primeiro porque existem agentes pol\u00edticos e estatais que est\u00e3o totalmente envolvidos com a gest\u00e3o dos mercados ilegais. N\u00f3s vemos a ponta do iceberg explodir nas posi\u00e7\u00f5es mais fr\u00e1geis, nas posi\u00e7\u00f5es hier\u00e1rquicas mais vulner\u00e1veis dessa cadeia econ\u00f4mica. Essas matan\u00e7as s\u00e3o as franjas de uma economia criminal e uma disputa de poder. N\u00e3o tem como combater organiza\u00e7\u00f5es criminais sem mexer com todas as articula\u00e7\u00f5es pol\u00edticas e econ\u00f4micas que elas t\u00eam. E \u00e9 exatamente isso que n\u00e3o se faz no Brasil, onde queremos enfrentar o narcotr\u00e1fico com o encarceramento de pequenos traficantes, o que acaba n\u00e3o resolvendo nosso problema e ainda aumentando o escopo dessas organiza\u00e7\u00f5es que t\u00eam na cadeia uma base de recrutamento de m\u00e3o-de-obra.<\/p>\n<p><strong>De que forma o d\u00e9ficit de vagas nos pres\u00eddios colabora para essa situa\u00e7\u00e3o de elevada criminalidade?<\/strong><\/p>\n<p>Esse problema do d\u00e9ficit \u00e9 estranho. N\u00e3o \u00e9 que tem d\u00e9ficit porque faltam vagam. O estado de S\u00e3o Paulo tem d\u00e9ficit ao mesmo tempo em que investiu como nunca na constru\u00e7\u00e3o de pres\u00eddios, chegando a ter 163 unidades prisionais. Minas Gerais tamb\u00e9m construiu muita cadeia num curto espa\u00e7o de tempo e o n\u00famero de presos cresceu seis vezes em dez anos. Esses estados fizeram investimento maci\u00e7o em constru\u00e7\u00f5es de pres\u00eddios, contrata\u00e7\u00e3o de m\u00e3o de obra especializada, cria\u00e7\u00e3o de carreira espec\u00edfica de agentes penitenci\u00e1rios. S\u00e3o Paulo e Minas Gerais s\u00e3o os dois estados que mais avan\u00e7aram nessa quest\u00e3o e mesmo assim t\u00eam d\u00e9ficit.<\/p>\n<p><strong>Por que se prende muito?<\/strong><\/p>\n<p>Porque se prende sem uma pol\u00edtica criminal respons\u00e1vel, se prende gente que n\u00e3o cometeu crime violento, mas isso n\u00e3o depende s\u00f3 da cabe\u00e7a do juiz, depende da legisla\u00e7\u00e3o tamb\u00e9m. H\u00e1 programas de metas de pris\u00f5es em S\u00e3o Paulo, Rio de Janeiro, Minas Gerais e Pernambuco. O sucesso da atividade policial \u00e9 medido pelo n\u00famero de pris\u00f5es e de apreens\u00f5es que s\u00e3o realizadas ou de casos solucionados. Quando se realiza uma pris\u00e3o em flagrante, toda a burocracia que existe numa investiga\u00e7\u00e3o, na pris\u00e3o em flagrante fica simplificada. Ent\u00e3o existe muita den\u00fancia de flagrante forjado. As pr\u00f3prias audi\u00eancias de cust\u00f3dia foram criadas pelo reconhecimento de que h\u00e1 muito preso provis\u00f3rio e que muitos detidos em flagrante n\u00e3o deveriam aguardar o julgamento preso ou, se chegarem a ser condenados, n\u00e3o v\u00e3o receber pena de pris\u00e3o. Ent\u00e3o vemos claramente que essas pris\u00f5es s\u00e3o realizadas numa magnitude que est\u00e1 relacionada a essa ideia de bonificar policiais pelo n\u00famero de pris\u00f5es e flagrantes realizados. E esses s\u00e3o os estados que mais aumentaram a popula\u00e7\u00e3o carcer\u00e1ria.<\/p>\n<p><strong>Dados do Mapa do Encarceramento mostram que 18,7% dos presos s\u00e3o condenados com penas de at\u00e9 quatro anos de reclus\u00e3o e, por isso, podiam estar cumprindo penas alternativas, mas n\u00e3o est\u00e3o.<\/strong><\/p>\n<p>\u00c9 uma popula\u00e7\u00e3o que realmente n\u00e3o devia estar presa e \u00e9 justamente a popula\u00e7\u00e3o visada pela audi\u00eancia de cust\u00f3dia, que \u00e9 para n\u00e3o manter encarcerado uma pessoa que quando julgada n\u00e3o receber\u00e1 uma pena privativa. Fala-se muito em superlota\u00e7\u00e3o\u2026 Faltam vagas? N\u00e3o sei se precisa construir mais pres\u00eddios. O que \u00e9 necess\u00e1rio, em primeiro lugar, \u00e9 evitar que as pessoas que n\u00e3o precisem cumprir pena em regime fechado estejam l\u00e1 dentro. As audi\u00eancias de cust\u00f3dia s\u00e3o exatamente para mexer neste quadro, s\u00f3 que elas n\u00e3o est\u00e3o implantadas em todos os lugares e tamb\u00e9m n\u00e3o temos estudo para avaliar como as audi\u00eancias est\u00e3o indo. H\u00e1 um estudo, do qual fa\u00e7o parte, promovido pelo Conselho Nacional de Justi\u00e7a (CNJ) para avaliar como as audi\u00eancias de cust\u00f3dia est\u00e3o funcionando. A pesquisa est\u00e1 sendo feita em Porto Alegre, Florian\u00f3polis, S\u00e3o Paulo, Jo\u00e3o Pessoa, Distrito Federal e Goi\u00e2nia.<\/p>\n<p><strong>Nas medidas anunciadas semana passada para enfrentar a crise, o ministro da Justi\u00e7a, Alexandre de Moraes, enfatizou o trabalho da Defensoria P\u00fablica para aliviar os presos provis\u00f3rios. \u00c9 esse o caminho?<\/strong><\/p>\n<p>O trabalho da Defensoria P\u00fablica poderia n\u00e3o ser t\u00e3o superdimensionado se n\u00e3o tiv\u00e9ssemos uma pol\u00edcia baseada em pris\u00e3o em flagrante, com metas de pris\u00e3o, e tamb\u00e9m com poss\u00edveis mudan\u00e7as legislativas. Por que n\u00e3o uma proposta legislativa de que crimes cometidos sem viol\u00eancia recebam penas alternativas? Isto seria uma medida muito mais efetiva. Caso contr\u00e1rio, sobrecarrega a Defensoria, as pris\u00f5es e o Minist\u00e9rio P\u00fablico tamb\u00e9m. N\u00e3o \u00e9 s\u00f3 a Defensoria que precisa fazer seu trabalho. Para ela atuar, o Minist\u00e9rio P\u00fablico tem de estudar a acusa\u00e7\u00e3o, fazer as provas e o juiz julgar. Agora, \u00e9 p\u00fablico e not\u00f3rio que as condi\u00e7\u00f5es de trabalho da Defensoria P\u00fablica n\u00e3o s\u00e3o compat\u00edveis com a estrutura e recursos do Minist\u00e9rio P\u00fablico e do Judici\u00e1rio, nem em sal\u00e1rios e nem em termos de quantidade de pessoal.<\/p>\n<p><strong>A Defensoria P\u00fablica \u00e9 uma ponta fr\u00e1gil do sistema?<\/strong><\/p>\n<p>\u00c9 preciso um trabalho de articula\u00e7\u00e3o entre todas as institui\u00e7\u00f5es, e n\u00e3o de fragmenta\u00e7\u00e3o. \u00c9 um trabalho que vai desde a pol\u00edcia civil e militar, que tem de ter prioridade e crit\u00e9rio. N\u00e3o faz sentido prender traficantes que muitas vezes s\u00e3o usu\u00e1rios, com pequen\u00edssima quantidade de drogas para consumo pr\u00f3prio, que se for para uma audi\u00eancia de cust\u00f3dia at\u00e9 resulta em soltura. H\u00e1 todo um trabalho do Judici\u00e1rio que poderia ser evitado e agilizado se houvesse uma articula\u00e7\u00e3o e estabelecimento de prioridades que sejam exequ\u00edveis. Homic\u00eddio \u00e9 prioridade, feminic\u00eddio \u00e9 prioridade, crimes graves que envolvem amea\u00e7as, estupro, sequestro, crimes que envolvem viol\u00eancia f\u00edsica devem ser as prioridades.<\/p>\n<p><strong>Mas essa eventual &#8220;descarceriza\u00e7\u00e3o&#8221; n\u00e3o pode ser mal vista pela sociedade?<\/strong><\/p>\n<p>A gente n\u00e3o quer passar a m\u00e3o na cabe\u00e7a do bandido. N\u00e3o queremos facilitar a vida do bandido. Estamos \u00e9 reconhecendo que existem \u00e1reas fundamentais para assegurar a seguran\u00e7a do cidad\u00e3o que est\u00e3o descobertas. E esse recurso valioso para o funcionamento da seguran\u00e7a p\u00fablica e do Poder Judici\u00e1rio est\u00e1 sendo desperdi\u00e7ado com casos que n\u00e3o t\u00eam tanta import\u00e2ncia, como pequenas quantidades de drogas ou pequenos furtos em lojas, um sujeito que rouba uma camiseta, algo para comer, casos que poderiam ser solucionados de outra forma. \u00c9 um delito, claro, mas est\u00e1 ocupando o sistema de Justi\u00e7a com uma solu\u00e7\u00e3o que poderia ser de natureza civil e penas alternativas.<\/p>\n<p>Quando a gente fala que precisa racionalizar a aplica\u00e7\u00e3o da pena de pris\u00e3o n\u00e3o \u00e9 porque somos a favor de que o bandido tenha liberdade, \u00e9 por que achamos que deve haver prioridade na a\u00e7\u00e3o. Aquilo que pode ser tratado de uma forma que n\u00e3o envolva a pena de pris\u00e3o deve ser feito porque \u00e9 mais barato tanto economicamente quanto nos efeitos sociais nefastos que a pris\u00e3o causa em quem vai ser encarcerado, incluindo o contato com as organiza\u00e7\u00f5es criminais dentro das pris\u00f5es. Voc\u00ea pega um jovem que se envolveu numa quest\u00e3o simples de furto ou de pequena quantidade de drogas e coloca ele na cadeia, ali ele vai ter contato com as organiza\u00e7\u00f5es que talvez n\u00e3o teria antes. Como as condi\u00e7\u00f5es carcer\u00e1rias s\u00e3o degradantes, a pessoa para sobreviver tem que se relacionar com quem d\u00e1 as ordens no ambiente prisional. N\u00e3o tem alternativa. No fim, isso tudo traz muito mais preju\u00edzos do que benef\u00edcios.<\/p>\n<p><strong>As quest\u00f5es de fundo ent\u00e3o passam por uma nova vis\u00e3o de quem prende?<\/strong><\/p>\n<p>H\u00e1 o enfrentamento equivocado do crime. H\u00e1 pouca efic\u00e1cia no combate ao crime em dimens\u00e3o macro, que s\u00e3o realmente as redes criminais, como elas lavam dinheiro, como se organizam, quem s\u00e3o as lideran\u00e7as principais e como ela corrompe o sistema. Se investe pouco nisso que \u00e9 a sustenta\u00e7\u00e3o da economia criminal. Por outro lado se gasta muito recurso e se usa uma m\u00e3o dura com pessoas que est\u00e3o na franja desse sistema, usando mecanismos que fazem com que ela v\u00e1 ter mais contato com o crime organizado e n\u00e3o menos.<\/p>\n<p>Aquela pessoa que est\u00e1 na rua praticando um pequeno delito pode ser que n\u00e3o tenha contato com o crime organizado, mas se ela for presa, certamente ter\u00e1. Pegar um jovem que n\u00e3o tem envolvimento com o crime organizado e jog\u00e1-lo dentro de uma cadeia que est\u00e1 em tens\u00e3o, voc\u00ea n\u00e3o est\u00e1 resolvendo problema nenhum, pelo contr\u00e1rio, est\u00e1 amplificando um problema de seguran\u00e7a que vai redundar nisso que estamos assistindo e ainda coisa pior que pode ser desdobrar, porque esses conflitos s\u00e3o disputas de poder, de territ\u00f3rio e de mercado que podem sair da penitenci\u00e1ria e vir pra rua mesmo. \u00c9 o que estamos assistindo empiricamente na Bahia, Alagoas, Rio Grande do Norte e Cear\u00e1.<\/p>\n<p><strong>O Mapa do Encarceramento fala bastante sobre a tend\u00eancia punitivista do Judici\u00e1rio. Como \u00e9 isso?<\/strong><\/p>\n<p>Ela \u00e9 punitivista, mas \u00e9 enviesada. Ela \u00e9 muito punitivista com o baixo potencial lesivo, mas \u00e9 leniente com crimes violentos, que s\u00e3o pouco investigados. Se calcula que s\u00f3 8% dos crimes violentos s\u00e3o esclarecidos e processados. O Judici\u00e1rio \u00e9 muito punitivo com crimes que n\u00e3o s\u00e3o violentos, ligados ao patrim\u00f4nio ou a drogas, e muito pouco punitivo com a corrup\u00e7\u00e3o, por exemplo. \u00c9 uma seletividade na orienta\u00e7\u00e3o daquilo que merece aten\u00e7\u00e3o do sistema penal. No caso dos crimes violentos, n\u00e3o \u00e9 para isso que a pol\u00edcia e o sistema penal est\u00e3o olhando.<\/p>\n<p><strong>Mas a sensa\u00e7\u00e3o de inseguran\u00e7a da popula\u00e7\u00e3o n\u00e3o est\u00e1 relacionada mais aos crimes contra a vida?<\/strong><\/p>\n<p>Sim, mas tamb\u00e9m \u00e0 quest\u00e3o patrimonial pessoal. Voc\u00ea ter a sua casa invadida \u00e9 algo de fato assustador, ter sua intimidade violada. Esses crimes que as pessoas mais t\u00eam medo, n\u00e3o produzem a maior parte da popula\u00e7\u00e3o carcer\u00e1ria. Hoje, 30% dos presos s\u00e3o por tr\u00e1fico de drogas e quase metade \u00e9 por crime patrimonial. Boa parte desses crimes patrimoniais n\u00e3o s\u00e3o cometidos de forma violenta, mas a outra parte sim e ent\u00e3o \u00e9 mesmo preocupante e deve ser combatido. Por\u00e9m, nossas pol\u00edticas de seguran\u00e7a p\u00fablica est\u00e3o t\u00e3o ocupadas com a quest\u00e3o das drogas e dos crimes patrimoniais indistintamente, que faltam recursos, falta tempo e faltam vagas em pres\u00eddios para tratar do que realmente \u00e9 importante e deveria ser a prioridade.<\/p>\n<p>Ilustra\u00e7\u00e3o: Pesquisadora defende que a seguran\u00e7a p\u00fablica se concentre em enfrentar os crimes violentos contra a vida. Reprodu\u00e7\u00e3o. TVT<\/p>\n<p>https:\/\/www.brasildefato.com.br\/2017\/01\/10\/pais-negligencia-o-crime-organizado-e-combate-o-inimigo-errado\/<\/p>\n","protected":false},"excerpt":{"rendered":"N\u00e3o se pode combater organiza\u00e7\u00f5es e fluxos ilegais sem mexer em articula\u00e7\u00f5es pol\u00edticas e econ\u00f4micas Luciano Velleda Rede Brasil Atual, 10 de Janeiro \n<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/13228\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[190],"tags":[],"class_list":["post-13228","post","type-post","status-publish","format-standard","hentry","category-fora-temer"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-3rm","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/13228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=13228"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/13228\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=13228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=13228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=13228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}