{"id":13554,"date":"2017-02-13T13:18:43","date_gmt":"2017-02-13T16:18:43","guid":{"rendered":"https:\/\/pcb.org.br\/portal2\/?p=13554"},"modified":"2017-03-02T18:18:41","modified_gmt":"2017-03-02T21:18:41","slug":"nova-biografia-de-caio-prado-junior-poe-luz-em-sua-militancia-comunista","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/13554","title":{"rendered":"Nova biografia de Caio Prado J\u00fanior p\u00f5e luz em sua milit\u00e2ncia comunista"},"content":{"rendered":"<p><img decoding=\"async\" class=\"imagem\" title=\"imagem\" src=\"https:\/\/ci5.googleusercontent.com\/proxy\/7unDVYZNclaqO8rdS4SCyF0qNniF553Y0s0IQTwTligecVkvvOZMMeZBaOEDQF-lYAT_YIIIVsMmYnkp6l6MoY7QoyiiJtpzRbjIdNIBJnxzO7GneK4=s0-d-e1-ft#https:\/\/farm8.staticflickr.com\/7068\/27340862712_1cba59f792_z.jpg\" alt=\"imagem\" \/><\/p>\n<p><strong>Luiz Bernardo Peric\u00e1s recupera viagens, mem\u00f3rias da pris\u00e3o e rela\u00e7\u00f5es que o autor teve com intelectuais estrangeiros<\/strong><\/p>\n<p>Camila Rodrigues da Silva &#8211; BRASIL DE FATO<!--more--><\/p>\n<p>Caio Prado J\u00fanior \u00e9 autor de obras fundamentais de cursos de gradua\u00e7\u00e3o de Economia, Sociologia e Hist\u00f3ria,\u00a0como &#8220;Hist\u00f3ria Econ\u00f4mica do Brasil&#8221; e\u00a0&#8220;Forma\u00e7\u00e3o do Brasil Contempor\u00e2neo&#8221;. De origem aristocr\u00e1tica &#8211;\u00a0ele \u00e9 filho de uma das fam\u00edlias paulistas que dominavam o mercado do caf\u00e9 no in\u00edcio do s\u00e9culo 20\u00a0&#8211;\u00a0ele costuma ser definido como um dos &#8220;int\u00e9rpretes do Brasil&#8221;, junto a S\u00e9rgio Buarque de Holanda e Gilberto Freire. Entretanto,\u00a0pouco se fala de sua milit\u00e2ncia pol\u00edtica e de suas posi\u00e7\u00f5es assumidamente comunistas.<\/p>\n<p>Sua milit\u00e2ncia come\u00e7ou no in\u00edcio da d\u00e9cada de 30, quando o stalinismo j\u00e1 era uma realidade concreta e influenciava todo o movimento comunista internacional. Ele atuou\u00a0na Alian\u00e7a Nacional Libertadora (ANL), foi preso entre 1935 e 1937,\u00a0durante o primeiro governo de Get\u00falio Vargas,\u00a0e se manteve filiado\u00a0ao Partido Comunista do Brasil (PCB) at\u00e9 sua morte, mesmo com constantes discord\u00e2ncias internas. Al\u00e9m disso, dedicou parte de sua vida a visitar a China, a URSS e Cuba, onde se viveram as primeiras experi\u00eancias\u00a0socialistas.<\/p>\n<p>Para recuperar detalhes dessa trajet\u00f3ria,\u00a0o historiador\u00a0Luiz Bernardo Peric\u00e1s dedicou seis anos de pesquisa para escrever <em>Caio Prado Junior &#8211; Uma biografia<\/em>, rec\u00e9m-lan\u00e7ado pela Editora Boitempo.<\/p>\n<p>&#8220;Na verdade, para Caio, o marxismo, o engajamento social e partid\u00e1rio e as experi\u00eancias socialistas n\u00e3o eram acess\u00f3rios, mas elementos essenciais de sua trajet\u00f3ria e vis\u00e3o de mundo. N\u00e3o eram apenas ferramentas para compreender o processo hist\u00f3rico\u00a0nacional, mas aspectos primordiais de sua vida e de sua luta por mudan\u00e7as estruturais&#8221;, afirma o autor no pref\u00e1cio.<\/p>\n<p>Confira a entrevista completa:<\/p>\n<p><strong>Brasil de Fato &#8211; Quando e o qu\u00ea fizeram voc\u00ea pensar que era necess\u00e1rio produzir uma biografia pol\u00edtica de Caio Prado J\u00fanior?<\/strong><\/p>\n<p><strong>Luiz Bernardo Peric\u00e1s &#8211; <\/strong>H\u00e1 v\u00e1rios anos comecei a pesquisar a vida e obra de Caio Prado J\u00fanior e percebi, neste processo, que ainda havia muito espa\u00e7o para novos estudos sobre o grande historiador. Encontrei lacunas em sua vida, rela\u00e7\u00f5es pessoais pouco exploradas por outros autores, falta de uma aproxima\u00e7\u00e3o maior dele com diferentes intelectuais marxistas, poucos detalhes sobre suas leituras e viagens ao mundo do socialismo.\u00a0Quando iniciei minha investiga\u00e7\u00e3o, me dei conta de que havia uma quantidade enorme de documentos in\u00e9ditos que poderiam iluminar a trajet\u00f3ria pol\u00edtica de Caio Prado J\u00fanior, um tema que ainda podia ser bastante explorado.<\/p>\n<p><strong>Como voc\u00ea analisa a inser\u00e7\u00e3o da contribui\u00e7\u00e3o de Caio Prado nas universidades, principalmente nos cursos de hist\u00f3ria e de economia? Os professores o referenciam adequadamente? At\u00e9 porque, ao que me parece, existe uma prefer\u00eancia pela interpreta\u00e7\u00e3o de Celso Furtado sobre a forma\u00e7\u00e3o econ\u00f4mica brasileira\u2026<\/strong><\/p>\n<p>Caio \u00e9 considerado um \u201ccl\u00e1ssico\u201d da historiografia brasileira. \u00c9, portanto, indispens\u00e1vel nos cursos de hist\u00f3ria. Ainda assim, seus livros, em boa medida, s\u00e3o estudados de forma descolada de suas ideias pol\u00edticas e milit\u00e2ncia. Seu marxismo, muitas vezes, \u00e9 dilu\u00eddo e visto apenas como um ap\u00eandice, um acess\u00f3rio metodol\u00f3gico que utilizava para construir suas interpreta\u00e7\u00f5es, o que, a meu ver, \u00e9 algo bastante problem\u00e1tico.<\/p>\n<p>H\u00e1 professores que fazem uma leitura seletiva de determinados cap\u00edtulos ou trechos das obras principais, sem se aprofundar no que est\u00e1 por tr\u00e1s daquelas asser\u00e7\u00f5es. Ou seja, n\u00e3o leem as entrelinhas nem associam necessariamente o texto de Caio Prado J\u00fanior\u00a0ao contexto pol\u00edtico e ideol\u00f3gico em que foi produzido.<\/p>\n<p>N\u00e3o podemos nos esquecer que Caio era um \u201ccomunista\u201d, membro do PCB [Partido Comunista Brasileiro], admirador da Uni\u00e3o Sovi\u00e9tica e leitor de cl\u00e1ssicos do marxismo. Tanto seu \u201cm\u00e9todo\u201d interpretativo como sua postura de vida n\u00e3o eram, portanto, os mais populares dentro de determinados c\u00edrculos acad\u00eamicos, o que fez com que ele tivesse as portas das universidades fechadasem diferentes ocasi\u00f5es. Isso tamb\u00e9m levou a um certo distanciamento e cr\u00edticas \u00e0 sua obra por parte de v\u00e1rios intelectuais, tanto de dentro como de fora da academia.<\/p>\n<p><strong>De que forma o pensamento de CPJ nos ajudaria a interpretar o atual momento da luta de classes no Brasil?<\/strong><\/p>\n<p>Caio Prado J\u00fanior ainda \u00e9 muito atual. Sua an\u00e1lise econ\u00f4mica sobre o papel e a inser\u00e7\u00e3o do Brasil no cen\u00e1rio internacional, suas opini\u00f5es sobre o imperialismo, sua postura em defesa da constru\u00e7\u00e3o de organiza\u00e7\u00f5es de massa, seu interesse pela solu\u00e7\u00e3o da quest\u00e3o agr\u00e1ria, o apoio \u00e0s lutas dos trabalhadores (com \u00eanfase \u00e0 dos rurais), seu combate ao reacionarismo e autoritarismo, sua preocupa\u00e7\u00e3o constante com a transforma\u00e7\u00e3o efetiva do Brasil em uma verdadeira \u201cna\u00e7\u00e3o\u201d (ou seja, em superar os resqu\u00edcios coloniais e tirar o pa\u00eds de sua posi\u00e7\u00e3o dependente, subordinada e perif\u00e9rica) e sua vis\u00e3o pol\u00edtica de longo prazo (tendo como objetivo o socialismo) s\u00e3o todos elementos que devem ser levados em conta quando se estuda sua obra e que podem servir como ferramentas para a compreens\u00e3o da realidade brasileira de hoje.<\/p>\n<hr \/>\n<p><strong>Caio da Silva Prado J\u00fanior<\/strong><br \/>\n(S\u00e3o Paulo, 11 de fevereiro de 1907 \u2014 S\u00e3o Paulo, 23 de novembro de 1990)<br \/>\nCaio Prado Jr foi um dos mais importantes historiadores brasileiros. Membro do Partido Comunista Brasileiro, PCB, foi um importante intelectual, contribuindo de maneira decisiva para a compreens\u00e3o da forma\u00e7\u00e3o do Brasil e de suas contradi\u00e7\u00f5es.<br \/>\nAs principais obras de Prado J\u00fanior:<\/p>\n<p>1933: Evolu\u00e7\u00e3o pol\u00edtica do Brasil<br \/>\n1934: URSS &#8211; um novo mundo<br \/>\n1942: Forma\u00e7\u00e3o do Brasil Contempor\u00e2neo<br \/>\n1945: Hist\u00f3ria Econ\u00f4mica do Brasil<br \/>\n1952: Dial\u00e9tica do Conhecimento<br \/>\n1953: Evolu\u00e7\u00e3o Pol\u00edtica do Brasil e Outros Estudos<br \/>\n1954: Diretrizes para uma Pol\u00edtica Econ\u00f4mica Brasileira<br \/>\n1957: Esbo\u00e7o de Fundamentos da Teoria Econ\u00f4mica<br \/>\n1959: Introdu\u00e7\u00e3o \u00e0 L\u00f3gica Dial\u00e9tica (Notas Introdut\u00f3rias)<br \/>\n1962: O Mundo do Socialismo<br \/>\n1966: A Revolu\u00e7\u00e3o Brasileira<br \/>\n1971: Estruturalismo de L\u00e9vi-Strauss &#8211; O Marxismo de Louis Althusser<br \/>\n1972: Hist\u00f3ria e Desenvolvimento<br \/>\n1979: A Quest\u00e3o Agr\u00e1ria no Brasil<br \/>\n1980: O que \u00e9 Liberdade<br \/>\n1981: O que \u00e9 Filosofia<\/p>\n<p>Ilustra\u00e7\u00e3o: Os livros de Caio Prado s\u00e3o estudados de forma descolada de suas ideias pol\u00edticas e milit\u00e2ncia, afirma o autor. Reprodu\u00e7\u00e3o<\/p>\n<p>https:\/\/www.brasildefato.com.br\/2016\/06\/06\/nova-biografia-de-caio-prado-junior-poe-luz-em-sua-militancia-comunista\/<\/p>\n","protected":false},"excerpt":{"rendered":"Luiz Bernardo Peric\u00e1s recupera viagens, mem\u00f3rias da pris\u00e3o e rela\u00e7\u00f5es que o autor teve com intelectuais estrangeiros Camila Rodrigues da Silva &#8211; BRASIL \n<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/13554\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[46],"tags":[],"class_list":["post-13554","post","type-post","status-publish","format-standard","hentry","category-c56-memoria"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-3wC","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/13554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=13554"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/13554\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=13554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=13554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=13554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}