{"id":13711,"date":"2017-03-04T16:21:54","date_gmt":"2017-03-04T19:21:54","guid":{"rendered":"https:\/\/pcb.org.br\/portal2\/?p=13711"},"modified":"2017-03-16T12:29:36","modified_gmt":"2017-03-16T15:29:36","slug":"em-surdina-mais-um-ataque-a-petrobras","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/13711","title":{"rendered":"Em surdina, mais um ataque \u00e0 Petrobras"},"content":{"rendered":"<p><img decoding=\"async\" class=\"imagem\" title=\"imagem\" src=\"https:\/\/ci3.googleusercontent.com\/proxy\/UhBCZfTINNT6cVG6c0raRaUcyy5uOUPRQ-lmoKkt9fZh94hiyrQ4oX_h5or7I30ssBZ8ssP1vi-BysQvuNAkZ2rDlq8YawVGiwB-ic1AVDc2ztUtWSnHRnCWj3432i3mrL-Mzq--Zytel60pu5jahJ_GOvzt1w=s0-d-e1-ft#http:\/\/outraspalavras.net\/wp-content\/uploads\/2017\/03\/170302-Petrobras-e1488469479845-485x232.jpg\" alt=\"imagem\" \/>Em meio a onda de desemprego, governo estimula importa\u00e7\u00e3o de equipamentos que Brasil produz. Medida n\u00e3o \u00e9 insana: faz parte de um projeto meticuloso de entrega da estatal<\/p>\n<p>Por\u00a0Jos\u00e9 \u00c1lvaro de Lima Cardoso<!--more--><\/p>\n<p>O governo divulgou em 22\/2 os novos \u00edndices de exig\u00eancia de conte\u00fado local no setor de petr\u00f3leo e g\u00e1s. A destrui\u00e7\u00e3o da pol\u00edtica de conte\u00fado local, um dos pilares da Lei de Partilha sobre a explora\u00e7\u00e3o do Pr\u00e9-Sal, \u00e9 parte constitutiva do golpe, como at\u00e9 as pedras j\u00e1 sabiam. Haver\u00e1, conforme mat\u00e9rias na imprensa, uma redu\u00e7\u00e3o m\u00e9dia de 50% nos percentuais de equipamentos e servi\u00e7os produzidos no pa\u00eds, exigidos em licita\u00e7\u00f5es de explora\u00e7\u00e3o de petr\u00f3leo e g\u00e1s. Nas plataformas mar\u00edtimas, cujo conte\u00fado local atual \u00e9 de 65%, a exig\u00eancia ser\u00e1 de apenas 25%. Estas novas regras valer\u00e3o j\u00e1 para a 14\u00aa rodada de licita\u00e7\u00f5es, que deve ocorrer em setembro, e para a terceira rodada de leil\u00f5es de blocos no pr\u00e9-sal, prevista para novembro.<\/p>\n<p>Segundo estimativa da Associa\u00e7\u00e3o Brasileira dos Produtores de M\u00e1quinas (Abimaq), o \u00edndice de 25% ser\u00e1 consumido apenas com servi\u00e7os, mesmo desconsiderando produtos industriais e de engenharia que entram na cadeia de servi\u00e7os. Reduzir \u00edndices de conte\u00fado local, em meio \u00e0 maior crise da hist\u00f3ria do capitalismo e \u00e0 maior recess\u00e3o do pa\u00eds diz muito sobre o governo atual. A medida significa perda dram\u00e1tica de mercado para as empresas brasileiras e mais demiss\u00f5es, num pa\u00eds que j\u00e1 amarga taxas, em algumas regi\u00f5es, acima de 20% de desemprego. China, Singapura, e outros pa\u00edses que t\u00eam pol\u00edtica industrial estruturada, agradecem muito a decis\u00e3o do governo entreguista, pela renda e os empregos gerados em seus respectivos pa\u00edses.<\/p>\n<p>O governo alega que o conte\u00fado local leva \u00e0 corrup\u00e7\u00e3o e \u00e0 baixa competitividade da ind\u00fastria nacional. Uma afirma\u00e7\u00e3o sobre o risco de corrup\u00e7\u00e3o, vinda de um governo como esse, \u00e9 de um sarcasmo infinito. A pol\u00edtica de conte\u00fado local, forma uma das bases que constitui o trip\u00e9 para explora\u00e7\u00e3o da riqueza do pr\u00e9-sal, juntamente com: a) exclusividade da Petrobr\u00e1s na explora\u00e7\u00e3o<br \/>\ndos po\u00e7os; b) exig\u00eancia de que a empresa brasileira participe com pelo menos 30% dos investimentos em cada um dos po\u00e7os do pr\u00e9-sal. Estas duas \u00faltimas exig\u00eancias j\u00e1 foram ceifadas pelo governo atrav\u00e9s de Lei, que, na pr\u00e1tica, foi o cumprimento da promessa de Jos\u00e9 Serra \u00e0 Chevron, de acabar com a Lei de Partilha, em 2010, conforme publicado pela organiza\u00e7\u00e3o Wikileaks.<\/p>\n<p>J\u00e1 se sabia que acabar com a pol\u00edtica de conte\u00fado local, por parte deste governo, era uma quest\u00e3o de tempo. A pol\u00edtica de conte\u00fado local foi respons\u00e1vel, em grande parte, pelo renascimento da ind\u00fastria naval no Brasil (que agora vai definhando). A exig\u00eancia de conte\u00fado local, que precede a pr\u00f3pria Lei de Partilha, e obriga a Petrobras a comprar mais de 65% de bens e servi\u00e7os no Brasil, tem o objetivo de alavancar a ind\u00fastria e os servi\u00e7os nacionais. A lei tem uma import\u00e2ncia evidente, pela relev\u00e2ncia do setor de petr\u00f3leo e g\u00e1s e pelo peso extraordin\u00e1rio que a Petrobr\u00e1s tem na economia brasileira, mesmo ap\u00f3s a pancadaria que vem sofrendo h\u00e1 tr\u00eas anos, e que constitui o chamado golpe dentro do golpe.<\/p>\n<p>O desmonte da empresa est\u00e1 sendo providenciado com rapidez. Recentemente a dire\u00e7\u00e3o da Petrobr\u00e1s convidou somente companhias estrangeiras para participar de licita\u00e7\u00e3o para a constru\u00e7\u00e3o da unidade de Processamento de G\u00e1s Natural (UPGN) do Complexo Petroqu\u00edmico do Rio de Janeiro (Comperj). Empresas que n\u00e3o t\u00eam nem ao menos unidades no pa\u00eds. Como no momento tentar privatizar seria dif\u00edcil, pelo simbolismo da estatal, est\u00e3o desvalorizando o pre\u00e7o dos ativos para facilitar a venda, e acabando com que a empresa tem de melhor, que \u00e9 a integra\u00e7\u00e3o do \u201cpo\u00e7o ao posto\u201d. Est\u00e3o vendendo o fil\u00e9 do patrim\u00f4nio para multinacionais, a pre\u00e7o de banana e com ativos depreciados, e condenando-a \u00e0 produ\u00e7\u00e3o e comercializa\u00e7\u00e3o de \u00f3leo cru. Al\u00e9m de liquidar com a Lei de Partilha \u2014 o que j\u00e1 fizeram em boa parte \u2014 precisam tamb\u00e9m destruir a Petrobr\u00e1s para entregar o nosso petr\u00f3leo \u00e0s estrangeiras, que n\u00e3o t\u00eam nenhum compromisso com os pa\u00edses nos quais se instalam, como revela a hist\u00f3ria do petr\u00f3leo do mundo.<\/p>\n<p>Em absolutamente todos os pa\u00edses onde a pol\u00edtica do petr\u00f3leo est\u00e1 ajustada aos interesses do pa\u00eds, h\u00e1 pol\u00edticas de valoriza\u00e7\u00e3o da produ\u00e7\u00e3o local, com desenvolvimento da tecnologia e da engenharia, e pol\u00edtica macroecon\u00f4mica adequada. No Brasil, montaram uma opera\u00e7\u00e3o, a Lava-Jato, que destruiu as empresas de engenharia fornecedoras da Petrobr\u00e1s, e que, sob o pretexto de recuperar R$ 6,2 bilh\u00f5es (um dado superestimado para obter apoio p\u00fablico), provocaram, somente em 2015, um preju\u00edzo de R$ 140 bilh\u00f5es \u00e0 economia brasileira. O estrago que a Lava-Jato causou, alavancando a destrui\u00e7\u00e3o da economia e auxiliando a ascens\u00e3o dos corruptos ao n\u00facleo de poder, ilustra com riqueza, sozinho, a exist\u00eancia do golpe contra a democracia.<\/p>\n<p>O Brasil foi o \u00fanico caso do mundo onde um grupo de procuradores, idiotizado pela ideologia, que nada entende de economia, destruiu, em nome do combate a corrup\u00e7\u00e3o, um setor da economia altamente competitivo, gerador de riqueza, tecnologia, e milh\u00f5es de empregos.<\/p>\n<p>O ataque que o Brasil e o seu povo v\u00eam sofrendo, \u00e9 inusitado. Est\u00e1 em franco funcionamento uma m\u00e1quina de destrui\u00e7\u00e3o do Estado social brasileiro, de entrega do patrim\u00f4nio nacional e de liquida\u00e7\u00e3o de direitos, obtidos \u00e0 duras penas nos \u00faltimos 70 anos. Al\u00e9m da execra\u00e7\u00e3o do Estado nacional os ataques tamb\u00e9m avan\u00e7am sobre o sistema econ\u00f4mico privado, ao destruir as empresas de engenharia nacionais e abrir espa\u00e7os para as multinacionais do setor. O processo de entrega e de queima do patrim\u00f4nio nacional est\u00e1 sendo realizado propositalmente muito r\u00e1pido, para n\u00e3o dar tempo da popula\u00e7\u00e3o reagir. S\u00e3o crimes de lesa-p\u00e1tria, cometidos em s\u00e9rie, e encaminhados por uma quadrilha que tomou o poder de assalto.<\/p>\n<p>http:\/\/outraspalavras.net\/brasil\/em-surdina-um-novo-ataque-a-petrobras\/<\/p>\n","protected":false},"excerpt":{"rendered":"Em meio a onda de desemprego, governo estimula importa\u00e7\u00e3o de equipamentos que Brasil produz. Medida n\u00e3o \u00e9 insana: faz parte de um projeto \n<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/13711\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[190,105],"tags":[],"class_list":["post-13711","post","type-post","status-publish","format-standard","hentry","category-fora-temer","category-c118-privatizacao"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-3z9","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/13711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=13711"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/13711\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=13711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=13711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=13711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}