{"id":13975,"date":"2017-04-01T16:49:38","date_gmt":"2017-04-01T19:49:38","guid":{"rendered":"https:\/\/pcb.org.br\/portal2\/?p=13975"},"modified":"2017-04-20T14:57:15","modified_gmt":"2017-04-20T17:57:15","slug":"os-donos-do-mundo","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/13975","title":{"rendered":"Os donos do mundo"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"imagem\" title=\"imagem\" src=\"https:\/\/i0.wp.com\/www.materiaincognita.com.br\/wp-content\/uploads\/2011\/07\/Banqueiros-e-Politicos.jpg?w=747\" alt=\"imagem\" \/>O PODER POPULAR<\/p>\n<p>Os bancos s\u00e3o os verdadeiros donos do mundo. Controlam o sistema financeiro de cerca de 200 pa\u00edses, as principais empresas de petr\u00f3leo, de minera\u00e7\u00e3o, de commodities em geral. Imp\u00f5em e dep\u00f5em governos, usam a m\u00eddia empresarial de acordo com seus interesses.<!--more--><\/p>\n<p>Os 28 maiores bancos do mundo t\u00eam mais recursos que as d\u00edvidas p\u00fablicas da maioria dos pa\u00edses juntos, algo em torno de US$ 50 trilh\u00f5es. Concentram 90% dos ativos financeiros banc\u00e1rios, apesar de existirem milhares de bancos planeta afora.<br \/>\nA gest\u00e3o dos derivativos feita pelos bancos \u2013 opera\u00e7\u00f5es futuras \u2013 representa cerca de US$ 700 trilh\u00f5es, o equivalente a dez vezes o PIB mundial. Ao mesmo tempo, a movimenta\u00e7\u00e3o cambial \u00e9 de US$ 6 bilh\u00f5es di\u00e1rios, na qual apenas cinco bancos controlam 51% do mercado. \u00c9 o chamado capital fict\u00edcio.<\/p>\n<p>Para conseguir tanto dinheiro, os bancos utilizam-se das estruturas de poder dos pa\u00edses capitalistas, cujos sucessivos governos lhes s\u00e3o subservientes. Assim, M\u00e1rio Draghi, presidente do Banco Central Europeu e presidente do Grupo de Governadores e Chefes de Supervis\u00e3o do Banco de Pagamentos Internacionais (BIS, da sigla em ingl\u00eas), foi vice-presidente do Goldman Sachs Europa. Mario Monti, tamb\u00e9m italiano, primeiro-ministro de seu pa\u00eds entre 2011 e 2013, foi conselheiro internacional do Goldman Sachs (2005). J\u00e1 Lu\u00eds de Guindos, ex-ministro da Economia da Espanha, foi do Lehman Brothers. Robert Rubin e Henry Paulsen foram secret\u00e1rios do Tesouro dos EUA nos governos Clinton e Obama, respectivamente. Ambos s\u00e3o do Goldman Sachs, assim como Steve Mnuchin, secret\u00e1rio de Donald Trump. N\u00e3o \u00e9 por acaso que a Europa e os EUA se encontram em crise.<\/p>\n<p>O Banco Central dos EUA (Federal Reserve) \u00e9 composto por 12 bancos centrais regionais, cujos principais acionistas s\u00e3o os Rothschild, Warburg Bank, Lehman Brothers, Lazard Brothers, Kuhn Loeb Bank, Israel Moses Seif Bank, Goldman Sachs e JP Morgan Chase Bank. Ou seja, alguns dos maiores bancos privados controlam a pol\u00edtica monet\u00e1ria e a econ\u00f4mica do pa\u00eds mais rico do mundo.<\/p>\n<p>Da mesma maneira, controlam o Banco Central da Europa, da Inglaterra, do Jap\u00e3o e da maioria dos pa\u00edses, inclusive do Brasil. N\u00e3o \u00e0 toa, fazem a m\u00eddia empresarial e pol\u00edticos corruptos defenderem a \u201cautonomia dos bancos centrais\u201d, mera cantilena para poder utilizar essas institui\u00e7\u00f5es de acordo com seus interesses.<\/p>\n<p>Hist\u00f3rico<\/p>\n<p>Por tr\u00e1s de todos esses bancos est\u00e1 o Bank for International Settlements (BIS), o Banco de Pagamentos Internacionais. Criado em 1930 pelos bancos da Inglaterra e da Alemanha, teve como primeiro presidente o banqueiro Gates McGarrah de Rockefeller.<br \/>\n\u00c9 uma institui\u00e7\u00e3o \u00fanica, sediada na Su\u00ed\u00e7a, protegida por tratados internacionais, fora do alcance de qualquer governo, pol\u00edtica monet\u00e1ria ou controle. Tem apenas 140 clientes, mas lucra bilh\u00f5es de d\u00f3lares anualmente, totalmente livres de impostos. \u00c9 o Banco Central dos bancos centrais, det\u00e9m 10% das reservas monet\u00e1rias de cerca de 80 bancos centrais mundiais e do FMI, entre outras. \u00c9 controlado pelas oito institui\u00e7\u00f5es mais poderosas do planeta: Goldman Sachs, Rockefellers, Lehmans e Kuhn Loebs (Nova Iorque), Rothschilds (Paris e Londres), Warburgs (Hamburgo), Lazards (Parise Israel Moses Seifs (Roma). S\u00e3o os verdadeiros donos do mundo.<\/p>\n<p>Cabe destacar que essas institui\u00e7\u00f5es agem estrategicamente. Assim, em 1944, quando j\u00e1 se delineava a derrota da Alemanha na II Guerra Mundial, firmaram o Acordo de Bretton Woods, que fundou o FMI, o Banco Mundial e estabeleceu o d\u00f3lar como moeda de troca do sistema financeiro internacional, com a garantia de que US$ 35 equivalessem a uma on\u00e7a troy de ouro (unidade de peso equivalente a 31 gramas). Em 1971, o ex-presidente dos EUA, Richard Nixon, acabou com a garantia do d\u00f3lar atrav\u00e9s do ouro.<br \/>\nAtualmente, apenas Cuba, Cor\u00e9ia do Norte e Ir\u00e3 t\u00eam bancos centrais n\u00e3o atrelados ao sistema financeiro mundial, dominado pelos grandes bancos privados. Isso explica, em parte, o \u00f3dio da m\u00eddia empresarial a esses pa\u00edses.<\/p>\n<p>As informa\u00e7\u00f5es contidas nesta mat\u00e9ria foram obtidas em diversos textos divulgados amplamente na internet, portanto de dom\u00ednio p\u00fablico.<\/p>\n","protected":false},"excerpt":{"rendered":"O PODER POPULAR Os bancos s\u00e3o os verdadeiros donos do mundo. Controlam o sistema financeiro de cerca de 200 pa\u00edses, as principais empresas \n<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/13975\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[140],"tags":[],"class_list":["post-13975","post","type-post","status-publish","format-standard","hentry","category-c140-jornal-o-poder-popular"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-3Dp","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/13975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=13975"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/13975\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=13975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=13975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=13975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}