{"id":16295,"date":"2017-09-24T15:18:42","date_gmt":"2017-09-24T18:18:42","guid":{"rendered":"https:\/\/pcb.org.br\/portal2\/?p=16295"},"modified":"2017-09-25T20:48:08","modified_gmt":"2017-09-25T23:48:08","slug":"kke-sobre-os-acontecimentos-perigosos-na-peninsula-coreana","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/16295","title":{"rendered":"KKE: sobre os acontecimentos perigosos na Pen\u00ednsula Coreana"},"content":{"rendered":"<p><img decoding=\"async\" class=\"imagem\" title=\"imagem\" src=\"https:\/\/i0.wp.com\/es.kke.gr\/export\/sites\/inter\/.content\/images\/news\/20140517_koreja_4.jpg_1811983680.jpg\" alt=\"imagem\" \/><!--more-->Boletim do KKE &#8211; 19\/09\/2017<\/p>\n<p>O Escrit\u00f3rio de Imprensa do Comit\u00ea Central do KKE, em seu comunicado sobre os acontecimentos perigosos na Pen\u00ednsula Coreana, destaca:<\/p>\n<p>O KKE expressa sua forte preocupa\u00e7\u00e3o pela situa\u00e7\u00e3o perigosa na Pen\u00ednsula Coreana. Os acontecimentos refletem a intensifica\u00e7\u00e3o da disputa econ\u00f4mica e militar e das contradi\u00e7\u00f5es interimperialistas em toda a regi\u00e3o da \u00c1sia e do Pac\u00edfico, entre fortes Estados capitalistas e os interesses de empres\u00e1rios a n\u00edvel internacional e regional. N\u00e3o \u00e9 resultado das decis\u00f5es dos l\u00edderes supostamente \u201cloucos\u201d dos EUA e da Coreia do Norte, como dizem deliberadamente os meios de comunica\u00e7\u00e3o para ocultar as causas do confronto.<\/p>\n<p>Esta competi\u00e7\u00e3o entre EUA, Jap\u00e3o, R\u00fassia e etc. tem rela\u00e7\u00e3o particular com a nova distribui\u00e7\u00e3o de mercados, a explora\u00e7\u00e3o dos grandes recursos energ\u00e9ticos que se encontram em regi\u00f5es como a Pen\u00ednsula Coreana, no mar da China Oriental e no mar da China Meridional, no \u00c1rtico e outras, resultando na constante intensifica\u00e7\u00e3o da corrida armamentista e a possibilidade inclusive de um conflito militar. Al\u00e9m disso, os EUA est\u00e3o preparando o caminho para o aumento da venda de armas modernas ao Jap\u00e3o e \u00e0 Coreia do Sul, enquanto mant\u00e9m grandes for\u00e7as militares (28.000 soldados) e equipamento militar em suas bases na Coreia do Sul, realiza continuamente grandes exerc\u00edcios militares com cen\u00e1rios provocadores de invas\u00e3o \u00e0 Coreia do Norte.<\/p>\n<p>N\u00e3o \u00e9 coincid\u00eancia que, desde o primeiro momento, a nova administra\u00e7\u00e3o dos EUA de Trump, junto com o objetivo da renegocia\u00e7\u00e3o de acordos econ\u00f4micos em grande escala, como \u00e9 o Acordo Transpac\u00edfico de Coopera\u00e7\u00e3o Econ\u00f4mica (TPP), levou ao centro das aten\u00e7\u00f5es a regi\u00e3o no ponto d\u00e9bil da China e da R\u00fassia, que \u00e9 considerada pela China como uma regi\u00e3o vital, assim como outras regi\u00f5es na \u00c1sia, que est\u00e3o na \u201cRota da Seda\u201d. Tudo isso junto com os grandes d\u00e9ficits comerciais dos EUA com a China, afetam a elabora\u00e7\u00e3o de uma pol\u00edtica agressiva para a defesa dos monop\u00f3lios dos EUA.<\/p>\n<p>Os EUA est\u00e3o em posi\u00e7\u00e3o predominante entre os Estados capitalistas possuindo um arsenal nuclear, que j\u00e1 utilizou: cabe assinalar que recentemente os EUA junto com a Gr\u00e3-Bretanha e a Fran\u00e7a se abstiveram das negocia\u00e7\u00f5es pela assinatura do Tratado de Proibi\u00e7\u00e3o das Armas Nucleares, com o pretexto de que ignora a realidade do entorno internacional de seguran\u00e7a.<\/p>\n<p>Ao mesmo tempo, a OTAN em suas reuni\u00f5es fala abertamente da capacidade de utilizar armas nucleares. Em consequ\u00eancia, o argumento dos EUA do perigo que sup\u00f5e o programa nuclear da Coreia do Norte \u00e9 uma grande hipocrisia e um \u00e1libi enquanto outros Estados capitalistas, como Gr\u00e3-Bretanha, Fran\u00e7a, Paquist\u00e3o, \u00cdndia, etc, t\u00eam \u00e0 sua disposi\u00e7\u00e3o armas nucleares.<\/p>\n<p>Os EUA utilizam como argumento o perigo nuclear tanto da parte da Coreia do Norte como do Ir\u00e3, para estabelecer na regi\u00e3o do Pac\u00edfico e da Europa o chamado \u201cescudo antim\u00edsseis\u201d, enquanto em coopera\u00e7\u00e3o com a Uni\u00e3o Europeia seguem seus pr\u00f3prios interesses e imp\u00f5em san\u00e7\u00f5es \u00e0s custas dos povos. Al\u00e9m disso, refor\u00e7am de novo sua presen\u00e7a militar no Afeganist\u00e3o, tendo como alvo a China, assim como a R\u00fassia. O mesmo ocorre com a concentra\u00e7\u00e3o de tropas da OTAN nos pa\u00edses b\u00e1lticos.<\/p>\n<p>De sua parte, a R\u00fassia se op\u00f5e a estes planos, que objetivamente est\u00e3o dirigidos a impedir uma poss\u00edvel resposta da R\u00fassia, no caso dos EUA e a alian\u00e7a da OTAN tentarem levar a cabo o \u201cprimeiro ataque nuclear\u201d.<\/p>\n<p>Os EUA aproveitam o posicionamento da Coreia do Norte de desenvolver seu programa nuclear com a finalidade de promover seus interesses geoestrat\u00e9gicos na regi\u00e3o e mais em geral. No entanto, o crime brutal que cometeram h\u00e1 72 anos dos EUA, provocando a destrui\u00e7\u00e3o nuclear de Hiroshima e Nagasaki, assim como consequ\u00eancia a longo prazo por causa deste crime, demonstram que a solu\u00e7\u00e3o n\u00e3o se encontra no desenvolvimento de armas nucleares. N\u00e3o \u00e9 uma coincid\u00eancia que a URSS, o primeiro estado oper\u00e1rio do mundo, tenha se negado lan\u00e7ar o primeiro ataque nuclear (princ\u00edpio de n\u00e3o primeiro uso) e desempenhou um papel destacado por um mundo sem armas nucleares.<\/p>\n<p>O aprofundamento da situa\u00e7\u00e3o na Pen\u00ednsula Coreana n\u00e3o mudar\u00e1 nem resolver\u00e1 a situa\u00e7\u00e3o no Mediterr\u00e2neo Oriental e no Oriente M\u00e9dio. N\u00e3o s\u00f3 porque as consequ\u00eancias de um poss\u00edvel conflito militar, e de fato com o uso de armas nucleares, ser\u00e3o mundiais, mas tamb\u00e9m porque em \u00faltima inst\u00e2ncia se trata de balan\u00e7as interimperialistas fr\u00e1geis e de um \u201cdom\u00ednio\u201d geopol\u00edtico que se desenvolve em escala internacional, desde o B\u00e1ltico, o Mar Negro e o Mediterr\u00e2neo Oriental at\u00e9 a \u00c1frica, \u00c1sia e o Pac\u00edfico.<\/p>\n<p>N\u00e3o \u00e9 a primeira vez que os EUA focam em dita regi\u00e3o. Desde 1950 at\u00e9 1953 desempenharam um papel dirigente na guerra da Coreia, que gerou mais de meio milh\u00e3o de mortos e levou a sua desintegra\u00e7\u00e3o. Al\u00e9m disso, n\u00e3o podemos esquecer que a Gr\u00e9cia tomou parte com suas tropas na interven\u00e7\u00e3o militar imperialista na Coreia, ap\u00f3s uma decis\u00e3o da burguesia e seus representantes pol\u00edticos, resultando em mais de 180 gregos mortos e 600 feridos.<\/p>\n<p>O governo grego, com o apoio do principal partido da oposi\u00e7\u00e3o e dos demais partidos burgueses, assume grandes responsabilidades posto que participa e respalda as decis\u00f5es e os planos perigosos da OTAN, que servem aos interesses da burguesia local, tal como fizeram todos os governos burgueses at\u00e9 hoje. Tenta fortalecer o papel da Gr\u00e9cia dentro da OTAN em nome do \u201cfortalecimento geoestrat\u00e9gico\u201d do pa\u00eds. Recentemente acordou de amplia a base de Suda e de outras bases militares e a infraestrutura para as opera\u00e7\u00f5es dos EUA, da OTAN e da UE. Al\u00e9m disso, este governo continua a contribui\u00e7\u00e3o da Gr\u00e9cia ao enorme or\u00e7amento da OTAN e envolve ainda mais profundamente as For\u00e7as Armadas nos planos imperialistas, intensificando o antagonismo com a Turquia.<\/p>\n<p>V\u00e1rios meios de comunica\u00e7\u00e3o assim como pol\u00edticos aproveitam da situa\u00e7\u00e3o em torno da quest\u00e3o nuclear da Coreia do Norte n\u00e3o s\u00f3 para caluniar a todas as lutas dos povos por um mundo sem explora\u00e7\u00e3o do homem pelo homem, mas tamb\u00e9m para preparar o terreno para que o povo aceite uma interven\u00e7\u00e3o militar dos EUA e da OTAN na Coreia do Norte, sob o pretexto de \u201crestaurar a democracia\u201d e \u201ccombater as armas de destrui\u00e7\u00e3o massiva\u201d, utilizada em outras interven\u00e7\u00f5es imperialistas, como por exemplo no Iraque. O KKE cr\u00ea que o povo de cada pa\u00eds \u00e9 exclusivamente respons\u00e1vel para decidir e escolher o regime econ\u00f4mico, social e pol\u00edtico do pa\u00eds, assim como para muda-lo com sua organiza\u00e7\u00e3o e luta.<\/p>\n<p>Os acontecimentos requerem vigil\u00e2ncia, intensifica\u00e7\u00e3o da solidariedade internacionalista e fortalecimento da luta contra as interven\u00e7\u00f5es e as guerras imperialistas, contra as armas nucleares. Esta luta est\u00e1 intrinsecamente ligada \u00e0 luta pela comida e pelos sal\u00e1rios, contra o capital e seus governos, de qualquer matiz burgu\u00eas que sejam.<\/p>\n<p>Est\u00e1 ligada \u00e0 luta contra as uni\u00f5es imperialistas, como s\u00e3o a OTAN, a UE, contra uni\u00f5es na \u00c1sia e em outros lugares, contra o pr\u00f3prio sistema capitalista de explora\u00e7\u00e3o e o poder do capital que, como demonstrou a hist\u00f3ria, n\u00e3o titubeia em cometer qualquer crime contra os povos com a finalidade de superar as contradi\u00e7\u00f5es intensas e os grandes problemas, alcan\u00e7ar seus objetivos e garantir sua domina\u00e7\u00e3o\u201d.<\/p>\n<p>Fonte: http:\/\/es.kke.gr\/es\/articles\/Comunicado-sobre-los-acontecimientos-peligrosos-en-la-Peninsula-Coreana\/<\/p>\n<p>Tradu\u00e7\u00e3o: Partido Comunista Brasileiro (PCB)<\/p>\n","protected":false},"excerpt":{"rendered":"<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/16295\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[38],"tags":[227],"class_list":["post-16295","post","type-post","status-publish","format-standard","hentry","category-c43-imperialismo","tag-5a"],"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p659gw-4eP","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/16295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=16295"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/16295\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=16295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=16295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=16295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}