{"id":17758,"date":"2017-12-10T13:05:45","date_gmt":"2017-12-10T16:05:45","guid":{"rendered":"https:\/\/pcb.org.br\/portal2\/?p=17758"},"modified":"2017-12-11T19:54:09","modified_gmt":"2017-12-11T22:54:09","slug":"educacao-como-contrato-de-servidao","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/17758","title":{"rendered":"A educa\u00e7\u00e3o como contrato de servid\u00e3o*"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"imagem\" title=\"A educa\u00e7\u00e3o como contrato de servid\u00e3o*\" src=\"https:\/\/i0.wp.com\/www.odiario.info\/b2-img\/studentloandebt.jpg?w=747&#038;ssl=1\" alt=\"A educa\u00e7\u00e3o como contrato de servid\u00e3o*\" \/><!--more-->ODIARIO.INFO &#8211; Ant\u00f3nio Santos<\/p>\n<p>No capitalismo tudo se torna mercadoria, incluindo direitos fundamentais como a Educa\u00e7\u00e3o e a Sa\u00fade. Nos EUA, quem queira prosseguir estudos superiores e n\u00e3o seja (muito) rico tem de contrair empr\u00e9stimos exorbitantes: o custo de uma licenciatura ronda os 80 mil d\u00f3lares. Daqui resulta, entre outras coisas, um endividamento que muitos acabam por n\u00e3o cumprir, ficando assim, como os servos da gleba feudais, nas m\u00e3os dos seus credores.<\/p>\n<p>Os empr\u00e9stimos contra\u00eddos para pagar os estudos superiores representam, logo ap\u00f3s o cr\u00e9dito \u00e0 habita\u00e7\u00e3o, a maior fatia da d\u00edvida dos estadunidenses. No total, s\u00e3o 1,4 bili\u00f5es de d\u00f3lares devidos em propinas aos bancos, um valor superior \u00e0 d\u00edvida somada de todos os cart\u00f5es de cr\u00e9dito dos EUA e com mais zeros do que o total do cr\u00e9dito autom\u00f3vel naquele pa\u00eds. Durante d\u00e9cadas, a especula\u00e7\u00e3o financeira apostou na d\u00edvida dos estudantes como se \u00e0 roleta jogasse: s\u00f3 desde 2007 a esta parte, o \u00abcr\u00e9dito \u00e0 educa\u00e7\u00e3o\u00bb passou de um para cinco por cento do PIB dos EUA.<\/p>\n<p>E assim continua a crescer, insaci\u00e1vel, insustent\u00e1vel, descontrolado, como cresce sempre o capitalismo, apesar de, todos os dias, tr\u00eas mil estadunidenses entrarem em inadimpl\u00eancia por n\u00e3o conseguirem pagar a d\u00edvida acad\u00eamica.<\/p>\n<p>Recordemos que o custo de uma licenciatura nos EUA ronda os 80 000 d\u00f3lares e que, em m\u00e9dia, os antigos estudantes demoram 20 anos a liquidar este cr\u00e9dito. Simultaneamente incapaz de deter o crescimento das d\u00edvidas dos trabalhadores e o emagrecimento dos sal\u00e1rios que permitem pagar essas d\u00edvidas, o capitalismo viu-se impotente para resolver o que, mais do que uma crise, \u00e9 a ess\u00eancia da sua pr\u00f3pria natureza.<\/p>\n<p>Em 19 Estados, a panaceia encontrada foi a redescoberta de um tipo de opress\u00e3o feudal: os devedores aos bancos s\u00e3o proibidos de trabalhar. Nestes estados, a inadimpl\u00eancia de uma d\u00edvida pode ditar a revoga\u00e7\u00e3o permanente de qualquer licen\u00e7a profissional e at\u00e9 da carteira de motorista. Segundo o New York Times, enfermeiros e professores est\u00e3o entre os trabalhadores mais afetados por estas leis.<br \/>\nEm alguns destes estados, como o Tennessee, os credores podem at\u00e9 executar a licen\u00e7a profissional e assenhorear-se permanentemente dela, numa reedi\u00e7\u00e3o moderna da servid\u00e3o da gleba. Em todos os casos, os trabalhadores que em consequ\u00eancia dos baixos sal\u00e1rios, de doen\u00e7a, de desemprego ou de uma jogada mais ousada de um especulador entrem em inadimpl\u00eancia, podem ser proibidos de vender a sua for\u00e7a de trabalho e, a\u00ed sim, incapazes de pagar a d\u00edvida. A inadimpl\u00eancia nos moldes e nas condi\u00e7\u00f5es impostos pelos credores.<br \/>\n\u00c9 a transforma\u00e7\u00e3o da educa\u00e7\u00e3o num instrumento de opress\u00e3o.<\/p>\n<p>Escusado ser\u00e1 dizer que n\u00e3o se suspende uma t\u00e3o tremenda espada de D\u00e2mocles sobre todos os estudantes do Ensino Superior sem objetivos pol\u00edticos mais vastos.<\/p>\n<p><em>*Este artigo foi publicado no \u201cAvante!\u201d n\u00ba 2296, 30.11.2017<\/em><\/p>\n<p><a href=\"https:\/\/www.odiario.info\/a-educacao-como-contrato-de-servidao\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.odiario.info\/a-educacao-como-contrato-de-servidao\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/17758\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[60],"tags":[],"class_list":["post-17758","post","type-post","status-publish","format-standard","hentry","category-c71-educacao"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-4Cq","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/17758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=17758"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/17758\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=17758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=17758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=17758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}