{"id":18414,"date":"2018-01-18T16:53:20","date_gmt":"2018-01-18T19:53:20","guid":{"rendered":"https:\/\/pcb.org.br\/portal2\/?p=18414"},"modified":"2018-01-18T12:58:42","modified_gmt":"2018-01-18T15:58:42","slug":"farc-analise-do-primeiro-ano-dos-acordos-de-havana","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/18414","title":{"rendered":"FARC: an\u00e1lise do primeiro ano dos Acordos de Havana"},"content":{"rendered":"<p><img decoding=\"async\" class=\"imagem\" title=\"FARC: an\u00e1lise do primeiro ano dos Acordos de Havana\" src=\"https:\/\/i0.wp.com\/www.resumenlatinoamericano.org\/wp-content\/uploads\/2018\/01\/93d91a0d9ac8604d953724b139da547a_XL-620x400.jpg\" alt=\"FARC: an\u00e1lise do primeiro ano dos Acordos de Havana\" \/><!--more--><a href=\"https:\/\/www.odiario.info\/intervencao-da-fuerza-alternativa-revolucionaria-del\/\">ODIARIO.INFO<\/a><\/p>\n<p>Um ano passado sobre a assinatura em Havana dos Acordos de Paz, o balan\u00e7o da sua implementa\u00e7\u00e3o \u00e9 muito negativo. Nem no plano pol\u00edtico, nem nos planos econ\u00f4mico e social foram dados quaisquer passos do que fora acordado, e recrudesce a viol\u00eancia paramilitar, agora de m\u00e3os ainda mais livres. Num quadro internacional desfavor\u00e1vel em que o imperialismo n\u00e3o quer ver enfraquecido o seu controlo sobre a plataforma colombiana, tudo o que h\u00e1 de pior \u2013 das institui\u00e7\u00f5es \u00e0 rea\u00e7\u00e3o e aos bar\u00f5es da droga &#8211; age contra a paz e contra o povo. E \u00e9 alarmante que as FARC encarem como \u00faltimo recurso o apelo \u00e0 interven\u00e7\u00e3o de algu\u00e9m como Juan Manuel Santos.<\/p>\n<p>Senhor Presidente, JUAN MANUEL SANTOS<\/p>\n<p>Senhores ex. presidentes PEPE MUJICA e FELIPE GONZ\u00c1LEZ<\/p>\n<p>Senhor vice-presidente de Col\u00f4mbia, General OSCAR NARANJO<\/p>\n<p>Senhor Alto Comiss\u00e1rio da Paz, senhores Ministros:<\/p>\n<p>A paz para a Col\u00f4mbia atravessa um dos sus momentos mais dif\u00edceis desde a assinatura do Acordo Final em Havana. A jurisdi\u00e7\u00e3o Especial para a Paz, transcendente componente do Acordo, foi desfigurada nos debates do parlamento e o seu texto actual n\u00e3o \u00e9 o consensualizado entre as partes. A Reforma Pol\u00edtica afundou-se no convulso mar da politiquice. As Circunscri\u00e7\u00f5es Territoriais Especiais de Paz n\u00e3o tiveram melhor sorte. Continuam na pris\u00e3o mais de 600 integrantes das FARC. A Procuradoria bloqueou no Congresso a aprova\u00e7\u00e3o da lei de tratamientos penais alternativos para pequenos cultivadores, sem cuja aprova\u00e7\u00e3o \u00e9 imposs\u00edvel por em marcha os programas de substitui\u00e7\u00e3o de culturas. Sem Reforma da lei 152 n\u00e3o temos um Plano Quadro de Implementa\u00e7\u00e3o; n\u00e3o h\u00e1 desembolsos para impulsionar projectos produtivos, n\u00e3o avan\u00e7a a titula\u00e7\u00e3o de terras e n\u00e3o cessam os assass\u00ednios de ex-combatentes e l\u00edderes sociais. Neste ambiente, sentimos que os Acordos de Paz de Havana n\u00e3o obtiveram um compromisso por parte do Estado, nem do seu cumprimento pelo conjunto das institui\u00e7\u00f5es.<\/p>\n<p>No passado 15 de Novembro de 2017, Jeffrey Feltman, Secret\u00e1rio-Geral Adjunto para Assuntos Pol\u00edticos da ONU, depois de ouvir representantes tanto do Governo como das FARC, manifestou, entre outras, as seguintes aprecia\u00e7\u00f5es:<\/p>\n<p>\u201cPreocupa-nos a falta de estrat\u00e9gia de reintegra\u00e7\u00e3o acompanhada de planos e recursos concretos que permitam o seu \u00eaxito. Cremos que s\u00e3o necess\u00e1rios esfor\u00e7os de maior escala, inclusivamente proporcionando terras para projectos produtivos. Compartilhamos a profunda preocupa\u00e7\u00e3o pelos vazios de autoridade em muitas \u00e1reas e a inseguran\u00e7a resultante para as comunidades na medida em que grupos ilegais se mobilizam para ocupar esse vazio. Continuamos a assistir a assass\u00ednios de l\u00edderes sociais e de alguns ex. membros das FARC. Vimos isto tragicamente em Tumaco e entristeceu-me tomar conhecimento do assass\u00ednio, nos \u00faltimos dias, de um ex. membro das FARC em Antioquia e de dois l\u00edderes comunit\u00e1rios em Nari\u00f1o e Cauca\u201d.<\/p>\n<p>Um terceiro ponto de preocupa\u00e7\u00e3o foram as incertezas legais, especialmente para os membros das FARC.<\/p>\n<p>\u201cA decis\u00e3o dos insurgentes de renunciar \u00e0 viol\u00eancia armada para exercer actividade pol\u00edtica pac\u00edfica num contexto democr\u00e1tico \u00e9 o cora\u00e7\u00e3o da quest\u00e3o. \u00c9 esse o acordo, e est\u00e1 no centro do acordo de paz. O n\u00e3o ser cumprido este compromisso essencial, depois da entrega das armas, teria repercuss\u00f5es muito graves para o processo e n\u00e3o seria entendido nem aceite pela comunidade internacional. Existe uma avalia\u00e7\u00e3o comum de que se deve fazer mais para garantir que se mantenham os not\u00e1veis sucessos da primeira fase do processo de paz\u201d.<\/p>\n<p>Uns dias depois, em 30 de Novembro, o Conselho de Seguran\u00e7a precisa atrav\u00e9s de um comunicado que o Acordo Final para a Termina\u00e7\u00e3o do Conflito e a Constru\u00e7\u00e3o da Paz Est\u00e1vel e Duradoura \u00e9 um documento oficial do Conselho de Seguran\u00e7a. A alta inst\u00e2ncia internacional apoia o expresso pelo senhor Feltman, e pede que se acelere a implementa\u00e7\u00e3o e o processo normativo em conson\u00e2ncia com o acordado, ao mesmo tempo que reitera a import\u00e2ncia de defender a participa\u00e7\u00e3o pol\u00edtica das FARC.<\/p>\n<p>Em entrevista recente o reconhecido colunista colombiano, Antonio Caballero, expressou o que \u00e9 j\u00e1 uma alargada certeza dentro do pa\u00eds:<\/p>\n<p>\u201cParece-me que a realidade pol\u00edtica actual \u00e9 sumamente catastr\u00f3fica. Na minha opini\u00e3o, o que se passou com a destrui\u00e7\u00e3o dos Acordos de Paz acabou com o que vinha sendo o mais importante durante o Governo de Juan Manuel Santos. A \u00fanica coisa boa que tinha sucedido no pa\u00eds ao longo de 30 anos, est\u00e3o a despeda\u00e7\u00e1-la sem nenhum sentido. Est\u00e1 tudo travado: as decis\u00f5es do Congresso, as conversa\u00e7\u00f5es com o ELN, as conversa\u00e7\u00f5es com os paramilitares. Espero que um dia possamos finalmente deixar de lado a obsess\u00e3o que temos tido com a viol\u00eancia. Isso manteve-nos estagnados durante meio s\u00e9culo. Enquanto n\u00e3o mudarmos a maneira de pensar, as coisas continuar\u00e3o pelo mesmo caminho\u201d.<\/p>\n<p>No f\u00f3rum IMPLEMENTACI\u00d3N: ENTRE LA PERFIDIA Y LA POTENCIA TRANSFORMADORA, realizado no Centro Cultural Gabriel Garc\u00eda M\u00e1rquez em Bogot\u00e1, n\u00e3o encontramos para expressar o nosso sentimento melhor ep\u00edgrafe que uma reflex\u00e3o contida em La nieve del Almirante do escritor \u00c1lvaro Mutis:<\/p>\n<p>\u2026 Saber que ningu\u00e9m ouve ningu\u00e9m. Ningu\u00e9m sabe nada de ningu\u00e9m. Que a palavra \u00e9 j\u00e1 em si um engano, uma ratoeira que encobre, disfar\u00e7a e sepulta o prec\u00e1rio edif\u00edcio dos nossos sonhos e verdades, todos marcados pelo signo do incomunic\u00e1vel.<\/p>\n<p>Senhores ex-presidentes, imediatamente desde o fim do Procedimento Legislativo Especial, mais conhecido como fast-track, que procurava a implementa\u00e7\u00e3o normativa de aspectos essenciais do Acordo de Havana, base do nosso futuro, temos vindo a presenciar o triste afundamento do maior esfor\u00e7o colectivo dos colombianos para alcan\u00e7ar a paz, sem que ningu\u00e9m dos que podem, se atreva, a contracorrente dos seus advers\u00e1rios, a tomar as decis\u00f5es que sejam necess\u00e1rias para a salvar.<\/p>\n<p>Lamentavelmente incidiu como uma maldi\u00e7\u00e3o a coincid\u00eancia do final das negocia\u00e7\u00f5es de Havana com o in\u00edcio da campanha eleitoral na Col\u00f4mbia. Para nossa desgra\u00e7a, o exerc\u00edcio sublime de consagrar a paz como direito superior exacerbou nas c\u00e1maras legislativas as mais baixas e repudi\u00e1veis condutas da politiquice: um mercado de transac\u00e7\u00f5es de v\u00edcios e de ambi\u00e7\u00f5es, de chantagens ao governo para votar cada norma, terminou distorcendo a letra e o esp\u00edrito do pactuado.<\/p>\n<p>De repente, e envoltos nesse turbilh\u00e3o de paix\u00f5es desbocadas, a contraparte, quer dizer as FARC atrav\u00e9s dos seus porta-vozes de paz no Congresso, ficaram convertidos em convidados de pedra, e obrigados a contemplar dolorosamente desde as galerias a depreda\u00e7\u00e3o do Acordo de Havana. \u00c9 a verdade pura e limpa.<\/p>\n<p>Deploramos a pouca vis\u00e3o e a insensibilidade manifestada por alguns legisladores e agentes institucionais, que n\u00e3o admitiram que a paz \u00e9 o mais elevado de todos os direitos, o direito s\u00edntese, sem o qual n\u00e3o ser\u00e1 poss\u00edvel a materializa\u00e7\u00e3o de nenhum outro direito, como o da alimenta\u00e7\u00e3o, o direito a ter agua, habita\u00e7\u00e3o, terra, sa\u00fade, educa\u00e7\u00e3o, trabalho, vias de comunica\u00e7\u00e3o, bom transporte p\u00fablico, conectividade, toler\u00e2ncia, e democracia.<\/p>\n<p>Acostumados a actuar de costas voltadas para o sentido comum, certos parlamentares converteram a implementa\u00e7\u00e3o normativa em um pretexto para renegociar o Acordo de Havana. Nem sequer leram com aten\u00e7\u00e3o o ponto 6.1.8. Inicio da implementa\u00e7\u00e3o do Acordo Final, cuja letra diz: \u201cConforme o estabelecido no Acordo de 7 de Novembro de 2016, o Acordo Final ser\u00e1 assinado como Acordo Especial do artigo 3 comum das Conven\u00e7\u00f5es de Genebra e depositado ap\u00f3s a sua assinatura ante o Conselho Federal Su\u00ed\u00e7o em Berna. Em seguida ser\u00e1 efectuada pelo Presidente da Rep\u00fablica se efectuar\u00e1 uma declara\u00e7\u00e3o unilateral de Estado ante as Na\u00e7\u00f5es Unidas comunicando o referido Acordo Final e solicitando a incorpora\u00e7\u00e3o do mesmo como documento do Conselho de Seguran\u00e7a das Na\u00e7\u00f5es Unidas nos termos estabelecidos no Acordo com data de 7 de Novembro de 2016\u201d.<\/p>\n<p>Entendemos que relativamente ao cumprimento do acordado o Estado adquiriu obriga\u00e7\u00f5es internacionais que n\u00e3o pode ignorar. Pela nossa parte solicitaremos ao Conselho de Seguran\u00e7a em Nova Iorque que promova uma consulta ao Tribunal Internacional de Justi\u00e7a sobre os deveres que adquire um Estado face a uma declara\u00e7\u00e3o unilateral de cumprimento, relativamente a um acordo de paz. Procederemos igualmente, enquanto parte, a consultar o gabinete Jur\u00eddico do CICR em Genebra acerca dos compromissos que vinculam um Estado que assina um Acordo Especial, como aquele que procura p\u00f4r fim ao conflito colombiano. N\u00e3o; isto n\u00e3o deve ser assumido como um questionamento ao Governo, antes pelo contr\u00e1rio. \u00c9 um direito que as FARC t\u00eam de exigir lealdade ao assinado, ao terem elas cumprido o compromisso supremo de deposi\u00e7\u00e3o das armas.<\/p>\n<p>Por outro lado, nem os legisladores, nem os poderes institucionais podem ignorar que o Acordo de paz de Havana j\u00e1 foi referendado pelo Congresso da Rep\u00fablica, e que foi investido de constitucionalidade pelo Tribunal Constitucional, portanto n\u00e3o pode ser modificado a t\u00e1bua rasa, preconceito ou capricho do Procurador, de um grupo de parlamentares, ou por conceitos contradit\u00f3rios do mesmo Tribunal. Os acordos s\u00e3o para ser cumpridos. Pacta Sunt Servanda.<\/p>\n<p>Claro est\u00e1 que as desgra\u00e7as do Acordo de Paz come\u00e7aram com os comunicados do Tribunal que, contrariando a sua pr\u00f3pria jurisprud\u00eancia, abriu a comporta para que todo o mundo lhe metesse a m\u00e3o, lan\u00e7ando-o assim ao fosso dos depredadores para que o fizessem em farrapos. Em mat\u00e9ria t\u00e3o elevada deveria prevalecer a coordena\u00e7\u00e3o harm\u00f3nica dos poderes para assegurar a paz e n\u00e3o a sua autonomia para alterar arbitrariamente, para assombro do mundo, a geografia do pactuado.<\/p>\n<p>Presidente Santos, vemos como muito dif\u00edcil que conclu\u00eddo o Fast Track possam ser aprovadas normas que reflictam fielmente o pactuado, por via de projectos de lei com mensagem de urg\u00eancia. Novas chantagens viriam, ainda mais em v\u00e9speras de elei\u00e7\u00f5es. Ainda h\u00e1 tempo para optar e exercer poderes constitucionais extraordin\u00e1rios para momentos de emerg\u00eancia. Aplic\u00e1-las n\u00e3o \u00e9 abuso de poder mas uma obriga\u00e7\u00e3o do Estado, sempre que estas sejam ajustadas ao esp\u00edrito do pactuado. O Governo tem o dever de defender o Acordo de Paz nos seus aspectos b\u00e1sicos. Quer dizer, o Governo deve fazer respeitar a obriga\u00e7\u00e3o do Estado de cumprir com o acordado em Havana. As compet\u00eancias para estabelecer Acordos de Paz e assin\u00e1-los s\u00e3o reservadas na Constitui\u00e7\u00e3o ao Presidente, que unicamente tem que dar conta deles ao Congresso. Contudo, o Presidente prescindiu da utiliza\u00e7\u00e3o das suas compet\u00eancias para alcan\u00e7ar acordos de paz nos termos do respeito e da correcta implementa\u00e7\u00e3o do acordado.<\/p>\n<p>Dentro desta perspectiva, pode ainda salvar-se o fundamental da Lei Estatut\u00e1ria da Jurisdi\u00e7\u00e3o Especial para a Paz. A JEP deve manter-se como jurisdi\u00e7\u00e3o para todos os actores do conflito, sem diferen\u00e7as odiosas nem escal\u00f5es de classes, porque esta nunca foi concebida exclusivamente para julgar as FARC. N\u00e3o se pode vulnerar o princ\u00edpio da igualdade entre as partes. O sistema Integral foi criado para examinar as responsabilidades de todos os actores no conflito. Tendo em conta que apenas a verdade pode sanar as profundas feridas ocasionadas pelo conflito, deve ser uma obriga\u00e7\u00e3o para todos oferec\u00ea-la de forma ampla e suficiente. N\u00e3o permitamos que a inexequibilidade da compet\u00eancia da JEP sobre terceiros civis ou agentes do Estado n\u00e3o combatentes, envolvidos em crimes internacionais, continue a manter a impunidade ao estabelecer foros com extens\u00e3o a todos os aforados constitucionalmente, reafirmando assim a exist\u00eancia de uma casta privilegiada de intoc\u00e1veis. Deix\u00e1-lo nessa forma seria equivalente a uma burla cruel \u00e0s v\u00edtimas el conflito.<\/p>\n<p>Como grave complemento \u00e0s distor\u00e7\u00f5es do acordado impede-se que os defensores dos direitos humanos sejam ju\u00edzes da JEP, limita\u00e7\u00e3o que n\u00e3o se introduz para aqueles que tenham sido defensores de membros da for\u00e7a p\u00fablica, de paramilitares ou das institui\u00e7\u00f5es do Estado.<\/p>\n<p>Por outra lado, n\u00e3o esque\u00e7amos que o Acordo Final foi alcan\u00e7ado sobre a premissa de que a justi\u00e7a ordin\u00e1ria tinha actuado durante o conflito de forma parcial, convertendo-se em certos momentos em outro instrumento mais de guerra e impunidade. \u00c9 necess\u00e1rio tramitar o Acto Legislativo que permita por em marcha de forma definitiva a Unidade Especial de luta contra as organiza\u00e7\u00f5es criminosas, para que tome conta das 15 mil queixas existentes contra o paramilitarismo que repousam sem inc\u00f3modo, engavetadas, na Procuradoria Geral da Na\u00e7\u00e3o. Deve preservar-se a autonomia da JEP, sem intromiss\u00f5es de ningu\u00e9m inventando incompatibilidades a magistrados para integrarem a JEP, nem a ex. guerrilheiros para fazer pol\u00edtica. Est\u00e1 claro que a condi\u00e7\u00e3o principal para fazer pol\u00edtica \u00e9 o abandono das armas. N\u00e3o encontramos explica\u00e7\u00e3o para o facto de nesta altura estarem a incrementar-se recursos de incompatibilidade pol\u00edtica ante o CNE, enquanto o governo dos EUA retira a poeira aos seus indictments ou requerimentos judiciais contra antigos dirigentes do Secretariado acusando-os de conspira\u00e7\u00e3o para delinquir com fins de narcotr\u00e1fico e lavagem de activos.<\/p>\n<p>Pedimos ao Governo do Presidente Santos que retire quanto antes, mediante ac\u00e7\u00e3o normativa, o epit\u00e1fio Requiescat In Pace (Que descanse em paz) que o congresso colou na Reforma Pol\u00edtica. Ningu\u00e9m na Col\u00f4mbia perde a esperan\u00e7a de ter uma democracia ampla e participativa. Desejamos uma nova qualidade para o sistema pol\u00edtico, abrir as portas \u00e0 participa\u00e7\u00e3o, recorrer ao voto electr\u00f3nico para suster, ou melhor, para desterrar a fraude, a corrup\u00e7\u00e3o e o clientelismo. A Reforma Pol\u00edtica \u00e9 e ser\u00e1 sempre quest\u00e3o central para superar as causas hist\u00f3ricas do conflito.<\/p>\n<p>Devemos reiterar a nossa preocupa\u00e7\u00e3o pelo crescimento, cada vez maior, da insatisfa\u00e7\u00e3o e desencanto dos antigos guerrilheiros nos espa\u00e7os territoriais pelos incumprimentos do Governo. Em nenhum lado se v\u00eam projectos produtivos em desenvolvimento que n\u00e3o sejam os empreendidos pelos esfor\u00e7os colectivos dos ex-combatentes atrav\u00e9s de cooperativas fundadas por eles, concentrando os poucos recursos do cr\u00e9dito banc\u00e1rio.<\/p>\n<p>Presidente, ordene aos seus funcion\u00e1rios esporear j\u00e1 o cavalo da reincorpora\u00e7\u00e3o pol\u00edtica, econ\u00f3mica e social que desde h\u00e1 um ano os ex-combatentes esperam. A muitos dos nossos n\u00e3o lhes resolveram ainda o problema da sua identidade, e portanto n\u00e3o t\u00eam acesso \u00e0 banca. Ordene libertar j\u00e1 as centenas de prisioneiros farianos que continuam presos nos c\u00e1rceres porque a alguns ju\u00edzes de execu\u00e7\u00e3o de penas n\u00e3o lhes deu na gana tratar disso, os quais n\u00e3o receberam nenhuma admoesta\u00e7\u00e3o ou san\u00e7\u00e3o por denega\u00e7\u00e3o da justi\u00e7a. Que actualizem as bases de dados da For\u00e7a P\u00fablica para que n\u00e3o se continue detendo guerrilheiros amnistiados. Que o corpo de elite da pol\u00edcia criado para proteger a vida de cidad\u00e3os e l\u00edderes sociais nos territ\u00f3rios comece a mostrar resultados. E se os h\u00e1, que se d\u00eaem a conhecer. Que seja motivo de preocupa\u00e7\u00e3o que a um ano de assinada la paz levamos 30 ex. guerrilheiros mortos, e tamb\u00e9m 11 dos seus familiares e mais de 150 dirigentes comunit\u00e1rios assassinados.<\/p>\n<p>Necessitamos de terras com t\u00edtulos de propriedade para desenvolver ali os nossos projectos produtivos e de vida. At\u00e9 ao dia de hoje n\u00e3o recebemos o primeiro cent\u00edmetro de terra para esse prop\u00f3sito. Que se comece a formalizar, sem temor, aos camponeses que actualmente a ocupam e se d\u00ea terra a aqueles que n\u00e3o a t\u00eam ou a t\u00eam de forma insuficiente. Todos queremos ver o in\u00edcio da materializa\u00e7\u00e3o dos compromissos do governo dirigidos a dignificar a vida no campo.<\/p>\n<p>A Reforma Rural Integral, 5 anos passados sobre o nosso primeiro acordo parcial, ainda n\u00e3o cobra vida. Mas temos, pelo contr\u00e1rio, um projecto de lei em consulta pr\u00e9via sem ter passado sequer pela CSIVI, que reduz em fanicos a lei 160 de 94 que era o corpo normativo a que as comunidades rurais se podiam agarrar um pouco para alcan\u00e7ar as suas reivindica\u00e7\u00f5es. Hoje continuam em expans\u00e3o o latif\u00fandio e a estrangeiriza\u00e7\u00e3o da terra, atropelando de caminho a soberania alimentar e a preserva\u00e7\u00e3o dos recursos comuns.<\/p>\n<p>A nova pol\u00edtica antidrogas pactuada em Havana n\u00e3o \u00e9 hoje um processo genu\u00edno de substitui\u00e7\u00e3o centrado no respeito dos direitos humanos, mas um processo de erradica\u00e7\u00e3o brutal que conta entre os seus resultados mais deplor\u00e1veis o massacre de camponeses em Tumaco e a multiplica\u00e7\u00e3o das culturas, pela persist\u00eancia numa pol\u00edtica errada. Enquanto se trata de mostrar efic\u00e1cia perseguindo o escal\u00e3o mais d\u00e9bil da produ\u00e7\u00e3o, nenhum resultado not\u00e1vel se observa no que concerne \u00e0 persegui\u00e7\u00e3o aos chefes assolapados nas capitais nem aos branqueadores de dinheiro que, incrustados no cora\u00e7\u00e3o do capital financeiro, s\u00e3o na realidade o motor do narcotr\u00e1fico.<\/p>\n<p>N\u00e3o desconhecemos a vontade do Presidente Santos, Premio Nobel da Paz, em tentar retirar o processo para outro lado, mas h\u00e1 muita burocracia e uns magotes de assessores que apenas sabem utilizar a norma, n\u00e3o para solucionar os problemas, mas para os agudizar. E n\u00e3o \u00e9 justo, porque isso s\u00f3 refor\u00e7a a sabotagem da direita aos esfor\u00e7os de paz. Temos testemunhado a preocupa\u00e7\u00e3o do Presidente pelo estado actual do processo, mas tamb\u00e9m lhe temos dito que tem \u00e0 sua disposi\u00e7\u00e3o poderes constitucionais para tomar nas suas m\u00e3os as r\u00e9deas da paz. Reiteramo-lo: Pode salv\u00e1-la porque tem \u00e0 disposi\u00e7\u00e3o instrumentos legais concebidos precisamente para salvar um processo de paz.<\/p>\n<p>Como final destas reflex\u00f5es, chamamos a aten\u00e7\u00e3o para a diminui\u00e7\u00e3o no ritmo de produ\u00e7\u00e3o da CSIVI e do CNR, o que come\u00e7a a aparecer como um prematuro ocaso das duas inst\u00e2ncias fundamentais concebidas para garantir o impulso da implementaci\u00f3n e da reincorpora\u00e7\u00e3o.<\/p>\n<p>Finalmente, queremos de forma especial sublinhar o papel da Procuradoria Geral da Na\u00e7\u00e3o contra o Acordo de Paz e a JEP:<\/p>\n<p>O Procurador tem agido como chefe de bancada de Cambio Radical no Congresso para conseguir a maioria das modifica\u00e7\u00f5es operadas na JEP, sempre em preju\u00edzo das FARC. Atendendo \u00e0s solicita\u00e7\u00f5es do Presidente Santos, at\u00e9 em tr\u00eas ocasi\u00f5es nos reunimos com o Procurador Geral para \u201cnegociar\u201d as suas propostas, mas uma vez alcan\u00e7ado o consenso o mencionado funcion\u00e1rio saiu-se com novas pretens\u00f5es que em \u00faltima an\u00e1lise foram as que fez aprovar pelo Congresso.<\/p>\n<p>3\u00ba.- A Procuradoria bloqueou no Congresso a aprova\u00e7\u00e3o das normas necess\u00e1rias para outorgar tratamento de ren\u00fancia \u00e0 ac\u00e7\u00e3o penal a mulheres em situa\u00e7\u00e3o de exclus\u00e3o social, com encargos familiares, condenadas por pequenos delitos relacionados com o narcotr\u00e1fico sem car\u00e1cter violento. Estes tratamientos penais especiais s\u00e3o recomenda\u00e7\u00e3o da OEA e assim foram acordados em Havana<\/p>\n<p>A Procuradoria impediu que fosse posta em marcha a Unidade Especial de Investiga\u00e7\u00e3o de crimes do paramilitarismo contemplada no n\u00famero 74 da JEP. Para isso, bloqueou as necess\u00e1rias reformas constitucionais para que esta unidade pudesse funcionar com autonomia dentro da Procuradoria Geral da Na\u00e7\u00e3o. Embora o Procurador tenha manifestado que estava de acordo em que para garantir a autonomia da Unidade Especial eram necess\u00e1rias reformas constitucionais, acabou bloqueando a sua realiza\u00e7\u00e3o.<\/p>\n<p>Para al\u00e9m disso, introduziu no Decreto 898 de 29 de Maio, em que se acordava a cria\u00e7\u00e3o da Unidade Especial no seio da PGN \u2013 que devia ser complementada com as reformas constitucionais bloqueadas &#8211; um t\u00edtulo II de reformas da Procuradoria que vai a provocar que o Tribunal Constitucional declare inexequ\u00edvel todo o Decreto, por terem sido nele introduzidas mat\u00e9rias n\u00e3o previstas para o procedimento Fast Track. Estas incorpora\u00e7\u00f5es, n\u00e3o consensualizadas na CSIVI, foram impostas com a inten\u00e7\u00e3o perversa de que fosse declarado inexequ\u00edvel o relacionado com a Unidade Especial.<\/p>\n<p>Presidente Santos, senhores ex-presidentes de Uruguai e Espanha, com todo respeito, estas s\u00e3o as nossas principais preocupa\u00e7\u00f5es em torno dos desenvolvimentos do processo de paz.<\/p>\n<p>Por todo o seu apoio ao processo de paz em Col\u00f4mbia, muito obrigado, senhores ex-presidentes Felipe Gonz\u00e1lez e Pepe Mujica; Muito obrigado aos governos de Cuba e de Noruega, pa\u00edses Garantes do processo; Muito obrigado \u00e0s Na\u00e7\u00f5es Unidas pelo extraordin\u00e1rio papel da sua Segunda Miss\u00e3o.<\/p>\n<p>Desde Cartagena, a Her\u00f3ica, queremos que v\u00f3s e o povo colombiano tenhais a certeza de que, n\u00e3o obstante as dificuldades, continuaremos a caminhar sobre a convic\u00e7\u00e3o de que ter posto fim ao conflito \u00e9 o facto mais importante das \u00faltimas d\u00e9cadas no pa\u00eds.<\/p>\n<p>Original: http:\/\/www.resumenlatinoamericano.org\/2018\/01\/04\/colombia-farc-analisis-sobre-el-estado-de-la-implementacion-del-primer-ano-de-los-acuerdos-de-la-habana\/<\/p>\n<p>Fonte: https:\/\/www.odiario.info\/intervencao-da-fuerza-alternativa-revolucionaria-del\/<\/p>\n","protected":false},"excerpt":{"rendered":"<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/18414\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[34],"tags":[227],"class_list":["post-18414","post","type-post","status-publish","format-standard","hentry","category-c39-colombia","tag-5a"],"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p659gw-4N0","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/18414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=18414"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/18414\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=18414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=18414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=18414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}