{"id":18524,"date":"2018-01-27T08:54:14","date_gmt":"2018-01-27T11:54:14","guid":{"rendered":"https:\/\/pcb.org.br\/portal2\/?p=18524"},"modified":"2018-01-27T08:54:14","modified_gmt":"2018-01-27T11:54:14","slug":"e-agora-e-hora-de-chutar-o-tabuleiro","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/18524","title":{"rendered":"E agora? \u00c9 hora de chutar o tabuleiro!"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"imagem\" title=\"E agora? \u00c9 hora de chutar o tabuleiro!\" src=\"https:\/\/boitempoeditorial.files.wordpress.com\/2018\/01\/lula-gleisi.jpg?w=747&#038;h=410&#038;fit=620%2C410\" alt=\"E agora? \u00c9 hora de chutar o tabuleiro!\" \/><!--more-->&#8220;Marx disse certa vez que n\u00e3o se deve brincar com a insurrei\u00e7\u00e3o se n\u00e3o quiser lev\u00e1-la at\u00e9 as \u00faltimas consequ\u00eancias. Ao que parece o lulopetismo espera que as massas garantam que Lula n\u00e3o seja preso e dispute as elei\u00e7\u00f5es, mas que depois saiam de cena para que tudo volte aos trilhos da normalidade para que se possa remendar o pacto social esgar\u00e7ado pelo golpe.&#8221;<\/p>\n<p>Por Mauro Iasi*<\/p>\n<p><a href=\"https:\/\/blogdaboitempo.com.br\/2018\/01\/26\/e-agora-e-hora-de-chutar-o-tabuleiro\/\" target=\"_blank\" rel=\"noopener\">Boitempo<\/a><\/p>\n<p>A confirma\u00e7\u00e3o da condena\u00e7\u00e3o de Lula seguiu o <em>script <\/em>esperado. Apesar da inconsist\u00eancia de provas, fatos e fundamentos jur\u00eddicos, era necess\u00e1rio retirar o ex-presidente da disputa eleitoral de 2018 e seguir com um governo cuja \u00fanica lealdade \u00e9 com as contrarreformas e os interesses do grande capital. O fim da democracia de coopta\u00e7\u00e3o operada pelos governos petistas abriu espa\u00e7o para a barb\u00e1rie expl\u00edcita e a canalhice que presenciamos, pol\u00edtica, jur\u00eddica, cultural e comunicacional.<\/p>\n<p>Os pesados ataques contra os trabalhadores, em especial a reforma trabalhista e a amea\u00e7a da reforma da previd\u00eancia, n\u00e3o tiveram a resposta necess\u00e1ria porque o petismo e seus aliados ainda esperavam a \u201cmarcha dos acontecimentos\u201d que desembocaria nas elei\u00e7\u00f5es de 2018, ainda que programaticamente isso n\u00e3o garantisse a revers\u00e3o das medidas aprovadas at\u00e9 aqui. Com a condena\u00e7\u00e3o de Lula a conjuntura muda radicalmente em dois sentidos.<\/p>\n<p>Primeiro que a aposta nas elei\u00e7\u00f5es se transforma em um desafio aberto a legalidade institucional estabelecida, uma vez que a manuten\u00e7\u00e3o da candidatura do ex-presidente se torna uma desobedi\u00eancia civil. Segundo que as fr\u00e1geis apar\u00eancias de normalidade institucional podem se esvanecer rapidamente e abrir espa\u00e7o para medidas pol\u00edticas mais duras de parte da classe dominante e do seguimento usurpador no comando do Estado.<\/p>\n<p>Nesse cen\u00e1rio, a combina\u00e7\u00e3o de espa\u00e7os institucionais estabelecidos e a\u00e7\u00f5es por fora e al\u00e9m da legalidade ganha relevo para os dois lados envolvidos na disputa. Da parte das classes dominantes, isso n\u00e3o \u00e9 uma novidade, porque diferente de certo setor da esquerda, a classe dominante nunca acreditou na institucionalidade democr\u00e1tica e sempre a utilizou pragmaticamente segundo seus interesses. O Estado trata a todos de forma igual perante a lei, mas nada que uma mala de dinheiro e um <em>lobby <\/em>eficiente n\u00e3o possam contornar. A burguesia pode operar no terreno da democracia porque tem os instrumentos de coer\u00e7\u00e3o do Estado e do dom\u00ednio econ\u00f4mico \u00e0 sua disposi\u00e7\u00e3o. Assim, pode alternar formas democr\u00e1ticas e autorit\u00e1rias com mais efici\u00eancia, o que n\u00e3o se d\u00e1 com os trabalhadores.<\/p>\n<p>Quando uma for\u00e7a pol\u00edtica escolhe operar nos limites da institucionalidade, fica muito dif\u00edcil romper e operar com formas abertamente insurgentes. A \u00fanica for\u00e7a pol\u00edtica que pode criar as condi\u00e7\u00f5es para tanto \u00e9 a disposi\u00e7\u00e3o das massas em romper a legalidade no sentido da rebeli\u00e3o. Como todo bom leitor de L\u00eanin sabe, esta \u00e9 uma condi\u00e7\u00e3o objetiva \u2013 isto \u00e9, n\u00e3o est\u00e1 ao alcance desta ou daquela for\u00e7a pol\u00edtica colocar as massas em movimento, de certa forma elas reagem a uma determinada situa\u00e7\u00e3o pol\u00edtica.<\/p>\n<p>O que a burguesia talvez tenha feito, inadvertidamente ou n\u00e3o, \u00e9 dar o pretexto para que as massas entrem em cena numa dimens\u00e3o que pode ir al\u00e9m da institucionalidade dada. Entretanto, neste ponto interv\u00e9m a intencionalidade pol\u00edtica dos sujeitos. Marx disse certa vez que n\u00e3o se deve brincar com a insurrei\u00e7\u00e3o se n\u00e3o quiser lev\u00e1-la at\u00e9 as \u00faltimas consequ\u00eancias. Ao que parece o lulopetismo espera que as massas garantam que Lula n\u00e3o seja preso e dispute as elei\u00e7\u00f5es, mas que depois saiam de cena para que tudo volte aos trilhos da normalidade para que se possa remendar o pacto social esgar\u00e7ado pelo golpe. De certa maneira a rebeli\u00e3o das massas se converte em um instrumento de chantagem ou amea\u00e7a para que os segmentos burgueses caiam em si e aceitem renegociar os termos do pacto.<\/p>\n<p>Esse \u00e9 um jogo perigoso. Primeiro porque n\u00e3o se deve blefar quando se trata de uma pol\u00edtica revolucion\u00e1ria que se pretenda s\u00e9ria. Parece que n\u00e3o se convoca as massas para que a classe trabalhadora estabele\u00e7a as condi\u00e7\u00f5es de seu pr\u00f3prio poder, mas para que garanta a correla\u00e7\u00e3o de for\u00e7as para que se recomponha as condi\u00e7\u00f5es que marcaram a concilia\u00e7\u00e3o de classes que prevaleceu at\u00e9 2016. O grande problema dessa alternativa \u00e9 que o petismo se assusta mais com a rebeli\u00e3o das massas do que a burguesia: n\u00e3o h\u00e1 lugar para a insurrei\u00e7\u00e3o na estrat\u00e9gia democr\u00e1tica popular e o PT n\u00e3o sabe o que fazer quando ela se apresenta, como ficou evidente em 2013. Por outro lado, a burguesia tem meios jur\u00eddicos, pol\u00edticos e repressivos para enfrentar um descontrole social \u2013 alguns desses instrumentos, ali\u00e1s, gentilmente oferecidos pelos governos petistas como a manuten\u00e7\u00e3o da Lei de Seguran\u00e7a Nacional, a Portaria Normativa que estabelece as Opera\u00e7\u00f5es da garantia da Lei e da Ordem de dezembro de 2013 e a Lei Antiterrorismo, s\u00f3 para citar alguns dispositivos \u2013, al\u00e9m, \u00e9 claro, de um sistema judici\u00e1rio que se emancipou da tutela incomoda do Direito e da Justi\u00e7a.<\/p>\n<p>Portanto, trata-se de definir at\u00e9 onde as for\u00e7as pol\u00edticas est\u00e3o dispostas a tencionar a legalidade. Estou convencido de que a burguesia mant\u00e9m suas apostas, mesmo se for necess\u00e1rio romper (como tem feito no governo do usurpador) qualquer base legal, pol\u00edtica e institucional. O PT est\u00e1 disposto a fazer o mesmo? N\u00e3o sei.<\/p>\n<p>Quais s\u00e3o os pr\u00f3ximos passos indicados pelo o segmento dominante? Tentar tocar as elei\u00e7\u00f5es sem Lula, diante do risco da extrema direita e da aus\u00eancia de uma candidatura que possa retomar a estabilidade que a burguesia precisa, ou, cancelar as elei\u00e7\u00f5es e constituir alguma esp\u00e9cie de transi\u00e7\u00e3o, uma junta provis\u00f3ria que prepare as condi\u00e7\u00f5es pol\u00edticas de uma alterativa mais est\u00e1vel nos termos da ordem, como o semi-presidencialismo, o parlamentarismo ou outra forma qualquer.<\/p>\n<p>Volto a dizer: a burguesia pode cancelar as elei\u00e7\u00f5es de 2018. E pergunto: as for\u00e7as populares est\u00e3o dispostas a colocar o enfrentamento diante das contrarreformas e o arb\u00edtrio burgu\u00eas acima das elei\u00e7\u00f5es, inclusive agindo no sentido de inviabiliz\u00e1-las?<\/p>\n<p>O ponto obscuro \u00e9 o pr\u00f3ximo passo do petismo. Ser\u00e1 que ele est\u00e1 mesmo disposto a resistir e enfrentar a decis\u00e3o judici\u00e1ria com todos os meios necess\u00e1rios, ou \u00e9 mais um blefe? A moderada e elegante presidente nacional do PT afirmou recentemente que a \u00fanica maneira de reagir \u00e0 consolida\u00e7\u00e3o de um cen\u00e1rio pol\u00edtico no qual Lula vai preso e \u00e9 impedido de disputar as elei\u00e7\u00f5es \u00e9 a greve geral. Vejam voc\u00eas! A esquerda j\u00e1 sabia que a \u00fanica maneira de evitar a consolida\u00e7\u00e3o do golpe contra os trabalhadores, a reforma trabalhista e da previd\u00eancia \u00e9 a greve geral, mas o PT discordava disso, pois acreditava que existia outra possibilidade: a candidatura de Lula. Agora que essa alternativa saiu de cena\u2026 ent\u00e3o, vamos \u00e0 greve!<\/p>\n<p>Marx e Engels, em um famoso texto de 1850, diziam que os trabalhadores n\u00e3o podem evitar que a pequena burguesia aja como o segmento social vacilante que est\u00e1 condenado a ser, mas os trabalhadores devem, em suas palavras, \u201cagir no sentido de contrapor-se \u00e0s dissuas\u00f5es burguesas\u201d contemporizadoras e \u201cobrigar os democratas a concretizar o seu fraseado terrorista atual\u201d (\u201cMensagem do Comit\u00ea Central \u00e0 Liga [dos comunistas]\u201d, em: Karl Marx e Friedrich Engels,<a href=\"https:\/\/www.boitempoeditorial.com.br\/produto\/lutas-de-classes-na-alemanha-221\" target=\"_blank\" rel=\"noopener\"><em> Lutas de classes na Alemanha<\/em><\/a>, Boitempo, 2010, p. 67). Querem um Greve Geral? Certo, ent\u00e3o vamos faz\u00ea-la at\u00e9 que as medidas contra os trabalhadores sejam revogadas e at\u00e9 que o governo Temer caia. A\u00ed discutiremos o que fazer. Certamente alguns ir\u00e3o propor que tudo volte ao \u201cnormal\u201d e que volte a se convocar elei\u00e7\u00f5es \u201climpas\u201d (como as de 2014, na qual o financiamento privado jogou R$ 5 bilh\u00f5es nas mais diferentes candidaturas, menos nas do PCB, do PSTU e do PCO). N\u00f3s manteremos nossa proposta de estabelecer um Poder Popular Revolucion\u00e1rio fundado em uma nova forma de governabilidade na classe trabalhadora da cidade e do campo, na juventude e nas massas urbanas.<\/p>\n<p>N\u00e3o importa agora que uns se mobilizem em torno de um l\u00edder cujos interesses no fundo, ao nosso ju\u00edzo, s\u00e3o contr\u00e1rios aos da classe trabalhadora porque quer recompor o pacto desfeito. Neste momento se produz uma aproxima\u00e7\u00e3o interessante na qual o interesse do lulopetismo em enfrentar a decis\u00e3o que tira Lula das elei\u00e7\u00f5es coincide com o interesse da esquerda em enfrentar as contrarreformas reacion\u00e1rias com uma Greve Geral. Se os interesses forem os mesmos (derrotar o governo Temer e suas contrarreformas), \u00f3timo! Caso contr\u00e1rio, os caminhos se bifurcar\u00e3o e n\u00f3s, como temos feito, pegaremos a caminho da esquerda.<\/p>\n<hr \/>\n<p>Ilustra\u00e7\u00e3o: Gleisi Hoffann, senadora e atual presidente nacional do PT, e Lula anunciam a pr\u00e9-candidatura do ex-presidente um dia ap\u00f3s sua condena\u00e7\u00e3o em segunda inst\u00e2ncia. 25\/01\/2017 (Nelson Almeida\/AFP).<\/p>\n<p><strong>Mauro Iasi\u00a0<\/strong>\u00e9 professor adjunto da Escola de Servi\u00e7o Social da UFRJ, pesquisador do NEPEM (N\u00facleo de Estudos e Pesquisas Marxistas), do NEP 13 de Maio e membro do Comit\u00ea Central do PCB. \u00c9 autor do livro\u00a0<a href=\"http:\/\/www.boitempoeditorial.com.br\/v3\/titles\/view\/48#.Ul8Kh1Csh8E\" target=\"_blank\" rel=\"noopener noreferrer\"><em>O dilema de Hamlet: o ser e o n\u00e3o ser da consci\u00eancia<\/em><\/a>\u00a0(Boitempo, 2002) e colabora com os livros\u00a0<a href=\"http:\/\/www.boitempoeditorial.com.br\/v3\/titles\/view\/cidades-rebeldes\" target=\"_blank\" rel=\"noopener noreferrer\"><em>Cidades rebeldes: Passe Livre e as manifesta\u00e7\u00f5es que tomaram as ruas do Brasil<\/em><\/a>\u00a0e\u00a0<a href=\"http:\/\/www.boitempoeditorial.com.br\/v3\/titles\/view\/gy%C3%B6rgy-lukacs-e-a-emancipacao-humana\" target=\"_blank\" rel=\"noopener noreferrer\"><em>Gy\u00f6rgy Luk\u00e1cs e a emancipa\u00e7\u00e3o humana<\/em><\/a>\u00a0(Boitempo, 2013), organizado por Marcos Del Roio. Colabora para o\u00a0<strong>Blog da Boitempo\u00a0<\/strong>mensalmente, \u00e0s quartas.<\/p>\n<p>Fonte: https:\/\/blogdaboitempo.com.br\/2018\/01\/26\/e-agora-e-hora-de-chutar-o-tabuleiro\/<\/p>\n","protected":false},"excerpt":{"rendered":"<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/18524\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[7,54],"tags":[222],"class_list":["post-18524","post","type-post","status-publish","format-standard","hentry","category-s8-brasil","category-c65-lulismo","tag-2b"],"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p659gw-4OM","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/18524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=18524"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/18524\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=18524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=18524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=18524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}