{"id":20104,"date":"2018-06-28T20:53:33","date_gmt":"2018-06-28T23:53:33","guid":{"rendered":"https:\/\/pcb.org.br\/portal2\/?p=20104"},"modified":"2018-06-28T20:53:33","modified_gmt":"2018-06-28T23:53:33","slug":"domenico-losurdo-1941-2018-intelectual-comunista","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/20104","title":{"rendered":"Domenico Losurdo (1941-2018): intelectual comunista"},"content":{"rendered":"<p><img decoding=\"async\" class=\"imagem\" title=\"imagem\" src=\"https:\/\/i0.wp.com\/lh3.googleusercontent.com\/qI5RgT5SqWwjAkK0FSriuVOJSo5r7c24zAo_hIV7U01L_cl90z4UIQ7d78A1KkUtXi9sMkuNycEVNDZq7yr-vFoW47SZxFdg6hcz74gk4ZnqSeLuIEsEM7QB030gaVEyOOiWIgkbzNCgV414U5Ew5ORtHxHQLZ505KKkk2qwvpuTAqBqjGF5gUmhOwgjWa9OEa3z3CGAcAs1_FSvegIdtohOZK_OPhgE8nNom-Y88GGs39PW-l62Zbm3Tn7IPCUXEeTMUnWa-bRKIgowf8MP2cpj8RY6PU3QSqWpmJ_YU7lvx-of1uF0jCRWJ66SEbGlT8aggACR3fC9WuQF_3lMPx0pI1nt3kXdZcl187uoj2bh5ONvoXWH7gdUnvZpJN5CYXMVFw9O6hxJk6vsZPUK6wHhkrhTalNV3wJRzVh2wZMmNGX3sWMDLzqY-OqUcXQTx-Z9KTiNOpGTP_4KzUBfIobhdkbZSG2xo0Qw1J3O6KhxWMSrJbYDQDoBhzWQCeI4_6T8T978gCmAQrE-_QDP_bVZU2fB3tOOY5CCw9CoE_izYamzeDpKZPwVRqv6XtkIF0rSpYl_ZRqEhLkEpC-1joyi9o-mls3bqmh6JK8ZtuC10BqeHg0eNNgd94a3-qpohB_ZqxhMcb-F7T9U7rQioH62iZoSF0jkeg=w640-h473-no\" alt=\"imagem\" \/><!--more-->Jones Manoel*<\/p>\n<p>Morreu neste dia 28\/06 o mais brilhante marxista europeu em atividade. Domenico Losurdo foi um gigante que andou entre os seres humanos. Sua obra, sem muita aceita\u00e7\u00e3o na universidade brasileira, \u00e9 uma ousada e incr\u00edvel releitura da modernidade burguesa a partir dos interesses e lutas dos &#8220;condenados da terra&#8221;: os povos colonizados. Comunista, homem de partido, militante, Losurdo \u00e9 a figura intelectual de maior relev\u00e2ncia do marxismo italiano depois da morte de Palmiro Togliatti. Sua obra \u00e9 indispens\u00e1vel para qualquer revolucion\u00e1rio, mas, especialmente para n\u00f3s, na periferia do sistema capitalista.<\/p>\n<p>Saiu da vida para entrar na hist\u00f3ria! Em homenagem a esse grande homem, publico um pequeno &#8220;guia&#8221; de introdu\u00e7\u00e3o a sua obra.<\/p>\n<hr \/>\n<p>Introdu\u00e7\u00e3o ao estudo de Domenico Losurdo.<\/p>\n<p>Para come\u00e7ar um estudo da obra do marxista italiano Domenico Losurdo \u2013 um dos maiores marxistas vivos que temos, seguem algumas indica\u00e7\u00f5es. Primeiro, considero que a obra de Losurdo cont\u00e9m quatro temas centrais: a quest\u00e3o nacional no processo revolucion\u00e1rio, uma contra-hist\u00f3ria do liberalismo e de maneira mais ampla da domina\u00e7\u00e3o burguesa na modernidade, um balan\u00e7o cr\u00edtico das experi\u00eancias socialistas no s\u00e9culo XX e uma tentativa de renovar o marxismo a partir de uma teoria pol\u00edtica que se pretende ser uma supera\u00e7\u00e3o dos \u201cres\u00edduos ut\u00f3picos\u201d ainda presentes no marxismo. Pois bem, essas quatro tem\u00e1ticas centrais est\u00e3o dentro de uma mesma problem\u00e1tica: uma contra-hist\u00f3rica da modernidade burguesa vista desde a perspectiva dos povos coloniais \u2013 os condenados da terra \u2013 e dos trabalhadores\/as do centro do capitalismo com vistas a criar uma vis\u00e3o de mundo pr\u00f3pria dos de baixo como elemento indispens\u00e1vel do processo revolucion\u00e1rio em suas duas faces (a destrui\u00e7\u00e3o da velha ordem e a edifica\u00e7\u00e3o de uma nova sociedade). Para tentar deixar mais did\u00e1tica a quest\u00e3o, segue uma s\u00e9rie de indica\u00e7\u00f5es de livros e artigos sobre as quatro tem\u00e1ticas centrais na obra losurdiana (n\u00e3o pretendo indicar todas as obras sobre cada tema, mas as que considero centrais).<\/p>\n<p>&#8211; Balan\u00e7o das experi\u00eancias socialistas.<br \/>\n* Fuga da hist\u00f3ria? A Revolu\u00e7\u00e3o Russa e a Revolu\u00e7\u00e3o Chinesa vistas de hoje (dispon\u00edvel na internet)<br \/>\n* St\u00e1lin \u2013 uma hist\u00f3ria cr\u00edtica de uma lenda negra (livro central de Losurdo nessa tem\u00e1tica).<br \/>\n* Marx, Crist\u00f3v\u00e3o Colombo e a revolu\u00e7\u00e3o de Outubro [artigo] (dispon\u00edvel na internet).<br \/>\n* O significado hist\u00f3rico da Revolu\u00e7\u00e3o de Outubro [tr\u00eas artigos] (dispon\u00edvel na internet \u2013 site da revista cr\u00edtica marxista).<\/p>\n<p>&#8211; Contra-hist\u00f3ria do liberalismo e da domina\u00e7\u00e3o burguesa.<br \/>\n* Contra-hist\u00f3ria do liberalismo (livro central nessa tem\u00e1tica)<br \/>\n*Liberalismo. Entre a civiliza\u00e7\u00e3o e a barb\u00e1rie (n\u00e3o tem na internet, mas \u00e9 um livro barato. Menos de 30 reais).<br \/>\n* A n\u00e3o viol\u00eancia: uma hist\u00f3ria fora do mito (dispon\u00edvel na internet).<br \/>\n* Democracia ou bonapartismo (at\u00e9 onde me consta, n\u00e3o dispon\u00edvel na internet e dif\u00edcil de achar).<br \/>\n* Nietzsche, o rebelde aristocrata (livro caro e at\u00e9 onde sei tamb\u00e9m n\u00e3o dispon\u00edvel na internet).<br \/>\n* A Linguagem do Imp\u00e9rio &#8211; l\u00e9xico da ideologia estadunidense (at\u00e9 onde sei, n\u00e3o dispon\u00edvel na internet, mas f\u00e1cil de achar e relativamente barato).<br \/>\n* O pecado original do s\u00e9culo XX (livro barato para comprar).<\/p>\n<p>&#8211; Teoria pol\u00edtica e do Estado.<br \/>\n*Hegel, Marx e a tradi\u00e7\u00e3o liberal (tamb\u00e9m n\u00e3o dispon\u00edvel na internet, mas f\u00e1cil de achar em qualquer biblioteca de universidade).<br \/>\n*Ant\u00f4nio Gramsci: do liberalismo ao \u201ccomunismo cr\u00edtico\u201d (f\u00e1cil de achar em sebos e creio que j\u00e1 est\u00e1 dispon\u00edvel na internet).<br \/>\n* Para uma cr\u00edtica da categoria de totalitarismo (dispon\u00edvel na internet, site da cr\u00edtica marxista).<\/p>\n<p>&#8211; A quest\u00e3o nacional e a revolu\u00e7\u00e3o.<br \/>\n* A luta de classes &#8211; Uma hist\u00f3ria filos\u00f3fica e pol\u00edtica (ao meu ver, esse livro junto com o sobre St\u00e1lin, \u00e9 uma esp\u00e9cie de s\u00edntese geral da obra de Losurdo abarcando todos os temas centrais de sua produ\u00e7\u00e3o na maturidade).<br \/>\n* Guerra e revolu\u00e7\u00e3o: um mundo um s\u00e9culo ap\u00f3s outubro de 1917.<\/p>\n<p>Advert\u00eancia: essa divis\u00e3o \u00e9 mais no tocante a temas centrais abordados. Na pr\u00e1tica os temas basilares da obra losurdiana comparecem em maior ou menor medida em todos os livros.<\/p>\n<p>*Militante do PCB de Pernambuco<\/p>\n","protected":false},"excerpt":{"rendered":"<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/20104\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[50],"tags":[221],"class_list":["post-20104","post","type-post","status-publish","format-standard","hentry","category-c61-cultura-revolucionaria","tag-2a"],"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p659gw-5eg","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/20104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=20104"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/20104\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=20104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=20104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=20104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}