{"id":20539,"date":"2018-08-16T19:58:45","date_gmt":"2018-08-16T22:58:45","guid":{"rendered":"https:\/\/pcb.org.br\/portal2\/?p=20539"},"modified":"2018-08-16T19:58:45","modified_gmt":"2018-08-16T22:58:45","slug":"por-uma-ciencia-voltada-aos-interesses-populares","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/20539","title":{"rendered":"Por uma ci\u00eancia voltada aos interesses populares"},"content":{"rendered":"<p><img decoding=\"async\" class=\"imagem\" title=\"imagem\" src=\"https:\/\/i0.wp.com\/graph.facebook.com\/1758243384292839\/picture\" alt=\"imagem\" \/><!--more-->UJC de S\u00e3o Paulo<\/p>\n<p>As v\u00e1rias mobiliza\u00e7\u00f5es de estudantes de gradua\u00e7\u00e3o e p\u00f3s-gradua\u00e7\u00e3o em todo pa\u00eds tiveram um saldo positivo muito importante para impedir os cortes no or\u00e7amento da CAPES para 2019, o que afetaria drasticamente a continuidade das bolsas de fomento \u00e0 pesquisa. O governo golpista recuou e n\u00e3o vetou os recursos da educa\u00e7\u00e3o na LDO de 2019. Agora \u00e9 hora de avan\u00e7ar com as lutas! \u00c9 preciso superar a pol\u00edtica de ajuste fiscal e derrubar a Emenda Constitucional 95, que definitivamente liquida nosso futuro.<\/p>\n<p>O ajuste fiscal impacta diretamente a educa\u00e7\u00e3o b\u00e1sica, as universidades federais e a p\u00f3s-gradua\u00e7\u00e3o desde 2015. Portanto, n\u00e3o \u00e9 suficiente apenas manter o or\u00e7amento de 2018. Ao mesmo tempo, \u00e1reas como a sa\u00fade, assist\u00eancia social e ci\u00eancia e tecnologia v\u00e3o sofrer cortes para o pr\u00f3ximo ano.<\/p>\n<p>O governo Temer vem aplicando um ajuste fiscal sem precedentes, que recai sobre as costas dos trabalhadores e da juventude no nosso pa\u00eds. Logo depois da aprova\u00e7\u00e3o da PEC 241\/55, apelidada de &#8220;PEC do Fim do Mundo&#8221;, que congela o or\u00e7amento p\u00fablico para \u00e1reas sociais por 20 anos, j\u00e1 come\u00e7amos a sentir seus efeitos.<\/p>\n<p>No dia 3 de agosto, a CAPES divulgou um of\u00edcio anunciando a possibilidade concreta do corte de milhares de bolsas de pesquisa em todo o pa\u00eds. A nota manifestava que tal corte poderia ter impactos, a partir de agosto de 2019, nas bolsas de mestrado, doutorado e p\u00f3s-doutorado, nos programas de bolsas de inicia\u00e7\u00e3o \u00e0 doc\u00eancia (Pibid), de resid\u00eancia pedag\u00f3gica e de forma\u00e7\u00e3o de professores da educa\u00e7\u00e3o b\u00e1sica (Parfor) e nos programas de fomento \u00e0 internacionaliza\u00e7\u00e3o.<\/p>\n<p>Para al\u00e9m disso, aqui em S\u00e3o Paulo enfrentamos situa\u00e7\u00f5es duras na educa\u00e7\u00e3o p\u00fablica e privada. De um lado, as negocia\u00e7\u00f5es da Lei de Diretrizes Or\u00e7ament\u00e1rias de 2019 no Estado t\u00eam mantido um repasse m\u00ednimo do ICMS para as universidades p\u00fablicas e o sucateamento \u00e9 uma realidade, com falta de professores, bolsas de perman\u00eancia estudantil e precariza\u00e7\u00e3o nas condi\u00e7\u00f5es de ensino, pesquisa e extens\u00e3o. De outro, as demiss\u00f5es em massa das universidades privadas aumentam o desemprego entre os professores, al\u00e9m de piorar ainda mais as condi\u00e7\u00f5es nas universidades privadas, aumentando o valor das mensalidades e deteriorando a forma\u00e7\u00e3o geral desses estudantes, que em sua maioria tamb\u00e9m trabalham para sustentar os estudos.<\/p>\n<p>Por isso, para comemorar com luta o Dia do Estudante, foi convocado um grande ato em defesa da educa\u00e7\u00e3o p\u00fablica, que contou com a participa\u00e7\u00e3o de diversos estudantes, organiza\u00e7\u00f5es, movimentos e entidades que entendem que s\u00f3 a luta muda a vida. Acreditamos que \u00e9 papel do movimento estudantil se colocar contra a situa\u00e7\u00e3o no nosso pa\u00eds e lutar contra esses ataques. Hoje, infelizmente, as entidades estudantis, como a Uni\u00e3o Nacional dos Estudantes e a Uni\u00e3o Estadual dos Estudantes &#8211; SP, est\u00e3o sob dire\u00e7\u00e3o de setores que n\u00e3o se preocupam com a nossa luta e n\u00e3o est\u00e3o dispostos a grandes mobiliza\u00e7\u00f5es combativas. Fazemos parte da oposi\u00e7\u00e3o a esses setores e acreditamos que devemos recuperar as nossas entidades hist\u00f3ricas para um campo combativo, de lutas, que v\u00e1 para as ruas lutar pelos seus direitos e pelas conquistas que tivemos!<\/p>\n<p>A LUTA CONTINUA!<\/p>\n<p>https:\/\/www.facebook.com\/ujcsaopaulo\/<wbr \/>posts\/1599643550162841<\/p>\n","protected":false},"excerpt":{"rendered":"<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/20539\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[27],"tags":[222],"class_list":["post-20539","post","type-post","status-publish","format-standard","hentry","category-c27-ujc","tag-2b"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-5lh","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/20539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=20539"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/20539\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=20539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=20539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=20539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}