{"id":21722,"date":"2018-12-24T04:06:53","date_gmt":"2018-12-24T06:06:53","guid":{"rendered":"https:\/\/pcb.org.br\/portal2\/?p=21722"},"modified":"2018-12-24T04:06:59","modified_gmt":"2018-12-24T06:06:59","slug":"critica-da-critica-da-razao-negra","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/21722","title":{"rendered":"Cr\u00edtica da Cr\u00edtica da Raz\u00e3o Negra"},"content":{"rendered":"<p><img decoding=\"async\" class=\"imagem\" title=\"imagem\" alt=\"imagem\" src=\"https:\/\/i0.wp.com\/bloglavrapalavra.files.wordpress.com\/2018\/12\/Mbembe-2.jpg\"><!--more-->Por In\u00eas Maia<\/p>\n<p>A sutileza, quase diria: a grandeza, com que Mbembe aborda o problema da inven\u00e7\u00e3o das ra\u00e7as e a cria\u00e7\u00e3o do substantivo negro, leva a pensar que talvez, finalmente, Fanon tenha encontrado um sucessor \u00e0 altura.Entre as pensadoras e os pensadores mais vitais, ainda sedentos de vida te\u00f3rica \u2013 \u00fanica maneira efetiva de transforma\u00e7\u00e3o radical da vida pr\u00e1tica \u2013 sem d\u00favida, seu nome ressoa como um nome que deu concretude ao paradoxo da constru\u00e7\u00e3o do significante ra\u00e7a.<\/p>\n<p>Ao tomar o partido contra o reducionismo protoidentit\u00e1rio e pronunciar com altivez a palavra \u2018cr\u00edtica\u2019[1], ao conceder ao pr\u00f3prio escopo te\u00f3rico a possibilidade de uma an\u00e1lise que vai a busca das formas determinantes da explora\u00e7\u00e3o colonial (observando-a como g\u00eanese e motor do capitalismo), Mbembe apontou com radicalidade os problemas centrais na cria\u00e7\u00e3o da ra\u00e7a e sua imbrica\u00e7\u00e3o com o termo \u201cnegro\u201d e, com isso, a maneira de ultrapassar essa condi\u00e7\u00e3o.<\/p>\n<p>Como modelo de explora\u00e7\u00e3o, paradigma de submiss\u00e3o e um complexo psicon\u00edrico; o significante ra\u00e7a tornou-se uma fic\u00e7\u00e3o \u00fatil para governo dos corpos e pr\u00e1ticas biopol\u00edticas \u2013 divis\u00e3o entre quem tem ou n\u00e3o status de cidad\u00e3o \u2013 que levar\u00e3o ao necropoder \u2013 defini\u00e7\u00e3o de quem pode ser morto, e quem n\u00e3o pode, por meio de um atributo, geralmente s\u00f3cio-racial criado exclusivamente para e pela exclus\u00e3o.<\/p>\n<p>O r\u00e1pido florescimento de seu pensamento, e a forma\u00e7\u00e3o que ir\u00e1 possibilitar, \u00e9 algo ainda a se mesurar no Brasil \u2013 principalmente num quadro em que a hegemonia de teorias liberais foram adotadas acriticamente por grande parte do Movimento Negro. Mas respostas assim se acham no drama da vida concreta, e \u00e9 tempo, finalmente, de se ver colher os resultados pol\u00edticos catastr\u00f3ficos, permitidos e fecundados, pelo total afastamento da esquerda da vida comum, o que, esperamos, chame os mais sens\u00edveis \u00e0 raz\u00e3o. Recomecemos ent\u00e3o.<\/p>\n<p>N\u00e3o importando o ponto de vista filos\u00f3fico em que nos situemos hoje: o car\u00e1ter dissoluto, prec\u00e1rio, degradado do mundo no qual vivemos, e da vida que nos restou, s\u00e3o as coisas mais firmes e seguras que podemos afirmar. Todos afundam no mesmo barco do retorno fascista, da constru\u00e7\u00e3o de muros em torno do velho pesadelo da identidade nacional, da manuten\u00e7\u00e3o da segrega\u00e7\u00e3o radical entre os diferentes povos. O refugiado \u00e9 o inimigo da vez.<\/p>\n<p>E, nesse sentido, o livro de Mbembe \u00e9 uma contribui\u00e7\u00e3o basilar para compreens\u00e3o n\u00e3o apenas das \u00e1reas marginais e subalternas do mundo contempor\u00e2neo em sua rela\u00e7\u00e3o contradit\u00f3ria  e dependente que mant\u00e9m a estrutura totalizadora do capital \u2013 que, a bem da verdade, se tornaram centrais para apreender os caminhos da estrutura de domina\u00e7\u00e3o pol\u00edtica atual, gra\u00e7as a crise permanente como forma de governo \u2013 como ainda porque, num momento em que os pa\u00edses, outrora essenciais para o capitalismo, se autodestroem para manter a taxa de lucro inabal\u00e1vel, a condi\u00e7\u00e3o de vida degradada se espalha pelo globo.<\/p>\n<p>Noutras palavras: todo o mundo est\u00e1 se tornando negro! \u00c9 a condi\u00e7\u00e3o negra que se torna, aos poucos, universal. E entender o negro como um produto da explora\u00e7\u00e3o radical que engendra o modo de sociabilidade do capital \u2013 entend\u00ea-lo como uma condi\u00e7\u00e3o de subsist\u00eancia prec\u00e1ria, exist\u00eancia degradada, vida coisificada e presen\u00e7a nadificada \u2013 \u00e9 determinante para apreender a possibilidade de supera\u00e7\u00e3o do racismo que passa pela supera\u00e7\u00e3o do pr\u00f3prio sistema que o engendrou.<\/p>\n<p>A esse respeito, Mbembe diz o seguinte:<\/p>\n<p>\u201cJ\u00e1 n\u00e3o h\u00e1 trabalhadores propriamente ditos, j\u00e1 s\u00f3 existem m\u00f4nadas de trabalho. Se, ontem, o drama do sujeito era ser explorado pelo capital, hoje, a trag\u00e9dia da multid\u00e3o \u00e9 n\u00e3o poder j\u00e1 ser explorada de todo, \u00e9 ser objeto de humilha\u00e7\u00e3o numa humanidade sup\u00e9rflua, entregue ao abandono, que j\u00e1 nem \u00e9 \u00fatil ao funcionamento do capital. Tem emergido uma forma in\u00e9dita da vida ps\u00edquica apoiada na mem\u00f3ria artificial e num\u00e9rica e em modelos cognitivos provindos das neuroci\u00eancias e da neuroeconomia. N\u00e3o sendo os automatismos ps\u00edquicos e os tecnol\u00f3gicos mais do que duas faces da mesma moeda, vai-se instalando a fic\u00e7\u00e3o de um novo ser humano, \u201cempres\u00e1rio de si mesmo\u201d pl\u00e1stico e convocado a reconfigurar-se permanentemente em fun\u00e7\u00e3o dos artefatos que a \u00e9poca oferece\u201d.[2]<\/p>\n<p>Mas, como come\u00e7ar a falar de um livro t\u00e3o denso no desnudamento das rela\u00e7\u00f5es que permitiram que o termo ra\u00e7a e o termo negro fossem naturalizados como \u201csempre existentes\u201d? Certamente, muita coisa se perder\u00e1 nesse caminho. Supondo que nada seja \u201cdado\u201d como natural, exceto nossa d\u00favida, e que n\u00e3o possamos descer ou subir a nenhuma outra verdade, exceto \u00e0 verdade provis\u00f3ria de nossa sociedade: n\u00e3o \u00e9 l\u00edcito fazer a tentativa de dar centralidade a quest\u00e3o da identidade como um dos m\u00faltiplos caminhos deslumbrados pela arg\u00facia do pensador camaron\u00eas? Afinal, talvez, n\u00e3o seja apenas l\u00edcito fazer esse percurso: \u00e9 algo imposto pela consci\u00eancia daquilo que atormenta nosso movimento atual.<\/p>\n<p>Ra\u00e7a e Negro s\u00e3o partes rec\u00edprocas de uma moeda colonial cunhada para domina\u00e7\u00e3o e explora\u00e7\u00e3o radical que fundamentar\u00e1 a modernidade. Se antes da modernidade, a fic\u00e7\u00e3o da identidade era algo descart\u00e1vel para a viv\u00eancia sob \u00e9gide da Igreja; com a fundamenta\u00e7\u00e3o dos Estados Nacionais, com a cria\u00e7\u00e3o da no\u00e7\u00e3o de Sujeito impulsionado por um mundo em que Deus est\u00e1 morto, com o vazio constitutivo dos anseios de Dom Quixote e Hamlet \u2013 verdadeiros prot\u00f3tipos do sujeito moderno \u2013 a identidade se tornar\u00e1 um dado central balizado, sobretudo, pela troca de mercadorias que fundamentar\u00e3o o mundo socializado do capital.<\/p>\n<p>Desde o in\u00edcio, justifica a \u00faltima d\u00favida o fato de que \u2013 entre as interpreta\u00e7\u00f5es centrais, tanto da modernidade, da racionalidade moderna, da din\u00e2mica que impulsiona o capitalismo, assim como o universalismo que visou produzir \u2013; os termos \u201cnegro\u201d e \u201cra\u00e7a\u201d surgem como um jogo de sombras, fantasmagorias obscuras, sem as quais n\u00e3o se poder\u00e1 entender a totalidade destes termos nem o seu motor determinante: a modernidade capitalista.<\/p>\n<p>O Outro que surge a partir da identidade europeia ou, para citar G. Spivak[3], do Ocidente como Sujeito, \u00e9 um Outro que surge como um objeto amea\u00e7ador. A forma de abordagem da identidade europeia, desse modo, \u00e9 a de semelhan\u00e7a e igualdade consigo mesma, n\u00e3o de rela\u00e7\u00e3o e co-perten\u00e7a ao pr\u00f3ximo. A autofic\u00e7\u00e3o identit\u00e1ria da Europa, uma autocontempla\u00e7\u00e3o de si mesmo que enclausura a potencialidade da diverg\u00eancia, tornam hiperidentificat\u00f3rios o significado de Negro, que para Mbembe, n\u00e3o tem diferen\u00e7a com rela\u00e7\u00e3o \u00e0 ra\u00e7a.<\/p>\n<p>A apari\u00e7\u00e3o do termo Negro no dicion\u00e1rio moderno foi, assim, paralelo a um projeto de conhecimento e de governan\u00e7a que se instaura com o desenvolvimento da pr\u00f3pria modernidade. Ra\u00e7a e Negro fazem parte de um del\u00edrio manipulat\u00f3rio produzido por essa mesma modernidade. Onde quer que o del\u00edrio tenha aparecido n\u00f3s o encontramos ligado a tr\u00eas prescri\u00e7\u00f5es pol\u00edticas: explora\u00e7\u00e3o, submiss\u00e3o e um complexo de fobia forjado por uma fic\u00e7\u00e3o patol\u00f3gica de identidade.<\/p>\n<p>Mbembe busca ent\u00e3o responder como esse del\u00edrio tornou-se poss\u00edvel e quais suas manifesta\u00e7\u00f5es elementares: \u201cPrimeiro, deve-se ao fato de o Negro ser aquele (ou ainda Aquele) que vemos quando nada se v\u00ea, quando nada compreendemos e, sobretudo, quando nada queremos compreender\u201d[4]. Aqui, mais do que em outra parte, deve-se ter clareza do processo de nadifica\u00e7\u00e3o, gerado pelo processo de coisifica\u00e7\u00e3o, do negro, que foi incorporado pela modernidade. Em torno de nenhum outro significante dado ao Outro (n\u00e3o-europeu) se desenvolveu at\u00e9 agora a invisibilidade e a supersti\u00e7\u00e3o cab\u00edvel em seu substantivo, nenhuma outra individualidade, reduzida em sua humanidade, foi colocada a meio caminho entre o homem e o animal.<\/p>\n<p>O del\u00edrio seria assim um exerc\u00edcio de expurgar as a\u00e7\u00f5es passionais e encontrar uma desculpa para o preenchimento de um vazio constitutivo pr\u00f3prio das diferen\u00e7as que constituem a todos. O Negro, portanto, \u00e9 colocado nesse n\u00e3o-lugar do del\u00edrio que ora tem lastro de liberta\u00e7\u00e3o libidinal, ora de regress\u00e3o violenta. Negro e ra\u00e7a constituem assim os polos convergentes de um mesmo del\u00edrio europeu; a redu\u00e7\u00e3o do corpo e do ser vivo a uma quest\u00e3o de apar\u00eancia.<\/p>\n<p>Produto de uma m\u00e1quina social e t\u00e9cnica indissoci\u00e1vel do capitalismo, da sua emerg\u00eancia e globaliza\u00e7\u00e3o, este nome foi inventado para significar exclus\u00e3o, embrutecimento e degrada\u00e7\u00e3o, ou seja, um limite sempre conjurado e abominado. E assim foi uma consequ\u00eancia genuinamente modernizante que seus partid\u00e1rios mais convictos completassem a obra de destitui\u00e7\u00e3o de humanidade ao Outro \u2013 sempre amea\u00e7ador \u2013 encarnado agora numa redu\u00e7\u00e3o epid\u00e9rmica inventada para domina\u00e7\u00e3o e explora\u00e7\u00e3o. E cuja escala ampliada hoje indique o motivo central dos enclaves fortificados, dos muros constru\u00eddos em torno das na\u00e7\u00f5es e da insensibilidade pelo imigrante que bate \u00e0 porta. A fobia ao Outro, o alteroc\u00eddio \u2013 como diz Mbembe \u2013 \u00e9 parte constitutiva dessa moderniza\u00e7\u00e3o explorat\u00f3ria e violenta.<\/p>\n<p>O negro tornou-se o grande exemplo do Ser-Outro trabalhado pelo vazio, pela noite do mundo, por um negativo que preenche todos os poros da exist\u00eancia. Se Fanon j\u00e1 anunciava uma esp\u00e9cie de ontologia degradada imposta pela identidade colonizadora, Mbembe aprofunda a investiga\u00e7\u00e3o e revela que, tanto \u00c1frica quanto Negro, indicam um projeto inacabado, para o colonizador; uma aus\u00eancia de obra.<\/p>\n<p>Face a um mundo de no\u00e7\u00f5es modernas, que gostaria de confinar cada individualidade numa identidade estanque, Mbembe se v\u00ea obrigado a situar as fontes batismais da nossa modernidade, elencando-a em dois processos rec\u00edprocos, quais sejam: 1) o com\u00e9rcio negreiro; 2) a col\u00f4nia de planta\u00e7\u00e3o; lugar no qual o princ\u00edpio da ra\u00e7a foi instaurado sob o signo do capital. Surgida na mercadoria e em decorr\u00eancia do processo de mercantiliza\u00e7\u00e3o do mundo, a consci\u00eancia negra, na fase inicial do capitalismo, emerge da din\u00e2mica do movimento e da circula\u00e7\u00e3o. Por isso: \u201ca transnacionaliza\u00e7\u00e3o da condi\u00e7\u00e3o negra \u00e9, portanto, um momento constitutivo da modernidade e o atl\u00e2ntico \u00e9 o seu lugar de incuba\u00e7\u00e3o\u201d.[5]<\/p>\n<p>Se, tais fontes j\u00e1 determinam de maneira central a constru\u00e7\u00e3o da ra\u00e7a, por sua vez data tamb\u00e9m a forma\u00e7\u00e3o do racismo enviesado pelos apegos identit\u00e1rios de uma Europa que ia surgindo alimentando um del\u00edrio para tornar rent\u00e1vel sua explora\u00e7\u00e3o. O negro como um Outro invisibilizado, ou melhor \u2013 prefiro \u2013 nadificado, \u00e9 a forma central de dinamizar o processo de mercantiliza\u00e7\u00e3o do mundo e da vida. Este Outro que n\u00e3o \u00e9 nada, um nada que \u00e9 \u2013 capaz ainda de transformar mat\u00e9ria inanimada em riqueza e ser ele mesmo mercadoria \u2013 tem de sa\u00edda seu processo, de tornar-se um Ser, barrado. N\u00e3o \u00e0 toa, Mbembe afirma: \u201co que chamamos de \u2018estado de ra\u00e7a\u2019 corresponde, assim o cremos, a um estado de degrada\u00e7\u00e3o de natureza ontol\u00f3gica\u201d.[6]<\/p>\n<p>Resulta o fato de que a maior parte daquilo que formou e codificou o indiv\u00edduo como negro est\u00e1 relacionado com o processo de advento do mundo da mercadoria e desde ent\u00e3o \u201co negro n\u00e3o existe enquanto tal. \u00c9 constantemente produzido. Produzir o negro \u00e9 produzir um v\u00ednculo social de submiss\u00e3o e um corpo de explora\u00e7\u00e3o\u201d[7]. N\u00e3o sendo um ser, um sujeito, o negro tem sua humanidade negada, e nos processos sociais seu corpo \u00e9 um corpo de exclus\u00e3o marcado como alvo preferido do Estado.<\/p>\n<p>\u00c9 desse lugar da exclus\u00e3o, todavia, que um grito pode ser lan\u00e7ado, que uma opera\u00e7\u00e3o de demarca\u00e7\u00e3o da individualidade pode brotar e universalizar-se, e se a \u201cra\u00e7a \u00e9 um aqu\u00e9m e um al\u00e9m do ser\u201d, como ali\u00e1s diz Mbembe, pode significar que o significante \u201cnegro\u201d \u00e9 prenhe de uma refunda\u00e7\u00e3o da pr\u00f3pria no\u00e7\u00e3o de ser. O nada que vem-a-ser. Gra\u00e7as a sua fantasmagoria, sua presen\u00e7a na noite, sua nega\u00e7\u00e3o como fundamento, sua posi\u00e7\u00e3o de diferen\u00e7a das diferen\u00e7as, Negro traz consigo o Novo \u2013 uma fantasmagoria amea\u00e7adora que pode desencadear uma transforma\u00e7\u00e3o profunda.<\/p>\n<p>Sendo assim, esta fobia do negro, esse del\u00edrio manipulat\u00f3rio que coloca o negro como amea\u00e7ador, e em constante amea\u00e7a, \u00e9 encarregado de guiar o moderno funcionamento do Estado; garantir a manuten\u00e7\u00e3o de uma viol\u00eancia controlada voltada para um corpo excedente \u00e0 moderniza\u00e7\u00e3o \u2013 o corpo negro. A forma estatal de reprodu\u00e7\u00e3o do capital que, em certos limites e condi\u00e7\u00f5es, passa pelo racismo para organizar e estruturar as formas de seu controle atrav\u00e9s do monop\u00f3lio da viol\u00eancia, portanto, \u00e9 normatizada e normalizada. Nessas limita\u00e7\u00f5es necropol\u00edticas, infelizmente, torna-se comum ver um negro sendo assassinado pelo Estado.<\/p>\n<p>Das contradi\u00e7\u00f5es erguidas pela viol\u00eancia da estrutura\u00e7\u00e3o da ra\u00e7a, pelo controle biopol\u00edtico eivado de racismo, Mbembe traz \u00e0 tona a quest\u00e3o da pr\u00f3pria descoberta do negro enquanto negro. Da\u00ed que nesse ponto temos uma quest\u00e3o important\u00edssima para tratar: \u201co ato de identifica\u00e7\u00e3o \u00e9 igualmente uma afirma\u00e7\u00e3o de exist\u00eancia\u201d[8]. Se este negro \u00e9 nadificado, se sua presen\u00e7a \u00e9 invisibilizada, se sua voz \u00e9 silenciada, o ato de descobrir-se e falar: Eu sou um negro!, \u00e9 um ato de afirmar a exist\u00eancia e sua resist\u00eancia. N\u00e3o se trata de um lugar de fala, mas de um n\u00e3o-lugar em que a fala d\u00e1 corpo a uma pol\u00edtica encarnada no n\u00e3o-ser \u2013 com sua potencialidade de vir-a-ser que resulta no Novo \u2013, isto \u00e9, em qualquer um que viva a condi\u00e7\u00e3o do negro e com ela se solidarize.<\/p>\n<p>Com um pensamento dial\u00e9tico atilado, o pensador camaron\u00eas joga no telhado os processos de sofrimento e supera\u00e7\u00e3o da condi\u00e7\u00e3o de nadifica\u00e7\u00e3o na qual o negro, em sua redu\u00e7\u00e3o epid\u00e9rmica, \u00e9 lan\u00e7ado. \u201cA cor negra n\u00e3o tem sentido. S\u00f3 existe por refer\u00eancia a um poder que a inventa, uma infraestrutura que a suporta e a contrasta com outras cores e, por fim, num mundo que a designa e a axiomatiza\u201d.[9]<\/p>\n<p>Retomando alguns pressupostos de Fanon \u2013 dos quais n\u00e3o poderei falar aqui \u2013 Mbembe demonstra como a implos\u00e3o do pr\u00f3prio mundo simb\u00f3lico, onde estas diferen\u00e7as foram engendradas para manipular e explorar os corpos, \u00e9 o que possibilitaria abrir caminho a uma outra imagina\u00e7\u00e3o de comunidade universal. Acontece que a redu\u00e7\u00e3o ao significante negro produz outro significante que visa destruir o motor no qual este significante \u00e9 gerado. A afirma\u00e7\u00e3o da exist\u00eancia \u00e9 um pressuposto da luta que se produzir\u00e1. Assim, ao afirmar-se negro est\u00e1 aberto o caminho para afirmar que o mundo \u00e9 plural, \u201cmilitar pela sua abertura \u00e9 dizer que a Europa n\u00e3o \u00e9 todo o mundo, mas apenas parte dele\u201d, \u00e9 ultrapassar o reducionismo europeu e reconduzir a no\u00e7\u00e3o de universal \u00e0s suas pr\u00f3prias dimens\u00f5es reabilitando a singularidade e a diferen\u00e7a! Mas, para tanto, \u00e9 preciso destruir o mundo no qual a manuten\u00e7\u00e3o da fic\u00e7\u00e3o \u201ccor\u201d seja equivalente a manuten\u00e7\u00e3o da exclus\u00e3o e do racismo, noutros termos, \u00e9 preciso destruir o mundo do capital.<\/p>\n<p>Vejamos que Mbembe, na linha de Fanon e Cesaire[10], n\u00e3o abandona, em nenhum momento, a no\u00e7\u00e3o de universalidade, radicaliza-a para um sentido em que o universal n\u00e3o seja a oblitera\u00e7\u00e3o das diferen\u00e7as, mas o lugar das multiplicidades: \u201cum mundo em que o que partilhamos em conjunto sejam as diferen\u00e7as\u201d[11]. Um mundo em que saibamos que o que temos em comum s\u00e3o as diferen\u00e7as que nos constitui. S\u00f3 assim poder\u00edamos realmente nos aproximar daquela concep\u00e7\u00e3o de identidade como uma auto-inven\u00e7\u00e3o incessante do nosso Eu e nos lan\u00e7ar na constru\u00e7\u00e3o do comum.<\/p>\n<p>A proclama\u00e7\u00e3o da diferen\u00e7a \u00e9 apenas um momento de um projeto mais vasto \u2013 de um mundo que vir\u00e1, de um mundo antes de n\u00f3s, no qual o destino \u00e9 universal, um mundo livre do peso da ra\u00e7a e do ressentimento e do desejo de vingan\u00e7a que qualquer situa\u00e7\u00e3o de racismo convoca\u201d[12]<\/p>\n<p>Apesar de j\u00e1 ter extrapolado o limite de uma resenha, encerro dizendo emocionada o seguinte: o livro de Mbembe \u00e9 um mergulho na constru\u00e7\u00e3o de um mundo que agora necrosa e precisa urgentemente ser ultrapassado, \u00e9 um voo ao atl\u00e2ntico onde o \u201ctempero do mar foi l\u00e1grima de preto\u201d, mas \u00e9 sobretudo, a constru\u00e7\u00e3o te\u00f3rica de uma luta antirracista que produz vida. E vida comum. Tudo o que eu disse at\u00e9 aqui n\u00e3o \u00e9 nada frente ao que o livro expressa, n\u00e3o \u00e9 nada diante do poder de s\u00edntese realizado numa das obras mais importantes desse s\u00e9culo. \u00c9 tarefa urgente que o leiamos, o discutamos e o critiquemos!<\/p>\n<p>Por fim, sabemos quem e o que matou Marielle!<\/p>\n<p>[1] MBEMBE, A. A Cr\u00edtica da Raz\u00e3o Negra. Antigona: Lisboa, Portugal, 2014. (A autora da resenha est\u00e1 \u201cdura\u201d para comprar a bonita e bem traduzida vers\u00e3o da N-1)<\/p>\n<p>[2] MBEMBE, 2014, p.14<\/p>\n<p>[3] SPIVAK, G. Can the Subaltern Speak? In Cary Nelson and Lawrence Grossberg (eds) Marxism and the Interpretation of Culture. London: Macmillan, 1988.<\/p>\n<p>[4] MBEMBE, 2014, p. 11<\/p>\n<p>[5] MBEMBE, 2014, p.34<\/p>\n<p>[6] MBEMBE, 2014, p.39<\/p>\n<p>[7] MBEMBE, 2014, p.40<\/p>\n<p>[8] MBEMBE, 2014, p.255<\/p>\n<p>[9] MBEMBE, 2014, p.258<\/p>\n<p>[10] \u00c9 importante dizer que remontando a trajet\u00f3ria de Garvey, Mbembe marca uma cr\u00edtica central as limita\u00e7\u00f5es m\u00edsticas e nacionalistas deste.<\/p>\n<p>[11] MBEMBE, 2014, p.297<\/p>\n<p>[12] MBEMBE, 2014, p.306<\/p>\n<p><a href=\"https:\/\/lavrapalavra.com\/2018\/12\/18\/critica-da-critica-da-razao-negra\/\">Cr\u00edtica da Cr\u00edtica da Raz\u00e3o&nbsp;Negra<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/21722\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[50],"tags":[226],"class_list":["post-21722","post","type-post","status-publish","format-standard","hentry","category-c61-cultura-revolucionaria","tag-4b"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-5Em","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/21722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=21722"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/21722\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=21722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=21722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=21722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}