{"id":22308,"date":"2019-02-11T22:59:25","date_gmt":"2019-02-12T00:59:25","guid":{"rendered":"https:\/\/pcb.org.br\/portal2\/?p=22308"},"modified":"2019-02-11T22:59:29","modified_gmt":"2019-02-12T00:59:29","slug":"meninos-do-flamengo-mais-um-crime-provocado-pela-ganancia","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/22308","title":{"rendered":"Meninos do Flamengo: mais um crime provocado pela gan\u00e2ncia"},"content":{"rendered":"\n<img decoding=\"async\" class=\"imagem\" title=\"imagem\"  alt=\"imagem\"  src=\"https:\/\/i2.wp.com\/jornalistaslivres.org\/wp-content\/uploads\/2019\/02\/0.jpg?w=620&#038;ssl=1\"\/><!--more-->N\u00c3O FOI FATALIDADE, FOI MAIS UM CRIME PROVOCADO PELA GAN\u00c2NCIA DE QUEM TEM MUITO, CONTRA QUEM QUASE NADA TEM<\/p><p>\nFoi isso que matou os meninos no alojamento do Flamengo no Rio de Janeiro.<\/p><p>\nINTERSINDICAL &#8211; INSTRUMENTO DE LUTA E ORGANIZA\u00c7\u00c3O DA CLASSE TRABALHADORA<\/p><p>\nOs meninos pobres foram jogados num container cheio de gambiarras el\u00e9tricas enquanto muito pr\u00f3ximo dali o Flamengo construiu um luxuoso alojamento em que os pobres meninos, ricos de talento sonhavam em entrar.\n<\/p><p>\nMeninos de 14 e 15, 16 anos foram mortos numa trag\u00e9dia que poderia ter sido evitada, n\u00e3o fosse o esporte mais uma mercadoria rent\u00e1vel para o capital. O esporte foi transformado em mais uma fonte de riqueza, onde meninos que come\u00e7am a arte de jogar nos campinhos de terra, nos campinhos de v\u00e1rzea nos grot\u00f5es da pobreza, s\u00e3o transformados em mercadoria rent\u00e1vel para a ind\u00fastria do futebol e seus neg\u00f3cios.\n<\/p><p>\nA maioria dos meninos que morreram no Ninho do urubu, alojamento do Flamengo no Rio de Janeiro vinha de v\u00e1rias regi\u00f5es do pa\u00eds e al\u00e9m de buscar a realiza\u00e7\u00e3o de um sonho, buscavam uma vida melhor n\u00e3o s\u00f3 para si, mas para os seus.\n<\/p><p>\nS\u00f3 quem vive a dura realidade da maioria da popula\u00e7\u00e3o trabalhadora sabe o que significa para um menino ter tanta alegria em poder com seu treinamento\/trabalho pagar o aluguel de sua av\u00f3. Isso n\u00e3o significa nada para quem se farta nas negociatas do mundo dos neg\u00f3cios do futebol.\n<\/p><p>\nO local onde estavam os meninos nem constava no projeto do Flamengo aprovado pela \u00e1rea de licenciamento e, nos \u00faltimos anos, foram mais de 30 autos de infra\u00e7\u00e3o, al\u00e9m de pedidos de interdi\u00e7\u00e3o. O alvar\u00e1 de funcionamento n\u00e3o foi concedido, pois a dire\u00e7\u00e3o do Flamengo n\u00e3o apresentou at\u00e9 hoje o certificado do Corpo de Bombeiros para o funcionamento.\n<\/p><p>\nDescaso no cuidado com os meninos e aten\u00e7\u00e3o nos neg\u00f3cios fizeram do Flamengo um dos times mais ricos do pa\u00eds faturando mais de R$600 milh\u00f5es at\u00e9 o final do segundo semestre de 2018.\n<\/p><p>\nPara o Capital, um jogador de futebol \u00e9 mais uma mercadoria a ser vendida. Os meninos, enquanto est\u00e3o na categoria de base, recebem pouco mais de um sal\u00e1rio m\u00ednimo e vivem na maioria das vezes em condi\u00e7\u00f5es prec\u00e1rias como as que se escancararam no Centro de Treinamento do Flamengo. Depois ser\u00e3o \u201cvendidos\u201d pelos Clubes em cifras milion\u00e1rias, numa carreira curta que vai garantir longevidade para os lucros da ind\u00fastria do esporte.\n<\/p><p>\nAssistir uma partida de futebol, torcer por um time est\u00e3o entre as alegrias das poucas horas de descanso da classe trabalhadora e tamb\u00e9m esses espa\u00e7os s\u00e3o transformados em mercadoria pelo Capital.\n<\/p><p>\nOs meninos que estavam buscando o sonho poss\u00edvel nessa sociedade dividida em classes, foram mortos pela neglig\u00eancia de quem lucra com o esporte e pela conviv\u00eancia dos governos de plant\u00e3o, enxergar isso \u00e9 o primeiro passo para transformar mais essa dor em revolta e movimento.\n<\/p><p>\nDuas semanas de trag\u00e9dias provocadas pelo Capital: A Vale matou em Brumadinho, a ind\u00fastria do esporte matou os meninos no CT do Flamengo, o descaso e a repress\u00e3o estatal mataram no Rio de Janeiro nas enchentes e na invas\u00e3o dos morros. Todas essas mortes n\u00e3o s\u00e3o fatalidades ou obras do destino, todas essas mortes seriam evitadas se a escolha fosse a vida e n\u00e3o o lucro.\n<\/p><p>\nN\u00e3o vamos esquecer e nem perdoar, est\u00e1 mais do que na hora de vingar nossos mortos fortalecendo a luta do conjunto daqueles que sofrem no dia a dia a opress\u00e3o e a explora\u00e7\u00e3o.\n<\/p><p>\nhttp:\/\/www.intersindical.org.br\/2019\/02\/11\/nao-foi-fatalidade-foi-mais-um-crime-provocado-pela-ganancia-de-quem-tem-muito-contra-quem-quase-nada-tem\/\n","protected":false},"excerpt":{"rendered":"<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/22308\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[7],"tags":[226],"class_list":["post-22308","post","type-post","status-publish","format-standard","hentry","category-s8-brasil","tag-4b"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-5NO","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/22308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=22308"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/22308\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=22308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=22308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=22308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}