{"id":23276,"date":"2019-06-03T21:33:01","date_gmt":"2019-06-04T00:33:01","guid":{"rendered":"https:\/\/pcb.org.br\/portal2\/?p=23276"},"modified":"2019-06-05T22:39:14","modified_gmt":"2019-06-06T01:39:14","slug":"educacao-ciencia-e-tecnologia-para-que-projeto-de-nacao","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/23276","title":{"rendered":"Educa\u00e7\u00e3o, ci\u00eancia e tecnologia para que projeto de na\u00e7\u00e3o?"},"content":{"rendered":"<p><img decoding=\"async\" class=\"imagem\" title=\"imagem\" src=\"https:\/\/i0.wp.com\/lh3.googleusercontent.com\/XJl8oqukpjfoQxcPFFe-VII1qXKS8Lo5qEypbUUOA09Qabp0VwY6GeJNLPIs8W4T5LY_Anp7wmGSop1ShMp8Fh-93EYAMrcOdgjOH1tX8IKqsyll1YNl1wl9AGW2pGvCHSjcnzhpg7CKKYGVkMmcGvwz0We40tfNXe9tbwbn-GFu8oAWS7Fs-XgjDYt_MrkfBgD3ZggZVAxJzY8VghJUO1hiG4GXj1xrkOMjF0KAt3v59Yji_MswJOGdmot9zLtmVWLv92HSjhNYcrBOqIQxp3LnSVbJa7B_3cezz-5Qvk-0shHilsK1x6Qs6GrjEyo8iMVkm4zfbayevgBJs4um6fuE0CVLZUpPSQDmOnk8exknTRky0EfX49zJOYJ9UaepwztWwB79tm5Ir9jo6L33EfQmgt67lqOeoRoMfLN9eMT_8McyekOyuZPiBcDO3HxEHGb6fB9AlFrrQBULn3NzB4VehxB1icf00fC-VPEANQ-xoW-brqnopTWzASwzgJ89ZUdII49sO5kHOh9XwwwUz0MqPOMzKf5uRQB0JqRf6HOqW8gPL15iXHCx5BJa30AXYqUSOaQIdFaQhlcwbs97LXgQoyTRRno9S7vIlafQ4Chu1xEUPhT8Mst_G4JCc29fSq1IxUzfNBgoVvhlgJGW62jFR-J_zi7z=w720-h716-no\" alt=\"imagem\" \/><!--more-->Allefy Matheus, militante da UJC-PI<\/p>\n<p>Anteriormente, discutimos os cortes na educa\u00e7\u00e3o e outros ataques no contexto da austeridade fiscal imposta pelas classes propriet\u00e1rias (leia-se, parasit\u00e1rias) no Brasil [1]. Pretendemos, aqui, levar o debate um pouco adiante: trata-se de discutir n\u00e3o apenas a situa\u00e7\u00e3o conjuntural da educa\u00e7\u00e3o, da ci\u00eancia e da tecnologia, mas sim sua tend\u00eancia ao longo do padr\u00e3o de acumula\u00e7\u00e3o capitalista que se reproduz em nosso pa\u00eds desde os anos 90.<\/p>\n<p>Primeiramente, adiantamos que o leitor ou leitora pode achar materiais com problematiza\u00e7\u00f5es similares j\u00e1 publicados; veja-se, por exemplo, o artigo dispon\u00edvel em: http:\/\/ujc.org.br\/a-destruicao-da-ciencia-e-tecnologia-no-brasil-e-a-necessidade-de-um-projeto-de-educacao-popular-e-socialista\/.<\/p>\n<p>Cabe-nos, ent\u00e3o, prosseguir com a discuss\u00e3o.<\/p>\n<p>O que significa discutir a quest\u00e3o da educa\u00e7\u00e3o, da ci\u00eancia e da tecnologia em termos de um \u2018\u2019projeto de na\u00e7\u00e3o\u2019\u2019? Trata-se de debat\u00ea-las como elementos de um projeto amplo de rela\u00e7\u00f5es e institui\u00e7\u00f5es sociais no pa\u00eds, e pondo \u00e0 mesa quest\u00f5es fundamentais como que educa\u00e7\u00e3o, ci\u00eancia e tecnologia s\u00e3o essas, como s\u00e3o elas? Que finalidade t\u00eam elas? A quem, consequentemente, elas beneficiam? Etc.<\/p>\n<p>Desde j\u00e1, portanto, \u00e9 preciso afirmar que a produ\u00e7\u00e3o nacional de educa\u00e7\u00e3o, ci\u00eancia e tecnologia se d\u00e1 sob profunda hegemonia burguesa, inclusive naqueles centros universit\u00e1rios aclamados como estando \u2018\u2019os melhores entre os de toda a Am\u00e9rica Latina\u2019\u2019 [2]. \u00c9 produ\u00e7\u00e3o de conhecimento a servi\u00e7o do capital, dedicando-se \u00e0 gera\u00e7\u00e3o de m\u00e3o de obra e entregando para a \u2018\u2019iniciativa privada\u2019\u2019 os frutos de pesquisas cient\u00edficas que poderiam ser de extremo benef\u00edcio social, mas se convertem em fonte de lucros de monop\u00f3lio.<\/p>\n<p>Pior, talvez, \u00e9 que mesmo essa privatiza\u00e7\u00e3o dos benef\u00edcios tornados poss\u00edveis pela produ\u00e7\u00e3o social de conhecimento n\u00e3o se d\u00e1 aperfei\u00e7oando a estrutura produtiva nacional de forma a aumentar a produtividade social do trabalho aqui, pelo contr\u00e1rio: os pr\u00f3prios economistas burgueses, de diversas \u2018\u2019escolas diferentes\u2019\u2019, alardeiam a estagna\u00e7\u00e3o da produtividade do trabalho no Brasil [3].<\/p>\n<p>Por que isso acontece? Em concord\u00e2ncia com os estudos marxistas que buscam compreender a condi\u00e7\u00e3o de subdesenvolvimento e depend\u00eancia que caracteriza o Brasil (e todos os outros pa\u00edses latino-americanos, com exce\u00e7\u00e3o de Cuba, bem como pa\u00edses perif\u00e9ricos de outros continentes), cremos em uma conex\u00e3o fundamental entre a situa\u00e7\u00e3o da ci\u00eancia, da tecnologia e da educa\u00e7\u00e3o e o padr\u00e3o de reprodu\u00e7\u00e3o do capital aqui nas \u00faltimas d\u00e9cadas. Mais claramente: a forma concreta de reprodu\u00e7\u00e3o ampliada do capital (e acumula\u00e7\u00e3o de riqueza privada) em nosso territ\u00f3rio nacional n\u00e3o se preocupa em promover a educa\u00e7\u00e3o que corresponda \u00e0s necessidades da vasta maioria da popula\u00e7\u00e3o, bem como de uma produ\u00e7\u00e3o nacional aut\u00f4noma de conhecimento cient\u00edfico e tecnol\u00f3gico.<\/p>\n<p>A prova disso \u00e9 a crescente import\u00e2ncia do agrobusiness &#8212; um nome cinicamente pomposo para a acumula\u00e7\u00e3o capitalista baseada na renda da terra, envolvendo profunda viol\u00eancia contra os trabalhadores e os povos do campo &#8212; e, por outro lado, a decrescente import\u00e2ncia da ind\u00fastria na atividade econ\u00f4mica (da qual o PIB \u00e9 um indicador razo\u00e1vel), bem como os crescentes lucros do setor banc\u00e1rio, mesmo em meio a uma crise profunda &#8212; ou seria como uma das causas da perman\u00eancia da crise? [5]<\/p>\n<p>Ali\u00e1s, para sermos justos, mesmo a \u2018\u2019produ\u00e7\u00e3o industrial nacional\u2019\u2019 tem, conforme estudo recentemente publicado, enorme coeficiente de importa\u00e7\u00e3o em seus insumos [6], o que significa, dentre outras coisas, reduzida capacidade, para a ind\u00fastria, de puxar gera\u00e7\u00e3o de emprego e renda para os trabalhadores brasileiros, bem como de aumentar a produtividade social do trabalho.<\/p>\n<p>Sintetizando, os grandes eixos de acumula\u00e7\u00e3o capitalista no Brasil das \u00faltimas d\u00e9cadas &#8212; o rentismo agromineiro, o rentismo financeiro, a produ\u00e7\u00e3o industrial e, poder-se-ia citar tamb\u00e9m, o com\u00e9rcio &#8212; dispensam uma produ\u00e7\u00e3o nacional aut\u00f4noma de conhecimento cient\u00edfico tecnol\u00f3gico, seja por sua pr\u00f3pria natureza, seja porque, quando lhes \u00e9 de interesse a obten\u00e7\u00e3o de novas m\u00e1quinas e ferramentas mais eficientes ou novos processos produtivos, eles recorrem \u00e0 produ\u00e7\u00e3o estrangeira, isto \u00e9, \u00e0s importa\u00e7\u00f5es &#8212; tipicamente de pa\u00edses centrais.<\/p>\n<p>A conclus\u00e3o inevit\u00e1vel, para citar o camarada Jones Manoel em artigo mencionado acima, \u00e9 que \u2018\u2019s\u00f3 com uma perspectiva estrat\u00e9gica renovada e ligada aos interesses e lutas das classes populares \u00e9 que a problem\u00e1tica da produ\u00e7\u00e3o de ci\u00eancia e tecnologia poder\u00e1 ser devidamente enfrentada no pa\u00eds no processo de constru\u00e7\u00e3o socialista superando a depend\u00eancia e o subdesenvolvimento. Nesse enfrentamento, desde j\u00e1, \u00e9 necess\u00e1rio ficar claro que a classe dominante, em seus mais diversos setores, nada tem a contribuir, mas s\u00e3o advers\u00e1rios a serem derrotados.\u2019\u2019<\/p>\n<p>[1] https:\/\/pcb.org.br\/portal2\/23060\/um-projeto-de-destruicao-nacional-e-a-necessaria-mudanca-de-rumo\/<\/p>\n<p>[2] http:\/\/ujc.org.br\/as-universidades-brasileiras-sao-as-melhores-da-america-latina-melhores-para-quem\/<\/p>\n<p>[3] Veja-se, por exemplo, os trabalhos de economistas \u2018\u2019novo-desenvolvimentistas\u2019\u2019 como Luis Carlos Bresser-Pereira e Paulo Gala, e \u2018\u2019ortodoxos\u2019\u2019 como Pedro Cavalcanti Ferreira.<\/p>\n<p>[4] https:\/\/istoe.com.br\/estagnada-industria-tem-a-menor-fatia-do-pib-desde-o-final-dos-anos-40\/<\/p>\n<p>[5] https:\/\/www.correiobraziliense.com.br\/app\/noticia\/economia\/2018\/06\/18\/internas_economia,689107\/lucro-dos-bancos-cresce-em-2018-apesar-da-crise.shtml<\/p>\n<p>[6] https:\/\/iedi.org.br\/cartas\/carta_iedi_n_929.html<\/p>\n","protected":false},"excerpt":{"rendered":"<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/23276\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[60],"tags":[247,219],"class_list":["post-23276","post","type-post","status-publish","format-standard","hentry","category-c71-educacao","tag-jd","tag-manchete"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-63q","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/23276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=23276"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/23276\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=23276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=23276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=23276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}