{"id":23580,"date":"2019-07-15T17:58:55","date_gmt":"2019-07-15T20:58:55","guid":{"rendered":"https:\/\/pcb.org.br\/portal2\/?p=23580"},"modified":"2019-07-15T17:58:55","modified_gmt":"2019-07-15T20:58:55","slug":"rejeitar-o-acordo-de-livre-comercio-ue-mercosul","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/23580","title":{"rendered":"Rejeitar o Acordo de Livre Com\u00e9rcio UE-Mercosul"},"content":{"rendered":"<p><img decoding=\"async\" class=\"imagem\" title=\"imagem\" src=\"https:\/\/i0.wp.com\/lh3.googleusercontent.com\/rr6k22Mq0l91tCAolnMtYLOyZK_PBDVdjxG5Q76VA7BImXVbj2neN-EOrxZs_X6Yxb3x8hX-aKW2-Vm156CEyLfJh9se2wAA-B3TO67N6orYCVGTqr4CWdaVNinufBOWKhQIuB6SY-H9h9Df72uxrq2GVji-UInFMples9KWREV4wtP4ZERK_FODDQ4fWjb-Xte8yKtPBDQBHwBIzKVQZe1y61cYdM1RsfpWTPneoMUkH2ZiPkrMoiII0uQseEUcck4yw5dBJmNh1uBiGvbbiWzqQ4npH5GOcJMTD9mWybQcKcxYCddInCMxJrAP84pi7eRA8j_-tDPZg_bEDPGPA5dPbXRbgq_y7PfdUyyZsLSkilkoS0vwveZwcgqVUT5g7n0ELjDvQ45d1Inaax3FIADgGuK_hKJRZaogKMITb816oyTF25ntlYCc5EWoajFzQ1T27eI9i3PypnjGEagC_SiCPxjYz2QrV4A9D2fnk13akJ7Useh2d1lu8USVa7JNOy1mvsqh8_mC9XwYJpHixV9hlP0qZallYkRZsc4N6h3mzZfhdvPUhToCv02zPKVThOzpVhuaLaT8YbC_t9q7NlyCjNi4l73xPwYN0OxkINxLJ0cVzqHSzq9Ww2QgJtv-sBJ2tX2bM1og2xE6gYuRPBeF32Z4-IOr=w419-h228-no\" alt=\"imagem\" \/><!--more-->Comunicado conjunto do Partido Comunista da B\u00e9lgica e das se\u00e7\u00f5es do Partido Comunista Franc\u00eas de Saint-Quentin, Gauchy e Val d&#8217;Origny na sequ\u00eancia das suas a\u00e7\u00f5es paralelas contra a &#8220;liberaliza\u00e7\u00e3o&#8221; do mercado europeu do a\u00e7\u00facar.<\/p>\n<p>11 de Julho de 2019<\/p>\n<p>No final de junho, foi assinado um importante acordo de livre com\u00e9rcio entre os pa\u00edses do Mercosul (Brasil, Uruguai, Paraguai e Argentina) e a Uni\u00e3o Europeia. Ter\u00e1 de ser ratificado em cada pa\u00eds da UE nos pr\u00f3ximos meses. Na B\u00e9lgica, tal como em Fran\u00e7a, faremos tudo o que estiver ao nosso alcance para nos opormos.<\/p>\n<p>O acordo n\u00e3o \u00e9 uma boa not\u00edcia para a classe trabalhadora, para os trabalhadores agr\u00edcolas e os camponeses de ambos os lados do Atl\u00e2ntico. &#8220;Este acordo \u00e9 um disparate social, energ\u00e9tico e ecol\u00f3gico&#8221;. Esta m\u00e1 not\u00edcia deve impulsionar o fortalecimento do internacionalismo prolet\u00e1rio, que requer a organiza\u00e7\u00e3o de nossa classe e em nenhum caso a defesa das &#8220;regras europeias&#8221; que servem ao grande capital europeu e seus objetivos imperialistas.<\/p>\n<p>Este acordo est\u00e1 em perfeita sintonia com a cria\u00e7\u00e3o do mercado europeu, que contribuiu para a concentra\u00e7\u00e3o da terra nas m\u00e3os dos propriet\u00e1rios e\/ou especuladores, o refor\u00e7o da agricultura intensiva e a cria\u00e7\u00e3o de monop\u00f3lios nos setores agroindustrial e agroalimentar. Os pa\u00edses do Mercosul poder\u00e3o exportar para a Europa, sem direitos aduaneiros, at\u00e9 99 000 toneladas de carne bovina, 100 000 toneladas de aves dom\u00e9sticas e 180 000 toneladas de a\u00e7\u00facar por ano. De acordo com os agricultores, as cotas de carne que seriam atribu\u00eddas ao Brasil, Argentina, Paraguai e Uruguai seriam essencialmente pe\u00e7as de alto valor agregado, como costela e contrafil\u00e9. Trata-se claramente de uma morte planejada do setor pecu\u00e1rio na Europa. Isto em troca da abertura do mercado do Mercosul aos autom\u00f3veis, produtos qu\u00edmicos e medicamentos. Em suma, um acordo quase que em benef\u00edcio dos imperialistas, nomeadamente dos alem\u00e3es e dos franceses.<\/p>\n<p>Este acordo complementa e aprofunda a liberaliza\u00e7\u00e3o dos mercados agr\u00edcolas europeus, em especial do a\u00e7\u00facar, ap\u00f3s o termo das quotas de produ\u00e7\u00e3o por pa\u00eds em 1 de outubro de 2017. A amea\u00e7a \u00e9 direta para o pr\u00f3prio futuro do setor da beterraba, nomeadamente na B\u00e9lgica e no Norte de Fran\u00e7a, que est\u00e1 sujeito \u00e0 concorr\u00eancia da produ\u00e7\u00e3o e da transforma\u00e7\u00e3o a custos muito baixos, especialmente no Brasil e \u00e0 especula\u00e7\u00e3o sobre os pre\u00e7os mundiais. Os trabalhadores j\u00e1 perderam ou v\u00e3o perder seus empregos, principalmente na multinacional Tereos em Aalst\/Alost ou na regi\u00e3o de Saint-Quentin, enquanto a Tereos, que investe fortemente no Brasil, viu seus lucros aumentarem em 213 milh\u00f5es de euros entre 2007 e 2017. As refinarias de Tirlemonto, propriedade da multinacional S\u00fczucker, que est\u00e1 fechando cinco unidades de produ\u00e7\u00e3o de a\u00e7\u00facar na Alemanha e na Fran\u00e7a, incluindo a de Eppeville, na Picardia, empregam 600 trabalhadores. A multinacional se recusa a revender os s\u00edtios porque quer reduzir a oferta para manter seus lucros. Localizado no Congo, Austr\u00e1lia e Holanda, o grupo multinacional Finasucre, cuja filial belga Iscal Sucre SA (215 empregados e 2664 agricultores) obteve 12 milh\u00f5es de euros em lucros em 2018, tamb\u00e9m tem interesses na produ\u00e7\u00e3o de a\u00e7\u00facar no exterior.<\/p>\n<p>A cria\u00e7\u00e3o desta grande zona de com\u00e9rcio livre n\u00e3o se destina a melhorar a oferta em circunst\u00e2ncia alguma, mas sim a concentrar os monop\u00f3lios que ir\u00e3o atacar as condi\u00e7\u00f5es de trabalho, liquidar o emprego e baixar os padr\u00f5es de sa\u00fade e seguran\u00e7a, e contribuir ativamente para a destrui\u00e7\u00e3o do nosso ambiente. O pior \u00e9 previs\u00edvel: os grupos capitalistas europeus v\u00e3o importar a\u00e7\u00facar das suas unidades de produ\u00e7\u00e3o no Brasil para competir com as suas instala\u00e7\u00f5es europeias e acelerar o seu fechamento! Neste imenso Brasil, no entanto, a autossufici\u00eancia alimentar e a erradica\u00e7\u00e3o da desnutri\u00e7\u00e3o est\u00e3o longe de ser alcan\u00e7adas!<\/p>\n<p>Para responder a este rolo compressor do capital, \u00e9 necess\u00e1rio intensificar a luta contra a Uni\u00e3o Europeia, fortalecer nossos la\u00e7os fraternos e solid\u00e1rios com os trabalhadores de todos os pa\u00edses em luta da Am\u00e9rica Latina e da Europa, mas sobretudo ampliar o trabalho de unifica\u00e7\u00e3o dos trabalhadores agr\u00edcolas com a classe trabalhadora. Estamos agora promovendo campanhas contra a ratifica\u00e7\u00e3o na B\u00e9lgica e na Fran\u00e7a do acordo UE-Mercosul. Recusamo-nos a entrar nas diverg\u00eancias provis\u00f3rias expostas entre os representantes deste ou daquele ramo capitalista, no debate entre com\u00e9rcio livre ou estrat\u00e9gias protecionistas, que competem, se complementam e se sucedem no interesse dos capitalistas. A nossa \u00fanica refer\u00eancia \u00e9 a resposta \u00e0s necessidades dos povos pelos povos e a coopera\u00e7\u00e3o mutuamente ben\u00e9fica entre eles.<\/p>\n<p>Esta uni\u00e3o de prolet\u00e1rios de todos os pa\u00edses \u00e9 necess\u00e1ria para derrubar o sistema capitalista, a fim de preparar o advento do socialismo, que s\u00f3 ele pode satisfazer as necessidades dos trabalhadores e impor a substitui\u00e7\u00e3o dos acordos de livre com\u00e9rcio por acordos de coopera\u00e7\u00e3o fraterna entre os povos.<\/p>\n<p>Tradu\u00e7\u00e3o: Partido Comunista Brasileiro (PCB)<\/p>\n<p>Fonte:<\/p>\n<p>http:\/\/www.particommuniste.be\/index.php\/international\/563-mobiliser-pour-repousser-l-accord-de-libre-echange-entre-l-ue-et-le-mercosur<\/p>\n","protected":false},"excerpt":{"rendered":"<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/23580\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[8,18],"tags":[234],"class_list":["post-23580","post","type-post","status-publish","format-standard","hentry","category-america-latina","category-s22-europa","tag-6b"],"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p659gw-68k","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/23580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=23580"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/23580\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=23580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=23580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=23580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}