{"id":23790,"date":"2019-08-17T04:09:01","date_gmt":"2019-08-17T07:09:01","guid":{"rendered":"https:\/\/pcb.org.br\/portal2\/?p=23790"},"modified":"2019-08-17T04:09:01","modified_gmt":"2019-08-17T07:09:01","slug":"venezuela-uma-nova-fase-do-ataque-imperialista","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/23790","title":{"rendered":"Venezuela: uma nova fase do ataque imperialista"},"content":{"rendered":"<p><img decoding=\"async\" class=\"imagem\" title=\"imagem\" src=\"https:\/\/i0.wp.com\/orinocotribune.com\/wp-content\/uploads\/2019\/08\/Venezuela-no-more-Trump-protest-Maduro-kicking.jpg?resize=800%2C445&amp;ssl=1\" alt=\"imagem\" \/><!--more-->Secretaria de Rela\u00e7\u00f5es Internacionais do PCB<\/p>\n<p>&#8220;O aprofundamento do bloqueio: uma nova fase do ataque imperialista&#8221;. Este \u00e9 o t\u00edtulo do texto sobre a situa\u00e7\u00e3o venezuelana que segue abaixo, escrito por Carlos Casanueva, professor de hist\u00f3ria e militante do Parido Comunista do Chile, publicado em 14\/08\/2019, no site El Siglo.<\/p>\n<p>Devemos nos preparar para lutar nos cen\u00e1rios que surgem: \u00e9 hora dos patriotas. H\u00e1, sem d\u00favida, a necessidade de levar-se em conta a situa\u00e7\u00e3o eleitoral interna dos Estados Unidos ao analisarmos a atual situa\u00e7\u00e3o venezuelana, j\u00e1 que a decis\u00e3o de Trump de se reeleger em novembro de 2020 poderia estar influenciando perigosamente a estabilidade da Venezuela, provocando um aumento na press\u00e3o da ultradireita de Miami contra Cuba e Venezuela, pe\u00e7a-chave nas aspira\u00e7\u00f5es de Trump para sua reelei\u00e7\u00e3o.<\/p>\n<p>O desespero de Trump em agradar aos setores mais recalcitrantes da direita \u00e9 t\u00e3o evidente, que ele n\u00e3o apenas n\u00e3o condenou o car\u00e1ter eminentemente racista do massacre em El Paso, Texas, por um supremacista branco, mas tamb\u00e9m ordenou ataques em massa para a deporta\u00e7\u00e3o de imigrantes, alguns dias ap\u00f3s o assassinato.<\/p>\n<p>Tudo isso mantendo a guerra comercial com a China, numa angustiante tentativa de cumprir suas promessas eleitorais, endossando a responsabilidade de seu fracasso para com o gigante asi\u00e1tico: \u201cPresidente Xi, que \u00e9 algu\u00e9m de quem gosto muito, acho que ele quer fazer um acordo, mas francamente, n\u00e3o \u00e9 r\u00e1pido o suficiente. Ele disse que ia comprar dos nossos agricultores, ele n\u00e3o fez isso\u201d, disse Trump h\u00e1 alguns dias, em uma tentativa absurda de se aproximar do setor produtivo agr\u00edcola, sob a premissa segundo a qual o setor agr\u00edcola dos EUA n\u00e3o conseguiu a recupera\u00e7\u00e3o prometida por Trump em sua campanha porque a China n\u00e3o cumpriu (a promessa).<\/p>\n<p>Neste contexto, o decreto de cerco comercial contra a Venezuela e a amea\u00e7a de san\u00e7\u00f5es a qualquer Estado ou indiv\u00edduo que comercialize com o pa\u00eds chega a ser uma esp\u00e9cie de sinal para aqueles que pedem san\u00e7\u00f5es ainda mais duras ou interven\u00e7\u00e3o direta, sem levar em conta os interesses da direita pol\u00edtica e econ\u00f4mica venezuelano, j\u00e1 que as san\u00e7\u00f5es afetam n\u00e3o s\u00f3 todo o povo venezuelano, mas tamb\u00e9m empres\u00e1rios e opera\u00e7\u00f5es financeiras privadas.<\/p>\n<p>Diante disso, as rea\u00e7\u00f5es na Venezuela n\u00e3o se fizeram esperar e n\u00e3o foi s\u00f3 o povo chavista que rejeitou essas san\u00e7\u00f5es com unidade e dignidade, j\u00e1 que a defesa da soberania \u00e9 algo muito mais transversal e definidor do ser venezuelano e venezuelana, por isso a cr\u00edtica deste aprofundamento do bloqueio veio de v\u00e1rios setores.<\/p>\n<p>Por sua parte, o presidente Nicol\u00e1s Maduro decidiu suspender a terceira rodada de di\u00e1logo, em Barbados, com a oposi\u00e7\u00e3o, revendo o mecanismo de di\u00e1logo e passando para a ofensiva revolucion\u00e1ria com o povo e a Assembleia Nacional Constituinte. Ordenou ao primeiro vice-presidente do PSUV, Diosdado Cabello, a revis\u00e3o das medidas em resposta a este novo ataque e a prepara\u00e7\u00e3o das estruturas do PSUV e do poder popular organizado, juntamente com todas as for\u00e7as populares do Grande Polo Patri\u00f3tico &#8211; GPP, para enfrentar este ataque imperialista.<\/p>\n<p>\u00c9 necess\u00e1rio salientar que, no plano internacional, a revolu\u00e7\u00e3o bolivariana vem recebendo mais apoio tanto dos governos como dos movimentos populares e dos partidos revolucion\u00e1rios em todo o mundo, com importantes eventos em Caracas em julho, com a reuni\u00e3o dos pa\u00edses n\u00e3o alinhados, que emitiu uma declara\u00e7\u00e3o de apoio ao governo e de rejei\u00e7\u00e3o das san\u00e7\u00f5es unilaterais do imp\u00e9rio, e com a XXV Assembleia do F\u00f3rum de S\u00e3o Paulo, que reuniu mais de 750 delegados de mais de 100 pa\u00edses da nossa Am\u00e9rica e do mundo.<\/p>\n<p>Diante deste cen\u00e1rio, o povo n\u00e3o deve e n\u00e3o pode aceitar a opress\u00e3o. Devemos nos preparar para lutar nos cen\u00e1rios que surgem: \u00e9 hora dos patriotas.<\/p>\n<p>Casanueva termina seu texto fazendo uma refer\u00eancia a um epis\u00f3dio da luta pela liberta\u00e7\u00e3o do pa\u00eds, em que Bolivar, diante de uma ofensiva das for\u00e7as espanholas, em grande vantagem num\u00e9rica, contra um agrupamento pouco numeroso de libertadores liderados pelo coronel Rond\u00f3n, recebeu deste a not\u00edcia de que seus comandados iriam entrar na luta, o que gerou uma for\u00e7a subjetiva t\u00e3o poderosa entre os patriotas que transformou uma derrota iminente em uma vit\u00f3ria: \u201cRond\u00f3n ainda n\u00e3o entrou na luta, mas se alista e se prepara no Poder Popular\u201d. Ou seja, por mais adverso que seja o cen\u00e1rio, o povo tem a \u00faltima palavra.<\/p>\n","protected":false},"excerpt":{"rendered":"<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/23790\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[45],"tags":[234],"class_list":["post-23790","post","type-post","status-publish","format-standard","hentry","category-c54-venezuela","tag-6b"],"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p659gw-6bI","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/23790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=23790"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/23790\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=23790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=23790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=23790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}