{"id":24370,"date":"2019-11-20T15:11:24","date_gmt":"2019-11-20T18:11:24","guid":{"rendered":"https:\/\/pcb.org.br\/portal2\/?p=24370"},"modified":"2019-11-20T15:11:24","modified_gmt":"2019-11-20T18:11:24","slug":"autocritica-ou-anticomunismo","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/24370","title":{"rendered":"Autocr\u00edtica ou anticomunismo?"},"content":{"rendered":"<p><img decoding=\"async\" class=\"imagem\" title=\"imagem\" src=\"https:\/\/i0.wp.com\/lh3.googleusercontent.com\/-1HMnwIC_tb2jpprezF-LmfQI8gVugJdjyQeQvysdVEksA4KLNvApAzvVLY-S4S08bWDA-GOmhsoIpo0I2sAyVP2ZrfClNmyeL-yPAgPAb-m8webvaWi5cQl8sBIPGogvtO141UsY-0SOW5EpYjBDREjruqRxHnCCU3YjrWBA6tzck1hKjKvpyJZ1QitE4oFDBBH9_tTRSIcq2SB8AbjP6VkYQjD8z1b0TAr_4KOtwWQUO_LXpvPdv2ki8vC-PTK1P6ZznxIz3T3iA67vl0uT2G9GaALNbItTaC1F5BFyMvUW4KlNV5Jo2BgyfkV2rpRBUVxhw4FVc_lNrgz0Jozv5KBLgKluv1Ilf072iO9UepHzhYzYzxmz5850mzwzHWx788XFA86XkgIq7Ad1-2ALaya1KFGsX6vANlzwChxeBDeScPA93HYBsA9M2xS2oVi920dIXjO1998h75IduCRWSpGh7oQfgMHino05SGcVxs0oOii_vTNW-ip4_2RDkDVBTbfM3_5ZnF8z3PjZNtNYD2DDMx9nYwmCsuQIQZAr53lJ8fo2CI3Bs71Pijo2G6tKmefpEoZmZi3qzBiqm_3ZmyvaUAUAijrQcwySD0-8zDpievqVl1FqMhRJdysDNo7KlyRKqIV3hZXDwn6v4DMwJlcefDoef_ym4iJ9XWkuEzRUgGPNSZQPIM=w335-h240-no\" alt=\"imagem\" \/><!--more-->por Jones Manoel<\/p>\n<p>Revista Opera<\/p>\n<p>Aportes te\u00f3ricos para compreender a autofobia na esquerda brasileira<\/p>\n<p>Domenico Losurdo (1941-2018), um dos maiores intelectuais da hist\u00f3ria do marxismo.<br \/>\nUm pensador dos condenados da terra.<\/p>\n<p>\u00c9 comum ouvirmos falar de forma gen\u00e9rica que \u201ca esquerda tem que fazer uma autocr\u00edtica dos seus erros passados\u201d. Os autores dessa frase partem, no entanto, de um pressuposto falso. Essa autocr\u00edtica n\u00e3o s\u00f3 existe, como desde a d\u00e9cada de 1990 at\u00e9 hoje \u00e9 praticamente imposs\u00edvel se afirmar marxista sem citar os \u201cerros do passado\u201d. A autocr\u00edtica, por\u00e9m, parece nunca ter fim. Como um fiel cat\u00f3lico, quanto mais perd\u00e3o pedimos, mais pecados parecemos ter.<\/p>\n<p>O n\u00edvel de dom\u00ednio ideol\u00f3gico dessa falsa concep\u00e7\u00e3o de \u201cautocr\u00edtica\u201d \u00e9 t\u00e3o grande que, habitualmente, quando se necessita de um exemplo negativo para criticar um governo, partido ou movimento de direita, o exemplo \u00e9 buscado no nazifascismo ou em algum pa\u00eds socialista. Jair Bolsonaro j\u00e1 foi comparado com L\u00eanin, Hugo Ch\u00e1vez, Mao Ts\u00e9-Tung e Fidel Castro. Na hagiografia do mundo constru\u00edda pelo liberalismo em que se conta: \u201cera uma vez um mundo feliz para sempre e democr\u00e1tico; um dia, por\u00e9m, dois lobos maus \u2013 o nazismo e o comunismo \u2013 tentaram devorar a Dona Democracia.\u201d Mas o liberalismo consegue derrotar os dois, e Fim da Hist\u00f3ria!<\/p>\n<p>Para compreendermos de verdade porque isso n\u00e3o tem nada a ver com autocr\u00edtica \u2013 n\u00e3o passando de uma express\u00e3o do anticomunismo [1] \u2013 cabe buscar adentrar nos fundamentos dessa ideologia caracterizando seus aspectos centrais, fundamentos te\u00f3ricos e seu balan\u00e7o hist\u00f3rico da modernidade burguesa. Depois de feito esse percurso, buscaremos pontuar o papel da falsifica\u00e7\u00e3o hist\u00f3rica, retirada dos horrores da hist\u00f3ria dos comunistas do seu quadro hist\u00f3rico-concreto e pontuar a substancial ignor\u00e2ncia que existe na esquerda brasileira sobre produ\u00e7\u00f5es recentes que derrubam v\u00e1rios mitos da Guerra Fria. Terminado esse caminho, finalizamos com a conclus\u00e3o.<\/p>\n<p>A hagiografia do liberalismo, o recalque da quest\u00e3o colonial e o mito da n\u00e3o viol\u00eancia<br \/>\nMarx ironiza as vis\u00f5es rom\u00e2nticas sobre o surgimento do capitalismo a partir do esfor\u00e7o individual de uma parte mais laboriosa e disciplinada da popula\u00e7\u00e3o, e diz que: \u201cna hist\u00f3ria real, como se sabe, o papel principal \u00e9 desempenhado pela conquista, a subjuga\u00e7\u00e3o, o assass\u00ednio para roubar, em suma, a viol\u00eancia\u201d (MARX, 2015, p. 786). O que Marx combate \u00e9 uma autoimagem do liberalismo, produzida por seus pr\u00f3prios ide\u00f3logos e vencedora ao final do s\u00e9culo XX, que coloca a hist\u00f3ria do liberalismo como um caminho inexor\u00e1vel em defesa das \u201cliberdades individuais\u201d e da democracia contra seus inimigos \u2013 especialmente o movimento oper\u00e1rio.<\/p>\n<p>Na hist\u00f3ria real o liberalismo nasce compreendendo que os direitos naturais n\u00e3o se estendiam aos escravos, povos coloniais, mulheres e trabalhadores, como bem demonstra Losurdo (2006, p. 13-42; 2017, p. 179-211). Ao contr\u00e1rio da vis\u00e3o muito difundida, o liberalismo nasce organicamente conectado com a escravid\u00e3o. N\u00e3o s\u00f3 grandes pensadores liberais, como John Locke e Adam Smith, eram abertamente a favor do lucrativo neg\u00f3cio da escravid\u00e3o colonial \u2013 sendo Locke acionista numa empresa de tr\u00e1fico de escravos; como tamb\u00e9m a Revolu\u00e7\u00e3o Gloriosa na Inglaterra e a Revolu\u00e7\u00e3o Americana deram grande impulso ao neg\u00f3cio da escravid\u00e3o[2].<\/p>\n<p>O direito de voto tamb\u00e9m era negado aos trabalhadores. Immanuel Kant, Bernard Mandeville, Bar\u00e3o de Montesquieu, Alexis de Tocqueville e muitos outros justificavam, a partir de diversos argumentos, a restri\u00e7\u00e3o ao direito de voto para os oper\u00e1rios. Um dos argumentos mais comuns era de que os oper\u00e1rios s\u00e3o \u201cinstrumentos de trabalho falantes\u201d, \u201cm\u00e1quinas b\u00edpedes\u201d. Em suma, seres despidos da raz\u00e3o e das luzes e incapazes de participar do poder. Muitos pensadores liberais, como o Bar\u00e3o de Montesquieu, ainda sublinhavam que a participa\u00e7\u00e3o do povo nos neg\u00f3cios pol\u00edticos tinha potencial de criar o caos na Rep\u00fablica e amea\u00e7ar a propriedade privada (LOSURDO, 2004. p. 15-60). Por falar em Tocqueville, \u00e9 oportuno lembrar que o autor, no seu cl\u00e1ssico \u201cA democracia na Am\u00e9rica\u201d, definiu os EUA como um exemplo de democracia a despeito da escravid\u00e3o dos negros, o exterm\u00ednio dos povos ind\u00edgenas peles vermelhas e as formas de segrega\u00e7\u00e3o racial que enfrentavam os negros livres \u2013 a democracia na Am\u00e9rica era democr\u00e1tica porque a ra\u00e7a dos senhores, os propriet\u00e1rios brancos, desfrutava de um regime constitucional-representativo. (LOSURDO, 2006b, p. 83-86; TOCQUEVILLE, 2005).<\/p>\n<p>O alargamento da esfera dos portadores de direitos naturais do homem, o fim do sistema colonial cl\u00e1ssico, a derrubada de regimes de apartheid, a luta pelo sufr\u00e1gio universal e a cria\u00e7\u00e3o de uma democracia burguesa que n\u00e3o fosse um regime constitucional com direitos pol\u00edticos apenas para burguesia n\u00e3o foram conquistas do liberalismo em defesa das liberdades individuais, mas vit\u00f3rias do movimento oper\u00e1rio e das lutas de liberta\u00e7\u00e3o nacional nas col\u00f4nias contra o liberalismo (LOSURDO, 2015).[3]<\/p>\n<p>A primeira tese fundamental do anticomunismo atual, portanto, \u00e9 a exclus\u00e3o do liberalismo da sua hist\u00f3ria real, transformando-o em um mito, produzindo uma hagiografia liberal. Esse mito est\u00e1 profundamente ligado a outro elemento central: o recalcamento da quest\u00e3o colonial. A hist\u00f3ria da domina\u00e7\u00e3o colonial, ser constitutivo do capitalismo, \u00e9 apagada como se nunca tivesse existido ou tratada de forma id\u00edlica, uma vers\u00e3o atualizada da ideologia do \u201cfardo civilizat\u00f3rio do homem branco\u201d (L\u00caNIN, 2016; LOSURDO, 2017).<\/p>\n<p>Podemos usar tr\u00eas exemplos ilustrativos desse recalcamento da quest\u00e3o colonial na hist\u00f3ria do capitalismo. O fil\u00f3sofo Norberto Bobbio defendia nos anos posteriores \u00e0 Segunda Guerra que os comunistas precisavam incorporar o liberalismo na sua teoria e pr\u00e1tica de governo nos pa\u00edses socialistas. O comunista italiano Palmiro Togliatti, por\u00e9m, faz o seguinte questionamento: \u201cQuando e em que medida foram aplicados aos povos coloniais aqueles princ\u00edpios liberais sobre os quais se diz fundado o Estado ingl\u00eas do s\u00e9culo XIX?\u201d E prossegue afirmando que \u201ca verdade \u00e9 que a doutrina liberal [\u2026] est\u00e1 fundada numa discrimina\u00e7\u00e3o b\u00e1rbara entre as criaturas humanas, que se alastra n\u00e3o s\u00f3 nas col\u00f4nias, mas na pr\u00f3pria metr\u00f3pole, como demonstra o caso dos negros estadunidenses\u201d (TOGLIATTI apud LOSURDO, 2018, p. 72).<\/p>\n<p>Bobbio sabia que liberalismo e democracia n\u00e3o s\u00e3o convergentes e que essa \u00faltima foi uma constru\u00e7\u00e3o das lutas do movimento oper\u00e1rio; ao mesmo tempo, pensava o liberalismo apagado da quest\u00e3o colonial e absolutizava uma certa vis\u00e3o da hist\u00f3ria do liberalismo na realidade europeia \u2013 balan\u00e7o hist\u00f3rico em si tamb\u00e9m mitificado[4]. Basta citar, por exemplo, a realidade colonial da Irlanda. J\u00e1 a filosofa alem\u00e3 Hannah Arendt, no seu cl\u00e1ssico livro \u201cAs Origens do Totalitarismo\u201d (ARENDT, [1949] 2012), come\u00e7a falando do imperialismo europeu na \u00c1frica e \u00c1sia e mostra como institui\u00e7\u00f5es totais, como o campo de concentra\u00e7\u00e3o, foram uma cria\u00e7\u00e3o da pol\u00edtica colonial dos Estados europeus. Eis que, misteriosamente, na terceira parte do seu livro, o imperialismo colonial desaparece de cena e o totalitarismo diz respeito apenas ao nazismo e a URSS (ARENDT, 2012, p. 415-611).<\/p>\n<p>Progredindo nesse caminho, no seu livro \u201cSobre a revolu\u00e7\u00e3o\u201d (ARENDT, [1965] 2011, p.92-158), a fil\u00f3sofa afirma que a Revolu\u00e7\u00e3o Americana, ao contr\u00e1rio da Francesa, garantiu a \u201cliberdade\u201d constituindo-se num processo revolucion\u00e1rio n\u00e3o violento que nunca conheceu epis\u00f3dios como o terror jacobino. A Revolu\u00e7\u00e3o Americana, por n\u00e3o ter a quest\u00e3o social como centro, evitou os perigos totalit\u00e1rios presentes no pensamento e na a\u00e7\u00e3o de uma tradi\u00e7\u00e3o hist\u00f3rica que vai de Robespierre, Marx, L\u00eanin e encontra seu \u00e1pice em St\u00e1lin. O colonialismo interno dos EUA com a \u201cmarcha para o oeste\u201d e o exterm\u00ednio dos peles vermelhas, a amplia\u00e7\u00e3o da escravid\u00e3o, o regime de supremacia racial e a a\u00e7\u00e3o imperialista dos EUA nos anos p\u00f3s revolu\u00e7\u00e3o \u2013 expropria\u00e7\u00e3o de territ\u00f3rios do M\u00e9xico, anexa\u00e7\u00e3o do Hava\u00ed, neocolonialismo nas Filipinas,etc. \u2013 n\u00e3o t\u00eam peso na constru\u00e7\u00e3o te\u00f3rico-filos\u00f3fica e no balan\u00e7o hist\u00f3rico da autora. Sai a an\u00e1lise hist\u00f3rica, e assume o papel central a apologia.[5]<\/p>\n<p>S\u00f3 que a apologia em Arendt ainda \u00e9 indireta, tendo como fundamento o ocultamento. J\u00e1 com o historiador Niall Ferguson, h\u00e1 uma exalta\u00e7\u00e3o do colonialismo. Ferguson \u00e9 um saudosista do Imp\u00e9rio ingl\u00eas e do colonialismo ocidental. Ele reconhece v\u00e1rios de seus atos de barb\u00e1rie, como os massacres, pr\u00e1ticas de tortura em massa, campos de concentra\u00e7\u00e3o, segrega\u00e7\u00e3o racial; mas, a despeito de tudo isso, celebra o Ocidente liberal como portador de valores superiores de democracia, direitos humanos, etc. (FERGUNSON, 2010; 2011) [6]. Ainda atribui ao Ocidente o m\u00e9rito inquestion\u00e1vel de ter fornecido uma via \u00e0 modernidade para os colonizados. Nesse sentido, por exemplo, n\u00e3o importa se quase metade da popula\u00e7\u00e3o do Congo foi massacrada pelo colonialismo belga; mesmo assim, a B\u00e9lgica representava a civiliza\u00e7\u00e3o contra a barb\u00e1rie nativa e possibilitou a esse povo \u201centrar na modernidade\u201d (LOSURDO, 2017, p. 253-308).<\/p>\n<p>O apagamento da quest\u00e3o colonial e a apologia do imperialismo caminham pari passu com o terceiro mito burgu\u00eas: a n\u00e3o viol\u00eancia. Na vis\u00e3o ideol\u00f3gica do capitalismo, a viol\u00eancia n\u00e3o \u00e9 parte constitutiva e estrutural do funcionamento desse sistema socioecon\u00f4mico. Segundo Habermas (2011) e Arendt (2011), a pol\u00edtica \u00e9 por ess\u00eancia uma a\u00e7\u00e3o humana mediada pela comunica\u00e7\u00e3o e o consenso (ROUANET, 1987). No plano filos\u00f3fico, est\u00e1 exclu\u00edda a viol\u00eancia que existe na hist\u00f3ria real. Para Joseph Schumpeter, o capitalismo n\u00e3o tem qualquer necessidade de guerra e viol\u00eancia, sendo esses fen\u00f4menos um resqu\u00edcio de elementos pr\u00e9-capitalistas [7]. A viol\u00eancia na pol\u00edtica \u00e9 uma pervers\u00e3o introduzida pela tradi\u00e7\u00e3o democr\u00e1tico-revolucion\u00e1ria que vai do jacobinismo ao bolchevismo [8].<\/p>\n<p>Os massacres nas metr\u00f3poles capitalistas como a repress\u00e3o \u00e0 Comuna de Paris, o assassinato de militantes na Revolu\u00e7\u00e3o Alem\u00e3 de 1918, as duas grandes guerras mundiais, o ciclo de ditaduras empresariais-militares na Am\u00e9rica Latina, massacres como o dos comunistas na Indon\u00e9sia e tantos outros epis\u00f3dios hist\u00f3ricos n\u00e3o perturbam a vis\u00e3o do liberalismo e da democracia burguesa como essencialmente n\u00e3o-violentos (MAGRI, 2014, p. 76-84).<\/p>\n<p>A partir desses tr\u00eas pilares \u00e9 que toda viol\u00eancia, repress\u00e3o e aparecimento de institui\u00e7\u00f5es totais nas experi\u00eancias socialistas devem ser vistas. N\u00e3o em um quadro hist\u00f3rico-concreto em toda sua complexidade, mas como um derivado necess\u00e1rio da ideologia marxista, ela pr\u00f3pria portadora de um v\u00edrus essencialmente totalit\u00e1rio \u2013 em suma, uma excepcionalidade hist\u00f3rica em um mundo democr\u00e1tico e pac\u00edfico. Nesse sentido, \u00e9 dever de todos os comunistas que fizeram a devida \u201cautocr\u00edtica\u201d olhar toda sua hist\u00f3ria como o \u00e1pice \u2013 ao lado do nazifascismo \u2013 da barb\u00e1rie na modernidade. Podemos ilustrar essa tese a partir da abordagem de duas figuras hist\u00f3ricas do primeiro plano durante a Segunda Guerra: Winston Churchill e Josef St\u00e1lin.<\/p>\n<p>O primeiro \u00e9 considerado um grande estadista e democrata. Churchill, todavia, foi um pol\u00edtico que ganhou notoriedade como um fan\u00e1tico defensor do imp\u00e9rio colonial ingl\u00eas. Era um entusiasta da white supremacy (supremacia branca), considerava os povos colonizados como b\u00e1rbaros, foi respons\u00e1vel por in\u00fameros massacres coloniais na \u00cdndia, defendeu com obsess\u00e3o o esmagamento militar da R\u00fassia Sovi\u00e9tica e nutria muitas simpatias pelo fascismo italiano [9]. Segundo Gandhi, o governo ingl\u00eas de Churchill era \u201chitleriano\u201d e aplicava na \u00cdndia tudo o que os nazistas defendiam[10].<\/p>\n<p>A despeito de tudo isso, \u00e9 poss\u00edvel, sem quaisquer problemas, reivindicar Churchill como exemplo de democrata; j\u00e1 qualquer men\u00e7\u00e3o a St\u00e1lin que n\u00e3o seja a mais apressada condena\u00e7\u00e3o, \u00e9 lida como ades\u00e3o ao totalitarismo. N\u00e3o importa se durante a lideran\u00e7a de St\u00e1lin na URSS houve um firme apoio aos movimentos de liberta\u00e7\u00e3o nacional, combate ao racismo e ao apartheid; se a URSS, sob St\u00e1lin, foi o primeiro pa\u00eds do mundo a criminalizar o racismo na Constitui\u00e7\u00e3o de 1936 e a p\u00f4r em pr\u00e1tica uma eficiente pol\u00edtica educacional e cultural de promo\u00e7\u00e3o da igualdade racial; ou se a URSS tornou-se, no auge do stalinismo, um centro mundial de forma\u00e7\u00e3o pol\u00edtica, cultural e militar totalmente gratuita para milhares de pessoas quebrarem as correntes do colonialismo; ou se toda periferia do sistema capitalista, da \u00c1frica do Sul passando pela Arg\u00e9lia, Vietn\u00e3 at\u00e9 o gueto negro dos EUA, St\u00e1lin era s\u00edmbolo de liberta\u00e7\u00e3o e emancipa\u00e7\u00e3o (MAGRI, 2014; LOSURDO, 2010; SALEM, 2008).[11]<\/p>\n<p>O ato de considerar, concretamente, a dial\u00e9tica entre emancipa\u00e7\u00e3o e desemancipa\u00e7\u00e3o nas experi\u00eancias socialistas, \u00e9 imediatamente interditado pela ideologia burguesa. Aliado a isso, os pr\u00f3prios momentos de horror \u2013 e eles aconteceram! \u2013 devem ser retirados do quadro hist\u00f3rico real e reduzidos a uma abordagem dedutiva da ideologia ou da personalidade de tal ou qual l\u00edder. Nesse sentido, a repress\u00e3o stalinista \u00e9 desconectada do permanente estado de exce\u00e7\u00e3o imposto \u00e0 URSS pelo imperialismo e seus atos de sabotagem, terrorismo, amea\u00e7a de guerra, bloqueio econ\u00f4mico, etc.<\/p>\n<p>Um exemplo \u00e9 suficiente para demonstrar isso: quando os comunistas conseguem chegar ao poder na China, a c\u00fapula do Estado norte-americano al\u00e9m de amea\u00e7ar usar armas at\u00f4micas, imp\u00f4s um duro bloqueio econ\u00f4mico. Eles sabiam que como os comunistas n\u00e3o tinham experi\u00eancia na administra\u00e7\u00e3o da economia urbana, o bloqueio econ\u00f4mico, junto de outros expedientes, como a press\u00e3o militar permanente, conduziriam a erros (POMAR, 2003). O \u201cGrande Salto para Frente\u201d nada mais foi que uma tentativa desesperada de queimar etapas no desenvolvimento econ\u00f4mico para superar as fragilidades da economia subdesenvolvida sabotada pelo imperialismo. Frente aos erros e trag\u00e9dias desse per\u00edodo hist\u00f3rico da China, por\u00e9m, essa \u201cparte\u201d da hist\u00f3ria incomoda, deve ser apagada e tudo se resume a um instinto assassino dos comunistas.<\/p>\n<p>Na guerra, a primeira v\u00edtima \u00e9 a verdade<br \/>\nNo quadro hegem\u00f4nico do balan\u00e7o hist\u00f3rico do movimento oper\u00e1rio comunista no s\u00e9culo XX, n\u00e3o \u00e9 exagerado insistir na retirada das condi\u00e7\u00f5es hist\u00f3rico-concretas onde os horrores foram produzidos. Isso, evidentemente, n\u00e3o significa nenhum relativismo moral, mas uma compreens\u00e3o verdadeiramente cient\u00edfica da hist\u00f3ria [12]. A requisi\u00e7\u00e3o por um balan\u00e7o hist\u00f3rico s\u00e9rio torna-se ainda mais urgente com a percep\u00e7\u00e3o de que a ideologia dominante, na sua opera\u00e7\u00e3o de escrita da hist\u00f3ria, recorre \u00e0 pura e simples mentira. Vejamos.<\/p>\n<p>Os n\u00fameros fant\u00e1sticos de mortos na URSS que sobem a cada ano sem o m\u00ednimo de rigor cient\u00edfico s\u00e3o um bom exemplo desse tipo de mentira [13]. N\u00fameros de presos e mortos durante a repress\u00e3o no per\u00edodo mao\u00edsta tamb\u00e9m s\u00e3o inflados \u2013 mesmo fen\u00f4meno que j\u00e1 atinge o jacobinismo franc\u00eas (LOSURDO, 2018, p. 22). Mas, se nesse caso existe um falseamento a partir de uma base real (mortes realmente aconteceram), em outros, a mentira caminha livre de qualquer lastro na realidade. Podemos citar alguns exemplos: a) o mito de que St\u00e1lin confiava em Hitler e ele e a dire\u00e7\u00e3o do PCUS ficaram surpresos com a quebra do Pacto de n\u00e3o agress\u00e3o germano-sovi\u00e9tico (Medvedev, 2006, p. 291); b) a exist\u00eancia de um suposto \u201cHolodomor\u201d contra os ucr\u00e2nios, mentira fundamental para aproximar sovi\u00e9ticos e nazistas (cada um com sua \u201cSolu\u00e7\u00e3o final\u201d) (LOSURDO, 2010, p. 198); c) a fome planejada na China que exterminou 90 milh\u00f5es de camponeses (ARRIGHI, 2008, p. 375); e d) o antissemitismo sovi\u00e9tico como pol\u00edtica de Estado (LOSURDO, 2010, p. 217).<\/p>\n<p>Guardada toda diversidade, no campo da direita, qualquer questionamento a essas mentiras \u00e9 lido como algo inaceit\u00e1vel. No diverso campo da esquerda, no geral, \u00e9 visto como um relativismo moral de algu\u00e9m que ainda n\u00e3o aceitou a \u201cnecess\u00e1ria autocr\u00edtica\u201d. Ora, recuperar a verdade hist\u00f3rica e mostrar, por exemplo, que o gulag sovi\u00e9tico n\u00e3o pode ser comparado ao campo de exterm\u00ednio nazista n\u00e3o significa dizer \u201co gulag era lindo\u201d.<\/p>\n<p>Nessa tem\u00e1tica, a particularidade brasileira \u00e9 ainda mais grave. A chamada \u201cnova historiografia sovi\u00e9tica\u201d, que surge ao final dos anos de 1970 e ganha for\u00e7a na d\u00e9cada seguinte, conseguiu derrubar v\u00e1rios mitos anticomunistas constru\u00eddos durante a Guerra Fria. Essa historiografia, por\u00e9m, simplesmente n\u00e3o tem espa\u00e7o no mercado editorial brasileiro e tamb\u00e9m n\u00e3o \u00e9 do interesse dos partidos de esquerda realizar sua divulga\u00e7\u00e3o [14]. Nesse sentido, as obras de Geoffrey Roberts, J. Arch Getty, Robert W. Thurston e Annie Lacroix-Riz, para citar alguns exemplos, continuam sendo desconhecidas do p\u00fablico leitor e do conjunto da milit\u00e2ncia brasileira.<\/p>\n<p>Conclus\u00e3o: superar a autofobia e realizar uma verdadeira autocr\u00edtica<br \/>\nDomenico Losurdo detalha um fen\u00f4meno interessante: grupos sociais derrotados, muitas vezes na hist\u00f3ria, passam a assimilar a ideologia, identidade e balan\u00e7o hist\u00f3rico dos vencedores. Essa \u00e9 a autofobia. A nega\u00e7\u00e3o da hist\u00f3ria e identidade em um processo de fuga da hist\u00f3ria. Essa postura pode assumir uma fei\u00e7\u00e3o de \u201cdireita\u201d e outra de \u201cesquerda\u201d. V\u00e1rios ex-comunistas renegaram esse passado vermelho, mesmo sendo dirigentes de partidos, e afirmaram que \u201cnunca foram comunistas\u201d e assumiram os \u201cvalores universais\u201d do Ocidente: propriedade privada, democracia burguesa, OTAN,etc. Outros, por\u00e9m, continuam se afirmando socialistas e lutam por uma sociedade p\u00f3s-capitalista; mas fazem isso guiados pela ideologia dominante. Confundem, assim, autocr\u00edtica com autofobia, diz Losurdo:<\/p>\n<p>Por\u00e9m, apesar das asson\u00e2ncias, autocr\u00edtica e autofobia constituem duas posi\u00e7\u00f5es antit\u00e9ticas. Em seu rigor, e at\u00e9 mesmo em seu radicalismo, a autocr\u00edtica exprime a consci\u00eancia da necessidade de acertar as contas com a pr\u00f3pria hist\u00f3ria; a autofobia \u00e9 uma fuga vil desta hist\u00f3ria e da realidade da luta ideol\u00f3gica e cultural que sob ela que ainda arde. Se a autocr\u00edtica \u00e9 o pressuposto da reconstru\u00e7\u00e3o da identidade comunista, a autofobia \u00e9 sin\u00f4nimo de capitula\u00e7\u00e3o e de ren\u00fancia da identidade aut\u00f4noma (LOSURDO, 2004, p. 15).<\/p>\n<p>Nesse sentido, a verdadeira autocritica n\u00e3o deve renegar toda experi\u00eancia do movimento comunista do s\u00e9culo XX. Posturas como defender um m\u00edtico \u201cretorno a Marx\u201d como se todos os l\u00edderes, militantes, partidos e movimentos no s\u00e9culo passado tivessem tra\u00eddo a palavra sagrada revelada nas escrituras, n\u00e3o passa de uma fuga covarde da realidade e uma express\u00e3o da autofobia que redunda no anticomunismo. Esse tipo de postura nos impede, por exemplo, de responder uma pergunta fundamental que o s\u00e9culo XX colocou aos revolucion\u00e1rios e que algumas experi\u00eancias socialistas, como Cuba, ainda procuram responder: como garantir a democracia socialista e uma forma de liberdade superior \u2013 a de tipo burguesa \u2013 numa situa\u00e7\u00e3o de estado de guerra permanente imposto pelo imperialismo e tendo que superar o subdesenvolvimento e a depend\u00eancia?<\/p>\n<p>A verdadeira autocr\u00edtica pressup\u00f5e, portanto, um balan\u00e7o cr\u00edtico e cient\u00edfico sobre o nosso passado; combatendo a ideologia dominante, inserindo os erros de nossa hist\u00f3ria em um quadro hist\u00f3rico-concreto e valorizando o nosso legado emancipat\u00f3rio. Sem o movimento comunista, dentre outras coisas, o mundo provavelmente ainda conheceria o nazismo e a escravid\u00e3o racial aberta.<\/p>\n<p>Pode parecer um tru\u00edsmo \u2013 e de fato o \u00e9 -, mas os intelectuais e ide\u00f3logos burgueses n\u00e3o est\u00e3o interessados em divulgar e debater o legado emancipat\u00f3rio dos comunistas. Para eles, como j\u00e1 dissemos, tudo n\u00e3o passa de uma s\u00e9rie infinita de horrores. Se n\u00e3o defendermos criticamente a nossa hist\u00f3ria, ningu\u00e9m o far\u00e1. O nosso passado ser\u00e1 expropriado \u2013 como \u00e9 a mais-valia dos trabalhadores \u2013 e o futuro, interditado. Como bem disse Walter Benjamin na famosa tese 7 sobre o conceito de Hist\u00f3ria: \u201cO dom de despertar no passado as centelhas da esperan\u00e7a \u00e9 privil\u00e9gio exclusivo do historiador convencido de que tamb\u00e9m os mortos n\u00e3o estar\u00e3o em seguran\u00e7a se o inimigo vencer. E esse inimigo n\u00e3o tem cessado de vencer\u201d.<\/p>\n<p>Notas:<\/p>\n<p>[1] \u2013 \u00c9 importante negritar que esse debate n\u00e3o \u00e9 uma escol\u00e1stica acad\u00eamica restrita ao ambiente universit\u00e1rio. Na linguagem pol\u00edtica de pol\u00edticos profissionais, como Fernando Haddad e Ciro Gomes (ambos candidatos a presid\u00eancia em 2018, ficando, respectivamente, com o segundo e o terceiro lugar do pleito), nos meios de comunica\u00e7\u00e3o chamados de \u201cprogressistas\u201d, como a Revista Carta Capital e no jornal El Pa\u00eds e em meios de informa\u00e7\u00e3o cada vez mais respons\u00e1veis pela \u201ceduca\u00e7\u00e3o pol\u00edtica\u201d de uma parcela da popula\u00e7\u00e3o, como canais no Youtube, a ideia de fugir de extremos iguais, extrema direita e extrema esquerda, ambos violentos, autorit\u00e1rios e antidemocr\u00e1ticos \u2013 o comunismo sovi\u00e9tico, o representante por excel\u00eancia da \u201cextrema esquerda\u201d e o nazismo da \u201cextrema direita\u201d \u2013 \u00e9 cada vez mais forte. Essa ideologia tem \u00edntima rela\u00e7\u00e3o com a hagiografia do liberalismo. Esperamos que ao final do texto o leitor perceba claramente essa rela\u00e7\u00e3o.<\/p>\n<p>[2] \u2013 \u201cA escravid\u00e3o n\u00e3o \u00e9 algo que permane\u00e7a n\u00e3o obstante o sucesso das tr\u00eas revolu\u00e7\u00f5es liberais; ao contr\u00e1rio, ela conhece o seu m\u00e1ximo desenvolvimento em virtude desse sucesso: \u201co total da popula\u00e7\u00e3o escrava nas Am\u00e9ricas somava aproximadamente 330.000 no ano de 1700, chegou a quase tr\u00eas milh\u00f5es no ano de 1800, at\u00e9 alcan\u00e7ar o pico de mais de 6 milh\u00f5es nos anos 50 do s\u00e9c. XIX\u201d (LOSURDO, 2006. p. 47).\u201d<\/p>\n<p>[3] \u2013 Em 5 de junho de 1920, no Esbo\u00e7o inicial das Teses sobre a Quest\u00e3o Nacional e Colonial, no II Congresso da Internacional Comunista, L\u00eanin expressa em termos te\u00f3ricos o que, na pr\u00e1tica, foi um elemento central (n\u00e3o sem contradi\u00e7\u00f5es e erros) da a\u00e7\u00e3o dos comunistas no s\u00e9culo XX: \u201cn\u00e3o s\u00f3 em toda propaganda e agita\u00e7\u00e3o dos partidos comunistas \u2013 tanto da tribuna parlamentar como fora dela \u2013 devem ser incansavelmente desmascaradas as constantes viola\u00e7\u00f5es da igualdade das na\u00e7\u00f5es e das garantias dos direitos das minorias nacionais em todos os Estados capitalistas, a despeito das suas constitui\u00e7\u00f5es \u2018democr\u00e1ticas\u2019 [\u2026]; Segundo, \u00e9 necess\u00e1rio uma ajuda direta de todos os partidos comunistas aos movimentos revolucion\u00e1rios nas na\u00e7\u00f5es dependentes ou que n\u00e3o gozam de igualdade de direitos (por exemplo, na Irlanda, entre os negros da Am\u00e9rica etc.) e nas col\u00f4nias\u201d (L\u00caNIN, 2017, p. 438).<\/p>\n<p>[4] \u2013 Importante pontuar que posteriormente, j\u00e1 nos anos de 1970, Bobbio expressa uma hist\u00f3ria mais cr\u00edtica do liberalismo e reconhece suas cl\u00e1usulas de exclus\u00e3o e a barb\u00e1rie colonial. Exemplo disso \u00e9 seu livro Pol\u00edtica e Cultura, Editora Unesp, [1977] 2015. Mesmo assim, por\u00e9m, em situa\u00e7\u00f5es concretas, como na invas\u00e3o de Granada, Panam\u00e1 e nos atos terroristas dos EUA contra a Nicar\u00e1gua Sandinista, Bobbio manteve sil\u00eancio e apoiou a primeira guerra [neocolonial] contra o Iraque. Esse \u00faltimo epis\u00f3dio chocou bastante os alunos e seguidores de Bobbio dado sua imagem de \u201cpacifista\u201d e defensor de uma ordem mundial baseada no direito internacional e n\u00e3o na for\u00e7a.<\/p>\n<p>[5] \u2013 N\u00e3o \u00e9 demais lembrar que Alexis de Tocqueville, o famoso liberal franc\u00eas, torna-se uma das grandes refer\u00eancias te\u00f3ricas de Hannah Arendt e \u00e9 not\u00f3ria sua influ\u00eancia no livro \u201cSobre a Revolu\u00e7\u00e3o\u201d. Tocqueville, que dentre outras proezas, foi um defensor total da conquista colonial francesa no Mabreg e da crucifica\u00e7\u00e3o colonial da China.<\/p>\n<p>[6] \u2013 A ideologia da superioridade civilizat\u00f3ria do europeu comparece, inclusive, em v\u00e1rios sujeitos pol\u00edticos \u2013 intelectuais, ve\u00edculos de comunica\u00e7\u00e3o, partidos pol\u00edticos etc. \u2013 identificados com a esquerda. Ano passado, durante uma entrevista ao jornal espanhol El pa\u00eds, disse o fil\u00f3sofo Slavoj \u017di\u017eek: \u201caceitemos que as pessoas venham para c\u00e1 porque, apesar de toda a corrup\u00e7\u00e3o, continuamos oferecendo ao mundo aquele que talvez seja o grande modelo de bem-estar relativo, um \u00fanico modelo que combina bem-estar e liberdade, o melhor at\u00e9 agora na hist\u00f3ria mundial. Portanto, dever\u00edamos estar orgulhosos do nosso destino europeu. O fant\u00e1stico da nossa tradi\u00e7\u00e3o democr\u00e1tica \u00e9 que a imperfei\u00e7\u00e3o est\u00e1 dentro do sistema, faz parte da capacidade da nossa democracia de ser cr\u00edtica consigo mesma. \u00c9 um sistema \u00fanico, que inclui a autocr\u00edtica.\u201d A entrevista completa pode ser acessada nesse link: https:\/\/brasil.elpais.com\/brasil\/2018\/12\/14\/cultura\/1544788158_128530.html<\/p>\n<p>[7] \u2013 Para uma cr\u00edtica \u00e0 vis\u00e3o de Schumpeter, presente em \u201cThe Sociology of Imperialism\u201d (A sociologia do imperialismo), ver o tamb\u00e9m j\u00e1 citado Losurdo, 2018, p. 155-158.<\/p>\n<p>[8] \u2013 \u201cNeste aspecto, \u00e9 surpreendente como boa parte das \u00e9ticas contempor\u00e2neas, t\u00e3o em voga nas academias, busca encontrar solu\u00e7\u00e3o para os problemas da sociedade contempor\u00e2nea, a partir de pretensos princ\u00edpios morais universaliz\u00e1veis, sem considerar a sua viabilidade junto \u00e0 base econ\u00f4mica-material que move a sociedade civil. Como se fosse poss\u00edvel construir-se valores morais justos sobre uma infraestrutura injusta [e eu acrescendo: violenta]. \u00c9 o caso das \u00e9ticas discursivas de K. Apel e J. Habermas e da teoria da justi\u00e7a de Jonh Rawls\u201d (VIEIRA, 2006, p. 16)<\/p>\n<p>[9] \u2013 Churchill era um grande admirador de Mussolini, que chegara ao poder em It\u00e1lia em 1922. Saudava tanto o anticomunismo de Mussolini, quanto a sua forma autorit\u00e1ria de organizar e disciplinar os italianos. Visitou a It\u00e1lia em 1927 [\u2026] e encontrou-se com Mussolini, sobre quem proferiu rasgados elogios numa confer\u00eancia de imprensa [\u2026]. \u2018Se fosse italiano, estou seguro que estaria de todo o cora\u00e7\u00e3o ao vosso lado, desde o in\u00edcio at\u00e9 ao fim, na vossa luta triunfante contra os apetites e paix\u00f5es animalescas do Leninismo\u2019. E sobre as simpatias de Churchill pelos golpistas espanh\u00f3is escreve Ponting: \u201ctodas as suas simpatias estavam com Franco e o lado nacionalista. [\u2026] Descreveu o governo leg\u00edtimo e a parte republicana como \u2018um proletariado pobre e atrasado que exige o derrube da Igreja, do Estado e da propriedade e a instala\u00e7\u00e3o dum regime Comunista\u2019. Contra eles erguiam-se \u2018for\u00e7as patri\u00f3ticas, religiosas e burguesas, sob o comando do ex\u00e9rcito [\u2026] em marcha para reestabelecer a ordem atrav\u00e9s da instaura\u00e7\u00e3o duma ditadura militar\u2019\u201d \u2013 CADIMA, Jorge. Nos 70 anos da vit\u00f3ria de 1945, 2015. Dispon\u00edvel no link: https:\/\/pcb.org.br\/portal2\/8195\/nos-70-anos-da-vitoria-de-1945\/<\/p>\n<p>[10] \u2013 \u201cNa \u00cdndia, temos um governo hitleriano, ainda que camuflado em termos mais brandos [\u2026] Hitler foi o pecado da Gr\u00e3-Bretanha. Hitler \u00e9 apenas uma resposta ao imperialismo brit\u00e2nico\u201d (GANDHI apud LOSURDO, 2010, P. 191).<\/p>\n<p>[11] \u2013 \u201cA URSS de Stalin influencia poderosamente a luta dos afro-americanos (e dos povos coloniais) contra o despotismo racial. No Sul dos EUA se assiste a um fen\u00f4meno novo e preocupante do ponto de vista da casta dominante: \u00e9 a crescente \u2018imprud\u00eancia\u2019 dos jovens negros. Estes, gra\u00e7as aos comunistas, come\u00e7am, de fato, a receber o que o poder teimosamente lhes negava, a saber, uma cultura que vai muito al\u00e9m da instru\u00e7\u00e3o elementar tradicionalmente transmitida aos que est\u00e3o destinados a fornecer trabalho semiescravo a servi\u00e7o da ra\u00e7a dos senhores. Agora, por\u00e9m, nas escolas organizadas pelo partido comunista no norte dos Estados Unidos ou nas escolas de Moscou, na URSS de Stalin, os negros se empenham em estudar economia, pol\u00edtica, hist\u00f3ria mundial; interrogam essas disciplinas para compreender tamb\u00e9m as raz\u00f5es da dura sorte reservada a eles num pa\u00eds que se comporta como campe\u00e3o da liberdade\u201d (Losurdo, 2010, p. 280-281)<\/p>\n<p>[12] \u2013 Interessante destacar que as duas principais revolu\u00e7\u00f5es liberais hoje defendidas pela burguesia, a Revolu\u00e7\u00e3o Inglesa e a Americana, n\u00e3o s\u00e3o moralizadas por sua viol\u00eancia ou elementos de barb\u00e1rie, como a manuten\u00e7\u00e3o e amplia\u00e7\u00e3o da escravid\u00e3o. O olhar moralizador e de horror \u00e9 reservado apenas \u00e0s revolu\u00e7\u00f5es socialistas e anticoloniais. Professor que sou, debatendo com colegas de profiss\u00e3o, quando apresento a contra-hist\u00f3ria das revolu\u00e7\u00f5es liberais, a resposta que sempre escuto era \u201cisso era a ideologia da \u00e9poca\u201d. Ou seja, a Revolu\u00e7\u00e3o Americana, por exemplo, est\u00e1 livre de qualquer ju\u00edzo \u00e9tico, pol\u00edtico e moral, afinal, era \u201cassim que se pensava no per\u00edodo\u201d.<\/p>\n<p>[13] \u2013 Jean Salem (2008, p. 30-32) mostra como essa l\u00f3gica se desenvolve na Fran\u00e7a. Um c\u00e1lculo que come\u00e7a com 10 milh\u00f5es de mortos na URSS e consegue, tranquilamente, alcan\u00e7ar a casa dos 110 milh\u00f5es de mortos j\u00e1 anos de 1970 (2008, p. 27).<\/p>\n<p>[14] \u2013 As exce\u00e7\u00f5es, como as tradu\u00e7\u00f5es de Domenico Losurdo e de Wendy Goldman, apenas confirmam a regra.<\/p>\n<p>Refer\u00eancias:<\/p>\n<p>ARENDT, Hannah. As origens do totalitarismo: antissemitismo, imperialismo, totalitarismo. Companhia das Letras, S\u00e3o Paulo, 2012.<\/p>\n<p>_______________. Sobre a revolu\u00e7\u00e3o. Companhia das Letras, S\u00e3o Paulo, 2011.<\/p>\n<p>ARRIGHI, Giovanni. Adam Smith em Pequim \u2013 origens e fundamentos do s\u00e9culo XXI. Boitempo Editorial, S\u00e3o Paulo, 2008.<\/p>\n<p>FERGUSON, Niall. Colosso: ascens\u00e3o e queda do imp\u00e9rio americano. Planeta, S\u00e3o Paulo, 2011.<\/p>\n<p>_______________. Imperio: como os brit\u00e2nicos fizeram o mundo moderno. Planeta, S\u00e3o Paulo, 2010.<\/p>\n<p>HABERMAS, J\u00fcrgen. Teoria do agir comunicativo \u2013 vol. 1: Racionalidade da a\u00e7\u00e3o e racionaliza\u00e7\u00e3o social. Martins Fontes, S\u00e3o Paulo, 2011.<\/p>\n<p>L\u00caNIN, V. I. Imperialismo, etapa superior do capitalismo. Express\u00e3o Popular, S\u00e3o Paulo, 2016.<\/p>\n<p>__________. Lenin e a revolu\u00e7\u00e3o de outubro \u2013 textos no calor da hora (1917-1923). Express\u00e3o Popular, S\u00e3o Paulo, 2017.<\/p>\n<p>LOSURDO, Domenico. A luta de classes. Uma hist\u00f3ria pol\u00edtica e filos\u00f3fica. Boitempo Editorial, S\u00e3o Paulo, 2015.<\/p>\n<p>__________________. Contra-hist\u00f3ria do liberalismo. Ideias e Letras, S\u00e3o Paulo, 2006.<\/p>\n<p>__________________. Democracia ou bonapartismo? Triunfo e decad\u00eancia do sufr\u00e1gio universal. Editora Unesp, S\u00e3o Paulo, 2004.<\/p>\n<p>__________________. Fuga da hist\u00f3ria? A Revolu\u00e7\u00e3o Russa e a revolu\u00e7\u00e3o chinesa vistas de hoje. Editora Revan, Rio de Janeiro, 2004.<\/p>\n<p>__________________. Guerra e revolu\u00e7\u00e3o \u2013 o mundo um s\u00e9culo ap\u00f3s Outubro de 2017. Boitempo Editorial, S\u00e3o Paulo, 2017.<\/p>\n<p>__________________. Liberalismo. Entre a civiliza\u00e7\u00e3o e a barb\u00e1rie. Editora Anita Garibaldi, 2006, S\u00e3o Paulo.<\/p>\n<p>__________________. O marxismo ocidental. Como nasceu, como morreu, como pode renascer. Boitempo Editorial, S\u00e3o Paulo, 2018.<\/p>\n<p>__________________. St\u00e1lin \u2013 uma hist\u00f3ria cr\u00edtica de uma lenda negra. Editora Revan, Rio de Janeiro, 2010.<\/p>\n<p>MAGRI, Lucio. O alfaiate de Ulm \u2013 uma hist\u00f3ria poss\u00edvel do Partido Comunista Italiano. Boitempo Editorial, S\u00e3o Paulo, 2014.<\/p>\n<p>MARX, Karl. O Capital: cr\u00edtica da economia pol\u00edtica \u2013 Volume I. Boitempo Editorial, S\u00e3o Paulo, 2015.<\/p>\n<p>MEDVEDEV, zhores A.; MEDVEDEV, roy A. Um St\u00e1lin desconhecido: novas revela\u00e7\u00f5es dos arquivos sovi\u00e9ticos. Editora Record, Rio de Janeiro, 2006.<\/p>\n<p>POMAR, Wladimir. A Revolu\u00e7\u00e3o Chinesa. Editora Unesp, S\u00e3o Paulo, 2003.<\/p>\n<p>ROUANET, S\u00e9rgio Paulo. As raz\u00f5es do iluminismo. Companhia das Letras, S\u00e3o Paulo, 1987.<\/p>\n<p>SALEM, Jean. L\u00eanin e a Revolu\u00e7\u00e3o. Express\u00e3o Popular, S\u00e3o Paulo, 2008.<\/p>\n<p>TOCQUEVILLE, alexis. A democracia na Am\u00e9rica. Leis e costumes \u2013 Livro I. Martins Fontes, S\u00e3o Paulo, 2005.<\/p>\n<p>VIEIRA, Luiz Vicente. A Democracia com p\u00e9s de Barro: O diagn\u00f3stico de uma crise que mina as estruturas do Estado de direito. Editora UFPE, Recife, 2006.<\/p>\n","protected":false},"excerpt":{"rendered":"<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/24370\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[50],"tags":[222],"class_list":["post-24370","post","type-post","status-publish","format-standard","hentry","category-c61-cultura-revolucionaria","tag-2b"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-6l4","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/24370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=24370"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/24370\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=24370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=24370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=24370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}