{"id":24898,"date":"2020-02-15T01:48:53","date_gmt":"2020-02-15T04:48:53","guid":{"rendered":"https:\/\/pcb.org.br\/portal2\/?p=24898"},"modified":"2020-02-15T01:48:53","modified_gmt":"2020-02-15T04:48:53","slug":"os-barbaros","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/24898","title":{"rendered":"Os B\u00e1rbaros"},"content":{"rendered":"<p><img decoding=\"async\" class=\"imagem\" title=\"imagem\" src=\"https:\/\/i0.wp.com\/www.middleeastmonitor.com\/wp-content\/uploads\/2020\/01\/20200104_2_40163933_50920962.jpg?w=1200&amp;quality=85&amp;strip=all&amp;ssl=1\" alt=\"imagem\" \/><!--more-->ODIARIO.INFO<\/p>\n<p>Gustavo Carneiro<\/p>\n<p>\u00abO surgimento de um novo v\u00edrus, combatido ali\u00e1s com impressionante determina\u00e7\u00e3o pelas autoridades chinesas, tem dado oportunidade a m\u00faltiplas e variadas express\u00f5es de racismo e arrog\u00e2ncia de timbre neocolonial. Ao mesmo tempo que nada se diz sobre a dram\u00e1tica realidade do sistema de sa\u00fade norte-americano, que deixa milhares sem acesso por n\u00e3o terem recursos econ\u00f4micos ou seguro.\u00bb<\/p>\n<p>Na Antiguidade, os gregos cunharam o termo b\u00e1rbaro para designar todos quantos falassem outras l\u00ednguas, para si incompreens\u00edveis. Eram b\u00e1rbaros povos t\u00e3o avan\u00e7ados quanto os persas, os fen\u00edcios, os eg\u00edpcios. J\u00e1 os romanos (eles pr\u00f3prios b\u00e1rbaros para os gregos) alargaram o \u00e2mbito do conceito para todos os estrangeiros que n\u00e3o partilhassem a tradi\u00e7\u00e3o cultural greco-romana, mas referiam-se principalmente \u00e0s v\u00e1rias tribos que amea\u00e7avam as suas fronteiras \u2013 e que acabariam por derrubar o seu imp\u00e9rio: os francos, os lombardos, os godos\u2026 A Hist\u00f3ria fixou esta \u00faltima defini\u00e7\u00e3o, exacerbada: os b\u00e1rbaros passaram a ser, mais do que diferentes, inferiores.<\/p>\n<p>A dicotomia n\u00f3s-civilizados versus eles-b\u00e1rbaros, sustentada na preponder\u00e2ncia econ\u00f4mica e supremacia militar das pot\u00eancias europeias, serviu ao longo de s\u00e9culos para justificar o colonialismo. E, com ele, a escravatura, o saque de recursos, a pilhagem de tesouros culturais. Hoje, com o predom\u00ednio econ\u00f4mico das pot\u00eancias imperialistas ocidentais seriamente amea\u00e7ado (mas n\u00e3o o poderio ideol\u00f3gico e militar), ela ressurge em for\u00e7a: a miss\u00e3o civilizadora do Ocidente \u00e9 associada, de forma mais ou menos sutil, \u00e0s agress\u00f5es militares, aos bloqueios, \u00e0s inger\u00eancias perpetradas pelos EUA e seus aliados.<\/p>\n<p>Que importa se o Ir\u00e3 descende da riqu\u00edssima civiliza\u00e7\u00e3o Persa e se a\u00ed est\u00e3o localizadas duas dezenas de s\u00edtios classificados pela UNESCO como Patrim\u00f4nio Mundial da Humanidade? Ou que as numerosas comunidades crist\u00e3s existentes na S\u00edria convivam pacificamente com xiitas e sunitas e que na grande Mesquita dos Om\u00edadas, em Damasco, se preste culto tamb\u00e9m a S\u00e3o Jo\u00e3o Batista? Ou ainda o fato de os refugiados que rumam \u00e0 Europa (uma fatia \u00ednfima do total) fujam, na sua maioria, das guerras que n\u00f3s instigamos nos seus pa\u00edses de origem? Nada!<\/p>\n<p>O que parece contar \u00e9 que eles, os b\u00e1rbaros isl\u00e2micos, n\u00e3o partilham dos nossos valores e da nossa civiliza\u00e7\u00e3o e que, por isso, s\u00e3o uma amea\u00e7a.<\/p>\n<p>O caso da China, com uma hist\u00f3ria milenar e um desenvolvimento econ\u00f4mico e tecnol\u00f3gico impressionante, \u00e9 a este respeito paradigm\u00e1tico. O surgimento de um novo v\u00edrus, combatido ali\u00e1s com impressionante determina\u00e7\u00e3o pelas autoridades chinesas, tem dado oportunidade a m\u00faltiplas e variadas express\u00f5es de racismo e arrog\u00e2ncia de timbre neocolonial. Ao mesmo tempo que nada se diz sobre a dram\u00e1tica realidade do sistema de sa\u00fade norte-americano, que deixa milhares sem acesso por n\u00e3o terem recursos econ\u00f4micos ou seguro.<\/p>\n<p>A Cultura n\u00e3o constitui nunca uma amea\u00e7a, antes \u00e9 uma fonte de enriquecimento da Humanidade. A disputa n\u00e3o \u00e9 entre o Ocidente e os b\u00e1rbaros\u2026 \u00c9 entre o imperialismo e os povos, entre capital e trabalho! E \u00e9 deste combate que \u00e9 preciso que saia vencedora a Humanidade e a Cultura.<\/p>\n<p>*Este artigo foi publicado no \u201cAvante!\u201d, n\u00ba 2410, 6.02.2020<\/p>\n","protected":false},"excerpt":{"rendered":"<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/24898\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[38],"tags":[234],"class_list":["post-24898","post","type-post","status-publish","format-standard","hentry","category-c43-imperialismo","tag-6b"],"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p659gw-6tA","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/24898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=24898"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/24898\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=24898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=24898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=24898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}