{"id":25486,"date":"2020-05-07T11:30:07","date_gmt":"2020-05-07T14:30:07","guid":{"rendered":"https:\/\/pcb.org.br\/portal2\/?p=25486"},"modified":"2020-05-07T11:30:07","modified_gmt":"2020-05-07T14:30:07","slug":"pandemia-capitalista-e-degradacao-do-trabalho","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/25486","title":{"rendered":"Pandemia capitalista e degrada\u00e7\u00e3o do trabalho"},"content":{"rendered":"<p><img decoding=\"async\" class=\"imagem\" title=\"imagem\" src=\"https:\/\/i0.wp.com\/www.cmm.am.gov.br\/wp-content\/uploads\/2020\/04\/30.04-Cabine-Desinfeccao.jpg\" alt=\"imagem\" \/><!--more-->Nota da Editoria: A P\u00e1gina Nacional do PCB reproduz essa importante mat\u00e9ria publicada no s\u00edtio do IHU-Unisinos no dia 1\u00ba de maio deste ano, na certeza de que as entrevistas com os renomados pesquisadores abaixo contribuem sobremaneira para a compreens\u00e3o, na l\u00f3gica dos interesses da classe trabalhadora, do complexo momento social, econ\u00f4mico e pol\u00edtico em que vivemos, em meio ao aprofundamento da crise estrutural do capitalismo, agravada com a pandemia. Em que pese uma ou outra opini\u00e3o distinta da linha editorial de nossa p\u00e1gina, o conjunto da mat\u00e9ria nos traz dados e an\u00e1lises essenciais para que, a partir do entendimento das transforma\u00e7\u00f5es que se operam no mundo do trabalho e nas rela\u00e7\u00f5es sociais impostas pelo capitalismo, possamos intervir nessa realidade com o objetivo primordial de combater os terr\u00edveis ataques sofridos pelos trabalhadores e pelas trabalhadoras e construir a contraofensiva na dire\u00e7\u00e3o do poder popular e do socialismo.<\/p>\n<p>IHU UNISINOS<\/p>\n<p>Por: Jo\u00e3o Vitor Santos | Edi\u00e7\u00e3o: Patricia Fachin e Ricardo Machado<\/p>\n<p>O mundo do trabalho vem sofrendo bruscamente in\u00fameras transforma\u00e7\u00f5es nos \u00faltimos tempos. A automa\u00e7\u00e3o e as tecnologias de plataforma, que engrossam os avan\u00e7os da Revolu\u00e7\u00e3o 4.0, t\u00eam tornado os conceitos de trabalho e emprego cada vez mais distantes. Sem emprego com todas as prote\u00e7\u00f5es constitucionais, as pessoas t\u00eam sido obrigadas a buscar trabalho contentando-se apenas com a renda gerada por ele, seja atrav\u00e9s da cl\u00e1ssica informalidade ou como novos \u2018servidores\u2019 do trabalho de plataformas a partir de empresas como Uber, iFood, entre outras. Esse cen\u00e1rio j\u00e1 sombrio \u00e9 ainda mais grave no tempo atual, em que uma crise em escala mundial eclode a partir da propaga\u00e7\u00e3o do novo coronav\u00edrus. Para pesquisadores ouvidos pelo Instituto Humanitas Unisinos &#8211; IHU, a crise leva \u00e0 beira do abismo: podemos nos jogar e tentar nos agarrar no que for poss\u00edvel para sobreviver ou, com apoio estatal, saltar para uma nova era, com uma nova forma de vida, consumo, produ\u00e7\u00e3o e trabalho, visando ao bem comum e ao pleno Estado de bem-estar social.<\/p>\n<p>Para o professor Ricardo Antunes, \u00e9 preciso ter consci\u00eancia de que \u201co capital s\u00f3 pode se ampliar destruindo e \u00e9 por isso que ele destr\u00f3i a for\u00e7a humana de trabalho em propor\u00e7\u00f5es monumentais, destr\u00f3i a natureza de modo visceral\u201d. Por isso leva a um esgotamento do atual sistema e, num contexto de crise, pensa um outro desde o esfacelamento da humanidade. \u201cQue trabalho os capitais querem? Um trabalho cada vez mais desprovido de direitos, mais informal, funcionando como um ap\u00eandice de uma m\u00e1quina que domina o mundo\u201d, aponta, na entrevista concedida \u00e0 IHU On-Line via WhatsApp. Para ele, \u00e9 preciso n\u00e3o deixar que o capitalismo d\u00ea as respostas. \u201cN\u00e3o podemos permitir que o lucro seja o ponto central; temos que fazer a defesa da vida. N\u00e3o se trata de economia e vida; n\u00e3o, a economia \u00e9 destrutiva e \u00e9 causadora da pandemia. A economia do capital n\u00e3o visa sa\u00fade p\u00fablica, educa\u00e7\u00e3o p\u00fablica, previd\u00eancia p\u00fablica, alimenta\u00e7\u00e3o; \u00e9 o destro\u00e7amento. Ent\u00e3o, a quest\u00e3o crucial hoje \u00e9 a luta pela vida\u201d, indica.<\/p>\n<p>O soci\u00f3logo Clemente Ganz L\u00facio vai na mesma linha e compreende que se \u201ctrata de disputar a estrat\u00e9gia de sa\u00edda que deve conter a perspectiva de supera\u00e7\u00e3o do modelo vigente\u201d. Mas ressalva: \u201cn\u00e3o se trata de voltar ao mundo do passado recente. Voltar para a \u2018normalidade\u2019 \u00e9 ingressar novamente no mundo que criou esse caos. Trata-se, portanto, de enfrentar o desafio criativo de inventar um novo mundo\u201d. Na entrevista concedida por e-mail \u00e0 IHU On-Line, indica que para concretizar isso \u00e9 importante o \u201cEstado atuar para promover crescente capacidade para o sistema de sa\u00fade proteger as vidas; atuar para garantir o abastecimento de alimentos, bens e servi\u00e7os de primeira necessidade e os insumos para o sistema de sa\u00fade\u201d. \u201cA emerg\u00eancia da cat\u00e1strofe ambiental acompanhar\u00e1 as novas crises sanit\u00e1rias que vir\u00e3o. Isso exigir\u00e1 novos protocolos e organiza\u00e7\u00e3o social e econ\u00f4mica. Um projeto de futuro deve colocar na centralidade o desafio social e ambiental\u201d, acrescenta.<\/p>\n<p>Jos\u00e9 Dari Krein reitera que a situa\u00e7\u00e3o \u00e9 cr\u00edtica e que a recess\u00e3o global pode ser ainda maior do que se projeta, assolando especialmente pa\u00edses perif\u00e9ricos como o Brasil. Assim, enfatiza que todos os esfor\u00e7os devem ser no sentido de, pelo menos, n\u00e3o aumentarem as desigualdades. \u201cA possibilidade de uma explos\u00e3o do desemprego refor\u00e7a as desigualdades existentes no mercado de trabalho, com claro recorte de ra\u00e7a e sexo. As hist\u00f3ricas discrimina\u00e7\u00f5es e exclus\u00f5es s\u00e3o refor\u00e7adas na crise\u201d, alerta, na entrevista concedida por e-mail \u00e0 IHU On-Line. Para ele, \u201ca travessia desej\u00e1vel da atual tempestade somente \u00e9 poss\u00edvel por meio da atua\u00e7\u00e3o do Estado\u201d, protegendo as pessoas de um capitalismo que se reconfigura diante da crise. \u201cA realidade mostra que o mercado autorregulado \u00e9 incapaz de responder ao tamanho da crise. Muitos, inclusive o governo brasileiro, acham que podem continuar com a sua agenda neoliberal, mas n\u00e3o h\u00e1 possibilidade de sa\u00edda sem o Estado\u201d, avalia. E faz um apelo: \u201cn\u00e3o podemos continuar perdendo tantas vidas por falta de condi\u00e7\u00f5es m\u00ednimas de trabalho, como est\u00e1 ocorrendo atualmente\u201d.<\/p>\n<p>Ricardo Antunes \u00e9 professor titular de Sociologia no Instituto de Filosofia e Ci\u00eancias Humanas &#8211; IFCH da Universidade Estadual de Campinas &#8211; Unicamp. Doutor em Ci\u00eancias Sociais pela Universidade de S\u00e3o Paulo &#8211; USP, publicou recentemente Riqueza e Mis\u00e9ria do Trabalho no Brasil IV: Trabalho Digital, Autogest\u00e3o e Expropria\u00e7\u00e3o da Vida (S\u00e3o Paulo: Boitempo, 2019), Politica Della Caverna: La Controrivoluzione di Bolsonaro (It\u00e1lia: Castelvecchi, 2019) e O Privil\u00e9gio da Servid\u00e3o. O Novo Proletariado de Servi\u00e7os na Era Digital (S\u00e3o Paulo: Boitempo, 2018).<\/p>\n<p>Clemente Ganz L\u00facio \u00e9 soci\u00f3logo, diretor t\u00e9cnico do Departamento Intersindical de Estat\u00edstica e Estudos Socioecon\u00f4micos &#8211; Dieese e membro do Conselho de Desenvolvimento Econ\u00f4mico e Social &#8211; CDES.<\/p>\n<p>Jos\u00e9 Dari Krein \u00e9 graduado em Filosofia pela Pontif\u00edcia Universidade Cat\u00f3lica do Paran\u00e1 &#8211; PUC-PR, tem mestrado e doutorado em Economia Social e do Trabalho pela Universidade Estadual de Campinas &#8211; Unicamp, onde atualmente \u00e9 professor no Centro de Estudos Sindicais e de Economia do Trabalho &#8211; Cesit.<\/p>\n<p>Confira as entrevistas.<\/p>\n<p>IHU On-Line \u2013 Que mudan\u00e7as de fundo vislumbra no mundo do trabalho?<\/p>\n<p>Ricardo Antunes \u2013 Primeiro \u00e9 preciso dizer que a pandemia do coronav\u00edrus n\u00e3o \u00e9 um elemento desconectado do sistema de metabolismo antissocial do capital de car\u00e1ter profundamente destrutivo. Por que \u00e9 destrutivo? Porque se trata de um sistema metab\u00f3lico no qual a necessidade de valoriza\u00e7\u00e3o do \u201cvalor\u201d, da cria\u00e7\u00e3o de mais dinheiro, mais lucro e mais apropria\u00e7\u00e3o privada da riqueza transforma esse metabolismo, na sua interioridade e processualidade, em algo profundamente expansionista e, no limite, incontrol\u00e1vel. Dito de modo direto, o capital s\u00f3 pode se ampliar destruindo e \u00e9 por isso que ele destr\u00f3i a for\u00e7a humana de trabalho em propor\u00e7\u00f5es monumentais, destr\u00f3i a natureza de modo visceral.<\/p>\n<p>Isto tudo se agrava no contexto da pandemia, que n\u00e3o \u00e9, portanto, um efeito \u201cnatural\u201d sem conex\u00f5es com o sistema de metabolismo social do capital. Marx j\u00e1 apontava, em O Capital, como o capitalismo tem um tra\u00e7o epid\u00eamico em sua interioridade e processualidade. O coronav\u00edrus \u00e9 o enfeixamento desta trag\u00e9dia de um sistema que \u00e9 letal em rela\u00e7\u00e3o ao trabalho, \u00e0 natureza, \u00e0 liberdade substantiva entre os g\u00eaneros, as ra\u00e7as, as etnias e tantas outras dimens\u00f5es que temos tratado nos nossos trabalhos, especialmente no Privil\u00e9gio da Servid\u00e3o (Boitempo, 2018), que publiquei recentemente e j\u00e1 saiu uma segunda edi\u00e7\u00e3o atualizada.<\/p>\n<p>Em uma economia destro\u00e7ada, num mundo social devastado e no pior cen\u00e1rio pol\u00edtico do mundo, afinal n\u00e3o h\u00e1 nenhum pa\u00eds do mundo com um cen\u00e1rio pol\u00edtico t\u00e3o brutalmente achincalhado como o nosso, com essa figura grotesca na presid\u00eancia da Rep\u00fablica, o que \u00e9 poss\u00edvel vislumbrar em rela\u00e7\u00e3o ao trabalho? Primeiro \u00e9 preciso dizer uma coisa, tantos autores dos pa\u00edses capitalistas avan\u00e7ados, euroc\u00eantricos em sua maioria, cansaram de dizer, nos anos 1970, 1980 e 1990, que o trabalho tinha perdido relev\u00e2ncia e que n\u00e3o tinha mais import\u00e2ncia. \u00c9 uma mir\u00edade de autores e tenho tratado criticamente desta bibliografia h\u00e1 muitas d\u00e9cadas. A evid\u00eancia do equ\u00edvoco destas teses est\u00e1 limpidamente estampada agora. O trabalho, na medida em que paralisa, o valor n\u00e3o se produz. O desespero do capital e, em particular, do capitalismo global, \u00e9 que sem trabalho o capital n\u00e3o se valoriza. Mas o capital sabe como enfrentar esta dilem\u00e1tica que lhe \u00e9 crucial.<\/p>\n<p>Trabalho e capital<br \/>\nComo o faz? Como ele sabe que n\u00e3o pode prescindir do trabalho, porque sem trabalho n\u00e3o h\u00e1 riqueza, ele pode depauperar, dilapidar e destro\u00e7ar o trabalho, eliminando direitos \u2013 \u00e9 um processo mundial desde 1973, que se agravou a partir de 2008\/2009 com a crise estrutural do sistema de metabolismo social do capital, em que s\u00e3o raros os pa\u00edses do mundo onde isso n\u00e3o ocorre e por isso as reformas de [Michel] Temer [no Brasil], [Maur\u00edcio] Macri [na Argentina] e [Emanuel] Macron [na Fran\u00e7a], no mesmo per\u00edodo, n\u00e3o s\u00e3o coincid\u00eancias.<\/p>\n<p>Que trabalho os capitais querem? Um trabalho cada vez mais desprovido de direitos, mais informal, funcionando como um ap\u00eandice de uma m\u00e1quina que domina o mundo. Um dos elementos centrais do capitalismo decorre do fato de que h\u00e1 um processo t\u00e9cnico-informacional-digital que n\u00e3o para de se desenvolver, mas cujo desenvolvimento \u00e9 estritamente voltado para o sistema de produ\u00e7\u00e3o de riquezas.<\/p>\n<p>Ou seja, trabalho uberizado, com trabalhadores e trabalhadoras (\u00e9 preciso sempre pensar a divis\u00e3o s\u00f3cio-sexual e racial do trabalho), em que o capital pode se utilizar ilimitadamente deste trabalho. \u00c9 por isso que eu tenho dito que o capitalismo da era das plataformas, o capitalismo de plataforma tem um claro tra\u00e7o e se assemelha \u00e0 protoforma do capitalismo. Em pleno s\u00e9culo XXI, com algoritmos, intelig\u00eancia artificial, internet das coisas, big data, ind\u00fastria 4.0, internet 5G e tudo o mais que temos deste arsenal informacional, h\u00e1 pessoas que t\u00eam trabalhado sob crit\u00e9rios t\u00edpicos da servid\u00e3o, por isso o \u201cprivil\u00e9gio da servid\u00e3o\u201d, isto \u00e9, os que tiverem sorte ser\u00e3o servos, ou, mais criticamente ainda, cria-se uma massa de trabalhadores e trabalhadoras que padecem das vicissitudes e dos aspectos nefastos da escravid\u00e3o digital.<\/p>\n<p>IHU On-Line \u2013 O que se pode esperar em termos de desemprego e desigualdades? Qual deve ser o papel do Estado nesse contexto?<\/p>\n<p>Ricardo Antunes \u2013 O que se pode esperar em termos de desemprego e desigualdade \u00e9 aprofundamento. Se estamos em uma sociedade do trabalho pautada pela brutalidade das desigualdades, intensa explora\u00e7\u00e3o global das for\u00e7as de trabalho e pela sua espolia\u00e7\u00e3o, no per\u00edodo da pandemia essas tend\u00eancias v\u00e3o se agravar com enorme profundidade. A Organiza\u00e7\u00e3o Internacional do Trabalho \u2013 OIT est\u00e1 prevendo n\u00edveis alt\u00edssimos de desemprego e eu tenho certeza que ser\u00e3o maiores do que a previs\u00e3o, porque se trata de uma din\u00e2mica dif\u00edcil de medir. Afinal, os dados concretos que temos nas primeiras quatro, cinco semanas de coronav\u00edrus nos Estados Unidos indicam que mais de 26 milh\u00f5es de trabalhadores e trabalhadoras entraram com a solicita\u00e7\u00e3o de seguro-desemprego. No mais rico imp\u00e9rio do mundo, explodiu o desemprego.<\/p>\n<p>Estamos vivendo um capitalismo t\u00f3xico e pand\u00eamico ou a pandemia do capitalismo. O que se pode esperar deste Estado? A quest\u00e3o \u00e9 complexa, ent\u00e3o vejamos:<\/p>\n<p>1) o Estado n\u00e3o \u00e9 um ente pol\u00edtico neutral, o Estado do nosso tempo \u00e9 calibrado, controlado, comandado e impulsionado pelos interesses das grandes corpora\u00e7\u00f5es sob hegemonia do capital financeiro. N\u00e3o podemos ter ilus\u00e3o nenhuma do que devemos esperar do Estado;<\/p>\n<p>2) Apesar disso, e por causo disso, toda a press\u00e3o tem que ser canalizada contra o Estado para exigir dele recursos aos trabalhadores e trabalhadoras da informalidade, que no Brasil somam 40 milh\u00f5es, al\u00e9m dos desempregados, que somam 12 milh\u00f5es no desemprego aberto mais 5 milh\u00f5es no desalento, sem nenhum recurso para sobreviver.<\/p>\n<p>Pandemia capitalista<br \/>\nPor isso a situa\u00e7\u00e3o pand\u00eamica \u00e9 tr\u00e1gica. Ao mesmo tempo que os trabalhadores e trabalhadoras, como todo cidad\u00e3o com o m\u00ednimo de dignidade, deveriam ficar em isolamento social para evitar a letalidade do capitalismo pand\u00eamico, se ficarem em casa est\u00e3o condenados a morrerem de fome. Ent\u00e3o v\u00e3o trabalhar onde \u00e9 poss\u00edvel trabalhar. Na medida em que v\u00e3o ao mercado de trabalho e \u00e0 aglomera\u00e7\u00e3o social, s\u00e3o os candidatos potenciais \u00e0 contamina\u00e7\u00e3o e \u00e0 morte. \u00c9 por isso que a pandemia chegou duramente, agora, de modo brutal na periferia onde moram os trabalhadores. Toda a press\u00e3o ao Estado \u00e9 para migrar, transferir para as periferias os recursos que, especialmente, desde o advento do neoliberalismo t\u00eam sido usados para preservar o mais destrutivo de todos os sistemas de metabolismo que \u00e9 o do capital e, mais ainda, o pior de todos, que \u00e9 o capital financeiro.<\/p>\n<p>IHU On-Line \u2013 Quais s\u00e3o as alternativas e propostas de sa\u00edda para a crise?<\/p>\n<p>Ricardo Antunes \u2013 Se deixarmos o capitalismo responder \u00e0 crise, a resposta do capitalismo \u00e9 clara: p\u00f5e a for\u00e7a de trabalho para trabalhar e, se ela morrer, e \u201cda\u00ed?\u201d, como disse essa figura grotesca que chegou \u00e0 presid\u00eancia do Brasil e colocou o pa\u00eds na condi\u00e7\u00e3o mais aviltada, mundialmente falando, que se viu em toda a sua hist\u00f3ria.<\/p>\n<p>Quais s\u00e3o as sa\u00eddas que n\u00f3s temos? Se a l\u00f3gica do sistema do capital der o tom, ser\u00e1 a destrui\u00e7\u00e3o e vamos conhecer o Inferno de Dante.<\/p>\n<p>Temos que considerar um segundo ponto importante: este \u00e9 um momento crucial em que a humanidade est\u00e1 se perguntando se temos que lutar pelo lucro, pela volta ao trabalho ou pelo enriquecimento de um min\u00fasculo percentual de pessoas \u2013 todos sabemos que os seis empres\u00e1rios brasileiros mais ricos ganham o equivalente ao que produzem cem milh\u00f5es de trabalhadores, o que mostra a absurdidade desta trag\u00e9dia social. Ent\u00e3o, n\u00e3o podemos permitir que o lucro seja o ponto central; temos que fazer a defesa da vida. N\u00e3o se trata de economia e vida; n\u00e3o, a economia \u00e9 destrutiva e \u00e9 causadora da pandemia. A economia do capital n\u00e3o visa sa\u00fade p\u00fablica, educa\u00e7\u00e3o p\u00fablica, previd\u00eancia p\u00fablica, alimenta\u00e7\u00e3o; \u00e9 o destro\u00e7amento. Ent\u00e3o, a quest\u00e3o crucial hoje \u00e9 a luta pela vida.<\/p>\n<p>Luta pela vida<br \/>\nO que significa lutar pela vida? Reinventar um modo de vida. A humanidade hoje tem uma oportunidade excepcional, vive um momento excepcional da hist\u00f3ria, em que ela pode reinventar o modo de vida. Vou dar alguns exemplos que s\u00e3o muito simples. Tem sentido milh\u00f5es de trabalhadores trabalharem 10, 12, 14, 16 horas por dia, como os trabalhadores uberizados e os dos aplicativos, enquanto centenas de outros milh\u00f5es de trabalhadores n\u00e3o t\u00eam nenhum trabalho e vivem nos bols\u00f5es de indig\u00eancia? Pense, por exemplo, na parcela monumental da classe trabalhadora que compreende os trabalhadores imigrantes do mundo global que vivem perambulando de um canto a outro em busca de trabalho. Ent\u00e3o, temos que tratar a quest\u00e3o do trabalho numa dimens\u00e3o central e trabalhar s\u00f3 no estritamente necess\u00e1rio para a produ\u00e7\u00e3o de bens socialmente \u00fateis, com poucas horas de trabalho di\u00e1rio para a produ\u00e7\u00e3o de coisas \u00fateis. Mas isso fere e ataca o sistema de metabolismo social do capital.<\/p>\n<p>\u00c9 preciso reinventar o trabalho humano e social, o trabalho humano como atividade livre, autodeterminada, fundada no tempo dispon\u00edvel contra o trabalho for\u00e7ado, animalizado, estranhado, que tipifica a sociedade do capitalismo informacional da era digital.<\/p>\n<p>Meio ambiente<br \/>\nA quest\u00e3o da natureza \u00e9 outra coisa importante. A destrui\u00e7\u00e3o nos coloca, como Istv\u00e1n M\u00e9sz\u00e1ros disse anos atr\u00e1s, lembrando Rosa Luxemburgo, que o futuro imediato nos coloca a quest\u00e3o do socialismo ou barb\u00e1rie, se tivermos sorte. Esta adi\u00e7\u00e3o de M\u00e9sz\u00e1ros \u00e9 espetacularmente atual: corremos o risco de n\u00e3o termos nem barb\u00e1rie porque estamos num patamar mais profundo, que est\u00e1 num degrau inferior e mais abaixo do que a barb\u00e1rie. A quest\u00e3o da natureza evidencia isso.<\/p>\n<p>Hoje, estamos vendo que as cidades brasileiras que est\u00e3o em isolamento social reduziram muito o n\u00edvel de polui\u00e7\u00e3o ambiental por dois motivos: os carros pararam de circular feito loucos e as ind\u00fastrias pararam de produzir. N\u00e3o \u00e9 dif\u00edcil perceber que recuperar uma dimens\u00e3o da natureza \u00e9 vital e isso significa que \u00e9 preciso parar o consumo destrutivo. \u00c9 importante entender que essa no\u00e7\u00e3o que vem de Marx, com a qual trabalhamos, do sistema de metabolismo social do capital, coloca uma quest\u00e3o vital: o sistema de metabolismo social do capital destr\u00f3i o trabalho, destr\u00f3i a humanidade e destr\u00f3i a natureza. \u00c9 preciso reinventar um outro sistema de metabolismo social contr\u00e1rio aos imperativos destrutivos do sistema de capital. Isso vale para quando pensamos na quest\u00e3o da liberdade substantiva, da emancipa\u00e7\u00e3o efetiva entre os g\u00eaneros. Isso \u00e9 vital quando se pensa na luta contra o racismo, contra a xenofobia, contra a homofobia, contra o sexismo, contra a cultura visceral e indigente da ignor\u00e2ncia.<\/p>\n<p>Temos hoje o mundo dos ignorantes; \u00e9 como se cultuar a ignor\u00e2ncia fosse o top. Isso mostra a indig\u00eancia do mundo em que estamos. S\u00f3 sairemos disso atrav\u00e9s das lutas das periferias, das comunidades ind\u00edgenas, da classe trabalhadora masculina, feminina, branca, negra, ind\u00edgena, da juventude, do movimento dos negros, da revolu\u00e7\u00e3o feminista &#8211; h\u00e1 uma revolu\u00e7\u00e3o feminista em curso e \u00e9 vital que ela adira, como muitos dos seus setores v\u00eam fazendo, a uma luta contra a opress\u00e3o masculina, contra a opress\u00e3o de g\u00eanero e contra as formas de opress\u00e3o e domina\u00e7\u00e3o do capital. Estamos num momento em que o imperativo \u00e9 reinventar outro modo de vida e a quest\u00e3o vital do nosso tempo \u00e9: temos que lutar pela vida e n\u00e3o pelo lucro.<\/p>\n<p>IHU On-Line \u2013 Que mudan\u00e7as de fundo vislumbra no mundo do trabalho?<\/p>\n<p>Clemente Ganz L\u00facio \u2013 O mundo do trabalho j\u00e1 passava, mesmo antes da crise sanit\u00e1ria, por um processo disruptivo, ou seja, um novo mundo do trabalho irrompia na base do sistema produtivo. Trata-se de uma transforma\u00e7\u00e3o profunda e radical promovida pelos avan\u00e7os tecnol\u00f3gicos em termos de energia, transporte e comunica\u00e7\u00e3o, com a expans\u00e3o para todos os setores econ\u00f4micos da intelig\u00eancia artificial, com os novos materiais, entre tantos outros elementos e fatores que irrompem no sistema produtivo e em um ambiente de globaliza\u00e7\u00e3o comandada hegemonicamente pelos interesses financeiros. Postos de trabalho s\u00e3o fechados, ocupa\u00e7\u00f5es desmobilizadas e profiss\u00f5es destru\u00eddas.<\/p>\n<p>A crise sanit\u00e1ria \u00e9 in\u00e9dita na velocidade de difus\u00e3o da contamina\u00e7\u00e3o, da agressividade sobre a sa\u00fade, os impactos sobre o sistema de sa\u00fade levam-no ao colapso, com mortes que tendem a chegar a milh\u00f5es. O isolamento social \u00e9 a \u00fanica alternativa de combate \u00e0 epidemia, mas que leva ao travamento de todo o sistema produtivo em todos os pa\u00edses, de maneira global e no mesmo tempo. Desemprego em massa e destrui\u00e7\u00e3o de empresas. Recess\u00e3o em magnitude incalcul\u00e1vel neste momento (proje\u00e7\u00f5es atuais de -6% PIB no Brasil) com risco de descambar para a depress\u00e3o econ\u00f4mica no pa\u00eds e no mundo.<\/p>\n<p>A trag\u00e9dia econ\u00f4mica pode conduzir para um colapso social com grav\u00edssimos desdobramentos sobre a coes\u00e3o social.<\/p>\n<p>Como prospectar o futuro pr\u00f3ximo no qual a expans\u00e3o da crise pode se desdobrar para uma situa\u00e7\u00e3o de caos econ\u00f4mico e social com reflexos complexos do ponto de vista pol\u00edtico? \u00c9 conduzir a nau do mundo em mar revoltoso e com um nevoeiro absoluto.<\/p>\n<p>Um mundo novo \u00e9 poss\u00edvel<br \/>\nSim, os riscos de sa\u00eddas autorit\u00e1rias existem e devemos articular um amplo leque de resist\u00eancia. As sa\u00eddas devem ser mobilizadas para a perspectiva de que \u201cum mundo novo \u00e9 poss\u00edvel\u201d. Trata-se de disputar a estrat\u00e9gia de sa\u00edda que deve conter a perspectiva de supera\u00e7\u00e3o do modelo vigente. N\u00e3o se trata de voltar ao mundo do passado recente. Voltar para a \u201cnormalidade\u201d \u00e9 ingressar novamente no mundo que criou esse caos. Trata-se, portanto, de enfrentar o desafio criativo de inventar um novo mundo. Mas isso \u00e9 um campo de disputa dura.<\/p>\n<p>H\u00e1 um alto risco de um mundo ainda mais desigual, com mais pobreza e mis\u00e9ria, com regimes autorit\u00e1rios de diferentes matizes. Os impactos para o mundo do trabalho ser\u00e3o dram\u00e1ticos. As condi\u00e7\u00f5es de vida e o meio ambiente ser\u00e3o ainda mais agredidos se vencer a volta ao passado.<\/p>\n<p>IHU On-Line \u2013 O que se pode esperar em termos de desemprego e desigualdades? Qual deve ser o papel do Estado nesse contexto?<\/p>\n<p>Clemente Ganz L\u00facio \u2013 Podemos ter no Brasil mais de 20 milh\u00f5es de desempregados, mais 35 milh\u00f5es de subocupados, postos de trabalho flex\u00edveis e prec\u00e1rios se expandindo no mundo formal. Essa destrui\u00e7\u00e3o agravar\u00e1 as desigualdades com pobreza e mis\u00e9ria em alta.<\/p>\n<p>Cabe ao Estado proteger as empresas e organiza\u00e7\u00f5es do sistema produtivo e os empregos. Para isso, \u00e9 fundamental sustentar a renda do trabalho por meio do aporte do Tesouro para pagar os sal\u00e1rios e o abono emergencial para garantir renda dos trabalhadores informais, sustentando a demanda econ\u00f4mica. In\u00fameras outras medidas devem ser mobilizadas que poder\u00e3o custar o equivalente a mais de 20% do PIB. Exige-se uma opera\u00e7\u00e3o complexa de economia pol\u00edtica.<\/p>\n<p>De imediato, \u00e9 fundamental o Estado atuar para promover crescente capacidade para o sistema de sa\u00fade proteger as vidas; atuar para garantir o abastecimento de alimentos, bens e servi\u00e7os de primeira necessidade e os insumos para o sistema de sa\u00fade. O Estado deve mobilizar e organizar a capacidade da sociedade para estruturar formas de distanciamento social que garantam a sa\u00fade daqueles que gradualmente voltar\u00e3o \u00e0s atividades dos diferentes setores, e de imediato, de todos os que est\u00e3o nas frentes de sa\u00fade e de servi\u00e7os essenciais. O Estado deve, ainda, produzir um plano de retomada da atividade econ\u00f4mica como parte de um projeto de desenvolvimento econ\u00f4mico e social.<\/p>\n<p>Mas tudo isso com esse governo federal? Estamos em uma situa\u00e7\u00e3o muito cr\u00edtica.<\/p>\n<p>IHU On-Line \u2013 Quais s\u00e3o as alternativas e propostas de sa\u00edda para a crise?<\/p>\n<p>Clemente Ganz L\u00facio \u2013 Apesar das grav\u00edssimas e desafiadoras adversidades, a vida continuar\u00e1 e ser\u00e1 sobre essas condi\u00e7\u00f5es objetivas que se deve atuar no campo pol\u00edtico para se criarem as condi\u00e7\u00f5es de resist\u00eancia e avan\u00e7o.<\/p>\n<p>A emerg\u00eancia da cat\u00e1strofe ambiental acompanhar\u00e1 as novas crises sanit\u00e1rias que vir\u00e3o. Isso exigir\u00e1 novos protocolos e organiza\u00e7\u00e3o social e econ\u00f4mica. Um projeto de futuro deve colocar na centralidade o desafio social e ambiental, como partes insepar\u00e1veis, e imaginar criativamente um novo modelo de exist\u00eancia coletiva e de produ\u00e7\u00e3o econ\u00f4mica cooperada.<\/p>\n<p>Contra a meritocracia e a competi\u00e7\u00e3o, a solidariedade e a coopera\u00e7\u00e3o. Esse novo projeto de desenvolvimento social, econ\u00f4mico, pol\u00edtico e ambiental deve visar criar ocupa\u00e7\u00f5es para todos, com jornada de trabalho reduzida para que todos trabalhem, com renda garantida e ampla prote\u00e7\u00e3o social por meio de pol\u00edticas de educa\u00e7\u00e3o, sa\u00fade, moradia, transporte, seguran\u00e7a, entre outras, universais.<\/p>\n<p>O trabalho deve voltar a ter centralidade no projeto de desenvolvimento. O incremento da produtividade deve gerar ganhos sociais coletivos para produzir o bem-estar de todos e um bom modo de coletivamente viver, com as virtuosas diferen\u00e7as que nos constituem como ser humano em uma sociedade intencionalmente igualit\u00e1ria.<\/p>\n<p>IHU On-Line \u2013 Que mudan\u00e7as de fundo vislumbra no mundo do trabalho?<\/p>\n<p>Jos\u00e9 Dari Krein \u2013 O cen\u00e1rio mais prov\u00e1vel no curto prazo \u00e9 um grande avan\u00e7o na desestrutura\u00e7\u00e3o do mercado de trabalho com a explos\u00e3o do desemprego aberto, dada pela perspectiva de que estamos come\u00e7ando um per\u00edodo de queda muito acentuada da economia, inclusive com muitos indicando que estaremos entrando em uma depress\u00e3o. O problema \u00e9 potencializado pelas pol\u00edticas hegem\u00f4nicas de car\u00e1ter neoliberal, a forma de inser\u00e7\u00e3o na globaliza\u00e7\u00e3o financeira em curso, particularmente como o Brasil respondeu \u00e0 crise de 2015\/2016, adotando uma agenda fiscalista e de redu\u00e7\u00e3o de direitos e prote\u00e7\u00e3o social, como pode ser exemplificado na reforma trabalhista.<\/p>\n<p>A situa\u00e7\u00e3o se complica ainda mais, pois est\u00e3o em curso expressivas inova\u00e7\u00f5es tecnol\u00f3gicas, que redesenham o mundo do trabalho e tendem a, na maioria dos setores, serem poupadoras de trabalho. As fortes inova\u00e7\u00f5es, em um contexto de hegemonia neoliberal, foram acompanhadas de pol\u00edticas p\u00fablicas de que os indiv\u00edduos s\u00e3o respons\u00e1veis pela sua inser\u00e7\u00e3o no mercado de trabalho (empregabilidade e empreendedorismo), combinadas com a l\u00f3gica de redu\u00e7\u00e3o dos servi\u00e7os sociais do Estado. Processo, por um lado, que fez redistribuir desigualmente os ganhos de produtividade para o capital em detrimento do Estado e dos trabalhadores.<\/p>\n<p>Por outro lado, na perspectiva de submeter todos \u00e0 l\u00f3gica da concorr\u00eancia, deixou os trabalhadores em condi\u00e7\u00f5es mais vulner\u00e1veis com as retiradas de direitos e prote\u00e7\u00f5es sociais. Ou seja, os ganhos de produtividade nos setores mais din\u00e2micos n\u00e3o foram acompanhados, como aconteceu ap\u00f3s a Segunda Revolu\u00e7\u00e3o Industrial, por uma redu\u00e7\u00e3o da jornada de trabalho e nem pela amplia\u00e7\u00e3o expressiva de servi\u00e7os p\u00fablicos (grande gerador de emprego). Ademais, a abertura fez com que muitas atividades que eram produzidas internamente passassem a ser realizadas fora do pa\u00eds, fazendo com que a ind\u00fastria perdesse participa\u00e7\u00e3o progressiva no PIB e no emprego.<\/p>\n<p>Assim, gera-se uma situa\u00e7\u00e3o nova de reconfigura\u00e7\u00e3o da classe trabalhadora, com a aloca\u00e7\u00e3o no setor de servi\u00e7os e cria\u00e7\u00e3o de situa\u00e7\u00e3o de crescente polariza\u00e7\u00e3o das ocupa\u00e7\u00f5es e renda, em uma concorr\u00eancia desenfreada de todos contra todos para ocupar as insuficientes ocupa\u00e7\u00f5es existentes. A maioria teve que se inserir em atividades mais prec\u00e1rias, de baixos sal\u00e1rios, pois dependem da for\u00e7a de trabalho para sobreviver, o que refor\u00e7ou que o trabalho \u00e9 simplesmente um meio para adquirir renda. Outra importante parte n\u00e3o conseguiu se inserir no emprego formal e teve que encontrar estrat\u00e9gias de sobreviv\u00eancia na informalidade e por conta pr\u00f3pria, buscando oportunidades de auferir renda, oferecendo servi\u00e7os e produtos. Assim h\u00e1 o fen\u00f4meno da precariza\u00e7\u00e3o estrutural do trabalho e da vira\u00e7\u00e3o.<\/p>\n<p>Agravamento de um quadro<br \/>\n\u00c9 verdade que n\u00e3o s\u00e3o fen\u00f4menos novos, especialmente no Brasil, que nunca chegou a estruturar o mercado de trabalho. A novidade \u00e9 que a vira\u00e7\u00e3o, processo de adapta\u00e7\u00e3o para sobreviver, n\u00e3o \u00e9 mais um fen\u00f4meno restrito aos setores que est\u00e3o na base da pir\u00e2mide social, pois atinge tamb\u00e9m segmentos m\u00e9dios da sociedade brasileira. Por exemplo, muitos de n\u00f3s conhecemos profissionais que tiveram que inventar algum trabalho para sobreviver porque n\u00e3o conseguiram se reinserir no mercado de trabalho &#8211; um engenheiro qualificado que vira motorista de Uber, um cientista social que abre um \u201cempreendimento\u201d. P\u00f3s-crise de 2015\/2016 houve um aumento forte do n\u00famero de cozinheiros(as), confeiteiros(as), motoristas, vendedores(as) de todo tipo etc.<\/p>\n<p>Esse processo de adapta\u00e7\u00e3o tamb\u00e9m est\u00e1 relacionado com as tecnologias dispon\u00edveis, o padr\u00e3o de consumo, a desigualdade social e com o modo de vida prevalecente de mercantilizar todas as esferas da vida.<\/p>\n<p>Polariza\u00e7\u00f5es das ocupa\u00e7\u00f5es e rendas<br \/>\n\u00c9 o fen\u00f4meno da polariza\u00e7\u00e3o das ocupa\u00e7\u00f5es e renda, em que as diferen\u00e7as de rendimentos e tipo de ocupa\u00e7\u00e3o se acentuam. \u00c9 a \u201cmcdonaliza\u00e7\u00e3o\u201d dos empregos x empregos qualificados e socialmente reconhecidos em que o rendimento \u00e9 muito acentuado. Dois exemplos. Um executivo de uma empresa ganhava 30 vezes mais do que um trabalhador no ch\u00e3o de f\u00e1brica no final da d\u00e9cada de 1960. No final da primeira d\u00e9cada dos anos 2000, passou a ganhar 296 vezes mais. Agora outro exemplo vinculado bem atual. O sal\u00e1rio m\u00e9dio do m\u00e9dico, segundo a Pesquisa Nacional por Amostra de Domic\u00edlios Cont\u00ednua &#8211; PNADC, \u00e9 dez vezes maior do que do profissional de n\u00edvel m\u00e9dio da sa\u00fade. N\u00e3o que o m\u00e9dico ganhe muito, mas o profissional de n\u00edvel m\u00e9dio \u00e9 que ganha muito pouco, pois a maioria dos ocupados est\u00e1 em condi\u00e7\u00e3o muito prec\u00e1ria.<\/p>\n<p>Tamb\u00e9m h\u00e1 uma progressiva concentra\u00e7\u00e3o nas atividades de servi\u00e7os. O grande setor cresceu 11% em tamanho entre 2012 e 2019, segundo a PNADC, e representa 78% do total dos ocupados. No mesmo per\u00edodo a ocupa\u00e7\u00e3o agr\u00edcola caiu 17% e a ind\u00fastria, 7%. O setor de servi\u00e7os \u00e9 marcado por uma profunda heterogeneidade e muito mais segmentado. No geral, muitas ocupa\u00e7\u00f5es de servi\u00e7os apresentam rela\u00e7\u00e3o com a reorganiza\u00e7\u00e3o na forma de produ\u00e7\u00e3o de bens e servi\u00e7os, terceiriza\u00e7\u00e3o, concentra\u00e7\u00e3o de renda (pessoais, tais como o peso dos servi\u00e7os dom\u00e9sticos na nossa estrutura ocupacional), mudan\u00e7as de h\u00e1bitos\/lazer, mudan\u00e7a do perfil da popula\u00e7\u00e3o, demandas de novos padr\u00f5es de consumo, estrat\u00e9gias de sobreviv\u00eancia etc. \u00c9 parte tamb\u00e9m de um processo de mercantiliza\u00e7\u00e3o de todas as esferas da vida, mas tamb\u00e9m do fen\u00f4meno da vira\u00e7\u00e3o. O importante \u00e9 que grande parte dos servi\u00e7os tamb\u00e9m significou a amplia\u00e7\u00e3o de ocupa\u00e7\u00f5es prec\u00e1rias. Por exemplo, cresceu muito fortemente nos \u00faltimos tempos os servi\u00e7os de terceiriza\u00e7\u00e3o (1\/3 do total dos empregos formais um ano ap\u00f3s a reforma trabalhista entrar em vigor).<\/p>\n<p>O impacto da tecnologia<br \/>\n\u00c9 preciso ainda afirmar que a tend\u00eancia \u00e9 uma acelera\u00e7\u00e3o da introdu\u00e7\u00e3o de inova\u00e7\u00f5es tecnol\u00f3gicas (automa\u00e7\u00e3o, intelig\u00eancia artificial, internet das coisas), em geral poupadoras de for\u00e7a de trabalho, especialmente em setores mais din\u00e2micos da economia nos tr\u00eas setores econ\u00f4micos (agricultura, ind\u00fastria e diversos servi\u00e7os). \u00c9 verdade que se criam novas ocupa\u00e7\u00f5es, mas em n\u00famero menor do que \u00e9 necess\u00e1rio para proporcionar trabalhos \u00fateis para os que precisam trabalhar. As inova\u00e7\u00f5es v\u00e3o reconfigurando a forma de realizar o trabalho em muitos segmentos, inclusive redefinindo as fun\u00e7\u00f5es e as ocupa\u00e7\u00f5es. O processo deve se intensificar.<\/p>\n<p>Por um lado, acho que h\u00e1 uma tend\u00eancia de deslocaliza\u00e7\u00e3o da produ\u00e7\u00e3o de bens para as regi\u00f5es mais pr\u00f3ximas dos consumidores, com uma crescente desglobaliza\u00e7\u00e3o, que deve se acelerar com a atual pandemia. Essa op\u00e7\u00e3o tende a constituir plantas de produ\u00e7\u00e3o mais enxutas e utilizando maior tecnologia na busca de reduzir os custos de produ\u00e7\u00e3o. Por outro lado, muitas tecnologias dispon\u00edveis tender\u00e3o a ser mais utilizadas ap\u00f3s a experi\u00eancia do isolamento social, do home office, da compra por internet etc.<\/p>\n<p>Tamb\u00e9m \u00e9 verdade que algumas ocupa\u00e7\u00f5es ganharam visibilidade na crise, especialmente aquelas consideradas essenciais para preserva\u00e7\u00e3o da vida e a necessidade de um olhar mais atento aos problemas ambientais, que podem ser geradores de empregos.<\/p>\n<p>Ou seja, dentro dos par\u00e2metros pol\u00edticos atuais, a situa\u00e7\u00e3o do trabalho \u00e9 muito preocupante no futuro pr\u00f3ximo, pois n\u00e3o haver\u00e1 ocupa\u00e7\u00e3o para todas as pessoas. \u00c9 um imenso desafio a ser enfrentado por aqueles que pensam na necessidade de ter uma sociedade pelo menos civilizada.<\/p>\n<p>IHU On-Line \u2013 O que se pode esperar em termos de desemprego e desigualdades? Qual deve ser o papel do Estado nesse contexto?<\/p>\n<p>Jos\u00e9 Dari Krein \u2013 Caso prevale\u00e7a a orienta\u00e7\u00e3o atual de pol\u00edtica econ\u00f4mica, a tend\u00eancia \u00e9 em poucos meses ocorrer uma explos\u00e3o do desemprego, especialmente do desemprego aberto, com o fechamento de muitas empresas, sobretudo pequenas e m\u00e9dias, que ir\u00e1 atingir de forma diferenciada os diversos setores de atividade. Apesar das medidas adotadas (Medida Provis\u00f3ria 927 e 936), a queda da massa de rendimentos ser\u00e1 enorme, mesmo que os empregos sejam mantidos temporariamente.<\/p>\n<p>A perda come\u00e7a a se evidenciar nas atuais pol\u00edticas de redu\u00e7\u00e3o de sal\u00e1rio e jornada, de suspens\u00e3o do contrato, de corte brutal da renda dos informais e por conta pr\u00f3pria. Estudos dos colegas do Centro de Estudos Sindicais e de Economia do Trabalho &#8211; Cesit, Pietro Borsari e Marcelo Manzano, projetam uma queda de 8,9 bilh\u00f5es ao m\u00eas caso as medidas sejam bem-sucedidas. No entanto, a previs\u00e3o \u00e9 uma queda substantiva do n\u00edvel de atividade econ\u00f4mica com consequ\u00eancia s\u00e9ria nas empresas e neg\u00f3cios e, consequentemente, de despedidas. Assim como levar\u00e1 a um agravamento financeiro dos estados e munic\u00edpios com a queda da arrecada\u00e7\u00e3o, que ter\u00e1 um efeito cascata de inibi\u00e7\u00e3o do investimento e, consequentemente, de despedidas.<\/p>\n<p>Ou seja, a perspectiva \u00e9 de uma brutal recess\u00e3o ou at\u00e9 depress\u00e3o da economia, especialmente se o governo continuar com a tese de acentuar uma pol\u00edtica baseada na austeridade fiscal, que implica reduzir o gasto p\u00fablico. O governo anunciou que n\u00e3o ir\u00e1 renovar as ajudas emergenciais adotadas em abril: R$ 600,00 por tr\u00eas meses para os informais e por conta pr\u00f3pria, financiamento da suspens\u00e3o dos contratos por dois meses e da redu\u00e7\u00e3o de jornada e sal\u00e1rios por tr\u00eas meses. A crise atual pode colapsar a economia nacional, inclusive desestruturando elos de produ\u00e7\u00e3o e presta\u00e7\u00e3o de servi\u00e7os, combinado com entraves nas engrenagens da economia internacional.<\/p>\n<p>Na crise, mais desigualdade<br \/>\nA possibilidade de uma explos\u00e3o do desemprego refor\u00e7a as desigualdades existentes no mercado de trabalho, com claro recorte de ra\u00e7a e sexo. As hist\u00f3ricas discrimina\u00e7\u00f5es e exclus\u00f5es s\u00e3o refor\u00e7adas na crise. A desigualdade dos rendimentos do trabalho voltou a crescer nos \u00faltimos anos. O \u00edndice de Gini entre os com renda positiva (exclui os sem rendimentos e os desempregados) subiu entre 2017 e 2019.<\/p>\n<p>Um indicador para mostrar a desestrutura\u00e7\u00e3o do nosso mercado de trabalho \u00e9 que 450 milh\u00f5es de pessoas foram eleg\u00edveis para receber o aux\u00edlio emergencial de R$ 600,00, sendo que est\u00e3o exclu\u00eddos os de maior renda, os contratados disfar\u00e7ados como pessoa jur\u00eddica (PJs). \u00c9 um n\u00famero impressionante que corresponde a mais de metade do total dos ocupados na PNADC, em final de 2019.<\/p>\n<p>Fun\u00e7\u00e3o do Estado<br \/>\nA a\u00e7\u00e3o primeira do Estado \u00e9 garantir a renda para as fam\u00edlias e, consequentemente o emprego. Assume a fun\u00e7\u00e3o de financiar a renda das fam\u00edlias e ao mesmo tempo assegura que n\u00e3o pode ocorrer demiss\u00e3o. Na contram\u00e3o de muitos outros pa\u00edses, o governo brasileiro ao adotar as medidas n\u00e3o exige contrapartida de manuten\u00e7\u00e3o do emprego das empresas beneficiadas.<\/p>\n<p>A travessia desej\u00e1vel da atual tempestade somente \u00e9 poss\u00edvel por meio da atua\u00e7\u00e3o do Estado. A realidade mostra que o mercado autorregulado \u00e9 incapaz de responder ao tamanho da crise. Muitos, inclusive o governo brasileiro, acham que podem continuar com a sua agenda neoliberal, mas n\u00e3o h\u00e1 possibilidade de sa\u00edda sem o Estado.<\/p>\n<p>O desej\u00e1vel \u00e9 que o Estado garanta a renda das fam\u00edlias no momento do isolamento social, que ir\u00e1 contribuir para preservar vidas \u2013 o que \u00e9 fundamental \u2013 e tamb\u00e9m facilitar a recupera\u00e7\u00e3o econ\u00f4mica p\u00f3s-pandemia. Mas \u00e9 preciso ir al\u00e9m, o Estado tem a fun\u00e7\u00e3o de garantir as condi\u00e7\u00f5es de funcionamento da economia na perspectiva de assegurar a seguran\u00e7a alimentar, uma reconvers\u00e3o industrial para suprir a falta de equipamentos hospitalares, a amplia\u00e7\u00e3o das estruturas de atendimento das pessoas e os problemas de log\u00edstica e infraestrutura, entre outros, em um momento excepcional. Inclusive muitas atividades, especialmente as essenciais para preserva\u00e7\u00e3o da vida, precisam ser desmercantilizadas na perspectiva de garantir um acesso universal e geral para o conjunto da popula\u00e7\u00e3o. Ou seja, como est\u00e1 no documento do GT &#8211; mundos do Trabalho: Reformas, do CESIT, \u201cEmprego, Trabalho e Renda para garantir o direito \u00e0 Vida\u201d, o \u201cmomento exige uma profunda transforma\u00e7\u00e3o do papel do Estado. Para isso, sua atua\u00e7\u00e3o precisa voltar-se para a crescente desmercantiliza\u00e7\u00e3o das rela\u00e7\u00f5es econ\u00f4micas, ampliando seu papel na coordena\u00e7\u00e3o e no planejamento da produ\u00e7\u00e3o e distribui\u00e7\u00e3o de bens e servi\u00e7os, seja para enfrentar as urg\u00eancias desse momento de crise, seja para evitar, no p\u00f3s-crise, que a sociedade se limite a atender exclusivamente as demandas dos neg\u00f3cios particulares. Al\u00e9m disso, para dar conta dos problemas recorrentes da \u2018parada s\u00fabita\u2019 dos mercados, \u00e9 inescap\u00e1vel a tarefa de injetar liquidez na economia, com direcionamento do cr\u00e9dito e cr\u00e9dito subsidiado, a fim de garantir a rearticula\u00e7\u00e3o das rela\u00e7\u00f5es entre os agentes econ\u00f4micos\u201d.<\/p>\n<p>Condi\u00e7\u00f5es dignas de trabalho<br \/>\nTamb\u00e9m \u00e9 importante destacar que \u00e9 papel do Estado garantir que todos os trabalhadores precisam ter asseguradas condi\u00e7\u00f5es dignas de trabalho, os seus direitos e a prote\u00e7\u00e3o social. Inclusive muitos que est\u00e3o em atividades essenciais trabalham na informalidade e sem direitos. Por exemplo, os entregadores por aplicativo com o delivery, trabalham para enriquecer propriet\u00e1rios de plataformas que lhes sonegam o direito de ter carteira assinada. A Remir (Rede de Estudos e Monitoramento Interdisciplinar da Reforma Trabalhista) fez uma nota p\u00fablica chamando aten\u00e7\u00e3o para o absurdo desta situa\u00e7\u00e3o de n\u00e3o reconhecimento do v\u00ednculo de emprego e consequentemente de proteger esses trabalhadores.<\/p>\n<p>Uma crise politica e um governo que descoordena as a\u00e7\u00f5es trazem problemas adicionais para enfrentamento da crise e manejar o barco da travessia e p\u00f3s crise.<\/p>\n<p>IHU On-line \u2013 Quais s\u00e3o as alternativas e propostas de sa\u00edda para a crise?<\/p>\n<p>Jos\u00e9 Dari Krein \u2013 A primeira quest\u00e3o de curto prazo \u00e9 garantir renda para as fam\u00edlias, trabalho, os direitos trabalhistas e a prote\u00e7\u00e3o social e assegurar condi\u00e7\u00f5es de trabalho para todos que est\u00e3o inseridos em atividades essenciais, permitindo a efetiva\u00e7\u00e3o do isolamento \u2013 que \u00e9 a principal recomenda\u00e7\u00e3o cient\u00edfica para enfrentar a atual pandemia \u2013 e a continuidade da subsist\u00eancia e dos cuidados da popula\u00e7\u00e3o.<\/p>\n<p>A renda \u00e9 fundamental tanto para os formais quanto para os informais; assim, seria importante tornar a renda emergencial em permanente na perspectiva de assegurar uma condi\u00e7\u00e3o m\u00ednima de acesso a todos e todas de condi\u00e7\u00f5es sobreviv\u00eancia. Mas precisa vir acompanhada de outras iniciativas como veremos abaixo.<\/p>\n<p>Valorizar os profissionais e assegurar condi\u00e7\u00f5es de trabalho aos que est\u00e3o na linha de frente, em atividades essenciais, \u00e9 fundamental. N\u00e3o podemos continuar perdendo tantas vidas por falta de condi\u00e7\u00f5es m\u00ednimas de trabalho, como est\u00e1 ocorrendo atualmente. Por isso, \u00e9 fundamental assegurar uma jornada compat\u00edvel com a atividade (no caso da sa\u00fade a Organiza\u00e7\u00e3o Mundial da Sa\u00fade &#8211; OMS recomenda que seja de 6 horas di\u00e1rias), intervalos de descanso, meio ambiente de trabalho salubre e n\u00e3o estressante, equipamentos de prote\u00e7\u00e3o, sal\u00e1rios condizentes, direitos, alimenta\u00e7\u00e3o e log\u00edstica para o trabalho.<\/p>\n<p>A crise pode nos levar a repensar o nosso padr\u00e3o de consumo e de vida social, o que implica tamb\u00e9m redefinir socialmente que atividades s\u00e3o importantes de serem desenvolvidas para o bem-estar geral da sociedade. Neste sentido, h\u00e1 a necessidade de redefini\u00e7\u00e3o das atividades \u00fateis e uma redistribui\u00e7\u00e3o delas entre todas as pessoas, pois a tend\u00eancia n\u00e3o \u00e9 ter emprego para todos, o que levar\u00e1 necessariamente a pensar o nosso padr\u00e3o de desenvolvimento, que inclua a dimens\u00e3o da sustentabilidade ambiental e que assegure uma condi\u00e7\u00e3o de vida digna para o conjunto da sociedade.<\/p>\n","protected":false},"excerpt":{"rendered":"<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/25486\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[9],"tags":[226],"class_list":["post-25486","post","type-post","status-publish","format-standard","hentry","category-s10-internacional","tag-4b"],"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p659gw-6D4","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/25486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=25486"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/25486\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=25486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=25486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=25486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}