{"id":25748,"date":"2020-06-25T21:50:38","date_gmt":"2020-06-26T00:50:38","guid":{"rendered":"https:\/\/pcb.org.br\/portal2\/?p=25748"},"modified":"2020-06-28T22:49:24","modified_gmt":"2020-06-29T01:49:24","slug":"nossas-vidas-entregues-ao-capital-nao-a-privatizacao","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/25748","title":{"rendered":"Nossas vidas entregues ao capital: n\u00e3o \u00e0 privatiza\u00e7\u00e3o!"},"content":{"rendered":"<p><img decoding=\"async\" class=\"imagem\" title=\"imagem\" src=\"https:\/\/i0.wp.com\/lh3.googleusercontent.com\/prAAzbErE1iaIAmomiIyMBca6NUIu7XXfdG6rW_QjL0IgvTYZB95P-ZAfPNf8wNqv9XGduWWQP8lczLBMhtE6t5aDxlCootglnLFSm3qmGxD8vhyemY-jNlucxn2y0sfXKySVib1SkNoR9sWghzjV3upi0sdCZvDkfPtpHy7rZiX4ne0lddycQN7whV-4iPHeTByWC5WxubGB2MS3SbXNZLy3THbPnmHMCWFZ8JyXSn6o3JqsqUAOvMT5NAHhbrc2aTanGGa6IWrCk0WOZZ42soEflBbhNzwqGWIXw7FILA8ZYfgYDx-FC_s0DxvLQvWsSPqFyGJuZLLnF03vH3RWveOgbpWMGSxOy6eu7J6WgKDar9HLgIKW3d8A9biWs2aruMp7i8hhph-yLilzIV0-gFnl8gA72qIjDJWgOGCWr8FeOyWfAGqH-7me-vAngSHeMOm0-DzH-7aFk23-bDch4MnjK47nifzni68ZtI0f_PbIzBB945tgvOxBsGHSyuc3w6Nxxe3wdW32DdNdmnNWzqMQn7su4qgtonnkFoHed5L5DZ1O2YldrEgWGuF3MXLmfJw6tEdt6nVID_z6xg3-6rY2WNHT5KE6MoTEzXMlUPPniICJXrkswA-hhdl8uxF9pKglU2WP9ZfBQOgg_poZTs3WPyjPSuqSUjH6wlkFA=w933-h646-no\" alt=\"imagem\" \/><!--more-->Eduardo Grandi, trabalhador em saneamento e militante do PCB<\/p>\n<p>O pa\u00eds com as maiores reservas de \u00e1gua do mundo levar\u00e1 a cabo o maior programa de privatiza\u00e7\u00e3o da \u00e1gua no mundo. Projeto de autoria de Bolsonaro e do senador Tasso Jereissati (PSDB-CE), dono de uma subsidi\u00e1ria da Coca Cola, \u00e9 um retrocesso monumental que abre a temporada \u00e0 maior onda de saques ao patrim\u00f4nio p\u00fablico desde a restaura\u00e7\u00e3o capitalista no Leste Europeu nos anos de 1990.<\/p>\n<p>Atualmente, os munic\u00edpios podem licitar os principais servi\u00e7os de saneamento (tratamento de \u00e1gua, esgoto e manejo de res\u00edduos s\u00f3lidos), firmar conv\u00eanio com companhias estaduais, ou at\u00e9 mesmo prest\u00e1-los diretamente. Com o PL 4162, aprovado na quarta-feira 24 no Senado, os munic\u00edpios n\u00e3o ter\u00e3o mais escolha. Dever\u00e3o, \u00fanica e exclusivamente, licitar os novos contratos. Na pr\u00e1tica, empresas p\u00fablicas n\u00e3o conseguem participar de licita\u00e7\u00f5es, o que tende \u00e0 completa privatiza\u00e7\u00e3o das companhias estaduais e municipais de saneamento do Brasil inteiro no m\u00e9dio e longo prazo. A lei tamb\u00e9m remove entraves legais \u00e0 privatiza\u00e7\u00e3o de companhias estaduais, abrindo espa\u00e7o para a venda da maioria das empresas estaduais, como Cedae, Copasa, Sabesp e outras.<\/p>\n<p>A baixa cobertura (52% dos brasileiros n\u00e3o t\u00eam coleta de esgoto) e a m\u00e1 qualidade dos servi\u00e7os prestados no modelo atual, pretexto para medida t\u00e3o brutal, foram causados em grande parte pelos mesmos pol\u00edticos que agora ganham com a privatiza\u00e7\u00e3o, no famoso m\u00e9todo de criar dificuldades para vender facilidades. A facilidade ser\u00e3o as maiores reservas de \u00e1gua pot\u00e1vel do mundo (12% do total se encontra no Brasil), objeto de cobi\u00e7a do grande capital privado transnacional.<\/p>\n<p>O saneamento jamais ser\u00e1 trazido \u00e0s cidades pequenas e pobres (portanto, deficit\u00e1rias) do interior pela l\u00f3gica do lucro. E mesmo que se traga, ser\u00e1 \u00e0s custas de um aumento brutal nas tarifas. Nosso povo pobre n\u00e3o poder\u00e1 acessar os servi\u00e7os pelo custo, a menos que se multipliquem os subs\u00eddios \u00e0s tarifas sociais, que ser\u00e3o pagos, obviamente, por nossos impostos. De uma forma ou de outra, com ou sem saneamento, o povo ter\u00e1 mais uma vez de bancar o lucro privado.<\/p>\n<p>Por esse motivo, h\u00e1 hoje uma tend\u00eancia mundial de reestatiza\u00e7\u00e3o do saneamento, ocorrida em mais de 800 cidades no mundo desde o ano 2000. Claro, para os porta-vozes do interesse privado, nada disso interessa. Outra vez, Guedes, Bolsonaro e a quadrilha dos liberais p\u00f5em o Brasil na contram\u00e3o do mundo, em preju\u00edzo do povo e em benef\u00edcio exclusivo dos interesses do capital privado. O povo brasileiro ainda n\u00e3o sabe, mas logo ter\u00e1 motivos suficientes para n\u00e3o perdo\u00e1-los por tamanho retrocesso.<\/p>\n","protected":false},"excerpt":{"rendered":"<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/25748\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[239,31],"tags":[219],"class_list":["post-25748","post","type-post","status-publish","format-standard","hentry","category-ambiental","category-c31-unidade-classista","tag-manchete"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-6Hi","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/25748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=25748"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/25748\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=25748"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=25748"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=25748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}