{"id":25750,"date":"2020-06-26T20:46:13","date_gmt":"2020-06-26T23:46:13","guid":{"rendered":"https:\/\/pcb.org.br\/portal2\/?p=25750"},"modified":"2020-06-26T20:46:13","modified_gmt":"2020-06-26T23:46:13","slug":"o-anticomunismo-e-a-hegemonia-liberal-burguesa","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/25750","title":{"rendered":"O anticomunismo e a hegemonia liberal burguesa"},"content":{"rendered":"<p><img decoding=\"async\" class=\"imagem\" title=\"imagem\" src=\"https:\/\/i0.wp.com\/faccaoficticia.noblogs.org\/files\/2018\/12\/AntifaGuerraaossenhores.jpg\" alt=\"imagem\" \/><!--more-->Thiago Salgado Vaz de Lima*<\/p>\n<p>Nas linhas que seguem abaixo trazemos uma breve an\u00e1lise sobre a conjuntura atual acerca das movimenta\u00e7\u00f5es pol\u00edticas e discursivas envolvendo burguesia brasileira (e a natureza de classe do Estado), a ideologia dominante e sua capacidade de colocar seus interesses particulares de classe como universalizantes.<br \/>\nProvavelmente o camarada ou leitor que est\u00e1 lendo esse texto j\u00e1 reparou o quanto esse discurso de Sa\u00fade x Economia se coloca falsa e propositalmente polarizado no debate atual, n\u00e3o \u00e9? De um lado uns tantos acusam de irrespons\u00e1veis aqueles que pressionam governantes para a abertura do com\u00e9rcio e das atividades econ\u00f4micas em um contexto de pandemia. De outro, estes \u00faltimos acusam os primeiros de ego\u00edstas por n\u00e3o perceberem que o n\u00e3o retorno da atividade econ\u00f4mica \u00e9 tirar a sua \u00fanica possibilidade de subsist\u00eancia familiar. Reparem quanto cada um dos lados consegue identificar e responsabilizar o outro pelos delet\u00e9rios efeitos econ\u00f4micos e sanit\u00e1rios, mas n\u00e3o consegue colocar como alvo comum a concentra\u00e7\u00e3o de capital em uma parcela muito m\u00ednima da popula\u00e7\u00e3o. Sendo acess\u00edvel aos demais (que configuram a acachapante maioria), os frutos da produ\u00e7\u00e3o capitalista conseguiriam garantir as condi\u00e7\u00f5es materiais a fim de que todos pudessem fazer o isolamento social adequado para enfrentar a pandemia. O discurso da insufici\u00eancia de recursos no fundo p\u00fablico para qualquer pol\u00edtica que minimamente mitigue os efeitos econ\u00f4micos sobre a pandemia \u00e9 aceito com a mesma passividade que se escuta ou se l\u00ea a not\u00edcia: &#8220;Banco Central anuncia conjunto de medidas que liberam R$ 1,2 trilh\u00e3o para o sistema financeiro&#8221;.<\/p>\n<p>Indo para a esfera pol\u00edtica:<\/p>\n<p>Ciro Gomes, Kim Kataguiri, Rodrigo Maia, Marina Silva, S\u00e9rgio Moro, Luciano Huck, FHC, Michel Temer e tantos outros &#8220;respeitados democratas&#8221; (fazendo uso de ironia) t\u00eam apresentado uma fala em comum extremamente coordenada&#8230; J\u00e1 perceberam? A hip\u00e9rbole utilizada para denotar o Lulopetismo como o extremo oposto ao decadente Bolsonarismo!<\/p>\n<p>Pois bem, at\u00e9 a\u00ed nada de novo na velha t\u00e1tica anticomunista da classe dominante em ocultar as determina\u00e7\u00f5es mais profundas da sociedade de classes e operar a reposi\u00e7\u00e3o da hegemonia liberal. Afinal, colocar o Lulopetismo, marcado pela concilia\u00e7\u00e3o de classes, como espectro de extremo oposto ao bolsonarismo \u00e9 uma forma, tamb\u00e9m, de moderar a rea\u00e7\u00e3o ao atual estado de coisas e n\u00e3o deixar reacender nas massas o desejo e o sentimento de transforma\u00e7\u00f5es profundas e radicais nas rela\u00e7\u00f5es sociais, pol\u00edticas e econ\u00f4micas da sociedade brasileira.<\/p>\n<p>Nesse cen\u00e1rio excluem-se o movimento comunista e sua cr\u00edtica radical, apresentando como \u00fanico cen\u00e1rio democr\u00e1tico e moderado poss\u00edvel de exist\u00eancia pol\u00edtica aquilo que falsamente \u00e9 chamado de &#8220;centro democr\u00e1tico&#8221; ou de &#8220;nem esquerda nem direita&#8221;, o que em sua ess\u00eancia \u00e9 esconder todo arcabou\u00e7o ideol\u00f3gico da classe dominante para manter sua condi\u00e7\u00e3o de classe (concentra\u00e7\u00e3o de capitais e, em \u00faltima inst\u00e2ncia, a manuten\u00e7\u00e3o da propriedade privada).<\/p>\n<p>Esse mesmo recurso j\u00e1 foi usado pelos mesmos &#8220;atores&#8221; (de forma mais enf\u00e1tica por uns que por outros, \u00e9 verdade) em outros exemplos recentes como em torno da Reforma da Previd\u00eancia, a partir de seu falacioso d\u00e9ficit e do discurso de eliminar privil\u00e9gios.<\/p>\n<p>Mas quem eram os privilegiados desse slogan? O que eles pretendiam ocultar?<\/p>\n<p>O funcionalismo p\u00fablico era apresentado como privilegiado por possuir estabilidade profissional e sal\u00e1rios m\u00e9dios mais altos que a iniciativa privada. Para al\u00e9m de entrar no m\u00e9rito bastante relevante que o instrumento nivelador n\u00e3o deveria ser o da precariza\u00e7\u00e3o (ou seja, a pauta deveria ser aumentar os sal\u00e1rios e proporcionar a mesma estabilidade empregat\u00edcia na iniciativa privada), o fato ocultado no discurso \u00e9 a sonega\u00e7\u00e3o de grandes empres\u00e1rios na sua contribui\u00e7\u00e3o da previd\u00eancia e uma carga tribut\u00e1ria que n\u00e3o mexe nas grandes fortunas e heran\u00e7as daqueles que se situam no topo da pir\u00e2mide social do pa\u00eds e produzem esse abismo social de caracter\u00edsticas genocidas no pa\u00eds. Estes sim s\u00e3o os privilegiados!<\/p>\n<p>Em todos os tr\u00eas cen\u00e1rios (pandemia, pol\u00edtico e tribut\u00e1rio) a ideologia dominante se estabelece levando para falsos debates e ocultando profundamente as determina\u00e7\u00f5es sociais dos fen\u00f4menos e, assim, pautando-se no mito do Estado liberal, aqui apresentado como um neutro mediador dos conflitos de classes que paira sobre as rela\u00e7\u00f5es sociais de produ\u00e7\u00e3o capitalistas.<\/p>\n<p>Nesse cen\u00e1rio s\u00f3 vemos um crescente anticomunismo se estabelecendo (hora mais barulhento, hora mais silencioso) e o enfrentamento de trabalhadores x trabalhadores travestidos de &#8220;trabalhadores em condi\u00e7\u00e3o de realizar isolamento&#8221; x &#8220;trabalhadores que necessitam retornar ao trabalho&#8221;, &#8220;trabalhadores da iniciativa privada&#8221; x &#8220;trabalhadores do servi\u00e7o p\u00fablico&#8221; e at\u00e9 um &#8220;democratas x autorit\u00e1rios&#8221; que possa velar a ditadura do capital a depender do representante que ocupe a cadeira no aparelho de Estado.<br \/>\nAt\u00e9 quando vamos nos digladiar por migalhas e deixar o banquete da burguesia intacto?<\/p>\n<p>Que tenhamos PAZ ENTRE N\u00d3S, GUERRA AOS SENHORES!<\/p>\n<p>* militante do PCB na C\u00e9lula Marcos Cardoso Filho de Florian\u00f3polis\/SC<\/p>\n","protected":false},"excerpt":{"rendered":"<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/25750\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[9],"tags":[226],"class_list":["post-25750","post","type-post","status-publish","format-standard","hentry","category-s10-internacional","tag-4b"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-6Hk","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/25750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=25750"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/25750\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=25750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=25750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=25750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}