{"id":2616,"date":"2012-04-03T18:10:00","date_gmt":"2012-04-03T18:10:00","guid":{"rendered":"http:\/\/pcb.org.br\/portal2\/?p=2616"},"modified":"2012-04-03T18:10:00","modified_gmt":"2012-04-03T18:10:00","slug":"manifesto-de-juizes-brasileiros-pela-comissao-da-verdade","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/2616","title":{"rendered":"MANIFESTO DE JUIZES BRASILEIROS PELA COMISS\u00c3O DA VERDADE"},"content":{"rendered":"\n<p>N\u00f3s, ju\u00edzas e ju\u00edzes brasileiros, exigimos que o pa\u00eds quite a enorme d\u00edvida que possui com o seu povo e com a comunidade internacional, no que diz respeito \u00e0 verdade e justi\u00e7a dos fatos praticados pela ditadura militar, que teve in\u00edcio com o golpe de 1964.<\/p>\n<p>A Comiss\u00e3o da Verdade, criada por lei, \u00e9 mecanismo que deve contribuir para melhorar o acesso \u00e0 informa\u00e7\u00e3o e dar visibilidade \u00e0s estruturas da repress\u00e3o, reconstruindo o contexto hist\u00f3rico das graves viola\u00e7\u00f5es humanas cometidas pela ditadura militar e promover o esclarecimento dos casos de tortura, mortes, desaparecimentos for\u00e7ados e oculta\u00e7\u00e3o de cad\u00e1veres.<\/p>\n<p>Estamos certos, como decidido pela Corte Interamericana de Direitos Humanos, que \u201cas atividades e informa\u00e7\u00f5es que, eventualmente, recolha (a Comiss\u00e3o de Verdade), n\u00e3o substituem a obriga\u00e7\u00e3o do Estado de estabelecer a verdade e assegurar a determina\u00e7\u00e3o judicial de responsabilidades\u201d.<\/p>\n<p>Manifesta\u00e7\u00f5es que buscam cobrir as viola\u00e7\u00f5es cometidas sob o manto da ignor\u00e2ncia s\u00e3o um golpe para os direitos humanos e afrontam o patamar da dignidade humana estabelecido na Constitui\u00e7\u00e3o Federal e normativa internacional. Todos e todas t\u00eam o direito de saber o que ocorreu em nosso pa\u00eds, tarefa que compete \u00e0 Comiss\u00e3o da Verdade, a ser composta por pessoas comprometidas com a democracia, institucionalidade constitucional e direitos humanos.<\/p>\n<p>Aguardamos que a Comiss\u00e3o da Verdade seja constitu\u00edda o quanto antes, devidamente fortalecida e com condi\u00e7\u00f5es reais para efetiva\u00e7\u00e3o do seu mister.<\/p>\n<p>Jorge Luiz Souto Maior &#8211; SP<\/p>\n<p>Jo\u00e3o Ricardo dos Santos Costa &#8211; RS<\/p>\n<p>Kenarik Boujikian Felippe \u2013 SP<\/p>\n<p>Alessandro da Silva- SC<\/p>\n<p>Marcelo Semer- SP<\/p>\n<p>Andr\u00e9 Augusto Salvador Bezerra &#8211; SP<\/p>\n<p>Gerivaldo Neiva \u2013 BA<\/p>\n<p>Roberto Luiz Corcioli Filho \u2013 SP<\/p>\n<p>Alu\u00edsio Moreira Bueno &#8211; SP<\/p>\n<p>Carlos Frederico Braga da Silva &#8211; MG<\/p>\n<p>Angela Maria Konrath &#8211; SC<\/p>\n<p>Fernanda Menna Pinto Peres &#8211; SP<\/p>\n<p>Adriano Gustavo Veiga Seduvim &#8211; PA<\/p>\n<p>Rubens Roberto Rebello Casara \u2013 RJ<\/p>\n<p>Mauro Caum Gon\u00e7alves &#8211; RS<\/p>\n<p>Roberto Arriada Lorea &#8211; RS<\/p>\n<p>Alexandre Morais da Rosa &#8211; SC<\/p>\n<p>Jo\u00e3o Batista Damasceno &#8211; RJ<\/p>\n<p>Marcos Augusto Ramos Peixoto \u2013 RJ<\/p>\n<p>Lygia Maria de Godoy Batata Cavalcanti \u2013 RN<\/p>\n<p>Lu\u00eds Carlos Valois Coelho &#8211; AM<\/p>\n<p>Dora Martins \u2013 SP<\/p>\n<p>Jos\u00e9 Henrique Rodrigues Torres \u2013 SP<\/p>\n<p>Andr\u00e9a Maciel Pach\u00e1 &#8211; RJ<\/p>\n<p>Maria Coeli Nobre da Silva \u2013 PB<\/p>\n<p>Ruy Brito &#8211; BA<\/p>\n<p>Paulo Augusto Oliveira Irion &#8211; RS<\/p>\n<p>Amini Haddad &#8211; MT<\/p>\n<p>Geraldo Prado &#8211; RJ<\/p>\n<p>Michel Pinheiro &#8211; CE<\/p>\n<p>Alberto Alonso Mu\u00f1oz &#8211; SP<\/p>\n<p>Julio Jos\u00e9 Araujo Junior &#8211; RJ<\/p>\n<p>Fernando Mendon\u00e7a &#8211; MA<\/p>\n<p>Andr\u00e9 Luiz Machado &#8211; PE<\/p>\n<p>Grijalbo Fernandes Coutinho &#8211; DF<\/p>\n<p>F\u00e1bio Prates da Fonseca &#8211; SP<\/p>\n<p>Marl\u00facia de Ara\u00fajo Bezerra &#8211; CE<\/p>\n<p>Maria das Gra\u00e7as Almeida de Quental &#8211; CE<\/p>\n<p>Rodolfo M\u00e1rio Veiga Pamplona Filho &#8211; BA<\/p>\n<p>Weliton M. dos Santos &#8211; MG<\/p>\n<p>C\u00e9lia Regina Ody Bernardes &#8211; MT<\/p>\n<p>Oscar Krost &#8211; SC<\/p>\n<p>Adriana Ramos de Mello &#8211; RJ<\/p>\n<p>Jos\u00e9 Roberto Furquim Cabella &#8211; SP<\/p>\n<p>Maria Cec\u00edlia Alves Pinto &#8211; MG<\/p>\n<p>Sergio Renato Domingos &#8211; SC<\/p>\n<p>M\u00e1rio Soares Caymmi Gomes &#8211; BA<\/p>\n<p>F\u00e1bio Henrique Rodrigues de Moraes Fiorenza &#8211; MT<\/p>\n<p>Jeferson Schneider &#8211; MT<\/p>\n<p>Eduardo Vandr\u00e9 Oliveira Lema Garcia \u2013 RS<\/p>\n<p>Lucas Vanucci Lins &#8211; MG Douglas de Melo Martins &#8211; MA<\/p>\n<p>Alberto Silva Franco \u2013 SP<\/p>\n<p>Fernanda Souza P. de Lima Carvalho &#8211; SP<\/p>\n<p>Cristiana de Faria Cordeiro &#8211; RJ<\/p>\n<p>Umberto Guaspari Sudbrack &#8211; RS<\/p>\n<p>Erico Ara\u00fajo Bastos &#8211; BA<\/p>\n<p>Edson Souza \u2013 BA<\/p>\n<p>Amilton Bueno de Carvalho &#8211; RS<\/p>\n<p>Jos\u00e9 Augusto Segundo Neto &#8211; PE<\/p>\n<p>Salem Jorge Cury &#8211; SP<\/p>\n<p>Rita de C\u00e1ssia M. M. F. Nunes &#8211; BA<\/p>\n<p>Jos\u00e9 Viana Ulisses Filho &#8211; PE<\/p>\n<p>Milton Lamenha de Siqueira &#8211; TO<\/p>\n<p>Maria da Gra\u00e7a Marques Gurgel &#8211; AL<\/p>\n<p>Luiz Alberto de Vargas \u2013 RS<\/p>\n<p>Jo\u00e3o Marcos Buch \u2013 SC<\/p>\n<p>Ivani Martins Ferreira Giuliani &#8211; SP<\/p>\n<p>Maria Cecilia Fernandes Alvares Leite &#8211; SP<\/p>\n<p>Saint-Clair Lima e Silva \u2013 SP<\/p>\n<p>Magda Barros Biavaschi \u2013 RS<\/p>\n<p>Bernardo Nunes da Costa Neto &#8211; PE<\/p>\n<p>Beatriz de Lima Pereira \u2013 SP<\/p>\n<p>Rodolfo M\u00e1rio Veiga Pamplona Filho &#8211; BA<\/p>\n<p>Edvaldo Jos\u00e9 Palmeira &#8211; PE<\/p>\n<p>Denival Francisco da Silva &#8211; GO<\/p>\n<p>Maria Madalena Telesca &#8211; RS<\/p>\n<p>Reginaldo Melhado &#8211; PR<\/p>\n<p>Ana Claudia Petruccelli de Lima- PE<\/p>\n<p>Alb\u00e9rico Viana Bezerra &#8211; PB<\/p>\n<p>Carlos Eduardo Oliveira Dias\u00a0 &#8211; SP<\/p>\n<p>Ana Paula Alvarenga Martins &#8211; SP<\/p>\n<p>Theodomiro Romeiro dos Santos \u2013 PE<\/p>\n<p>Jos\u00e9 Tadeu Picolo Zanoni \u2013 SP<\/p>\n<p>Maria Sueli Neves Espicalquis \u2013 SP<\/p>\n<p>Sandra Miguel Abou Assali Bertelli -SP<\/p>\n<p>Lu\u00eds Christiano Enger Aires &#8211; RS<\/p>\n<p>Carmen Izabel Centena Gonzalez &#8211; RS<\/p>\n<p>Rute dos Santos Rossato \u2013 RS<\/p>\n<p>Reno Viana\u00a0 &#8211;\u00a0 BA<\/p>\n<p>Orlando Am\u00e2ncio Taveira &#8211; SP<\/p>\n<p>Andr\u00e9 Luis de Moraes Pinto &#8211; RS<\/p>\n<p>Norivaldo de Oliveira &#8211; SP<\/p>\n<p>Eug\u00eanio Couto Terra &#8211; RS<\/p>\n<p>Denise Oliveira Cezar \u2013 RS<\/p>\n<p>Helder Lu\u00eds Henrique Taguchi \u2013 PR<\/p>\n<p>S\u00e9rgio Mazina Martins &#8211; SP<\/p>\n<p>Eug\u00eanio Facchini Neto &#8211;\u00a0 RS<\/p>\n<p>Gilberto Sch\u00e4fer &#8211; RS<\/p>\n<p>Rodrigo de Azevedo Bortoli &#8211; RS<\/p>\n<p>Andr\u00e9 Luis de Moraes Pinto \u2013 RS<\/p>\n<p>Paulo da Cunha Boal &#8211; PR<\/p>\n<p>Laura Benda &#8211; SP<\/p>\n<p>Joana Ribeiro Zimmer &#8211; SC<\/p>\n<p>Br\u00e1ulio Gabriel Gusm\u00e3o &#8211; PR<\/p>\n<p>Gra\u00e7a Carvalho de Souza &#8211; MA<\/p>\n<p>Andrea Saint Pastous Nocchi &#8211; RS<\/p>\n<p>Fernando de Castro Faria &#8211; SC<\/p>\n<p>Dyrceu Aguiar Dias Cintra Junior &#8211; SP<\/p>\n<p>Ang\u00e9lica de Maria Mello de Almeida &#8211; SP<\/p>\n<p>Andr\u00e9ia Terre do Amaral &#8211; RS<\/p>\n<p>Fabiana Fiori Hallal &#8211; RS<\/p>\n<p>Maria Lucia Boutros Buchain Zoch Rodrigues &#8211; RS.<\/p>\n<p>Laura Borba Maciel Fleck &#8211; RS<\/p>\n<p>Lu\u00eds Fernando Camargo de Barros Vidal \u2013 SP<\/p>\n<p>R\u00e9gis Rodrigues Bonvicino \u2013 SP<\/p>\n<p>Luis Manuel Fonseca Pires \u2013 SP<\/p>\n<p>Carlos Vico Ma\u00f1as\u00a0 &#8211; SP<\/p>\n<p>Mylene Gloria Pinto Vassal &#8211;\u00a0 RJ<\/p>\n","protected":false},"excerpt":{"rendered":"\n\n\nCr\u00e9dito: pzap\n\n\n\n\n\n\n\n\n<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/2616\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[53],"tags":[],"class_list":["post-2616","post","type-post","status-publish","format-standard","hentry","category-c64-ditadura"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-Gc","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/2616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=2616"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/2616\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=2616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=2616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=2616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}