{"id":2618,"date":"2012-04-03T18:36:36","date_gmt":"2012-04-03T18:36:36","guid":{"rendered":"http:\/\/pcb.org.br\/portal2\/?p=2618"},"modified":"2012-04-03T18:36:36","modified_gmt":"2012-04-03T18:36:36","slug":"mais-um-sem-terra-assassinado-em-pe","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/2618","title":{"rendered":"Mais um Sem Terra assassinado em PE"},"content":{"rendered":"\n<p>O trabalhador rural Sem Terra Pedro Bruno foi assassinado na manh\u00e3 desta segunda-feira, (02) com v\u00e1rios tiros, pr\u00f3ximo ao engenho Pereira Grande, no munic\u00edpio de Gameleira, Zona da Mata Sul de Pernambuco.<\/p>\n<p>Pedro Bruno era assentado no Assentamento Dona (Margarida Alves), e se dirigia a outro assentamento, Frescudim, ambos tamb\u00e9m no munic\u00edpio de Gameleira, quando foi alvejado por v\u00e1rios tiros de arma de fogo. A pol\u00edcia foi avisada pela fam\u00edlia, mas at\u00e9 o momento ainda n\u00e3o tinha chegado no local.<\/p>\n<p>O MST acredita que o assassinato de Pedro Bruno tenha sido uma retalia\u00e7\u00e3o \u00e0 reocupa\u00e7\u00e3o do engenho Pereira Grande, que ocorreu na madrugada de ontem (01\/04).<\/p>\n<p>O engenho Pereira grande pertence \u00e0 Usina Estreliana, e \u00e9 uma das \u00e1reas mais emblem\u00e1ticas de conflitos de terra no estado de Pernambuco. A \u00e1rea foi declarada de interesse social para fins de reforma agr\u00e1ria em novembro de 2003, mas depois de uma s\u00e9rie de recursos impetrados, a Usina consegue barrar o processo de desapropria\u00e7\u00e3o quando a Ministra Ellen Gracie, ent\u00e3o Presidente do Supremo Tribunal Federal, que havia dado imiss\u00e3o de posse da \u00e1rea ao Instituto Nacional de Coloniza\u00e7\u00e3o e Reforma Agr\u00e1ria (INCRA) uma semana antes, rev\u00ea sua decis\u00e3o e determina que a imiss\u00e3o de posse e o seguimento da a\u00e7\u00e3o de desapropria\u00e7\u00e3o s\u00f3 poder\u00e3o se dar ap\u00f3s o julgamento final do processo. O caso est\u00e1, desde ent\u00e3o, pendente na justi\u00e7a.<\/p>\n<p>Ainda recai sobre a Usina Estreliana v\u00e1rios crimes trabalhistas. Em janeiro de 2010, o propriet\u00e1rio da Usina, Gustavo Costa de Albuquerque Maranh\u00e3o, que havia sido denunciado pelo Minist\u00e9rio P\u00fablico Federal (MPF), foi condenado, a quatro anos e meio de reclus\u00e3o, por deixar de repassar ao INSS, durante 18 meses, as contribui\u00e7\u00f5es previdenci\u00e1rias recolhidas no valor de mais de R$ 600 mil de seus empregados.<\/p>\n<p>No \u00faltimo dia 08 de mar\u00e7o, cerca de 200 mulheres do MST realizaram um ato na engenho Pereira Grande, exigindo a desapropria\u00e7\u00e3o da \u00e1rea e condenando as consequ\u00eancias econ\u00f4micas e sociais do monocultivo de cana na regi\u00e3o. Na ocasi\u00e3o elas foram cercadas por pistoleiros do engenho que disparara v\u00e1rios tiros contra as camponesas.<\/p>\n<p><strong>A impunidade incentiva a viol\u00eancia do latif\u00fandio<\/strong><\/p>\n<p>No dia 23 de mar\u00e7o de 2012, o trabalhador Rural Sem Terra Ant\u00f4nio Tiningo foi assassinado em uma emboscada quando se dirigia para o acampamento da fazenda A\u00e7ucena, no munic\u00edpio de Jata\u00faba, agreste de Pernambuco. Tiningo era um dos coordenadores do MST na regi\u00e3o.<\/p>\n<p>No mesmo dia, pistoleiros atiraram contra fam\u00edlias Sem Terra acampadas pr\u00f3ximo \u00e0 fazenda Serro Azul, no munic\u00edpio de Altinho, tamb\u00e9m no agreste de Pernambuco. Duas mulheres e uma crian\u00e7a foram atingidas.<\/p>\n<p>Em outubro do ano passado, o trabalhador rural Sem Terra Jos\u00e9 Amaro da Silva, desapareceu na zona da mata de Pernambuco quando sa\u00eda do acampamento do MST no Engenho Brasileiro, munic\u00edpio de Joaquim Nabuco, mais umas das \u00e1reas de conflito agr\u00e1ria do estado.<\/p>\n<p>O MST e organiza\u00e7\u00f5es de direitos humanos como a Terra de Direitos vem denunciando amplamente a viol\u00eancia no campo em Pernambuco: pistoleiros recebem R$ 50,00 por dia para atirarem contra trabalhadores rurais Sem Terra; fazendeiros andam armados e amea\u00e7am agricultores at\u00e9 mesmo em suas pr\u00f3prias casas; a pol\u00edcia atua como seguran\u00e7a privada de fazendas, intimidando e amea\u00e7ando fam\u00edlias Sem Terra; delegados, ju\u00edzes e promotores legitimam o uso de viol\u00eancia e de mil\u00edcias armadas por parte de propriet\u00e1rios de terra; trabalhadores rurais desaparecem e s\u00e3o mortos em emboscadas.<\/p>\n<p>Mas tanto o Governo Estadual, como o Instituto Nacional de Coloniza\u00e7\u00e3o e Reforma Agr\u00e1ria e demais \u00f3rg\u00e3os respons\u00e1veis parecem continuar de bra\u00e7os cruzados.<\/p>\n<p>http:\/\/www.mst.org.br\/Mais-uma-lideranca-do-MST-assassinada-no-agreste-pernambucano<\/p>\n","protected":false},"excerpt":{"rendered":"\n\n\nCr\u00e9dito: MST\n\n\n\n\n\n\n\n\nDa P\u00e1gina do\u00a0MST\n<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/2618\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[20],"tags":[],"class_list":["post-2618","post","type-post","status-publish","format-standard","hentry","category-c1-popular"],"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p659gw-Ge","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/2618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=2618"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/2618\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=2618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=2618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=2618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}