{"id":26533,"date":"2020-12-05T19:47:41","date_gmt":"2020-12-05T22:47:41","guid":{"rendered":"https:\/\/pcb.org.br\/portal2\/?p=26533"},"modified":"2020-12-09T21:31:05","modified_gmt":"2020-12-10T00:31:05","slug":"ocupacao-marighella-conquista-terreno-para-moradia-popular","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/26533","title":{"rendered":"Ocupa\u00e7\u00e3o Marighella conquista terreno para moradia popular"},"content":{"rendered":"<p><img decoding=\"async\" class=\"imagem\" title=\"imagem\" src=\"https:\/\/i0.wp.com\/lh3.googleusercontent.com\/pw\/ACtC-3cMsxgBul0eEhCnfzy4pPXQyoeKALf10L5mD2Kh-V0iWDmKqFd4_QzA3ZoVnzGYNP3_lHg9GvRXTSjQfjUcA-POJydnNmu0K_HbnaLXSz7PS_NDuXzfHtuJxs-uh8_zIwa4axxfsEF5pGON_S5xrtjy=w647-h303-no\" alt=\"imagem\" \/><!--more-->Por Antonio Lima J\u00fanior, jornalista do jornal O Poder Popular &#8211; sucursal Cear\u00e1<\/p>\n<p>A Ocupa\u00e7\u00e3o Carlos Marighella realizou, na \u00faltima quarta-feira (2), uma ocupa\u00e7\u00e3o na sede do diret\u00f3rio estadual do PDT em Fortaleza, como forma de protesto pedindo a realiza\u00e7\u00e3o de audi\u00eancia com o atual prefeito, Roberto Cl\u00e1udio, e o futuro prefeito, Jos\u00e9 Sarto, ambos do PDT.<\/p>\n<p>As 85 fam\u00edlias est\u00e3o ocupando desde junho um terreno no bairro Mondubim, periferia da capital cearense. A empresa AKASA\/DIRECIONAL afirma ser dona do terreno, mas, segundo moradores do entorno, o espa\u00e7o est\u00e1 h\u00e1 mais de trinta anos sem fun\u00e7\u00e3o social, como um terreno baldio.<\/p>\n<p>A ocupa\u00e7\u00e3o da sede do PDT foi uma iniciativa das fam\u00edlias, decidida em assembleia, para chamar a aten\u00e7\u00e3o da prefeitura sobre a situa\u00e7\u00e3o, visto que h\u00e1 meses em di\u00e1logo com a secretaria de habita\u00e7\u00e3o do munic\u00edpio, a Habitafor, tem sido negada a proposta de constru\u00e7\u00e3o de moradias populares atrav\u00e9s da doa\u00e7\u00e3o de terreno p\u00fablico. A Habitafor, ao inv\u00e9s de escutar a demanda, insistia apenas no aluguel social, medida paliativa contestada pela Ocupa\u00e7\u00e3o.<\/p>\n<p>Diante da repercurss\u00e3o da manifesta\u00e7\u00e3o, a audi\u00eancia foi realizada no dia seguinte, com a presen\u00e7a do prefeito Roberto Cl\u00e1udio e de representa\u00e7\u00e3o do futuro prefeito Jos\u00e9 Sarto, com a media\u00e7\u00e3o da Defensoria P\u00fablica e do mandato do deputado estadual Renato Roseno (PSOL). Ao final, foi acordado o encaminhamento para a C\u00e2mara Municipal de transfer\u00eancia de terreno p\u00fablico para a constru\u00e7\u00e3o das moradias populares, al\u00e9m de aluguel social facultativo \u00e0s fam\u00edlias interessadas, enquanto o projeto estiver em andamento.<\/p>\n<p>Entretanto, a luta da Ocupa\u00e7\u00e3o Carlos Marighella ainda n\u00e3o acabou. A ordem de despejo continua mantida para o pr\u00f3ximo dia 11 de dezembro. As fam\u00edlias e diversos movimentos apoiadores da Ocupa\u00e7\u00e3o agora mobilizam o apelo ao poder judici\u00e1rio para adiar a ordem de despejo, visto que a conquista do terreno \u00e9 uma situa\u00e7\u00e3o concreta que impede tamanha a\u00e7\u00e3o contra o povo, em plena pandemia.<\/p>\n<p>Em defesa da moradia popular!<\/p>\n","protected":false},"excerpt":{"rendered":"<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/26533\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[200,20],"tags":[222],"class_list":["post-26533","post","type-post","status-publish","format-standard","hentry","category-moradia","category-c1-popular","tag-2b"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-6TX","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/26533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=26533"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/26533\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=26533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=26533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=26533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}