{"id":26585,"date":"2020-12-15T22:08:00","date_gmt":"2020-12-16T01:08:00","guid":{"rendered":"https:\/\/pcb.org.br\/portal2\/?p=26585"},"modified":"2020-12-15T22:08:00","modified_gmt":"2020-12-16T01:08:00","slug":"engels-e-lenin-na-america-latina-ontem-e-hoje","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/26585","title":{"rendered":"Engels e L\u00eanin na Am\u00e9rica Latina ontem e hoje"},"content":{"rendered":"<p><img decoding=\"async\" class=\"imagem\" title=\"imagem\" src=\"https:\/\/i0.wp.com\/boitempoeditorial.files.wordpress.com\/2020\/11\/engels-lenin.jpg\" alt=\"imagem\" \/><!--more-->BLOG DA BOITEMPO<\/p>\n<p>Por Marcos Del Roio<\/p>\n<p>A atual crise do capital, que amea\u00e7a a pr\u00f3pria sobreviv\u00eancia da humanidade, d\u00e1 nova vida \u00e0 obra desses dois gigantes na luta pela liberdade.<\/p>\n<p>O ano de 2020 desde j\u00e1 fica como um marco na hist\u00f3ria, quando um v\u00edrus assombrou a Humanidade e induziu a necessidade das pessoas se manterem afastadas umas das outras, a necessidade de se cobrir o rosto, de se expressarem apenas por meio das telas da tecnologia eletr\u00f4nica. Mas se observarmos mais de perto essa \u00e9 j\u00e1 uma tend\u00eancia que vem mais de longe, talvez desde os anos 80 do s\u00e9culo passado, quando a desintegra\u00e7\u00e3o dos sujeitos coletivos conformados em organiza\u00e7\u00f5es pol\u00edticas, econ\u00f4micas, culturais come\u00e7ou a proceder velozmente em torno da inova\u00e7\u00e3o tecnol\u00f3gica e de uma concentra\u00e7\u00e3o de hegemonia por parte do capital. Estados sempre mais controladores e repressivos e com crescente elimina\u00e7\u00e3o de direitos sociais, rela\u00e7\u00f5es sociais fundadas em extremado individualismo, tudo conforma o ambiente de uma regress\u00e3o cultural sobre a qual o obscurantismo avan\u00e7a. Esse ano de 2020, que evidenciou uma crise assim profunda, \u00e9 tamb\u00e9m um ano prop\u00edcio para resgatar a lembran\u00e7a dos 200 anos de nascimento de Friedrich Engels e os 150 anos do nascimento de Vladimir L\u00eanin. Ter\u00e3o eles a nos dizer algo nessa situa\u00e7\u00e3o que clama a luta, no limite, pela sobreviv\u00eancia da humanidade?<\/p>\n<p>Nesse cen\u00e1rio mundial a Am\u00e9rica meridional oferece a sua contradit\u00f3ria contribui\u00e7\u00e3o. Essa vasta e diversificada regi\u00e3o se conformou, desde o s\u00e9culo XVI, com a invas\u00e3o e ocupa\u00e7\u00e3o europeia, como um Ocidente subalterno, no qual a domina\u00e7\u00e3o colonial se estabeleceu sobre os povos ind\u00edgenas e sobre os povos transplantados da \u00c1frica pela for\u00e7a. A ideologia cat\u00f3lica reformada serviu de instrumento dessa ocupa\u00e7\u00e3o, que gerou formas sociais heterog\u00eaneas, onde conviviam formas de escravismo e de feudalismo. A riqueza assim gerada serviu, em grande medida, para garantir a acumula\u00e7\u00e3o origin\u00e1ria do capital, que ent\u00e3o ocorria na Europa.<\/p>\n<p>Essas formas sociais foram terrivelmente duradouras. A forma\u00e7\u00e3o de Estados territoriais por toda essa \u00e1rea serviu apenas para internalizar a domina\u00e7\u00e3o colonial. O afastamento de Espanha e Portugal do continente logo deu lugar a disputas entre oligarquias regionais formadas em torno dos interesses coloniais que se procurava agora substituir. Os povos submetidos secularmente \u2013 fossem os ind\u00edgenas sobreviventes do secular genoc\u00eddio, fossem os africanos que continuaram a chegar ainda por algum tempo como escravos \u2013 s\u00f3 tiveram voz quando das explos\u00f5es de rebeldia. A persist\u00eancia da explora\u00e7\u00e3o e da opress\u00e3o dentro dos Estados formados segundo os interesses de oligarquias geradas no decorrer do dom\u00ednio colonial possibilitou que a forma da subalternidade da Indo-Afro-Am\u00e9rica fosse redefinida. Estados \u201cnacionais\u201d mim\u00e9ticos e ficticiamente soberanos passaram a gerir a persistente rela\u00e7\u00e3o colonial \u00e0s custas dos povos origin\u00e1rios e dos transplantados da \u00c1frica, aos quais se juntariam mesti\u00e7os e migrantes pobres.<\/p>\n<p>Quando a fase imperialista do capitalismo teve in\u00edcio, em torno de 1880, essa forma de produ\u00e7\u00e3o da riqueza e de explora\u00e7\u00e3o da for\u00e7a de trabalho come\u00e7ou a se internalizar no continente em alguns lugares de alguns pa\u00edses, em particular no M\u00e9xico e no Cone Sul. O tema do imperialismo se colocou no debate europeu em torno da sua utilidade (para os imperialistas) ou de sua validade \u00e9tica, de uma pretensa miss\u00e3o civilizadora do Ocidente. Esse debate tomou conta tamb\u00e9m do movimento socialista, com posi\u00e7\u00f5es diferenciadas no seio dos intelectuais que pensavam e elaboravam a ideologia socialista. Foi L\u00eanin, no entanto, que em livro de 1916, O imperialismo como fase superior do capitalismo, ofereceu uma s\u00edntese que, sem d\u00favida, \u00e9 v\u00e1lida at\u00e9 hoje.<\/p>\n<p>Para L\u00eanin, o imperialismo n\u00e3o era apenas uma escolha pol\u00edtica dos governos, o imperialismo era sim uma fase de desenvolvimento do capitalismo na qual as contradi\u00e7\u00f5es do movimento do capital se agravavam. Formava-se uma oligarquia financeira, que passava a ser a classe dominante nos pa\u00edses capitalistas mais avan\u00e7ados, avan\u00e7ava a concentra\u00e7\u00e3o e centraliza\u00e7\u00e3o do capital ao modo de monop\u00f3lios, uma disputa crescente por fatias do mercado mundial, que implicava na exporta\u00e7\u00e3o de capitais. Com a importa\u00e7\u00e3o de capitais \u00e9 que o capitalismo come\u00e7a a se desenvolver na Am\u00e9rica meridional (de modo muito desigual, bom que se insista). Tem in\u00edcio a forma\u00e7\u00e3o de uma burguesia interna e de um g\u00e9rmen de proletariado. O proletariado que se forma \u00e9, em grande parte, originado das regi\u00f5es da Europa onde o acesso \u00e0 terra era dificultado ao m\u00e1ximo e o capitalismo era relativamente atrasado. Mas com os migrantes a mancha do capitalismo come\u00e7a a se espalhar e tamb\u00e9m a resist\u00eancia \u00e0 explora\u00e7\u00e3o.<\/p>\n<p>L\u00eanin, em 1916, era conhecido apenas nos c\u00edrculos marxistas socialistas da Europa, mas ainda n\u00e3o reconhecido como grande te\u00f3rico e estrategista da pol\u00edtica revolucion\u00e1ria que foi. Passados mais tr\u00eas anos, o nome de L\u00eanin j\u00e1 corria de boca em boca por quase todo o mundo, inclusive grande parte da Am\u00e9rica chamada de Latina. Com o nome de L\u00eanin \u00e9 que o marxismo, determinado marxismo, come\u00e7ou a se difundir pelo continente.<\/p>\n<p>Qual marxismo? Ainda que logo na sequ\u00eancia da morte de Engels, em 1895, o seu nome tenha sido acoplado ao de Marx como se fosse um dupla que havia composto uma obra \u00fanica, o fato \u00e9 que forma autores diferentes, com agendas de estudo e pesquisa diferentes, mesmo que tenham sempre colaborado um com o outro. Nos 12 anos que sobreviveu a Marx, Engels comp\u00f4s o marxismo como pensamento mais seu do que de Marx. Uma an\u00e1lise apurada de seus escritos em compara\u00e7\u00e3o com os de Marx mostra bem a diferen\u00e7a em diversos pontos, em particular aqueles relativos \u00e0 dial\u00e9tica. Marx fundou uma nova dial\u00e9tica negando a dial\u00e9tica de Hegel, Engels apenas despiu o inv\u00f3lucro idealista da dial\u00e9tica de Hegel. O marxismo fundado por Engels nos anos 80-90 do s\u00e9culo XIX teve em Kautsky o seu principal continuador e difusor. Ao se difundir, o marxismo tamb\u00e9m se diversifica e se adapta ao novo ambiente, de modo que o marxismo \u00e9 sempre determinado pelas condi\u00e7\u00f5es sociais e culturais com as quais se encontra.<\/p>\n<p>Quando da morte de Engels, na R\u00fassia, um jovem com os seus 25 anos, publicou um artigo no qual reconhecia o enorme m\u00e9rito de Engels na composi\u00e7\u00e3o da obra revolucion\u00e1ria que o proletariado encarnava. No marxismo que se formava na R\u00fassia, Engels oferecia o substrato filos\u00f3fico e pol\u00edtico no qual Plekhanov se amparou para introduzir o marxismo na R\u00fassia. Eis que se formava o elo Engels-Plekhanov-Kautsky-L\u00eanin. Mais tarde L\u00eanin romperia com Plekhanov e com Kautsky, mas o la\u00e7o com Engels permaneceu s\u00f3lido, fosse no livro Materialismo e empiriocriticismo (1909) ou em O Estado e a revolu\u00e7\u00e3o (1917).<\/p>\n<p>Na Am\u00e9rica Latina, os nomes de Marx e de Engels eram conhecidos por poucos desde os anos 80 do s\u00e9culo XIX, mas em geral vinham dentro de um cesto que continha outros frutos das ideologias cientificistas e naturalistas da Europa burguesa. Entre os primeiros socialistas eram vistos por meio de uma leitura reformista justificada pelo atraso do capitalismo e pela escassez num\u00e9rica do proletariado industrial. Ora, sem um capitalismo ao menos razoavelmente desenvolvido e um proletariado industrial numericamente expressivo, segundo certa leitura do marxismo, n\u00e3o havia como se pensar em revolu\u00e7\u00e3o, apenas na melhoria das condi\u00e7\u00f5es de vida dos trabalhadores e na sua representa\u00e7\u00e3o pol\u00edtica.<\/p>\n<p>A revolu\u00e7\u00e3o russa eclodiu numa conjuntura de guerra imperialista e de rebeli\u00e3o universal do mundo do trabalho e dos povos oprimidos. Muitos pa\u00edses de todos os continentes foram palco de revoltas, rebeli\u00f5es, revolu\u00e7\u00f5es, Nuestra Am\u00e9rica inclu\u00edda. M\u00e9xico, Argentina, Chile, Brasil assistiram greves de massa, manifesta\u00e7\u00f5es e confrontos com o Estado das oligarquias. Essa movimenta\u00e7\u00e3o acabou derrotada em todo lugar, mas abriu espa\u00e7o para a difus\u00e3o do marxismo, determinado marxismo, aquele produzido pela teoria e pr\u00e1tica dos bolcheviques russos, pelo pensamento de L\u00eanin. Afinal, foi L\u00eanin o primeiro te\u00f3rico e militante do movimento oper\u00e1rio a colocar em pauta a necessidade da emancipa\u00e7\u00e3o dos povos dominados pelo imperialismo na forma de colonialismo. A Internacional Comunista, fundada em 1919, por partidos revolucion\u00e1rios formados em meio a batalha pela defesa e difus\u00e3o da revolu\u00e7\u00e3o socialista surgida na R\u00fassia, aos poucos se espalhou pela maior parte do globo. A concep\u00e7\u00e3o de L\u00eanin da necessidade de uma organiza\u00e7\u00e3o internacional solid\u00e1ria que estimulasse e apoiasse toda luta social das classes e regi\u00f5es subalternizadas contribuiu para a funda\u00e7\u00e3o de partidos comunistas na Am\u00e9rica Latina. A primeira onda (1918-1925) cobriu Argentina, Uruguai, Chile, Brasil, M\u00e9xico e Cuba. Uma segunda onda alcan\u00e7ou a Am\u00e9rica andina.<\/p>\n<p>Al\u00e9m da li\u00e7\u00e3o de que a luta pela emancipa\u00e7\u00e3o do trabalho se vinculava \u00e0 luta pela emancipa\u00e7\u00e3o nacional, L\u00eanin tamb\u00e9m mostrou a import\u00e2ncia da organiza\u00e7\u00e3o disciplinada no partido revolucion\u00e1rio. Os partidos comunistas n\u00e3o foram, por suposto, as \u00fanicas organiza\u00e7\u00f5es que visavam a constitui\u00e7\u00e3o efetiva de um povo\/na\u00e7\u00e3o e de um Estado democr\u00e1tico nos diferentes pa\u00edses, mas \u00e9 importante dizer que, mesmo que impotentes para assumir a dire\u00e7\u00e3o do processo que endere\u00e7ou todo o continente para o capitalismo \u2013 um capitalismo que reproduziu e atualizou o estatuto colonial e as estruturas internas de poder \u2013, os partidos comunistas contribu\u00edram para fazer as classes subalternas expressarem as suas reivindica\u00e7\u00f5es.<\/p>\n<p>Os limites principais desses partidos est\u00e3o ligados ao limitado conhecimento da realidade que se queria transformar e ao limitado conhecimento das obras te\u00f3ricas de Engels e Marx, mas tamb\u00e9m de L\u00eanin. De fato, o marxismo foi vitimado por certa estagna\u00e7\u00e3o e redu\u00e7\u00e3o a f\u00f3rmulas doutrin\u00e1rias. Vale ent\u00e3o lembrar que o marxismo que alcan\u00e7ou a Am\u00e9rica Latina foi uma ideologia fundada por Engels, refundada por L\u00eanin e congelada com Stalin e parcialmente hibridizada com o positivismo.<\/p>\n<p>As implica\u00e7\u00f5es pol\u00edticas desses limites se mostraram com for\u00e7a a partir dos anos 60 do s\u00e9culo XX. Houve uma busca pela renova\u00e7\u00e3o te\u00f3rica e houve uma grande diversifica\u00e7\u00e3o de organiza\u00e7\u00f5es que se diziam marxistas, mas a derrota de todas as variantes foi quase completa na passagem dos anos 70 para os 80. Ditaduras militares cru\u00e9is se instalaram na Am\u00e9rica Latina para impedir que a revolu\u00e7\u00e3o burguesa \u2013 que procedia pelo alto, tendo o Estado como sujeito \u2013 se transformasse em revolu\u00e7\u00e3o democr\u00e1tica.<\/p>\n<p>Nos anos 80 do s\u00e9culo XX come\u00e7ou o processo de instaura\u00e7\u00e3o de democracias liberal-burguesas, que se fez articulado com o projeto de uma sociabilidade neoliberal, ultra individualista e contr\u00e1ria a qualquer forma de organiza\u00e7\u00e3o popular. As classes dominantes pretendiam agora consolidar o seu poder e expressar isso em primeira pessoa, como propriet\u00e1rios, como empres\u00e1rios, sem a necessidade mais da institui\u00e7\u00e3o militar. A inten\u00e7\u00e3o era mesmo que a democracia e os direitos sociais n\u00e3o passassem de fic\u00e7\u00e3o.<\/p>\n<p>Talvez o Partido dos Trabalhadores, no Brasil, tenha sido a \u00faltima experi\u00eancia de uma \u00e9poca na qual a vanguarda era a classe oper\u00e1ria fordista, mesmo que marcada por forte corporativismo sindical, que n\u00e3o ultrapassa o talhe liberal, como demonstrado quando chegou ao governo do Estado brasileiro (2003-2016). A crise org\u00e2nica dos partidos comunistas e da ideologia marxista que lhes eram constitutivas deixou as classes subalternas parcialmente desarmadas. A vit\u00f3ria ideol\u00f3gica do capital com a sua proposta neoliberal incluiu a demoli\u00e7\u00e3o dos institutos do movimento oper\u00e1rio, sindicato e partido (com a marcante exce\u00e7\u00e3o do PT) e tamb\u00e9m de seus s\u00edmbolos. A v\u00edtima maior foi a figura de L\u00eanin, em particular depois da vit\u00f3ria reacion\u00e1ria neoliberal no que fora a Europa oriental e as democracias populares. Tudo se passou como se fosse L\u00eanin o respons\u00e1vel pelos descaminhos dessa importante experi\u00eancia hist\u00f3rica.<\/p>\n<p>Um grande desafio se apresentou (e ainda se apresenta) \u00e0s classes subalternas deste Ocidente meridional. Nas condi\u00e7\u00f5es de decl\u00ednio hist\u00f3rico do capitalismo, uma grande ofensiva contra os trabalhadores foi empreendida com o revestimento da ideologia e economia pol\u00edtica dita neoliberal. Desde logo ficou claro que uma revolu\u00e7\u00e3o democr\u00e1tica com o objetivo de desenvolver um capitalismo aut\u00f4nomo com eventual participa\u00e7\u00e3o de franjas da burguesia era algo que n\u00e3o havia mais como se sustentar. Tentou-se um novo come\u00e7o por diversos caminhos, na maior parte com o descarte do marxismo, como se certo marxismo derivado da ideologia do Estado sovi\u00e9tico refletisse o pensamento de Marx.<\/p>\n<p>Esses caminhos foram genericamente chamados de movimentos sociais, que na verdade s\u00e3o fragmentos da luta popular de resist\u00eancia. S\u00e3o movimentos pela terra, pela moradia, pelo ambiente, pelos direitos das diferentes sexualidades, dos povos origin\u00e1rios, dos descendentes de escravos. Deixou-se lado o eixo fundamental da luta, aquela capaz de unificar toda essa diversidade, que \u00e9 a luta do trabalho contra o capital. A maior parte dessas lutas sociais n\u00e3o ultrapassa a perspectiva do direito e da justi\u00e7a, de modo a permanecerem no horizonte ideol\u00f3gico do mundo burgu\u00eas, mesmo que aqui e acol\u00e1 se fale de socialismo. Os institutos hist\u00f3ricos do movimento oper\u00e1rio, sindicato e partido, continuam a perder for\u00e7a e influ\u00eancia com a persist\u00eancia do desgaste de uma crise que \u00e9 org\u00e2nica.<\/p>\n<p>O Brasil foi o \u00faltimo dos pa\u00edses do continente a abra\u00e7ar o neoliberalismo. A burguesia ainda buscava outros caminhos. A for\u00e7a do movimento democr\u00e1tico possibilitou a emerg\u00eancia de um forte movimento oper\u00e1rio sindical, seguido por um movimento de luta pela terra. A forma\u00e7\u00e3o do PT, da Central \u00danica dos Trabalhadores e do Movimento dos Trabalhadores Rurais Sem-Terra, mais que o come\u00e7o, demarcava o fim de uma era. O PT logo se homologou \u00e0 nova ordem (congresso de 1981), assim que essa se definiu ap\u00f3s o chamado \u201cconsenso de Washington\u201d (1989). Importante dizer que o quase vazio na esquerda orientada pelo marxismo foi coberto pelos cat\u00f3licos da \u201cteologia da liberta\u00e7\u00e3o\u201d.<\/p>\n<p>A mais clara express\u00e3o de oposi\u00e7\u00e3o dentro da nova era que come\u00e7ava (era neoliberal ou era da barb\u00e1rie) foi a emerg\u00eancia do EZLN no M\u00e9xico: um movimento do povo maia pela autodetermina\u00e7\u00e3o dentro do Estado mexicano, pelo resgate da terra e da vida comunit\u00e1ria. Os povos ind\u00edgenas da Am\u00e9rica andina seguiram tamb\u00e9m o caminho da organiza\u00e7\u00e3o e da luta, sempre tendo por fundamento seus direitos hist\u00f3ricos e sua tradi\u00e7\u00e3o cultural. Equador e Bol\u00edvia foram exemplos expressivos, assim como a Venezuela e Chile, menos Col\u00f4mbia e Peru. O exemplo mais bem sucedido foi mesmo a Bol\u00edvia, com a ideologia do bem viver, do resgate das tradi\u00e7\u00f5es comunit\u00e1rias dos povos ind\u00edgenas dos Andes e que chegou ao governo.<\/p>\n<p>Mas talvez a mais promissora movimenta\u00e7\u00e3o de for\u00e7a social \u2013 e que tem car\u00e1ter universal \u2013 tem sido o movimento das mulheres. Gigantescas manifesta\u00e7\u00f5es femininas na Argentina, Chile, M\u00e9xico, Brasil, a participa\u00e7\u00e3o das mulheres na vida p\u00fablica vem carregada de enorme potencial transformador em sociedades brutalmente machistas.<\/p>\n<p>Contudo, em todos esses movimentos, como j\u00e1 foi dito, h\u00e1 uma limita\u00e7\u00e3o de car\u00e1ter ideol\u00f3gico de grande dimens\u00e3o, pois continuam submetidos \u00e0 filosofia neoliberal e p\u00f3s-moderna do mundo, uma concep\u00e7\u00e3o de mundo fragmentado, composto por singularidades. Essa ideologia p\u00f3s-moderna de esquerda se manifesta com frequ\u00eancia em demandas por a\u00e7\u00f5es \u201cafirmativas\u201d, pol\u00edticas de Estado focalizadas em setores sociais, sem a necess\u00e1ria universalidade.<\/p>\n<p>Todavia \u00e9 tamb\u00e9m verdade que nessa \u00e9poca neoliberal na qual a barb\u00e1rie germina e floresce, o conhecimento da obra de Marx e de alguns dos autores mais importantes que se puseram na sua trilha cresceu bastante. Fontes prim\u00e1rias e publica\u00e7\u00f5es se multiplicaram, estudiosos dedicados e s\u00e9rios surgiram em v\u00e1rios lugares. Acontece que essa massa intelectual se encontra descolada do movimento popular, o qual, por sua vez ignora, quando n\u00e3o repele esse conhecimento que tem dificuldade em se fazer pr\u00e1tica. Mas \u00e9 exatamente da pr\u00e1tica que se deve partir, da experi\u00eancia acumulada, da rebeldia espor\u00e1dica do senso comum, que explode em raiva, n\u00e3o do senso comum que naturaliza ou transfere a algum deus a responsabilidade pela explora\u00e7\u00e3o social. Ent\u00e3o h\u00e1 que se retomar, conhecer a experi\u00eancia de lutas anteriores de lutas pela liberdade dos trabalhadores escravos, servos e assalariados, das mulheres, dos povos. A mem\u00f3ria \u00e9 fundamental para a constru\u00e7\u00e3o do futuro, assim como \u00e9 a cultura.<\/p>\n<p>Mas o que pode mesmo significar lembrar autores como Engels e L\u00eanin que viveram em outros tempos, em outros espa\u00e7os? Engels tem obra importante e vasta que aborda v\u00e1rias \u00e1reas do conhecimento, algumas das quais abriram um caminho muito promissor, mas talvez tenha sido o mais importante, nos anos que se passaram depois da morte de Marx, o seu papel de efetivo fundador do marxismo como ideologia do movimento oper\u00e1rio, o seu trabalho na difus\u00e3o do marxismo, na educa\u00e7\u00e3o da classe. Engels se dava conta da necessidade de agrupar e educar a classe oper\u00e1ria para a revolu\u00e7\u00e3o, num trabalho \u00e1rduo e longo dada a for\u00e7a que o capital e o seu Estado contavam ao se encerrar o s\u00e9culo XIX. Foi Engels a afirmar que a emancipa\u00e7\u00e3o do trabalho estava associada \u00e0 emancipa\u00e7\u00e3o da mulher, isso num momento em que esse tema era tratado ainda de maneira muito embrion\u00e1ria no movimento oper\u00e1rio socialista.<\/p>\n<p>De Engels, L\u00eanin preservou a necessidade da organiza\u00e7\u00e3o disciplinada, da educa\u00e7\u00e3o, do estudo sistem\u00e1tico e paciente. L\u00eanin realmente inovou na an\u00e1lise de uma realidade particular, concreta como necessidade para o empreendimento da transforma\u00e7\u00e3o social e tamb\u00e9m na teoria da a\u00e7\u00e3o pol\u00edtica, da necessidade de um \u00f3rg\u00e3o operador da pol\u00edtica revolucion\u00e1ria. A revolu\u00e7\u00e3o de 1917 demonstrou, com os sovietes, a capacidade de auto-organiza\u00e7\u00e3o e autogoverno das massas, mas a \u00eanfase do \u00faltimo L\u00eanin foi a necessidade de uma revolu\u00e7\u00e3o cultural que preparasse a transi\u00e7\u00e3o socialista. Muitos dos temas mais instigantes e atuais tratados por Engels e L\u00eanin foram desenvolvidos por Gramsci \u2013 que cumpre 130 anos de nascimento em 2021 \u2013 nos seus Cadernos do C\u00e1rcere, com sua usual postura dial\u00f3gica.<\/p>\n<p>Os 200 anos do nascimento de Engels e os 150 anos de nascimento de L\u00eanin s\u00e3o um momento para que resgatemos a enorme contribui\u00e7\u00e3o cient\u00edfica e pr\u00e1tica pol\u00edtica desses personagens, que contribu\u00edram e instigaram a luta de milhares, milh\u00f5es de homens e mulheres que se entregaram \u00e0 obra da revolu\u00e7\u00e3o em meio a incont\u00e1veis e terr\u00edveis sofrimentos, que ousaram lutar para construir um mundo novo e uma nova humanidade. Os fracassos foram muitos, mas a esperan\u00e7a que move a luta continua viva.<\/p>\n<p>A atual crise do capital, que amea\u00e7a a pr\u00f3pria sobreviv\u00eancia da humanidade, d\u00e1 nova vida \u00e0 obra desses (e de muitos outros) gigantes na luta pela liberdade. Engels e L\u00eanin novamente se tornam leitura indispens\u00e1vel para alimentar a vontade de luta contra a barb\u00e1rie que avan\u00e7a cotidianamente, mas tamb\u00e9m e principalmente para oferecer li\u00e7\u00f5es de organiza\u00e7\u00e3o, de disciplina e mostrar a necessidade de concentrar for\u00e7as, de aprender, de estudar, de travar a luta ideol\u00f3gica, que \u00e9 ao mesmo tempo a luta pela verdade e pela emancipa\u00e7\u00e3o humana. Esses dois grandes revolucion\u00e1rios t\u00eam muito ainda a dizer para que o movimento de massas na Am\u00e9rica Latina seja levado a bom porto com a travessia \u00e1rdua de supera\u00e7\u00e3o da pesada heran\u00e7a colonial e de explora\u00e7\u00e3o abusiva de um capitalismo predat\u00f3rio, que s\u00f3 pode ser substitu\u00eddo por um caminho que leve \u00e0 transi\u00e7\u00e3o socialista.<\/p>\n<p>Marcos Del Roio \u00e9 professor titular de Ci\u00eancias Pol\u00edticas da UNESP-FFC e autor de Os prismas de Gramsci: a f\u00f3rmula pol\u00edtica da frente \u00fanica (1919-1926) (Boitempo, 2019), al\u00e9m de integrar o conselho editorial da cole\u00e7\u00e3o Arsenal L\u00eanin, da Boitempo.<\/p>\n","protected":false},"excerpt":{"rendered":"<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/26585\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[8],"tags":[219],"class_list":["post-26585","post","type-post","status-publish","format-standard","hentry","category-america-latina","tag-manchete"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-6UN","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/26585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=26585"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/26585\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=26585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=26585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=26585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}