{"id":28106,"date":"2021-11-30T02:05:43","date_gmt":"2021-11-30T05:05:43","guid":{"rendered":"https:\/\/pcb.org.br\/portal2\/?p=28106"},"modified":"2021-11-30T02:05:43","modified_gmt":"2021-11-30T05:05:43","slug":"palestina-ampliar-luta-contra-projeto-sionista","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/28106","title":{"rendered":"Palestina: ampliar luta contra projeto sionista"},"content":{"rendered":"<p><img decoding=\"async\" class=\"imagem\" title=\"imagem\" src=\"https:\/\/i0.wp.com\/secondary.hcdsb.org\/xavier\/wp-content\/uploads\/sites\/6\/2021\/06\/pal.jpg\" alt=\"imagem\" \/><!--more-->A \u00fanica forma de derrotar o projeto sionista \u00e9 o caminho da resist\u00eancia<\/p>\n<p>Resumen Oriente M\u00e9dio<\/p>\n<p>Tendo como motivo o Dia Internacional de Solidariedade com o Povo Palestino, os Comit\u00eas de Resist\u00eancia afirmaram em um comunicado nesta segunda-feira que la \u00fanica e fact\u00edvel forma de derrotar o projeto sionista \u00e9 o caminho da resist\u00eancia em todas as suas formas e meios, porque este inimigo s\u00f3 entende a linguagem da for\u00e7a e da confronta\u00e7\u00e3o aberta\u00bb.<\/p>\n<p>O texto considerou que a nefasta decis\u00e3o de dividir a Palestina representa uma cumplicidade ocidental e internacional que n\u00e3o legitima a usurpa\u00e7\u00e3o da Palestina pela entidade criminosa sionista inimiga. Ele indicou que a divis\u00e3o lan\u00e7ou as bases para promover a maior expuls\u00e3o e deslocamento em massa do povo palestino na hist\u00f3ria.<\/p>\n<p>Os comit\u00eas tamb\u00e9m exigiram da Autoridade Palestina que suspenda imediatamente todas as formas de relacionamento com o inimigo, retire o reconhecimento da entidade terrorista sionista, cancele todos os acordos injustos e pare de apostar no caminho das negocia\u00e7\u00f5es.<\/p>\n<p>No mesmo contexto, a Frente Popular de Liberta\u00e7\u00e3o da Palestina considerou que a vontade do povo palestino \u00e9 intensificar a luta contra o inimigo sionista e apelou \u00e0 unifica\u00e7\u00e3o da posi\u00e7\u00e3o \u00e1rabe diante dos projetos de normaliza\u00e7\u00e3o e alian\u00e7a com o inimigo sionista.<\/p>\n<p>O movimento de Al Ahrar reconheceu que a vontade do povo palestino, que se expressa em cada confronto, \u00e9 intensificar a luta contra o inimigo sionista. Destacou que se requer da lideran\u00e7a da Autoridade a associa\u00e7\u00e3o com a solidariedade internacional para fortalecer apoio ao nosso povo e rejeitar a ocupa\u00e7\u00e3o sionista e sua a\u00e7\u00e3o criminosa.<\/p>\n<p>A Campanha Global pelo Retorno \u00e0 Palestina reviveu a ocasi\u00e3o do Dia Internacional de Solidariedade ao Povo Palestino com uma s\u00e9rie de projetos e atividades em apoio ao povo palestino e a fixa\u00e7\u00e3o em sua terra. A atividade da campanha global deste ano, com a participa\u00e7\u00e3o de seus membros espalhados por dezenas de pa\u00edses, est\u00e1 focada em fortalecer a determina\u00e7\u00e3o dos palestinos em se firmar em sua terra, ajudando-os a enfrentar as consequ\u00eancias dos ataques permanentes de Israel em seu dia a dia.<\/p>\n<p>O Dia Internacional de Solidariedade com o Povo Palestino \u00e9 uma oportunidade para chamar a aten\u00e7\u00e3o da comunidade internacional para o fato de que a quest\u00e3o palestina permanece pendente e sem solu\u00e7\u00e3o at\u00e9 hoje, apesar da passagem de d\u00e9cadas e da emiss\u00e3o de muitas resolu\u00e7\u00f5es e leis internacionais relevantes, j\u00e1 que o povo palestino ainda n\u00e3o obteve seus direitos inalien\u00e1veis.<\/p>\n<p>Fonte: Al Mayadeen<\/p>\n<p>https:\/\/www.resumenlatinoamericano.org\/2021\/11\/29\/palestina-la-unica-forma-de-desarraigar-el-proyecto-sionista-es-el-camino-de-la-resistencia\/<\/p>\n<p>Tradu\u00e7\u00e3o: Partido Comunista Brasileiro (PCB)<\/p>\n","protected":false},"excerpt":{"rendered":"<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/28106\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[78],"tags":[227],"class_list":["post-28106","post","type-post","status-publish","format-standard","hentry","category-c91-solidariedade-a-palestina","tag-5a"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-7jk","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/28106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=28106"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/28106\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=28106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=28106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=28106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}