{"id":28549,"date":"2022-03-09T10:19:55","date_gmt":"2022-03-09T13:19:55","guid":{"rendered":"https:\/\/pcb.org.br\/portal2\/?p=28549"},"modified":"2022-03-09T10:19:55","modified_gmt":"2022-03-09T13:19:55","slug":"o-pcb-tem-um-projeto-politico-de-transformacao-radical","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/28549","title":{"rendered":"&#8220;O PCB tem um projeto pol\u00edtico de transforma\u00e7\u00e3o radical\u201d"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"imagem\" title=\"imagem\" src=\"https:\/\/i0.wp.com\/lavrapalavra.com\/wp-content\/uploads\/2015\/08\/image-4.png?w=747&#038;ssl=1\" alt=\"imagem\" \/><!--more--><\/p>\n<p><strong>Entrevista com a professora Sofia Manzano, pr\u00e9-candidata do PCB a Presidenta do Brasil, para o Canal do Poder Popular<\/strong><\/p>\n<p><strong>O Poder Popular:<\/strong> Quais s\u00e3o os objetivos centrais da pr\u00e9-candidatura do PCB \u00e0 Presid\u00eancia da Rep\u00fablica?<\/p>\n<p><strong>Prof\u00aa Sofia:<\/strong> Em primeiro lugar, devo dizer que \u00e9 uma honra para mim ter sido escolhida como pr\u00e9-candidata do Partido Comunista Brasileiro, neste ano em que comemoramos o centen\u00e1rio da nossa organiza\u00e7\u00e3o. O PCB \u00e9 o Partido mais antigo em atividade no pa\u00eds, passou grande parte da sua vida na clandestinidade, mas nunca deixou de existir, pois os militantes comunistas seguiram, mesmo na ilegalidade, atuando diuturnamente para construir o processo revolucion\u00e1rio no Brasil. \u00c9 um momento muito importante para n\u00f3s, que vamos debater com os trabalhadores e as trabalhadoras o que as\/os comunistas prop\u00f5em para o pa\u00eds. O PCB tem um projeto pol\u00edtico de transforma\u00e7\u00e3o radical da realidade brasileira, no rumo do Socialismo.<\/p>\n<p><strong>OPP:<\/strong> Movimentos sociais e partidos de oposi\u00e7\u00e3o est\u00e3o divididos quanto \u00e0 t\u00e1tica adotada para derrotar o projeto genocida do Governo Bolsonaro. Enquanto algumas for\u00e7as pol\u00edticas se preocupam em ocupar as ruas em prol da organiza\u00e7\u00e3o popular, outras preferem apostar unicamente nas elei\u00e7\u00f5es. Como a pr\u00e9-candidatura do PCB se coloca neste quadro?<\/p>\n<p><strong>Prof\u00aa Sofia:<\/strong> Estamos diante de um governo de destrui\u00e7\u00e3o nacional. O PCB e seus coletivos de luta, em conjunto com outros movimentos pol\u00edticos e sociais, ocupamos as ruas para tentar derrubar o governo. As principais for\u00e7as da burguesia brasileira agiram, por meio do Congresso Nacional e do Judici\u00e1rio, no sentido de impedir at\u00e9 agora a derrubada efetiva do governo Bolsonaro. Por outro lado, uma parcela da esquerda optou por abandonar as lutas nas ruas, priorizando a quest\u00e3o eleitoral. N\u00f3s n\u00e3o podemos fazer essa \u00fanica op\u00e7\u00e3o, por v\u00e1rios motivos.<\/p>\n<p><strong>&#8220;Cada dia que Bolsonaro continua \u00e0 frente do governo, s\u00e3o mais pessoas que v\u00e3o passar fome, s\u00e3o mais jovens que n\u00e3o ter\u00e3o emprego, s\u00e3o mais pessoas que v\u00e3o morrer seja da viol\u00eancia ou da Covid.\u201d<\/strong><\/p>\n<p>N\u00f3s n\u00e3o sairemos das ruas. Temos todo um calend\u00e1rio de lutas e mobiliza\u00e7\u00f5es neste ano (08 de Mar\u00e7o, Dia Internacional das Mulheres, as lutas do movimento sindical e popular, etc) e s\u00f3 poderemos implementar um programa pol\u00edtico que n\u00e3o seja rebaixado, que n\u00e3o seja apenas um melhorismo marginal da situa\u00e7\u00e3o da classe trabalhadora, mas que seja capaz de colocar trabalhadores e trabalhadoras como protagonistas da pol\u00edtica e do desenvolvimento do Brasil se estas elei\u00e7\u00f5es estiverem combinadas com o ascenso da luta de classes. Acreditar simplesmente que \u00e9 poss\u00edvel ganhar elei\u00e7\u00f5es atrav\u00e9s de acordos eleitorais sem mobilizar as massas para defender seu programa pol\u00edtico \u00e9 uma grande ilus\u00e3o.<\/p>\n<p><strong>OPP:<\/strong> O povo trabalhador brasileiro precisa que seus problemas imediatos sejam resolvidos, a exemplo da fome, que volta a assolar quase metade da popula\u00e7\u00e3o, e do desemprego. Como enfrentar esse cen\u00e1rio de extrema precariza\u00e7\u00e3o da vida da classe trabalhadora?<\/p>\n<p><strong>Prof\u00aa Sofia:<\/strong> Diante do crescimento brutal da fome, da desnutri\u00e7\u00e3o, das dificuldades que milh\u00f5es de fam\u00edlias est\u00e3o passando neste momento, medidas emergenciais s\u00e3o necess\u00e1rias, com a transfer\u00eancia de recursos do Estado para essas fam\u00edlias manterem sua sobreviv\u00eancia. Al\u00e9m disso, o programa pol\u00edtico do PCB visa a aplica\u00e7\u00e3o de um projeto de desenvolvimento anticapitalista. A hist\u00f3ria mostra que, mesmo quando tivemos um governo progressista, que chegou a elevar o padr\u00e3o de vida da popula\u00e7\u00e3o mais pobre, retirou o Brasil do mapa da fome, incluiu uma quantidade significativa de jovens na universidade, quando estas for\u00e7as pol\u00edticas perdem a elei\u00e7\u00e3o, todas essas conquistas s\u00e3o varridas imediatamente. As medidas assistenciais e emergenciais s\u00e3o necess\u00e1rias, por\u00e9m insuficientes. Passamos, nos \u00faltimos 30 anos, sob a l\u00f3gica da ideologia neoliberal, sofrendo com a destrui\u00e7\u00e3o de significativa parcela do parque industrial brasileiro. A desindustrializa\u00e7\u00e3o e a reprimariza\u00e7\u00e3o da nossa economia pioram as condi\u00e7\u00f5es da produ\u00e7\u00e3o e tamb\u00e9m da inser\u00e7\u00e3o dos trabalhadores e das trabalhadoras no mercado de trabalho.<\/p>\n<p><strong>&#8220;A burguesia interna brasileira viu todo esse processo de desindustrializa\u00e7\u00e3o acontecer e aplaudiu. Ela n\u00e3o se contrap\u00f4s a isso.&#8221;<\/strong><\/p>\n<p>N\u00e3o d\u00e1 mais pra ter ilus\u00e3o com um projeto de desenvolvimento contando com parceiros dessa esp\u00e9cie. O nosso programa tem independ\u00eancia de classe. O Brasil tem um potencial imenso de ir por um caminho que supere todos os problemas estruturais vividos pela classe trabalhadora. Mas quem deve comandar esse processo de mudan\u00e7as \u00e9 a pr\u00f3pria classe trabalhadora, pois a burguesia brasileira \u00e9 predat\u00f3ria e todas as medidas tomadas por ela s\u00e3o no sentido da explora\u00e7\u00e3o e expropria\u00e7\u00e3o brutal das riquezas produzidas pela classe trabalhadora.<\/p>\n<p><strong>OPP:<\/strong> Atualmente o maior problema da juventude brasileira \u00e9 o desemprego. Como fazer para o pa\u00eds crescer e gerar empregos de qualidade para a juventude?<\/p>\n<p><strong>Prof\u00aa Sofia:<\/strong> A taxa de desemprego na juventude brasileira \u00e9 muito alta e, no interior da juventude negra, maior ainda. A primeira coisa que devemos fazer \u00e9 um grande movimento para revogar as contrarreformas aprovadas desde o Governo Fernando Henrique. <strong>Propomos uma grande mobiliza\u00e7\u00e3o em favor de um plebiscito revogat\u00f3rio das medidas que destru\u00edram direitos trabalhistas e previdenci\u00e1rios, para revogar a lei do teto de gastos, as medidas respons\u00e1veis pelo aumento da degrada\u00e7\u00e3o ambiental por conta da expans\u00e3o do agroneg\u00f3cio.<\/strong> Nosso programa prev\u00ea a redu\u00e7\u00e3o dr\u00e1stica da jornada de trabalho sem redu\u00e7\u00e3o de sal\u00e1rios, eleva\u00e7\u00e3o do valor do sal\u00e1rio-m\u00ednimo de forma a que todas as outras atividades tamb\u00e9m tenham a remunera\u00e7\u00e3o elevada, medidas que devem vir acompanhadas do protagonismo da classe trabalhadora e da juventude na sustenta\u00e7\u00e3o das mudan\u00e7as, para evitar que sejam posteriormente anuladas por meio de outras contrarreformas.<\/p>\n<p>OPP: As quest\u00f5es da sa\u00fade, da educa\u00e7\u00e3o e da seguran\u00e7a p\u00fablica afligem a popula\u00e7\u00e3o brasileira. Mesmo na pandemia, o projeto neoliberal segue avan\u00e7ando com sua pol\u00edtica de privatiza\u00e7\u00e3o dos servi\u00e7os p\u00fablicos. Que proposta tem o PCB para enfrentar essa situa\u00e7\u00e3o?<\/p>\n<p>Prof\u00aa Sofia: Defendemos que o setor de sa\u00fade seja totalmente p\u00fablico. N\u00e3o s\u00f3 o SUS deve ser 100% p\u00fablico, todo setor de sa\u00fade deve ser p\u00fablico, assim como a educa\u00e7\u00e3o. Combatemos a expans\u00e3o da sa\u00fade privada e o crescimento dos planos de sa\u00fade, mas tamb\u00e9m a privatiza\u00e7\u00e3o que ocorre dentro do SUS. Atrav\u00e9s de mecanismos como a contrata\u00e7\u00e3o de OSs (Organiza\u00e7\u00f5es Sociais) e de cooperativas, o Estado garante o equipamento p\u00fablico e paga ao setor privado o gerenciamento do servi\u00e7o, que muitas vezes nem \u00e9 feito. O setor privado \u00e9 muito prejudicial \u00e0 sa\u00fade. No caso da educa\u00e7\u00e3o, os servidores p\u00fablicos federais est\u00e3o se mobilizando na luta pela recomposi\u00e7\u00e3o de seus sal\u00e1rios, para enfrentar o desmonte das estruturas p\u00fablicas e a PEC da reforma administrativa, que representa a destrui\u00e7\u00e3o do servi\u00e7o p\u00fablico no Brasil. Nossa pr\u00e9-campanha est\u00e1 na luta dos servidores p\u00fablicos em todas as esferas e em defesa da estatiza\u00e7\u00e3o da sa\u00fade e da educa\u00e7\u00e3o.<\/p>\n<p>OPP: Que projeto o PCB tem para a universidade brasileira?<\/p>\n<p><strong>Prof\u00aa Sofia:<\/strong> Eu sou professora universit\u00e1ria, milito no movimento sindical na minha universidade e temos sim um projeto para a universidade brasileira. Inclusive todos podem seguir nas redes sociais o MUP, Movimento por uma Universidade Popular. A UJC e os sindicalistas da Unidade Classista levam essa bandeira, com o objetivo de pensar uma universidade que sirva aos interesses e \u00e0s necessidades da classe trabalhadora e n\u00e3o aos interesses da burguesia. A universidade tem que ser totalmente p\u00fablica, gratuita e estatal. O que hoje existe no sistema universit\u00e1rio brasileiro \u00e9 uma aberra\u00e7\u00e3o, com uma quantidade gigantesca de universidades privadas com qualidade absolutamente duvidosa, funcionando de forma t\u00e3o prec\u00e1ria, desregulamentada, explorando a necessidade educacional da juventude brasileira. O que existe hoje \u00e9 uma \u201cxepa\u201d de ensino superior privado de p\u00e9ssima qualidade, cujo \u00fanico objetivo \u00e9 fazer com que os jovens tenham a ilus\u00e3o de que pagando essas mensalidades eles ter\u00e3o melhores possibilidades de futuro. \u00c9 preciso acabar com isso, a universidade tem que ser totalmente p\u00fablica, desde que a sua estrutura n\u00e3o esteja voltada aos interesses da burguesia, como ocorre hoje. Nos tr\u00eas componentes que fazem parte da universidade p\u00fablica brasileira, ou seja, ensino, extens\u00e3o e pesquisa, temos muitas vezes um ensino tecnicista, fazendo da universidade um espa\u00e7o de treinamento de m\u00e3o de obra qualificada para o mercado de trabalho e n\u00e3o de constru\u00e7\u00e3o de conhecimento e do crescimento cultural no sentido amplo. Claro que \u00e9 preciso desenvolver habilidades para o trabalho, o que tamb\u00e9m ser\u00e1 feito no comunismo, mas nossa universidade \u00e9 t\u00e3o acr\u00edtica em rela\u00e7\u00e3o \u00e0 sociedade que os jovens n\u00e3o escolhem hoje o curso que querem fazer de acordo com suas potencialidades e habilidades, mas de acordo com o que o mercado de trabalho pode lhe oferecer. Quanto \u00e0 pesquisa, grande parte dela hoje se volta para os interesses do capital, mesmo na \u00e1rea da sa\u00fade. Muitas doen\u00e7as que afligem a popula\u00e7\u00e3o negra n\u00e3o t\u00eam dentro da universidade um espa\u00e7o de pesquisa t\u00e3o grande quanto outras doen\u00e7as que afligem a popula\u00e7\u00e3o branca e de mais alta renda. N\u00f3s queremos fortalecer a universidade, n\u00e3o destru\u00ed-la. Ela precisa ser expandida, precisa ter muito mais recursos, estrutura, carreira docente, perman\u00eancia estudantil, todo um conjunto de medidas para que o jovem que entra na universidade n\u00e3o viva a situa\u00e7\u00e3o de eterna inseguran\u00e7a em saber se vai ter aula direito ou se vai padecer dos problemas resultantes da defasagem salarial dos docentes ou da estrutura f\u00edsica prec\u00e1ria. Temos, portanto, estudos e propostas concretas de como esta universidade deva se transformar em algo que a classe trabalhadora merece e precisa.<\/p>\n<p><strong>OPP:<\/strong> Quando vemos a conforma\u00e7\u00e3o da classe trabalhadora brasileira, vemos que \u00e9 uma classe tamb\u00e9m feminina, negra, LGBT, numa diversidade que deve ser objeto de an\u00e1lise pol\u00edtica para combater as opress\u00f5es que afligem esses grupos sociais. O que voc\u00ea pensa sobre essas pautas, na perspectiva de garantir vida digna \u00e0 nossa classe em toda essa diversidade?<\/p>\n<p><strong>Prof\u00aa Sofia:<\/strong> Minha pr\u00e9-candidatura n\u00e3o \u00e9 pessoal, \u00e9 uma pr\u00e9-candidatura do PCB e dos seus Coletivos, cujas propostas s\u00e3o resultantes da constru\u00e7\u00e3o coletiva em torno tanto da an\u00e1lise da realidade brasileira quanto dos programas necess\u00e1rios para enfrentar essa realidade. Nossos coletivos partid\u00e1rios dedicam-se a estudar a realidade dos grupos sociais que sofrem diferentes formas de opress\u00e3o, levando a luta destes grupos e propondo medidas profundas e estruturais que fa\u00e7am com que deixem de ser grupos segregados e oprimidos, trabalhando as pautas das mulheres contra o machismo, da popula\u00e7\u00e3o negra que sofre no Brasil um racismo brutal, das LGBTs. Somos um dos pa\u00edses que mais matam LGBTs, mulheres, negras e negros. Temos de agir no \u00e2mbito das pautas imediatas de cada um desses grupos populacionais, lembrando sempre que as causas das opress\u00f5es, em \u00faltima inst\u00e2ncia, est\u00e3o ligadas \u00e0 quest\u00e3o da classe a que esses grupos pertencem. O machismo se expressa, por exemplo, no fato de que todo trabalho dom\u00e9stico \u00e9 quase sempre realizado por uma mulher prolet\u00e1ria. Temos de organizar essas popula\u00e7\u00f5es a partir da perspectiva de classe para a constru\u00e7\u00e3o do Poder Popular e para um projeto revolucion\u00e1rio.<\/p>\n<p><strong>OPP:<\/strong> Qual \u00e9 a perspectiva em rela\u00e7\u00e3o \u00e0 luta internacionalista?<\/p>\n<p><strong>Prof\u00aa Sofia:<\/strong> Estamos vivendo um momento de ascens\u00e3o de uma ideologia reacion\u00e1ria no pa\u00eds e no mundo, de um anticomunismo doentio. J\u00e1 fui questionada em outras entrevistas a meios de comunica\u00e7\u00e3o da seguinte forma: \u201cse voc\u00ea for presidente, voc\u00ea vai prestar solidariedade a Cuba e \u00e0 Venezuela?\u201d. Respondo que somente solidariedade, n\u00e3o. Vamos apoiar efetivamente todos os povos que est\u00e3o construindo seu processo de caminhar para o socialismo. S\u00e3o vis\u00edveis os resultados das pol\u00edticas adotadas nesses pa\u00edses quanto \u00e0 qualidade de vida da popula\u00e7\u00e3o. Vamos apoiar tamb\u00e9m os povos que est\u00e3o sofrendo com a opress\u00e3o imperialista, a exemplo da luta em defesa do povo palestino, dos curdos, do povo iraniano, que vive embargos por se tratar de um pa\u00eds que apresenta uma atitude anti-imperialista. Vamos nos esfor\u00e7ar no plano internacional para construir um bloco anti-imperialista, que enfrente de fato as grandes pot\u00eancias imperialistas, principalmente os Estados Unidos, mas tamb\u00e9m os pa\u00edses europeus que exercem seus imperialismos sobre outros povos, trabalhadores e trabalhadoras das regi\u00f5es perif\u00e9ricas do mundo. N\u00e3o vamos apenas voltar a ter uma diplomacia como as pessoas costumam dizer que era a diplomacia brasileira.<\/p>\n<p><strong>&#8220;Nossa postura ser\u00e1 de enfrentamento ao imperialismo, mobilizando a popula\u00e7\u00e3o a apoiar um governo anti-imperialista, a partir do entendimento do que significa a a\u00e7\u00e3o do imperialismo para o cotidiano da classe trabalhadora.&#8221;<\/strong><\/p>\n<p><strong>OPP:<\/strong> Outra quest\u00e3o importante da atual conjuntura \u00e9 que 2022 come\u00e7ou com muitos desastres ambientais no Sul da Bahia, em Minas Gerais e, mais recentemente, em Petr\u00f3polis, no Estado do Rio de Janeiro, em consequ\u00eancia, dentre outros motivos, da especula\u00e7\u00e3o imobili\u00e1ria, do avan\u00e7o dos grandes empreendimentos sobre as cidades. Que propostas voc\u00ea tem em rela\u00e7\u00e3o \u00e0 quest\u00e3o da moradia?<\/p>\n<p><strong>Prof\u00aa Sofia:<\/strong> Devemos em primeiro lugar considerar que os desastres s\u00e3o provocados pelo capitalismo. \u00c9 evidente que h\u00e1 mudan\u00e7as clim\u00e1ticas que est\u00e3o provocando tamb\u00e9m mudan\u00e7as nos padr\u00f5es de chuva e seca, que tamb\u00e9m s\u00e3o consequ\u00eancia da a\u00e7\u00e3o do capitalismo. \u00c9 preciso debater o que leva a ocorrer o desastre, desde as mudan\u00e7as clim\u00e1ticas, a destrui\u00e7\u00e3o do meio ambiente, at\u00e9 o momento em si da cat\u00e1strofe, do alagamento, dos desmoronamentos, \u00e9 poss\u00edvel perceber o quanto interferem situa\u00e7\u00f5es como a especula\u00e7\u00e3o imobili\u00e1ria, a expuls\u00e3o da popula\u00e7\u00e3o das regi\u00f5es mais apropriadas para a habita\u00e7\u00e3o e a constru\u00e7\u00e3o das moradias deixadas por conta das pr\u00f3prias fam\u00edlias. Por que as pessoas s\u00e3o obrigadas a viver em locais em que frequentemente s\u00e3o atingidas por cat\u00e1strofes? \u00c9 todo um modelo de cidade que s\u00f3 visa atender as necessidades do capital. Vivo numa cidade que vive um boom imobili\u00e1rio gigantesco, ao mesmo tempo em que tem muito morador de rua, o que n\u00e3o existia h\u00e1 um tempo atr\u00e1s, popula\u00e7\u00f5es que foram submetidas \u00e0 situa\u00e7\u00e3o de rua porque perderam a m\u00ednima condi\u00e7\u00e3o de habita\u00e7\u00e3o que tinham antes. \u00c9 preciso promover um plano de reestrutura\u00e7\u00e3o urbana que vincule a quest\u00e3o da moradia com a quest\u00e3o do transporte e da distribui\u00e7\u00e3o dos empregos, para al\u00e9m das regi\u00f5es centrais j\u00e1 altamente urbanizadas. O desenvolvimento brasileiro precisa contar com uma estrat\u00e9gia de desenvolvimento regional descentralizada.<\/p>\n<p>Muitos podem perguntar: com que dinheiro voc\u00ea vai fazer tudo isso que est\u00e1 previsto no seu programa?<\/p>\n<p><strong>&#8220;Lutamos pela revoga\u00e7\u00e3o da Lei de Responsabilidade Fiscal e pela implanta\u00e7\u00e3o de uma Lei de Responsabilidade Social.&#8221;<\/strong><\/p>\n<p>A LRF, aprovada no governo FHC e n\u00e3o questionada pelos governos seguintes, limita os gastos com os servidores p\u00fablicos e com as estruturas p\u00fablicas, para sobrar dinheiro p\u00fablico a fim de remunerar os t\u00edtulos da d\u00edvida p\u00fablica, que est\u00e3o enriquecendo os banqueiros e os bilion\u00e1rios que inclusive dobraram suas fortunas durante a pandemia. Nossa proposta \u00e9 fazer justamente o contr\u00e1rio: sa\u00fade, educa\u00e7\u00e3o, emprego, seguran\u00e7a p\u00fablica, moradia, saneamento, tudo aquilo que \u00e9 essencial para a vida da classe trabalhadora vai estar em primeiro lugar. Se conseguirmos transformar essas propostas num grande movimento popular, faremos com que o parlamento aprove medidas dessa natureza, porque \u00e9 a for\u00e7a da classe trabalhadora que faz a luta de classes avan\u00e7ar.<\/p>\n<p><strong>Assista na \u00edntegra a entrevista de Sofia Manzano no Canal do Poder Popular:<\/strong><\/p>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"747\" height=\"421\" src=\"https:\/\/www.youtube.com\/embed\/ezAzTBJk-ps?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=pt-BR&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/28549\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"\"Propomos uma grande mobiliza\u00e7\u00e3o por um plebiscito revogat\u00f3rio das medidas que destru\u00edram direitos trabalhistas e previdenci\u00e1rios, para revogar a lei do teto de gastos, as medidas respons\u00e1veis pela degrada\u00e7\u00e3o ambiental para expans\u00e3o do agroneg\u00f3cio.\"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[219],"class_list":["post-28549","post","type-post","status-publish","format-standard","hentry","category-geral","tag-manchete"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-7qt","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/28549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=28549"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/28549\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=28549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=28549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=28549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}