{"id":28805,"date":"2022-05-20T17:52:43","date_gmt":"2022-05-20T20:52:43","guid":{"rendered":"https:\/\/pcb.org.br\/portal2\/?p=28805"},"modified":"2022-05-20T17:52:43","modified_gmt":"2022-05-20T20:52:43","slug":"a-luta-antimanicomial-segue-contra-os-retrocessos","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/28805","title":{"rendered":"A Luta Antimanicomial segue contra os retrocessos"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"imagem\" title=\"imagem\" src=\"https:\/\/i0.wp.com\/lavrapalavra.com\/wp-content\/uploads\/2015\/08\/unnamed.jpg?w=747&#038;ssl=1\" alt=\"imagem\" \/><!--more--><\/p>\n<p><strong>Por Let\u00edcia Caroline* e Renata Regina*, via\u00a0O Poder Popular MG<\/strong><\/p>\n<p>A pr\u00e1tica manicomial surgiu numa conjuntura higienista e contraria a classe trabalhadora. Os manic\u00f4mios eram direcionados \u00e0quelas e aqueles considerados fora dos padr\u00f5es de normalidade e eram pouco \u00fateis aos modos de reprodu\u00e7\u00e3o do capitalismo. Desta forma, as(os) trabalhadoras(es) que n\u00e3o eram submetidas(os) \u00e0 explora\u00e7\u00e3o, sendo pessoas com quest\u00f5es de sa\u00fade mental ou n\u00e3o, acabavam sendo varridas(os) dos espa\u00e7os p\u00fablicos e de socializa\u00e7\u00e3o. Mais que isso, eram jogadas aos manic\u00f4mios. Nos manic\u00f4mios, os considerados loucos eram medicalizados, lobotomizados, torturados e mortos. Eram desumanizados e destitu\u00eddos de qualquer direito ou dignidade.<\/p>\n<p>Na cidade mineira de Barbacena ocorreu o chamado \u201cholocausto brasileiro\u201d, onde foram \u201cinternadas\u201d milhares de pessoas no hospital Col\u00f4nia. Estas pessoas eram retiradas \u00e0 for\u00e7a das ruas, dos atos pol\u00edticos e do enfrentamento ao estado burgu\u00eas. Eram comunistas, mulheres feministas ou quem de alguma forma afrontava a fam\u00edlia tradicional burguesa, como trabalhadoras dom\u00e9sticas que engravidavam do patr\u00e3o, pessoas negras, ind\u00edgenas, lgbtqia+, em situa\u00e7\u00e3o de rua, com defici\u00eancias e\/ou com comportamentos que contrariavam a ordem vigente. Retirar estas pessoas dos espa\u00e7os p\u00fabicos foi fundamental para o desenvolvimento do capitalismo que conhecemos. Torturar e matar parte da classe trabalhadora evidencia a forma de fazer pol\u00edtica da burguesia.<\/p>\n<p>Somente no hospital Col\u00f4nia morriam cerca de 16 pessoas por dia. Nem 30% destas sequer continham diagn\u00f3stico de doen\u00e7a mental. Ao final, foram mais de 60 mil mortes somente em um manic\u00f4mio e em curto per\u00edodo temporal. Por este motivo, trabalhadoras e trabalhadores, usu\u00e1rios e familiares dos usu\u00e1rios dos servi\u00e7os de sa\u00fade mental constru\u00edram popularmente um movimento para denunciar o genoc\u00eddio. O Movimento Antimanicomial, que era contra o modelo manicomial e as graves viola\u00e7\u00f5es de direitos que ocorriam nele.<\/p>\n<p>O movimento incorporou-se \u00e0 luta pelo cuidado da sa\u00fade mental em liberdade, ap\u00f3s a carta redigida no II Congresso Nacional de Trabalhadores em Sa\u00fade Mental em 1987, conhecida como \u201cManifesto de Bauru\u201d. Cuidar em liberdade \u00e9 garantir dignidade \u00e0s pessoas em sofrimento mental, \u00e9 considerar que n\u00e3o devemos retirar as pessoas loucas dos espa\u00e7os p\u00fablicos e de socializa\u00e7\u00e3o, e n\u00e3o mercantilizar as formas de tratamento.<\/p>\n<p>Nise da Silveira, filiada ao Partido Comunista Brasileiro (PCB) e reconhecida mundialmente por revolucionar o tratamento de sa\u00fade mental no Brasil, foi pioneira da da reforma psiqui\u00e1trica e da luta antimanicomial em nosso pa\u00eds: ainda na d\u00e9cada de 1940, defendia formas humanizadas de tratamento quando era comum tratar pacientes internados em manic\u00f4mios com m\u00e9todos agressivos, como o eletrochoque, camisa de for\u00e7a e lobotomia. Nomes como Franco Basaglia, psiquiatra italiano que tinha como princ\u00edpio o \u201cpertencimento de classe: classe dos loucos\u201d e Marcus Vinicius Matraga, professor da UFBA assassinado em 2016 justamente por denunciar as formas abusivas de tratamento, tamb\u00e9m estiveram no enfrentamento e deixaram suas pr\u00e1ticas revolucion\u00e1rias como legado.<\/p>\n<p>A luta antimanicomial foi fundamental para a conquista de leis e pol\u00edticas p\u00fablicas que tratam da prote\u00e7\u00e3o dos direitos das pessoas com transtornos mentais e redireciona o modelo de assist\u00eancia. Essas leis atribu\u00edram ao Estado a responsabilidade de promover um tratamento em comunidade, possibilitando a livre circula\u00e7\u00e3o dos pacientes e n\u00e3o mais a interna\u00e7\u00e3o e o isolamento, contando com os servi\u00e7os de Centros de Aten\u00e7\u00e3o Psicossocial (CAPS); os Servi\u00e7os Residenciais Terap\u00eauticos (SRT); os Centros de Conviv\u00eancia e Cultura, as Unidade de Acolhimento (UAs), e os leitos de aten\u00e7\u00e3o integral (em Hospitais Gerais, nos CAPS III).<\/p>\n<p>Em 2001 foi aprovada legisla\u00e7\u00e3o que estabeleceu tamb\u00e9m a responsabilidade do Estado no desenvolvimento da pol\u00edtica de sa\u00fade mental no Brasil, atrav\u00e9s do fechamento de hospitais psiqui\u00e1tricos, abertura de novos servi\u00e7os comunit\u00e1rios e participa\u00e7\u00e3o social no acompanhamento de sua implementa\u00e7\u00e3o. A lei tamb\u00e9m impede as interna\u00e7\u00f5es compuls\u00f3rias, que s\u00e3o realizadas sem o consentimento do paciente ou de seus respons\u00e1veis e indica que a interna\u00e7\u00e3o deveria ser um \u00faltimo recurso em casos de extrema urg\u00eancia, quando o paciente \u00e9 tido como algu\u00e9m que pode oferecer amea\u00e7a para si e\/ou para terceiros, e determina que, nesses casos, o m\u00e9dico deve notificar ao Minist\u00e9rio P\u00fablico sobre a interna\u00e7\u00e3o e alta. Outro marco importante foi a institui\u00e7\u00e3o da Rede de Aten\u00e7\u00e3o Psicossocial (RAPS) em 2011, que previa a amplia\u00e7\u00e3o e a articula\u00e7\u00e3o de pontos de aten\u00e7\u00e3o \u00e0 sa\u00fade para pessoas com sofrimento ou transtorno mental e com necessidades decorrentes do uso de crack, \u00e1lcool e outras drogas no \u00e2mbito do SUS.<\/p>\n<p>No entanto, mesmo com todos os avan\u00e7os, alguns manic\u00f4mios continuam existindo. \u00c9 importante ressaltar que essa legisla\u00e7\u00e3o ainda n\u00e3o \u00e9 devidamente implementada e est\u00e1 em constante amea\u00e7a, por isso a luta antimanicomial \u00e9 t\u00e3o importante e necess\u00e1ria. Na conjuntura atual, com o avan\u00e7o da onda neoliberal e fascista, a l\u00f3gica manicomial voltou a ganhar for\u00e7a e a Pol\u00edtica de Sa\u00fade Mental est\u00e1 passando por retrocessos significativos. O atual governo segue realocando as verbas para a abertura de mais leitos em hospitais psiqui\u00e1tricos, que deveriam ser extintas de acordo com a legisla\u00e7\u00e3o brasileira e tratados internacionais, al\u00e9m de financiar as comunidades terap\u00eauticas.Em mar\u00e7o deste ano, o Minist\u00e9rio da Cidadania publicou edital que destina R$10 milh\u00f5es para Organiza\u00e7\u00f5es da Sociedade Civil (OSC) que prestam atendimento como hospitais psiqui\u00e1tricos.<\/p>\n<p>Para resolver a quest\u00e3o da insufici\u00eancia dos servi\u00e7os p\u00fablicos no atendimento \u00e0 alta demanda por servi\u00e7os de sa\u00fade mental, precisamos garantir o fortalecimento do SUS, com investimento de recursos que proporcionem amplia\u00e7\u00e3o, melhoria das estruturas, condi\u00e7\u00f5es de trabalho e remunera\u00e7\u00e3o para os trabalhadores. Retomar a l\u00f3gica manicomial e destinar recursos p\u00fablicos para iniciativa privada agravam o problema e representam um enorme retrocesso em todas as conquistas do movimento antimanicomial.<\/p>\n<p>N\u00e3o defendemos a abertura de mais leitos psiqui\u00e1tricos, pois, com a reforma, a interna\u00e7\u00e3o deveria ser considerada apenas em \u00faltima inst\u00e2ncia. Abrir mais leitos significa priorizar algo que o Movimento Antimanicomial visa como exce\u00e7\u00e3o, al\u00e9m de fortalecer a pr\u00e1tica. Defendemos tamb\u00e9m o fim das comunidades terap\u00eauticas, pois n\u00e3o est\u00e3o alinhadas com o princ\u00edpio de cuidar em liberdade. Estas comunidades, localizadas em locais isolados como fazendas e s\u00edtios, aproveitam da interna\u00e7\u00e3o compuls\u00f3ria de jovens para utiliz\u00e1-las como for\u00e7a de trabalho. Investir em comunidades terap\u00eauticas \u00e9 financiar a explora\u00e7\u00e3o dos trabalhadores em subempregos por parte de integrantes de igrejas evang\u00e9licas, diretamente ligadas \u00e0 coordena\u00e7\u00e3o das casas e manuten\u00e7\u00e3o da pr\u00e1tica escravagista.<\/p>\n<p>Por fim, na conjuntura atual, onde a Dra. Cl\u00e1udia Navarro, ex-Diretora do Conselho Regional de Medicina de Minas Gerais (CRM-MG), foi nomeada como secret\u00e1ria de Sa\u00fade de Belo Horizonte, precisamos mais que nunca estar junto \u00e0 Luta Antimanicomial. O CRM na secretaria de Sa\u00fade de Belo Horizonte (cidade refer\u00eancia nos servi\u00e7os de sa\u00fade mental) representa um risco \u00e0 defesa das pol\u00edticas p\u00fablicas, principalmente, da Pol\u00edtica de Sa\u00fade Mental, pois o Conselho se evidencia sendo contra a reforma psiqui\u00e1trica e em 2021 tentou impedir o atendimento nos Centros de Refer\u00eancia de Sa\u00fade Mental (Cersams), pedindo que os mesmos fossem interditados, ap\u00f3s supostamente encontrar irregularidade em vistorias realizadas nas unidades. Na pr\u00e1tica, o Conselho queria impedir que os m\u00e9dicos realizassem atendimentos nos centros, ignorando o impacto social que isso acarretaria. Al\u00e9m disso, se posicionou a favor do kit covid, defendido pelo genocida presidente e toda a burguesia negacionista.<\/p>\n<p>Por esse motivo, afirmamos que: sa\u00fade n\u00e3o se vende, loucura n\u00e3o se prende. Lugar do CRM \u00e9 na CPI da Covid. Em defesa do SUS. Pelo cuidado em liberdade!<\/p>\n<p>Viva a Luta Antimanicomial!<br \/>\n*Let\u00edcia Caroline \u00e9 Psic\u00f3loga social, abolicionista penal e militante no CFCAM. Atua como analista social na Pol\u00edtica de Preven\u00e7\u00e3o \u00e0 Criminalidade, tamb\u00e9m no apoio psicossocial e reterritorializa\u00e7\u00e3o de ind\u00edgenas venezuelanos refugiados pela SJMR, \u00e9 da diretoria do n\u00facleo Abrapso BH e comp\u00f5e o Desencarcera MG.<\/p>\n<p>**Renata Regina \u00e9 m\u00e3e, doula, fot\u00f3grafa e jornalista em forma\u00e7\u00e3o. Comp\u00f5e a Coordena\u00e7\u00e3o Nacional do Coletivo Feminista Classista, a dire\u00e7\u00e3o nacional e estadual do PCB e \u00e9 pr\u00e9-candidata ao governo de Minas Gerais pelo partido.<\/p>\n","protected":false},"excerpt":{"rendered":"<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/28805\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"\"Os manic\u00f4mios eram direcionados a quem era considerados fora dos padr\u00f5es de normalidade e pouco \u00fatil ao capitalismo. A luta antimanicomial foi fundamental para a conquista da prote\u00e7\u00e3o dos direitos das pessoas com transtornos mentais.\"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[225],"class_list":["post-28805","post","type-post","status-publish","format-standard","hentry","category-geral","tag-4a"],"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p659gw-7uB","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/28805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=28805"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/28805\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=28805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=28805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=28805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}