{"id":28812,"date":"2022-05-21T15:02:42","date_gmt":"2022-05-21T18:02:42","guid":{"rendered":"https:\/\/pcb.org.br\/portal2\/?p=28812"},"modified":"2022-05-21T15:02:42","modified_gmt":"2022-05-21T18:02:42","slug":"eduardo-serra-pcb-rj-pre-candidato-ao-governo-rj","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/28812","title":{"rendered":"Eduardo Serra (PCB-RJ): pr\u00e9-candidato ao governo RJ"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"imagem\" title=\"imagem\" src=\"https:\/\/i0.wp.com\/lavrapalavra.com\/wp-content\/uploads\/2015\/08\/image-26.png?w=747&#038;ssl=1\" alt=\"imagem\" \/><!--more--><\/p>\n<p><strong>Entrevista a O Globo<\/strong><\/p>\n<p>&#8220;Minha candidatura \u00e9 necess\u00e1ria porque outras for\u00e7as de esquerda viraram liberais&#8221;, diz Eduardo Serra em entrevista<\/p>\n<p>Candidato do PCB defende n\u00e3o pagar d\u00edvida do estado com a Uni\u00e3o<\/p>\n<p>RIO \u2014 O candidato do PCB ao governo do Rio, Eduardo Serra, diz que n\u00e3o v\u00ea utopia em defender plataforma \u2018anticapitalista\u2019 nas elei\u00e7\u00f5es e defende n\u00e3o pagar d\u00edvida com a Uni\u00e3o para reduzir a crise econ\u00f4mica no estado. Em entrevista ao GLOBO, fala sobre a fragmenta\u00e7\u00e3o da esquerda e as raz\u00f5es a que atribui o desempenho de 4% a 5% nas pesquisas, apesar de n\u00e3o ser muito conhecido pela popula\u00e7\u00e3o.<\/p>\n<p>Sua candidatura n\u00e3o fragmenta ainda mais o campo da esquerda?<\/p>\n<p>No segundo turno h\u00e1 uma converg\u00eancia natural de for\u00e7as. Nosso inimigo \u00e9 o Bolsonaro e o bolsonarismo aqui no Rio \u00e9 Cl\u00e1udio Castro. Sentimos a necessidade de apresentar um programa claramente de esquerda, porque infelizmente outras for\u00e7as desse campo est\u00e3o se apresentando com programas em parte liberais, que falam em alian\u00e7as amplas, em ter secretariado t\u00e9cnico e n\u00e3o pol\u00edtico. Quero t\u00e9cnicos competentes, mas com a pol\u00edtica de esquerda na cabe\u00e7a.<\/p>\n<p>O senhor apareceu entre 4% e 5% em pesquisas recentes. \u00c9 a confus\u00e3o de seu nome com o do ex-ministro Jos\u00e9 Serra? A que atribui o desempenho?<\/p>\n<p>A maioria da popula\u00e7\u00e3o nem sabe quem \u00e9 Jos\u00e9 Serra, mas sabe o que \u00e9 o PCB. Sou algu\u00e9m que tem experi\u00eancia pol\u00edtica, j\u00e1 concorreu, j\u00e1 exerceu cargos de gest\u00e3o na universidade. E o PCB existe como uma alternativa \u00e0 esquerda, j\u00e1 que outros est\u00e3o no caminho mais ao centro.<\/p>\n<p>Refere-se ao Marcelo Freixo?<\/p>\n<p>\u00c9 um movimento que tenta compor uma frente mais ampla para derrotar a direita com componentes fascistas, tanto com Bolsonaro quanto com Castro. Mas a gente considera insuficiente. \u00c9 necess\u00e1rio apresentar uma proposta claramente de esquerda, claramente anticapitalista.<\/p>\n<p>Um projeto anticapitalista n\u00e3o \u00e9 utopia para um candidato a governador?<\/p>\n<p>Os problemas econ\u00f4micos do Rio est\u00e3o associados aos problemas nacionais. Temos um regime de recupera\u00e7\u00e3o fiscal, uma d\u00edvida com a Uni\u00e3o, que a nosso ver deveria ser extinta. N\u00e3o \u00e9 justo que a rela\u00e7\u00e3o da Uni\u00e3o com os estados seja como de um banco privado com o seu tomador de empr\u00e9stimo. A proposta \u00e9 uma mobiliza\u00e7\u00e3o da sociedade do Rio para fazer press\u00e3o e zerar essa d\u00edvida. Uma consulta \u00e0 popula\u00e7\u00e3o, que vai apoiar, porque a d\u00edvida \u00e9 impag\u00e1vel.<\/p>\n<p>O PCB faz cem anos. Ainda \u00e9 vi\u00e1vel defender o socialismo como o regime a ser aplicado?<\/p>\n<p>N\u00f3s consideramos as elei\u00e7\u00f5es um espa\u00e7o importante de luta. E \u00e9 um espa\u00e7o que faz parte de um processo maior de luta pelo socialismo. N\u00f3s entendemos que n\u00f3s vamos chegar no socialismo com muita mobiliza\u00e7\u00e3o social, muito debate de ideias e tamb\u00e9m nas elei\u00e7\u00f5es. \u00c9 parte de um processo maior.<\/p>\n<p>Link da entrevista: https:\/\/oglobo.globo.com\/politica\/minha-candidatura-necessaria-porque-outras-forcas-de-esquerda-viraram-liberais-diz-eduardo-serra-em-entrevista-1-25514143<\/p>\n<p>SABATINA UOL\/FOLHA:<\/p>\n<p>&#8220;Nos apresentamos como anticapitalistas e n\u00e3o estamos propondo utopia&#8221;.<\/p>\n<p>Eduardo Serra (PCB), pr\u00e9-candidato ao governo do Rio de Janeiro, defendeu os ideais socialistas como norte para o estado a partir de 2023, afirmando que o programa que a sigla dele apresenta para o RJ \u00e9 &#8220;realiz\u00e1vel&#8221;. &#8220;Nos apresentamos como uma alternativa de esquerda socialista. Deixamos claro essa nossa posi\u00e7\u00e3o. E, com isso, nos diferenciamos de outras for\u00e7as que est\u00e3o \u00e0 esquerda, mas se colocam no campo da social-democracia. N\u00e3o estamos propondo uma utopia de curto prazo, mas coisas realiz\u00e1veis&#8221;, disse Serra durante sabatina UOL\/Folha de S.Paulo.<\/p>\n<p>Citando exemplos de pautas do PCB para o Rio e para o Brasil, Serra falou em expandir a sa\u00fade p\u00fablica gratuita &#8220;e de alta qualidade&#8221;, um caminho para o emprego que passa pela &#8220;reindustrializa\u00e7\u00e3o&#8221; da economia nacional, &#8220;com a revers\u00e3o do agroneg\u00f3cio e uma reforma agr\u00e1ria que gere mais emprego no campo&#8221;, e mais apoio do governo federal para estados e munic\u00edpios sobre a educa\u00e7\u00e3o b\u00e1sica. &#8220;Propomos um conjunto de medidas emergenciais para combater o desemprego agudo que estamos passando.&#8221;<\/p>\n<p>&#8220;As elei\u00e7\u00f5es s\u00e3o um momento importante para a gente colocar essas ideias. E n\u00f3s nos apresentamos como programa de car\u00e1ter anticapitalista, com medidas concretas para dialogar com o conjunto da popula\u00e7\u00e3o&#8221;, acrescentou. Ele afirmou tamb\u00e9m defender uma participa\u00e7\u00e3o popular de massa, com a elei\u00e7\u00e3o de conselhos, negando a possibilidade de chegar a um autoritarismo do regime socialista. &#8220;Fazemos uma leitura cr\u00edtica de outras experi\u00eancias socialistas no mundo.&#8221;<\/p>\n<p>Os entrevistadores de Serra foram Kennedy Alencar e Chico Alves, colunistas do UOL, e Italo Nogueira, rep\u00f3rter da Folha.<\/p>\n<p>Assista na \u00edntegra em https:\/\/www.uol.com.br\/eleicoes\/2022\/05\/19\/eduardo-serra-pcb-governo-do-rj-eleicoes-2022-sabatin-uol-folha-i.htm?fbclid=IwAR3SW9xKZbvTwL5M3PDsRHyDQxmVcWodsTdDy8Hfq2tWJKzbbCbP5xzkIE4<\/p>\n","protected":false},"excerpt":{"rendered":"<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/28812\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"\"Minha candidatura \u00e9 necess\u00e1ria porque outras for\u00e7as de esquerda viraram liberais\".","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[221],"class_list":["post-28812","post","type-post","status-publish","format-standard","hentry","category-geral","tag-2a"],"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p659gw-7uI","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/28812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=28812"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/28812\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=28812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=28812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=28812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}