{"id":28863,"date":"2022-06-02T18:41:36","date_gmt":"2022-06-02T21:41:36","guid":{"rendered":"https:\/\/pcb.org.br\/portal2\/?p=28863"},"modified":"2022-06-02T18:41:36","modified_gmt":"2022-06-02T21:41:36","slug":"comentando-o-artigo-do-pstu-sobre-o-pcb-e-a-frente-eleitoral","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/28863","title":{"rendered":"Comentando o artigo do PSTU sobre o PCB e a \u201cFrente Eleitoral\u201d"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"imagem\" title=\"imagem\" src=\"https:\/\/i0.wp.com\/www.esquerdadiario.com.br\/local\/cache-vignettes\/L720xH540\/arton43074-275ee.jpg?w=747&#038;ssl=1\" alt=\"imagem\" \/><!--more--><\/p>\n<p><strong>Por F\u00e1bio Bezerra (membro do CC do PCB)<\/strong><\/p>\n<p>Recentemente, em seu portal na internet, o PSTU publicou uma mat\u00e9ria com o seguinte t\u00edtulo: \u201cPor que n\u00e3o \u00e9 poss\u00edvel uma frente eleitoral com o PCB\u201d, sob a pretensa inten\u00e7\u00e3o de \u201cesclarecer\u201d as raz\u00f5es do malogro de uma frente eleitoral de esquerda. Diante das mentiras e acusa\u00e7\u00f5es promovidas nesse artigo, na suposta tentativa de justificar a n\u00e3o constitui\u00e7\u00e3o da frente eleitoral entre PSTU, PCB e UP, nos sentimos no dever de responder \u00e0s fal\u00e1cias e incorre\u00e7\u00f5es desse texto, assinado por um dirigente nacional do PSTU.<\/p>\n<p>O artigo inicia sua apresenta\u00e7\u00e3o procurando justificar a n\u00e3o unidade em uma chapa para as elei\u00e7\u00f5es presidenciais de 2022 com um peculiar argumento que caberia supostamente \u00e0s \u201corganiza\u00e7\u00f5es revolucion\u00e1rias\u201d: \u201c(&#8230;) predomina a necessidade de que os revolucion\u00e1rios apresentem seus pr\u00f3prios programas, e n\u00e3o a unidade dos distintos setores.\u201d Dessa forma, o pr\u00f3prio artigo j\u00e1 deixa evidente de in\u00edcio a inten\u00e7\u00e3o de tamb\u00e9m justificar o direito de cada uma das organiza\u00e7\u00f5es lan\u00e7arem seus programas e chapas pr\u00f3prios, mas o faz com um conjunto de ataques fabricados e caluniosos, que mais procuram criar ciz\u00e2nia e fazer chicana nas redes sociais do que de fato tratar de modo s\u00e9rio e coerente o debate ao qual se propuseram.<\/p>\n<p>Em primeiro lugar, no in\u00edcio desse ano a dire\u00e7\u00e3o do PSTU procurou a dire\u00e7\u00e3o do PCB para a discuss\u00e3o do processo eleitoral e, na reuni\u00e3o que tivemos, mesmo antes de aprofundarmos qualquer debate sobre conjuntura, programa e estrat\u00e9gia, foi \u201coferecida\u201d a vice candidatura em uma poss\u00edvel chapa encabe\u00e7ada pelo PSTU. Um jeito nada h\u00e1bil de se iniciar qualquer poss\u00edvel debate program\u00e1tico, que deveria ser feito sem a\u00e7odamentos e com real disposi\u00e7\u00e3o para construir uma \u201cFrente eleitoral\u201d. Esse artigo \u00e9 de uma hipocrisia muito grande: nos bastidores, buscaram uma alian\u00e7a; como n\u00e3o aconteceu, jogam para a plateia com acusa\u00e7\u00f5es infundadas.<\/p>\n<p>O referido artigo aborda tr\u00eas temas para justificar a n\u00e3o consecu\u00e7\u00e3o da frente eleitoral. O primeiro deles, de car\u00e1ter hist\u00f3rico, citando o apoio ao Governo de Jo\u00e3o Goulart com a descabida acusa\u00e7\u00e3o de o PCB \u00e0 \u00e9poca ter atuado como se estivesse\u201c (&#8230;) impedindo um papel independente da classe oper\u00e1ria perante esse governo e desarmando a rea\u00e7\u00e3o das massas ao golpe militar\u201d. No per\u00edodo, o PCB manteve uma posi\u00e7\u00e3o de independ\u00eancia em rela\u00e7\u00e3o ao Governo Jango, apoiando as medidas que considerava avan\u00e7adas para o contexto como a proposta de reforma agr\u00e1ria, os aumentos do sal\u00e1rio m\u00ednimo, a taxa\u00e7\u00e3o das remessas de lucros das empresas multinacionais, assim como as chamadas \u201cReformas de Base\u201d, medidas que provocaram a rea\u00e7\u00e3o da classe dominante, que articulou o Golpe de 1964 e imp\u00f4s no pa\u00eds mais de vinte anos de ditadura, com a suspens\u00e3o de direitos pol\u00edticos, cassa\u00e7\u00e3o de mandatos, censura \u00e0 imprensa, \u00e0s atividades liter\u00e1rias, sindicais, estudantis e culturais, persegui\u00e7\u00f5es, pris\u00f5es arbitr\u00e1rias, tortura, assassinatos e desaparecimentos de ativistas contr\u00e1rios ao regime, dentre outros tantos crimes e a\u00e7\u00f5es que ampliaram o poder pol\u00edtico e econ\u00f4mico da burguesia e a presen\u00e7a imperialista n\u00e3o apenas no Brasil, mas tamb\u00e9m na Am\u00e9rica Latina.<\/p>\n<p>\u00c9 uma mentira absurda, totalmente desrespeitosa e falsificadora, dizer nesse artigo que o PCB desarmou a popula\u00e7\u00e3o e que n\u00e3o estimulou qualquer tipo de rea\u00e7\u00e3o ao Golpe. Diversas lideran\u00e7as comunistas foram presas, torturadas e tiveram seus mandatos parlamentares e sindicais cassados. Nosso Partido foi posto na ilegalidade e nosso Secret\u00e1rio Geral \u00e0 \u00e9poca figurava como primeiro na lista dos perseguidos pelos militares que tomaram o poder em 1964. Tais afirma\u00e7\u00f5es s\u00e3o um desrespeito para com todos(as) aqueles(as) &#8211; inclusive seus familiares &#8211; que tiveram suas vidas atingidas pela repress\u00e3o violenta que se seguiu ao golpe.<\/p>\n<p>Sobre o apoio ao Governo Lula entre 2003 e 2005, deve-se lembrar sempre que \u00e0 \u00e9poca foi formado um amplo leque de composi\u00e7\u00e3o pol\u00edtica com diversas organiza\u00e7\u00f5es de esquerda, em torno de um programa que propunha combater o avan\u00e7o do neoliberalismo no Brasil, as privatiza\u00e7\u00f5es e demais reformas nocivas \u00e0 classe trabalhadora, em um contexto conjuntural espec\u00edfico, sendo que o pr\u00f3prio PSTU apoiou a elei\u00e7\u00e3o de Lula no 2\u00ba turno! Ap\u00f3s dois anos de embates e com a evid\u00eancia de que n\u00e3o havia a menor possibilidade de disputa em torno dos rumos do Governo Lula, o PCB fez sua ruptura \u00e0 esquerda, muito antes dos esc\u00e2ndalos do \u201cMensal\u00e3o\u201d, com cr\u00edticas que acentuavam as contradi\u00e7\u00f5es do Governo Lula e sua capitula\u00e7\u00e3o frente aos interesses de setores da burguesia brasileira e do mercado financeiro, interesses esses que impediam qualquer avan\u00e7o em medidas populares como a reforma agr\u00e1ria, reforma urbana e amplia\u00e7\u00e3o de direitos sociais, reformas essas que nunca sa\u00edram do papel.<\/p>\n<p>Esquece-se o autor do artigo de que o CC do PCB fez duras cr\u00edticas \u00e0 reforma previdenci\u00e1ria de 2003 e se solidarizou com os deputados petistas que votaram contra ela. Sobre a cita\u00e7\u00e3o \u00e0 entrevista de um dirigente do Partido, \u00e9 importante ressaltar a distor\u00e7\u00e3o do trecho pin\u00e7ado, descontextualizado do conjunto da entrevista, para tentar dessa forma causar uma clara manipula\u00e7\u00e3o com o objetivo de difama\u00e7\u00e3o de nosso Partido, no momento em que estamos construindo uma pr\u00e9-campanha anticapitalista e anti-imperialista com cr\u00edticas n\u00e3o apenas ao ultraliberalismo reacion\u00e1rio de Bolsonaro, mas tamb\u00e9m \u00e0 requentada f\u00f3rmula da concilia\u00e7\u00e3o de classes representada pela chapa Lula\/Alckmin.<\/p>\n<p>A pretexto de nos acusar de estalinismo e, a partir desse velho e desgastado clich\u00ea tentar demarcar, de forma manique\u00edsta, algum campo propositivo em rela\u00e7\u00e3o ao debate da conjuntura internacional ou da atual geopol\u00edtica, \u00e9 importante desmascarar mais uma vez a pr\u00e1tica de cal\u00fania e difama\u00e7\u00e3o que certas correntes trotskistas ainda insistem em promover e que no artigo publicado na p\u00e1gina do PSTU fica muito evidente.<\/p>\n<p>\u00c9 mentirosa e c\u00ednica a declara\u00e7\u00e3o de que apoiamos o governo Putin e o Estado russo no conflito militar na Ucr\u00e2nia! Em nossa nota pol\u00edtica publicada em 25 de fevereiro desse ano, &#8220;<a href=\"https:\/\/pcb.org.br\/portal2\/28478\">Declara\u00e7\u00e3o Pol\u00edtica sobre a crise militar na Ucr\u00e2nia<\/a>\u201d, deixamos claro que esse conflito \u00e9 o resultado direto das contradi\u00e7\u00f5es da crise do sistema capitalista, que teve seu epicentro em 2008 e que, de l\u00e1 para c\u00e1, agudizaram-se os conflitos imperialistas na geopol\u00edtica mundial, conflitos esses que exp\u00f5em os interesses do avan\u00e7o militar da OTAN e da hegemonia estadunidense na regi\u00e3o, em contraposi\u00e7\u00e3o aos interesses da burguesia russa, a qual encontra apoio no governo conservador de Putin.<\/p>\n<p>Mas de fato temos muitas diferen\u00e7as no plano internacional e tomo como empr\u00e9stimo parte do artigo que ataca o PCB no site do PSTU como par\u00e2metro para demarcar, entre tantas outras diferen\u00e7as, aquilo que compreendemos como atitudes contrarrevolucion\u00e1rias que se passam por \u201crevolucion\u00e1rias\u201d, como indicado no referido artigo. Essa corrente trotskista se comporta no Brasil como a m\u00e3o esquerda do imperialismo. A come\u00e7ar por quem apoiou o movimento \u201cSolidarinosc\u201d na Pol\u00f4nia dos anos 1980 (quando o PSTU ainda era uma tend\u00eancia do PT) e seu l\u00edder sindical Lech Walesa, que, com o apoio da CIA e dos setores mais reacion\u00e1rios da Igreja Cat\u00f3lica, combateram o governo socialista sob o lema da \u201cliberdade\u201d, implementando, quando eleito presidente, reformas neoliberais como privatiza\u00e7\u00f5es de empresas p\u00fablicas e servi\u00e7os sociais e desmonte do legado socialista.<\/p>\n<p>Saudaram o fim do bloco socialista e a queda da antiga URSS, como um sinal de renova\u00e7\u00e3o \u201crevolucion\u00e1ria\u201d das massas contra a burocracia e o \u201cestalinismo\u201d, quando de fato houve significativos retrocessos, em especial a destrui\u00e7\u00e3o das conquistas sociais e da soberania desses povos, com efeitos no plano ideol\u00f3gico em todo o mundo, contribuindo em diversos pa\u00edses para a prolifera\u00e7\u00e3o do discurso liberal, dos valores da economia de mercado de um lado e dos renegados p\u00f3s-marxistas de outro, os quais ocuparam diversos espa\u00e7os para semear as &#8220;boas novas&#8221; do &#8220;fim da luta de classes\u201d, da concilia\u00e7\u00e3o e do reformismo como metas do movimento popular e sindical.<\/p>\n<p>Tamb\u00e9m n\u00e3o \u00e9 poss\u00edvel esquecer a oposi\u00e7\u00e3o sistem\u00e1tica que a LIT e o PSTU fazem contra a Revolu\u00e7\u00e3o Cubana e sua hist\u00f3rica e heroica resist\u00eancia em mais de 60 anos de um embargo criminoso mantido pelo imperialismo estadunidense. Muitas vezes assistimos perplexos a resson\u00e2ncia que promovem das campanhas midi\u00e1ticas promovidas pelo complexo de propaganda anticomunista estadunidense.<\/p>\n<p>Da mesma forma temos diverg\u00eancias com as investidas panflet\u00e1rias e sect\u00e1rias contra as conquistas que os povos da Am\u00e9rica Latina, mesmo em condi\u00e7\u00f5es adversas, contabilizam contra o jugo do imperialismo e suas elites subalternas, n\u00e3o podendo deixar de citar aqui os arroubos vanguardistas de quem em plena crise que culminou no impeachment de Dilma em 2016. Por mais que estiv\u00e9ssemos em oposi\u00e7\u00e3o ao Governo do PT, n\u00e3o conseguiram compreender o avan\u00e7o reacion\u00e1rio das for\u00e7as mais retr\u00f3gradas do pa\u00eds, reduzindo sua an\u00e1lise e sua bandeira de agita\u00e7\u00e3o a uma palavra de ordem esquizofr\u00eanica em torno do \u201cFora Todos!\u201d, que nunca conseguiu dialogar com as massas sobre as contradi\u00e7\u00f5es e a gravidade daquele contexto!<\/p>\n<p>Gostaria de terminar essas considera\u00e7\u00f5es dizendo que \u00e9 lament\u00e1vel que tenhamos de responder a um artigo que, em nome de procurar \u201cesclarecer\u201d as raz\u00f5es da n\u00e3o consolida\u00e7\u00e3o de uma \u201cfrente eleitoral\u201d, preferiu, sob esse pretexto, atacar e desqualificar de forma oportunista e mesquinha uma organiza\u00e7\u00e3o pol\u00edtica que vem marchando lado a lado a tantas outras organiza\u00e7\u00f5es socialistas na defesa da classe trabalhadora e na luta diuturna contra o modo de produ\u00e7\u00e3o capitalista e seus gestores de plant\u00e3o.<\/p>\n<p>N\u00e3o somos contra o bom e necess\u00e1rio debate e as pol\u00eamicas que possam surgir, at\u00e9 porque os marxistas n\u00e3o podem recear o debate cr\u00edtico, fundamental para trazer \u00e0 tona diferen\u00e7as e equacionar conjecturas nos diversos cen\u00e1rios colocados, envolvendo atores pol\u00edticos, inimigos, advers\u00e1rios e poss\u00edveis aliados na trama conjuntural. Mas n\u00e3o podemos confundir cr\u00edticas com cal\u00fania e admitir em hip\u00f3tese alguma difama\u00e7\u00e3o gratuita contra nosso Partido e contra nossos camaradas, tampouco falsifica\u00e7\u00e3o da hist\u00f3ria e intriga torpe e desqualificada, muito comuns nas a\u00e7\u00f5es arrivistas que a direita tradicional lan\u00e7a em seus peri\u00f3dicos e que &#8211; diga-se de passagem &#8211; n\u00e3o nos intimidam!<\/p>\n<p>Vivemos um dos piores cen\u00e1rios das \u00faltimas d\u00e9cadas sob todos os aspectos e esse am\u00e1lgama de contradi\u00e7\u00f5es acentuam ainda mais nossos desafios e nosso compromisso com a revolu\u00e7\u00e3o socialista. Nesse sentido sabemos muito bem quem s\u00e3o nossos inimigos de classe, quem nos assassina nas vilas, favelas e periferias, quem nos explora e retira paulatinamente nossos direitos, quem saqueia o fundo p\u00fablico, privatiza nossas empresas e riquezas naturais e se fortalece com as benesses do Estado para impor e aumentar seu poder pol\u00edtico e econ\u00f4mico. Espero que tenhamos a sensatez de reconhecer nesse turbilh\u00e3o de ataques da burguesia, de mis\u00e9ria ideol\u00f3gica, de vacila\u00e7\u00f5es e trai\u00e7\u00f5es, de mentiras e desalentos, aqueles que possam estar lado a lado nas trincheiras de luta contra a barb\u00e1rie capitalista, aliados n\u00e3o por escolha, mas por convic\u00e7\u00e3o e necessidade de resistir, lutar e transformar revolucionariamente a realidade brasileira.<\/p>\n<p>Espero tamb\u00e9m que todos aqueles que entendam o processo eleitoral como um palco para a disputa de \u201ccora\u00e7\u00f5es e mentes\u201d, como um espa\u00e7o privilegiado para a agita\u00e7\u00e3o e propaganda revolucion\u00e1ria, possam aproveitar cada minuto, cada segundo em que ainda temos tido condi\u00e7\u00f5es de participar nesse processo, para combater o protofascismo em curso, denunciar esse governo reacion\u00e1rio, assassino, respons\u00e1vel direto pelo genoc\u00eddio de mais de 660 mil vidas no Brasil e as contradi\u00e7\u00f5es do capitalismo, da burguesia e do imperialismo, bem como as fal\u00e1cias daqueles que prop\u00f5em concilia\u00e7\u00f5es de classes como \u201crem\u00e9dio\u201d para a crise do sistema!<\/p>\n<p>Que n\u00e3o percamos tempo em ataques est\u00e9reis e descabidos entre n\u00f3s, pois a conjuntura exige dos revolucion\u00e1rios toda a aten\u00e7\u00e3o e empenho contra os verdadeiros inimigos do povo!<\/p>\n","protected":false},"excerpt":{"rendered":"<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/28863\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"\"N\u00e3o podemos confundir cr\u00edticas com cal\u00fania e admitir em hip\u00f3tese alguma difama\u00e7\u00e3o gratuita contra nosso Partido e contra nossos camaradas, tampouco falsifica\u00e7\u00e3o da hist\u00f3ria e intriga torpe e desqualificada.\"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[227],"class_list":["post-28863","post","type-post","status-publish","format-standard","hentry","category-geral","tag-5a"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-7vx","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/28863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=28863"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/28863\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=28863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=28863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=28863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}