{"id":30734,"date":"2023-08-13T08:41:25","date_gmt":"2023-08-13T11:41:25","guid":{"rendered":"https:\/\/pcb.org.br\/portal2\/?p=30734"},"modified":"2023-08-13T08:41:25","modified_gmt":"2023-08-13T11:41:25","slug":"solidariedade-militante-ao-partido-comunista-da-venezuela-pcv","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/30734","title":{"rendered":"Solidariedade Militante ao Partido Comunista da Venezuela (PCV)!"},"content":{"rendered":"<p><img decoding=\"async\" class=\"imagem\" title=\"imagem\" src=\"https:\/\/i0.wp.com\/www.marxismo.org.br\/wp-content\/uploads\/2023\/06\/PCV_Image_PCV.jpg\" alt=\"imagem\" \/><!--more-->Nota Pol\u00edtica do Partido Comunista Brasileiro (PCB)<\/p>\n<p>O Partido Comunista Brasileiro (PCB), vem a p\u00fablico denunciar mais um ataque violento perpetrado pelo governo de Nicol\u00e1s Maduro contra o hist\u00f3rico, heroico e combativo Partido Comunista da Venezuela \u2013 PCV.<\/p>\n<p>N\u00e3o \u00e9 de hoje que o governo Maduro, afastando-se das diretrizes socialistas propostas pelos revolucion\u00e1rios venezuelanos, vem implementando pol\u00edticas liberais burguesas, contra os interesses do povo. Para tal, a investida principal do Partido Socialista Unificado da Venezuela &#8211; PSUV (liderado por Maduro) \u00e9 contra o PCV, principalmente ap\u00f3s a realiza\u00e7\u00e3o de seu exitoso XVI Congresso de 2022, em que os comunistas reafirmaram sua consequente pol\u00edtica de independ\u00eancia de classe e de enfrentamento \u00e0 pol\u00edtica liberal e anti povo do governo Nicol\u00e1s Maduro.<\/p>\n<p>Diante da coes\u00e3o e forte unidade interna do PCV, a dire\u00e7\u00e3o do PSUV contratou mercen\u00e1rios e disfar\u00e7ou alguns de seus militantes que se \u201cvestiram\u201d com os s\u00edmbolos dos comunistas, como o Galo Vermelho, para ludibriar a opini\u00e3o p\u00fablica e dizer que h\u00e1 um descontentamento nas bases do Partido Comunista da Venezuela, utilizando-se de falsas assembleias financiadas pelo governo Maduro, com objetivo de criar uma \u201ccrise\u201d falaciosa que possibilitasse uma interven\u00e7\u00e3o jur\u00eddica no Partido Comunista.<\/p>\n<p>Nessa sexta feira, 11 de agosto, os magistrados do Supremo Tribunal de Justi\u00e7a decidiram por aceitar um recurso de um grupo de pessoas que n\u00e3o pertencem \u00e0s fileiras do PCV, e que n\u00e3o possuem nenhuma idoneidade moral, pol\u00edtica e legal que os legitime a falar em nome do PCV.<\/p>\n<p>Com essa atitude, o Supremo Tribunal de Justi\u00e7a venezuelano atenta n\u00e3o somente contra os direitos do PCV, mas fundamentalmente contra os direitos dos trabalhadores e das trabalhadoras do pa\u00eds. Essa medida arbitr\u00e1ria, sem precedentes na hist\u00f3ria pol\u00edtica e jur\u00eddica da Venezuela revela o car\u00e1ter autocr\u00e1tico, antidemocr\u00e1tico e reacion\u00e1rio do governo de Nicol\u00e1s Maduro.<\/p>\n<p>A Dire\u00e7\u00e3o Nacional do PCV articula uma resposta pol\u00edtica, assentada nos interesses da classe trabalhadora e prepara a\u00e7\u00f5es jur\u00eddicas nacionais e internacionais para defender os direitos inalien\u00e1veis do povo trabalhador venezuelano, e de continuidade da organiza\u00e7\u00e3o das for\u00e7as pol\u00edticas populares, oper\u00e1rias e camponesas, visando fortalecer o campo socialista que possibilite uma sa\u00edda revolucion\u00e1ria da crise do capitalismo venezuelano.<\/p>\n<p>Todo Apoio Solid\u00e1rio e Militante ao Partido Comunista da Venezuela!<br \/>\nViva o Povo Trabalhador da Venezuela!<\/p>\n<p>Comit\u00ea Central do Partido Comunista Brasileiro (PCB), fundado em 25 de mar\u00e7o de 1922<\/p>\n","protected":false},"excerpt":{"rendered":"<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/30734\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[26],"tags":[234],"class_list":["post-30734","post","type-post","status-publish","format-standard","hentry","category-c25-notas-politicas-do-pcb","tag-6b"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-7ZI","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/30734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=30734"}],"version-history":[{"count":1,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/30734\/revisions"}],"predecessor-version":[{"id":30735,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/30734\/revisions\/30735"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=30734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=30734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=30734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}