{"id":31146,"date":"2023-12-08T22:55:31","date_gmt":"2023-12-09T01:55:31","guid":{"rendered":"https:\/\/pcb.org.br\/portal2\/?p=31146"},"modified":"2023-12-08T22:55:31","modified_gmt":"2023-12-09T01:55:31","slug":"menos-um-criminoso-de-guerra-a-bordo","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/31146","title":{"rendered":"Menos um criminoso de guerra a bordo"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"31147\" data-permalink=\"https:\/\/pcb.org.br\/portal2\/31146\/attachment\/21286\" data-orig-file=\"https:\/\/i0.wp.com\/pcb.org.br\/portal2\/wp-content\/uploads\/2023\/12\/21286.jpg?fit=705%2C470&amp;ssl=1\" data-orig-size=\"705,470\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"21286\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/pcb.org.br\/portal2\/wp-content\/uploads\/2023\/12\/21286.jpg?fit=705%2C470&amp;ssl=1\" class=\"alignnone size-full wp-image-31147\" src=\"https:\/\/i0.wp.com\/pcb.org.br\/portal2\/wp-content\/uploads\/2023\/12\/21286.jpg?resize=705%2C470&#038;ssl=1\" alt=\"\" width=\"705\" height=\"470\" srcset=\"https:\/\/i0.wp.com\/pcb.org.br\/portal2\/wp-content\/uploads\/2023\/12\/21286.jpg?w=705&amp;ssl=1 705w, https:\/\/i0.wp.com\/pcb.org.br\/portal2\/wp-content\/uploads\/2023\/12\/21286.jpg?resize=300%2C200&amp;ssl=1 300w\" sizes=\"auto, (max-width: 705px) 100vw, 705px\" \/><!--more--><\/p>\n<p>Henry Kissinger, secret\u00e1rio de Estado dos EUA, com o primeiro-ministro sul-africano do apartheid, John Vorster, durante um encontro na Alemanha Ocidental, em Junho de 1976 &#8211; Cr\u00e9ditos \/ AP Photo<\/p>\n<p>Jos\u00e9 Goul\u00e3o<\/p>\n<p>ABRIL ABRIL<\/p>\n<p>Diz o povo que quando uma pessoa morre passa a ser um po\u00e7o de virtudes, como se deixasse para tr\u00e1s, bem enterrados e esquecidos, os seus pecados em vida, por muito graves que sejam.<\/p>\n<p>Temo que o conceito, mesmo na sua amplitude, n\u00e3o seja aplic\u00e1vel a Henry Kissinger, o quase eterno ide\u00f3logo do aparelho imperialista que agora se foi aos 100 anos, n\u00e3o sem ainda ter comparecido, como insubstitu\u00edvel patrono, nas mais recentes assembleias conspirativas do Grupo de Bilderberg e do F\u00f3rum Econ\u00f4mico Mundial, o Olimpo do liberal-globalismo.<\/p>\n<p>S\u00f3 figuras incontorn\u00e1veis daquilo a que chamam \u00aba democracia liberal\u00bb o endeusam depois de morto, mas isso n\u00e3o acarreta qualquer mudan\u00e7a de atitude porque j\u00e1 o faziam em vida. Obama, o casal Clinton, democratas e tamb\u00e9m republicanos que o falecido servia (e conduzia) com o mesmo zelo s\u00e3o pr\u00f3digos em adjetivos para um epit\u00e1fio de her\u00f3i.<\/p>\n<p>E tamb\u00e9m o presidente desta pequena mas bem ocidental rep\u00fablica, em todas as acep\u00e7\u00f5es, se apressou a enviar condol\u00eancias ao \u00abpresidente Biden\u00bb, ainda fatigado ao tentar limpar das m\u00e3os o sangue das chacinas em Gaza e na Cisjord\u00e2nia, intrigado com o fato de Pilatos ter sido bastante mais eficaz a faz\u00ea-lo. O venerando chefe de Estado foi mais uma vez muito previs\u00edvel, igual a si pr\u00f3prio, escolhendo sempre bem os afetos, provavelmente guardando um lugar de honra nas suas ora\u00e7\u00f5es pelo amigo Henry, encomendando-lhe a alma com gratid\u00e3o eterna pelo benfazejo 25 de Novembro.<\/p>\n<p>Diz tamb\u00e9m o povo que n\u00e3o se deve gastar cera \u2013 palavras, neste caso \u2013 com defuntos ruins. E se este \u00e9 ruim\u2026 E bem ruim\u2026 Registremos o seu passamento apenas com singelas evoca\u00e7\u00f5es f\u00fanebres tornadas poss\u00edveis pela verve do pr\u00f3prio que, honra lhe seja feita, nunca precisou de carteiros para que os seus recados chegassem aos destinat\u00e1rios.<\/p>\n<p>Deixemos antes para os seus aduladores internos, distribu\u00eddos por um alargado \u00abarco da governan\u00e7a\u00bb novembrista do PS ao Chega, as eloquentes elegias transbordando de nutridas profiss\u00f5es de f\u00e9 democr\u00e1tica, compreensivelmente humedecidas por uma ou outra teimosa lagrimazinha.<\/p>\n<p>Um her\u00f3i da democracia<\/p>\n<p>Kissinger foi, e assim ficar\u00e1 para sempre, um her\u00f3i da \u00abdemocracia liberal\u00bb ou \u00abdemocracia ocidental\u00bb, essa mesma que continua a cilindrar os direitos dos povos, principalmente os europeus, para sustentar o nazi-banderismo na Ucr\u00e2nia e as chacinas praticadas por Israel, sempre em conson\u00e2ncia com o seu estatuto de \u00ab\u00fanica democracia do Oriente M\u00e9dio\u00bb.<\/p>\n<p>\u00abA seguran\u00e7a de Israel \u00e9 um imperativo moral para todos os povos livres\u00bb, ditava Henry Kissinger. Da\u00ed que, respeitando os mais s\u00e3os princ\u00edpios democr\u00e1ticos e as liberdades essenciais, \u00abIsrael deve impedir a entrada da c\u00e2maras de televis\u00e3o e rep\u00f3rteres nos territ\u00f3rios ocupados, no \u00e2mbito dos seus esfor\u00e7os para reprimir os protestos violentos\u00bb; e o mestre da estrat\u00e9gia deu ent\u00e3o como exemplos os regimes de apartheid que vigoraram na Rod\u00e9sia e na \u00c1frica do Sul.<\/p>\n<p>Kissinger exerceu com este esp\u00edrito a fun\u00e7\u00e3o de conselheiro de todos os presidentes norte-americanos dos \u00faltimos 60 anos, transbordando de absoluta autoconfian\u00e7a gra\u00e7as \u00e0 tenacidade com que respeitava a \u00e9tica e a moral, seus inabal\u00e1veis princ\u00edpios de vida. Por isso, recomenda, \u00abum pa\u00eds que exija a perfei\u00e7\u00e3o moral na pol\u00edtica externa n\u00e3o alcan\u00e7ar\u00e1 nem a perfei\u00e7\u00e3o, nem a seguran\u00e7a\u00bb; ou ent\u00e3o, \u00abporque o Estado \u00e9 uma organiza\u00e7\u00e3o fr\u00e1gil, o estadista n\u00e3o tem o direito moral de arriscar a sua sobreviv\u00eancia com restri\u00e7\u00f5es \u00e9ticas\u00bb. At\u00e9 porque \u00abo poder \u00e9 afrodis\u00edaco\u00bb, deix\u00e1-lo ser\u00e1 um sinal de fraqueza sujeito a especula\u00e7\u00f5es mal\u00e9volas.<\/p>\n<p>Respeitando escrupulosamente os princ\u00edpios humanistas, e sempre em nome da democracia, Kissinger supervisionou a sangrenta guerra contra o povo do Vietn\u00e3 e, consumido pela raiva de n\u00e3o conseguir desenvencilhar-se com \u00eaxito da tarefa, fez lan\u00e7ar 2 756 941 toneladas de bombas sobre o Camboja entre 1965 e 1973, matando pelo menos 600 mil pessoas e transformando mais de dois milh\u00f5es em refugiadas. Para o caso de, ainda assim, o n\u00famero citado n\u00e3o ser elucidativo em termos absolutos, ent\u00e3o comparemos: na Segunda Guerra Mundial os aliados lan\u00e7aram em conjunto pouco mais de dois milh\u00f5es de toneladas de bombas, umas centenas de milhar menos do que a proeza asi\u00e1tica de Kissinger. E n\u00e3o fiquem d\u00favidas sobre a sua responsabilidade, e as dos presidentes Nixon e Johnson, nessa matan\u00e7a cega de civis inocentes: o conselheiro presidencial bipartid\u00e1rio entendia que \u00abos militares s\u00e3o apenas burros e est\u00fapidos que podem ser usados como pe\u00f5es na pol\u00edtica externa\u00bb. Para que conste, porque ficou registado em grava\u00e7\u00f5es operacionais, a ordem que a tropa recebeu do ent\u00e3o secret\u00e1rio de Estado foi a de \u00ablargar tudo o que voa sobre tudo o que se mova\u00bb.<\/p>\n<p>Em boa verdade, como lembra o jornalista espanhol Hibal Arbide Aza, \u00abn\u00e3o h\u00e1 mal que dure 100 anos, exceto Henry Kissinger\u00bb.<\/p>\n<p>Tend\u00eancias eug\u00eanicas<\/p>\n<p>A\u00e7\u00f5es de exterm\u00ednio em massa de seres humanos como a do Camboja, a que deve acrescentar-se o recurso indiscriminado do agente laranja no Vietn\u00e3, cujos efeitos no povo e na natureza, se fazem sentir ainda hoje, conduzem-nos inevitavelmente \u00e0s teses eug\u00eanicas, de tend\u00eancia malthusiana, que Henry Kissinger congeminou como refor\u00e7o da a\u00e7\u00e3o imperial contra o chamado Terceiro Mundo.<\/p>\n<p>Em 1974, \u00e9poca em que ocupava o cargo de Secret\u00e1rio de Estado, Kissinger orientou a execu\u00e7\u00e3o de um relat\u00f3rio confidencial a partir da ideia de que a \u00abredu\u00e7\u00e3o da popula\u00e7\u00e3o deve ser a mais elevada prioridade da pol\u00edtica externa dos Estados Unidos para o Terceiro Mundo\u00bb. Nesse documento considera-se que o acesso norte-americano aos recursos naturais dos pa\u00edses em desenvolvimento \u00e9 prejudicado pelas altas taxas demogr\u00e1ficas, prop\u00edcias \u00e0 instabilidade social e \u00e0 falta de controle sobre os estratos mais carenciados, situa\u00e7\u00f5es suscept\u00edveis de perturbar as atividades de explora\u00e7\u00e3o dos recursos dessas na\u00e7\u00f5es. O relat\u00f3rio sugere que medidas como a generaliza\u00e7\u00e3o do aborto, a propaganda da contracep\u00e7\u00e3o e o aumento das taxas de esteriliza\u00e7\u00e3o devem integrar os programas para redu\u00e7\u00e3o da popula\u00e7\u00e3o, na falta dos quais os pa\u00edses podem deixar de ter \u00abajuda\u00bb norte-americana no combate \u00e0s cat\u00e1strofes naturais ou no dom\u00ednio da assist\u00eancia alimentar. \u00abPode a alimenta\u00e7\u00e3o ser considerada um instrumento do poder nacional?\u00bb, interrogam-se os autores do Relat\u00f3rio Kissinger.<\/p>\n<p>No entanto, reconhecem, \u00ab\u00e9 importante, tanto no estilo como na subst\u00e2ncia, evitar a apar\u00eancia de coer\u00e7\u00e3o\u00bb, \u00abdisfar\u00e7ar os rastos\u00bb das exig\u00eancias norte-americanas e apresentar os programas de redu\u00e7\u00e3o da popula\u00e7\u00e3o com inten\u00e7\u00f5es \u00abaltru\u00edstas\u00bb, elaborados segundo \u00abos interesses\u00bb desses pa\u00edses e n\u00e3o dos Estados Unidos da Am\u00e9rica. Sempre com os princ\u00edpios democr\u00e1ticos acima de quaisquer outros, o Relat\u00f3rio Kissinger recomenda que \u00abos dirigentes dos pa\u00edses em vias de desenvolvimento devem comprometer-se com os programas de controlo da popula\u00e7\u00e3o passando por cima da vontade dos seus povos\u00bb.<\/p>\n<p>Povos e eleitores s\u00e3o \u00abirrespons\u00e1veis\u00bb<\/p>\n<p>Dotado de uma criatividade sem limites para os crimes de guerra e contra a humanidade, na parte final na chacina asi\u00e1tica Henry Kissinger matutava j\u00e1 no golpe de Estado que levaria precisamente um militar, o general fascista Pinochet, ao poder no Chile. \u00abN\u00e3o vejo porque tenhamos de ficar parados a ver um pa\u00eds tornar-se comunista devido \u00e0 irresponsabilidade do seu povo\u00bb, explicou Kissinger como norma a adotar por Washington na generalidade das situa\u00e7\u00f5es e n\u00e3o apenas em rela\u00e7\u00e3o ao Chile. Sobretudo quando est\u00e3o em jogo \u00abquest\u00f5es que s\u00e3o importantes demais para que os eleitores sejam deixados a decidir por si pr\u00f3prios\u00bb, m\u00e1xima que assim conforta todos os que ainda possam interrogar-se sobre a pureza da \u00abdemocracia liberal\u00bb ou \u00abdemocracia ocidental\u00bb. Tanto mais que, Kissinger dixit, \u00abn\u00e3o \u00e9 a quest\u00e3o do que \u00e9 verdade que conta, mas sim a quest\u00e3o do que \u00e9 percebido como verdade\u00bb. Uma cultura de transpar\u00eancia que a comunica\u00e7\u00e3o social corporativa aplica com absoluto rigor, como se percebe neste quintal dom\u00e9stico pelo simples fato de a TV balsem\u00e2nica por cabo, sempre fiel aos seus mestres de Bilderberg, ter eleito o falecido dirigente como \u00abdiplomata do s\u00e9culo XX\u00bb. E do s\u00e9culo XXI, deve acrescentar-se, porque a sua heran\u00e7a \u00e9 de uma atualidade gritante.<\/p>\n<p>Massacrados os povos asi\u00e1ticos por milh\u00f5es de toneladas de bombas, entronizado Pinochet no Chile \u2013 \u00abprestou um grande servi\u00e7o ao Ocidente ao derrubar Allende\u00bb, assim o elogiou o conselheiro e secret\u00e1rio de Estado \u2013 Henry Kissinger foi agraciado em 1973 com o Pr\u00eamio Nobel da Paz. Uma distin\u00e7\u00e3o inquestion\u00e1vel para um pr\u00eamio que ficou unicamente nas suas m\u00e3os, apesar de ter sido atribu\u00eddo tamb\u00e9m ao dirigente comunista vietnamita Le Duc Tho. Por\u00e9m, provavelmente por n\u00e3o partilhar dos mesmos conceitos de moral, \u00e9tica e humanismo que Kissinger, o her\u00f3i do povo do Vietname rejeitou a homenagem.<\/p>\n<p>Pouqu\u00edssimo tempo depois e, apesar de o conselheiro presidencial em regime de perman\u00eancia dizer frequentemente que \u00abn\u00e3o pode haver uma crise na pr\u00f3xima semana porque a minha agenda j\u00e1 est\u00e1 cheia\u00bb, um outro problema passou a atorment\u00e1-lo: a queda do fascismo em Portugal, um regime t\u00e3o c\u00f4modo para Washington, t\u00e3o a leste de tormentas, t\u00e3o ajustado \u00e0 imagem democr\u00e1tica com que nasceu a OTAN. Deve lembrar-se, a prop\u00f3sito, que da sua experi\u00eancia na Casa Branca o conselheiro de presidentes aprendeu uma li\u00e7\u00e3o assegurando que \u00abem Washington a apar\u00eancia de poder \u00e9 quase t\u00e3o importante como a realidade do poder; na verdade, a apar\u00eancia \u00e9 frequentemente a realidade essencial do poder\u00bb. Assim sendo, nada de contradit\u00f3rio haveria na presen\u00e7a do regime fascista portugu\u00eas entre os fundadores da \u00abalian\u00e7a das democracias\u00bb.<\/p>\n<p>Imagens alusivas aos tempos revolucion\u00e1rios de Abril de 1974 est\u00e3o agora sendo passadas nas TVs portuguesas, acompanhadas por arrebatados enc\u00f4mios, exibindo um Kissinger saltitante descendo as escadas de um avi\u00e3o no aeroporto de Lisboa para vir restabelecer a ordem neste recanto inesperadamente tumultuado. Porque \u00abo que deve acontecer, em \u00faltima an\u00e1lise, deve acontecer imediatamente\u00bb.<\/p>\n<p>N\u00e3o havia, pois, tempo a perder, at\u00e9 porque \u00abo que \u00e9 ilegal faz\u00eamo-lo imediatamente e o que \u00e9 inconstitucional demora mais um pouco\u00bb; e, no seu diagn\u00f3stico da situa\u00e7\u00e3o revelado em 27 de Mar\u00e7o de 1975, em plena Casa Branca, Kissinger explicou o seguinte: em rela\u00e7\u00e3o a Portugal, \u00abos europeus estabeleceram dois objetivos: a realiza\u00e7\u00e3o de elei\u00e7\u00f5es e evitar a tomada do poder pelos comunistas; acho que podemos conseguir esses dois objetivos e mesmo assim perder o pa\u00eds porque os comunistas governam atrav\u00e9s do MFA (\u2026) Provavelmente temos de atacar Portugal qualquer que seja o resultado, e expuls\u00e1-lo da OTAN\u00bb.<\/p>\n<p>Da visita de Kissinger a Lisboa no in\u00edcio da Primavera de 1975 at\u00e9 o golpe de 25 de Novembro passaram-se menos de oito meses, durante os quais os sinais de conspira\u00e7\u00e3o se tornaram mais abundantes e amea\u00e7adores de dia para dia, por vezes com paralelismos arrepiantes em rela\u00e7\u00e3o ao Chile de 1973.<\/p>\n<p>Os recursos conspirativos manifestados pelo conselheiro imperial permitem que, a partir de agora, possamos deduzir que se houver golpe de Estado no Inferno ser\u00e1 f\u00e1cil encontrar o respons\u00e1vel, conclui o jornalista basco I\u00f1igo Errej\u00f3n no seu espa\u00e7o no X (Twitter).<\/p>\n<p>Se a \u00absolu\u00e7\u00e3o Pinochet\u00bb foi uma das que viajou at\u00e9 Lisboa na bagagem de Kissinger \u00e9 uma d\u00favida dif\u00edcil de esbater. No entanto, o 25 de Novembro de 1975 ter-se-\u00e1 ficado pelo que foi porque os planos do conselheiro, do seu embaixador Carlucci e de pol\u00edticos colaboracionistas que funcionaram como seus agentes esbarraram no patriotismo e tamb\u00e9m nos compromissos com a democracia honrados por militares \u2013 afinal n\u00e3o \u00abt\u00e3o burros e est\u00fapidos\u00bb como os encarava o homem de tantos presidentes.<\/p>\n<p>Os portugueses perceberam ent\u00e3o, de uma maneira que lhes causa danos at\u00e9 hoje, a mensagem de Kissinger, afinal nada enigm\u00e1tica, segundo a qual \u00abser inimigo da Am\u00e9rica \u00e9 perigoso, mas ser amigo da Am\u00e9rica \u00e9 fatal\u00bb. Uma outra maneira de dizer que amigos assim dispensam a exist\u00eancia de inimigos. Nada que seja impeditivo da vassalagem rastejante da classe pol\u00edtica lusitana perante \u00abo amigo americano\u00bb, na realidade o dono americano, como ambas as partes assumem.<\/p>\n<p>Do mesmo modo, os pa\u00edses da Uni\u00e3o Europeia e os que comp\u00f5em o chamado mundo ocidental t\u00eam dados mais do que suficientes para perceberem o sentido de uma outra m\u00e1xima imperial program\u00e1tica de Kissinger: \u00aba Am\u00e9rica n\u00e3o tem amigos ou inimigos permanentes, a Am\u00e9rica tem apenas interesses\u00bb. Observemos, por exemplo, o papel reservado aos seus \u00abamigos europeus\u00bb na crise ucraniana e nada fica por explicar, branco \u00e9 galinha o p\u00f5e.<\/p>\n<p>Henry Kissinger partiu, mas n\u00e3o foi em v\u00e3o; ensinou-nos tudo sobre a \u00abdemocracia liberal\u00bb ou \u00abdemocracia ocidental\u00bb, a leg\u00edtima, afinal a \u00fanica tolerada porque, como o mestre gostava de dizer, \u00aba aus\u00eancia de alternativa limpa maravilhosamente a mente\u00bb. Rebanhos de \u00abmente limpa\u00bb, como os apascentados pelas classes financeiras, pol\u00edticas e midi\u00e1ticas cujos interesses Henry Kissinger t\u00e3o bem soube interpretar e ensinar, mesmo que as provas pr\u00e1ticas sejam brutais e sangrentas. Mas tudo passa, desde que o poder imperial colonial fique.<\/p>\n<p>Por\u00e9m, existe sempre quem esteja alerta, s\u00e3o muitos e cada vez mais os que est\u00e3o alerta sabendo identificar muito bem a democracia que Henry Kissinger nos deixou como heran\u00e7a. H\u00e1 que renegar essa heran\u00e7a e construir uma democracia aut\u00eantica. A caricatura em vigor atingiu o prazo de validade, tal como o criminoso de guerra que contribuiu decisivamente para imp\u00f4-la.<\/p>\n","protected":false},"excerpt":{"rendered":"<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/31146\"> <\/a>","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[73,9,65,146,75,10],"tags":[234],"class_list":["post-31146","post","type-post","status-publish","format-standard","hentry","category-c86-anti-imperialismo","category-s10-internacional","category-c78-internacional","category-internacionalismo","category-c88-internacionalismo","category-s19-opiniao","tag-6b"],"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p659gw-86m","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/31146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=31146"}],"version-history":[{"count":1,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/31146\/revisions"}],"predecessor-version":[{"id":31148,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/31146\/revisions\/31148"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=31146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=31146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=31146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}