{"id":31556,"date":"2024-04-09T10:26:46","date_gmt":"2024-04-09T13:26:46","guid":{"rendered":"https:\/\/pcb.org.br\/portal2\/?p=31556"},"modified":"2024-04-09T10:26:46","modified_gmt":"2024-04-09T13:26:46","slug":"seis-meses-de-genocidio-em-gaza","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/31556","title":{"rendered":"Seis meses de genoc\u00eddio em Gaza"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"31557\" data-permalink=\"https:\/\/pcb.org.br\/portal2\/31556\/photo_2024-04-09_10-13-28\" data-orig-file=\"https:\/\/i0.wp.com\/pcb.org.br\/portal2\/wp-content\/uploads\/2024\/04\/photo_2024-04-09_10-13-28.jpg?fit=1280%2C960&amp;ssl=1\" data-orig-size=\"1280,960\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"photo_2024-04-09_10-13-28\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/pcb.org.br\/portal2\/wp-content\/uploads\/2024\/04\/photo_2024-04-09_10-13-28.jpg?fit=747%2C560&amp;ssl=1\" class=\"alignnone size-large wp-image-31557\" src=\"https:\/\/i0.wp.com\/pcb.org.br\/portal2\/wp-content\/uploads\/2024\/04\/photo_2024-04-09_10-13-28.jpg?resize=747%2C560&#038;ssl=1\" alt=\"\" width=\"747\" height=\"560\" srcset=\"https:\/\/i0.wp.com\/pcb.org.br\/portal2\/wp-content\/uploads\/2024\/04\/photo_2024-04-09_10-13-28.jpg?resize=900%2C675&amp;ssl=1 900w, https:\/\/i0.wp.com\/pcb.org.br\/portal2\/wp-content\/uploads\/2024\/04\/photo_2024-04-09_10-13-28.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/pcb.org.br\/portal2\/wp-content\/uploads\/2024\/04\/photo_2024-04-09_10-13-28.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/pcb.org.br\/portal2\/wp-content\/uploads\/2024\/04\/photo_2024-04-09_10-13-28.jpg?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 747px) 100vw, 747px\" \/><!--more--><\/p>\n<p>Cr\u00e9ditos da Imagem: Rovena Rosa (Ag\u00eancia Brasil)<\/p>\n<hr \/>\n<p>A import\u00e2ncia e o significado da solidariedade \u00e0 Causa Palestina<\/p>\n<p>Por F\u00e1bio Bezerra<\/p>\n<p>Neste dia 09 de abril, os ataques do governo israelense de Benjamin Netanyahu \u00e0 Faixa de Gaza completam seis meses, revelando nesse primeiro quarto de s\u00e9culo o descalabro do primeiro genoc\u00eddio transmitido em tempo real a bilh\u00f5es de seres humanos.<\/p>\n<p>Em primeiro lugar, a m\u00eddia tradicional tem tratado o conflito como uma \u201cguerra\u201d entre Israel e o grupo Hamas, intitulado na maioria das mat\u00e9rias jornal\u00edsticas como um grupo terrorista. N\u00e3o se trata de uma guerra convencional, mas de um genoc\u00eddio que escancara o holocausto ao qual a popula\u00e7\u00e3o palestina, n\u00e3o apenas na Faixa de Gaza, mas tamb\u00e9m na Cisjord\u00e2nia ocupada, vem vivenciando de forma mais intensa nesses \u00faltimos seis meses.<\/p>\n<p>A compreens\u00e3o e a devida aplica\u00e7\u00e3o do termo guerra, nesse conflito que ocorre na Palestina, s\u00f3 poderia ser utilizada adequadamente, se as for\u00e7as oponentes em conflito possu\u00edssem paridade de condi\u00e7\u00f5es b\u00e9licas ou, ao menos, condi\u00e7\u00f5es que aproximassem o poderio militar entre ambas, o que n\u00e3o \u00e9 o caso desse conflito. Estamos falando de um Estado que possui um dos maiores arsenais militares do mundo, com tecnologia sofisticada, ao contr\u00e1rio da resist\u00eancia palestina e que, mesmo assim, tem deliberadamente massacrado indistintamente a popula\u00e7\u00e3o civil em Gaza.<\/p>\n<p>O que presenciamos \u00e9 um massacre deliberado da popula\u00e7\u00e3o civil palestina, sobretudo das mulheres e crian\u00e7as, sob o pretexto de combate \u00e0s for\u00e7as da resist\u00eancia na Faixa de Gaza. Esse massacre deliberado j\u00e1 martirizou mais de 33 mil palestinos, destruiu quase todos os hospitais em Gaza e devastou cerca de 70% do territ\u00f3rio, acabando com o pouco de infraestrutura que havia nas principais cidades da regi\u00e3o, obrigando milh\u00f5es de pessoas a se refugiarem ao sul do territ\u00f3rio.<\/p>\n<p>Em segundo lugar, afirmar que se trata de uma guerra contra o terrorismo \u00e9 uma forma de tentar dissuadir a opini\u00e3o p\u00fabica de que n\u00e3o h\u00e1 um genoc\u00eddio em curso contra a popula\u00e7\u00e3o palestina e de que as mortes se legitimam como resultado da luta contra \u201cextremistas terroristas que se escondem\u201d atr\u00e1s da popula\u00e7\u00e3o civil! Em todas as atrocidades cometidas em conflitos b\u00e9licos, ao longo da hist\u00f3ria, a narrativa ideol\u00f3gica sempre foi um recurso para tentar encobrir viola\u00e7\u00f5es e barbaridades e justificar os massacres em massa.<\/p>\n<p>Nesse caso espec\u00edfico, afirmamos que o terrorismo em curso \u00e9 o terrorismo de Estado promovido pelo governo de ultradireita h\u00e1 d\u00e9cadas e que se intensificaram contra a popula\u00e7\u00e3o palestina, principalmente a partir de 2009. A Faixa de Gaza nesses \u00faltimos 15 anos tinha se tornado um verdadeiro campo de concentra\u00e7\u00e3o a c\u00e9u aberto! As condi\u00e7\u00f5es de vida de cerca de 2,3 milh\u00f5es de palestinos nessa regi\u00e3o eram extremamente deplor\u00e1veis, com racionamento de luz, dificuldade de acesso a \u00e1gua pot\u00e1vel, alimentos e rem\u00e9dios, al\u00e9m de insumos b\u00e1sicos para a produ\u00e7\u00e3o agr\u00edcola e at\u00e9 mesmo a circula\u00e7\u00e3o de mercadorias. O confinamento sistem\u00e1tico, al\u00e9m das humilha\u00e7\u00f5es e priva\u00e7\u00f5es \u00e0s quais a popula\u00e7\u00e3o de Gaza j\u00e1 vinha sendo submetida \u00e9 uma forma perversa de tortura, t\u00edpica dos campos de concentra\u00e7\u00e3o, ao qual todo o movimento de solidariedade a Palestina denuncia como apartheid social.<\/p>\n<p>Por isso, come\u00e7ar qualquer an\u00e1lise sobre a situa\u00e7\u00e3o atual da popula\u00e7\u00e3o palestina sem ressaltar o cen\u00e1rio de genoc\u00eddio sist\u00eamico na Faixa de Gaza, que nos leva a afirmar que h\u00e1 tamb\u00e9m um etnoc\u00eddio em curso, assim como n\u00e3o qualificar as a\u00e7\u00f5es de Estado do Governo israelense como terrorismo de Estado, n\u00e3o seria poss\u00edvel avan\u00e7ar em qualquer an\u00e1lise honesta sobre essa trag\u00e9dia imposta ao povo palestino.<\/p>\n<p>O Sionismo, a ultradireita e o Imperialismo<\/p>\n<p>O conflito atual em Gaza \u00e9 parte de um processo de resist\u00eancia, tanto ao colonialismo israelense e a todas as atrocidades e desrespeitos que seguem h\u00e1 mais de 75 anos, quanto ao descumprimento deliberado a tratados e acordos firmados por Israel junto \u00e0 ONU e de luta do povo palestino pela soberania de seu territ\u00f3rio. Nessas \u00faltimas d\u00e9cadas o movimento sionista se tornou a express\u00e3o pol\u00edtico e ideol\u00f3gica da ultradireita israelense, fortalecendo la\u00e7os com os movimentos reacion\u00e1rios em todo o mundo e com apoio financeiro a partir do chamado Keren Hayesod, um fundo internacional que arrecada recursos para o movimento sionista. Este \u201cFundo Comunit\u00e1rio\u201d \u00e9 um dos respons\u00e1veis diretos pelo financiamento de ocupa\u00e7\u00f5es ilegais israelenses em solo palestino, principalmente na Cisjord\u00e2nia, al\u00e9m de financiar as a\u00e7\u00f5es de diversas entidades sionistas n\u00e3o apenas em Israel, mas tamb\u00e9m em outras partes do mundo.<\/p>\n<p>Se o sionismo (express\u00e3o que prov\u00e9m do termo Sion, que designa a origem do povo hebreu) surge no final do s\u00e9culo XIX a partir do Congresso da Basileia em 1896 com o prop\u00f3sito de constituir um \u201cEstado Judeu\u201d ao povo judeu compartilhando da ades\u00e3o de diversos segmentos ideol\u00f3gicos \u00e0 \u00e9poca, a partir da instaura\u00e7\u00e3o do Estado de Israel em 1948 e nos anos subsequentes, esse movimento passou a expressar n\u00e3o apenas a defesa da constitui\u00e7\u00e3o de um Estado Judeu, mas sobretudo a expans\u00e3o do territ\u00f3rio e por consequ\u00eancia a expuls\u00e3o arbitr\u00e1ria e violenta do povo palestino, anexa\u00e7\u00e3o de suas terras e imposi\u00e7\u00e3o do dom\u00ednio de Israel por todas as vias e meios poss\u00edveis. Esse processo s\u00f3 foi poss\u00edvel com o apoio pol\u00edtico das grandes pot\u00eancias mundiais \u00e0 \u00e9poca, fruto do lobby sionista que se processava desde antes mesmo do in\u00edcio da 2\u00aa Guerra Mundial, e o financiamento de um Estado autorit\u00e1rio, repressivo, militarizado e cada vez mais restritivo e xen\u00f3fobo em rela\u00e7\u00e3o \u00e0 popula\u00e7\u00e3o \u00e1rabe e em especial \u00e0 popula\u00e7\u00e3o palestina.<\/p>\n<p>O lobby sionista e sua rela\u00e7\u00e3o direta com os EUA e os governos de plant\u00e3o das principais economias capitalistas mundiais, al\u00e9m de permitir o desenvolvimento do Estado de Israel e o expansionismo colonialista em terras palestinas com flagrantes desrespeitos a tratados internacionais, tornou-se a express\u00e3o ideol\u00f3gica dos interesses do imperialismo estadunidense na regi\u00e3o, como salvaguarda pol\u00edtica frente ao crescimento da resist\u00eancia \u00e1rabe e a identifica\u00e7\u00e3o da luta pela liberta\u00e7\u00e3o nacional como elemento de oposi\u00e7\u00e3o ao colonialismo israelense e a seus la\u00e7os pol\u00edticos com o imperialismo. \u00c9 importante compreender que esse processo s\u00f3 foi poss\u00edvel se consolidar gra\u00e7as aos acordos que os governos israelenses, chancelados pela diplomacia estadunidense, celebrou com governos conservadores e suas respectivas burguesias locais, interessados em evitar o crescimento da influ\u00eancia pol\u00edtica que a luta pela liberta\u00e7\u00e3o nacional da Palestina com perspectivas contra hegem\u00f4nicas poderia produzir na geopol\u00edtica local, contrapondo-se aos interesses das elites \u00e1rabes e seus acordos com os EUA.<\/p>\n<p>Toda e qualquer rea\u00e7\u00e3o que ponha em xeque os interesses e as alian\u00e7as pela manuten\u00e7\u00e3o de poder de determinados grupos associados ao cons\u00f3rcio EUA-Israel, mesmo que essas rea\u00e7\u00f5es n\u00e3o tenham a priori uma perspectiva de ruptura revolucion\u00e1ria, passam a ser alvo de investidas ideol\u00f3gicas, econ\u00f4micas, pol\u00edticas e em \u00faltima inst\u00e2ncia de agress\u00e3o b\u00e9lica. Isso ajuda a compreender a dissemina\u00e7\u00e3o ideol\u00f3gica, arbitr\u00e1ria, preconceituosa e por conseguinte manipuladora do termo \u201cterrorista\u201d a qualquer um que manifesta apoio \u00e0 Causa Palestina, quando n\u00e3o se apoiam em interpreta\u00e7\u00f5es religiosas distorcidas para induzir o senso comum a justificar as agress\u00f5es israelenses e discriminar qualquer iniciativa de solidariedade aos palestinos e de den\u00fancia do que realmente representa o sionismo.<\/p>\n<p>Nesse sentido deve-se entender o movimento sionista n\u00e3o mais como a express\u00e3o daquilo que foi o seu surgimento no final do s\u00e9culo XIX, mas como a express\u00e3o pol\u00edtica e ideol\u00f3gica dos interesses imperialistas na regi\u00e3o e da extrema-direita israelense, que revela atrav\u00e9s do genoc\u00eddio do povo palestino n\u00e3o apenas uma pol\u00edtica de estado, mas sobretudo um projeto de poder para toda a regi\u00e3o. Projeto de poder que estipula um alinhamento internacional com o crescente movimento reacion\u00e1rio em curso em v\u00e1rios pa\u00edses desenvolvidos, os quais expressam, por sua vez, a agudiza\u00e7\u00e3o da crise do modo de produ\u00e7\u00e3o capitalista, aumentando as tens\u00f5es sociais e as contradi\u00e7\u00f5es pol\u00edticas, que alimentam o intento reacion\u00e1rio e retr\u00f3grado em diversos segmentos da burguesia em dezenas de pa\u00eds no mundo, tendo o neofascismo como uma das suas principais express\u00f5es.<\/p>\n<p>\u00c9 importante destacar nessa passagem que n\u00e3o h\u00e1 uma crise do imperialismo como alguns assim entendem, mas o aprofundamento da crise sist\u00eamica e estrutural do capitalismo, produzindo rea\u00e7\u00f5es diversas e contradit\u00f3rias em todas as esferas da vida social. O imperialismo \u00e9 parte constitutiva dessa crise, que se equaciona em conflitos de interesses entre as grandes na\u00e7\u00f5es capitalistas por mercados consumidores e territ\u00f3rios, mat\u00e9rias primas, recursos h\u00eddricos e tudo aquilo que possa garantir dom\u00ednio e perman\u00eancia de um status de poder na din\u00e2mica de busca de hegemonia nas tens\u00f5es presentes na geopol\u00edtica mundial.<\/p>\n<p>Pensar a Causa Palestina, a resist\u00eancia palestina e a luta pela liberta\u00e7\u00e3o nacional significa refletir esse processo entrela\u00e7ado com o contexto das a\u00e7\u00f5es imperialistas na regi\u00e3o do Oriente M\u00e9dio, suas poss\u00edveis conex\u00f5es com a rea\u00e7\u00e3o burguesa \u00e0 crise do capitalismo, sobretudo atrav\u00e9s de alian\u00e7as que o movimento sionista estabelece com outras for\u00e7as reacion\u00e1rias como forma de apoio pol\u00edtico nos respectivos pa\u00edses, que s\u00e3o, por sua vez, a express\u00e3o da for\u00e7a do lobby sionista e ao mesmo tempo a express\u00e3o do alinhamento ideol\u00f3gico da direita mundial.<\/p>\n<p><strong>A Solidariedade Internacional e o papel dos Comit\u00eas<\/strong><\/p>\n<p>Para n\u00f3s, comunistas, a solidariedade \u00e9 antes de tudo uma tomada de posi\u00e7\u00e3o pol\u00edtica e um instrumento de a\u00e7\u00e3o que deve denunciar as causas dos abusos e todos os tipos de contradi\u00e7\u00f5es que ressaltam e estruturam a desumaniza\u00e7\u00e3o dos povos sob v\u00e1rias formas. \u00c9 uma atitude que deve ir al\u00e9m da evidencia\u00e7\u00e3o das consequ\u00eancias que nos causa repulsa. \u00c9 mais do que um valor moral universal, como filosoficamente muitos classificam.<\/p>\n<p>Mais do que uma consterna\u00e7\u00e3o subjetiva, \u00e9 a manifesta\u00e7\u00e3o consciente do lastro daquilo que nos causa repulsa e sensibiliza como consequ\u00eancia direta das contradi\u00e7\u00f5es do capitalismo. O que faz de todo ato de solidariedade um necess\u00e1rio processo pedag\u00f3gico de den\u00fancia das estruturas e da din\u00e2mica das contradi\u00e7\u00f5es que geram a viol\u00eancia contra os povos e que muitas vezes s\u00e3o naturalizadas pela ideologia dominante, contaminando o senso comum com a insensatez que tanto se faz presente em uma sociedade cada vez mais individualista.<\/p>\n<p>O recrudescimento da viol\u00eancia do Estado de Israel ao povo palestino nesses \u00faltimos seis meses possui uma estrutura e uma din\u00e2mica que est\u00e3o associadas \u00e0 l\u00f3gica do imperialismo na regi\u00e3o e de uma de suas express\u00f5es locais mais contradit\u00f3rias: o colonialismo sionista em terras palestinas e o apartheid social como mecanismo de subjuga\u00e7\u00e3o da identidade de um povo. As chamadas For\u00e7as de Defesa de Israel t\u00eam empreendido, sem nenhum escr\u00fapulo e sem nenhum limite, um desproporcional ataque \u00e0 popula\u00e7\u00e3o civil palestina em Gaza. Esse ataque tem revelado ao mundo n\u00e3o apenas as atrocidades da barb\u00e1rie dessa incurs\u00e3o militar em Gaza, mas sobretudo a metodologia genocida, a estrat\u00e9gia de destrui\u00e7\u00e3o sistem\u00e1tica das cidades de Gaza e seu componente ideol\u00f3gico que se traduz em xenofobia e a\u00e7\u00f5es ditas \u201cpreventivas\u201d, que s\u00e3o a express\u00e3o daquilo que acusamos de terrorismo de Estado, al\u00e9m do recrudescimento do apartheid social.<\/p>\n<p>Al\u00e9m dos ataques indiscriminados \u00e0 popula\u00e7\u00e3o civil em Gaza, h\u00e1 tamb\u00e9m o apoio financeiro a mil\u00edcias de colonos, com a entrega de armas a essas mil\u00edcias nas terras ocupadas da Cisjord\u00e2nia, promovendo uma escalada sem precedentes de atentados aos palestinos na regi\u00e3o ocupada, ultrapassando mais de 400 palestinos assassinados desde outubro de 2023. O pr\u00f3prio ministro da defesa do Estado de Israel, Yoav Gallant, j\u00e1 foi flagrado em reuni\u00f5es com representantes extremistas das comunidades de \u201ccolonos\u201d na Cisjord\u00e2nia estimulando o porte de armas e o ataque a popula\u00e7\u00e3o civil palestina local.<\/p>\n<p>Toda essa carnificina tem sido revelada ao mundo gra\u00e7as \u00e0 din\u00e2mica das redes sociais que, de certa forma, consegue quebrar parte do monop\u00f3lio de comunica\u00e7\u00e3o internacional que durante d\u00e9cadas foi represada e ou filtrada pelas grandes ag\u00eancias de not\u00edcias internacionais, restringindo o acesso a imagens e a dados importantes como n\u00famero de v\u00edtimas ou atentados a hospitais, escolas, entre outros. Em todo o mundo ampliou-se o sentimento de solidariedade \u00e0 Causa Palestina e de repulsa ao massacre do povo palestino. Milhares de manifesta\u00e7\u00f5es de rua contra os ataques israelenses a alvos civis e iniciativas, que v\u00e3o desde abaixo-assinados pela ruptura das rela\u00e7\u00f5es diplom\u00e1ticas dos pa\u00edses locais com o Estado de Israel at\u00e9 o boicote a produtos de empresas que financiam o sionismo, foram algumas das diversas iniciativas de protestos.<\/p>\n<p>No Brasil tamb\u00e9m n\u00e3o tem sido diferente: centenas de iniciativas surgiram em todas as regi\u00f5es, resultando na organiza\u00e7\u00e3o de Comit\u00eas de Solidariedade \u00e0 Palestina. Esses comit\u00eas locais possuem como principais caracter\u00edsticas um formato horizontalizado e mais democr\u00e1tico na sua estrutura de organiza\u00e7\u00e3o, envolvendo os mais diversas setores da classe trabalhadora, partidos pol\u00edticos e movimentos sociais sens\u00edveis \u00e0 causa palestina, com din\u00e2micas pr\u00f3prias de funcionamento e tendo como principal ponto de unidade a suspens\u00e3o imediata das incurs\u00f5es militares em Gaza e a retirada das for\u00e7as invasoras dos territ\u00f3rios ocupados, o cessar-fogo e a defesa da constitui\u00e7\u00e3o de um Estado Palestino soberano.<\/p>\n<p>Al\u00e9m disso, outra importante caracter\u00edstica que mant\u00e9m a unidade de a\u00e7\u00e3o na diversidade pol\u00edtico-ideol\u00f3gica daqueles que se associam \u00e0 defesa da causa palestina e \u00e0 solidariedade a seu povo \u00e9 a justa compreens\u00e3o e o reconhecimento da autodetermina\u00e7\u00e3o do povo palestino em suas quest\u00f5es internas. O foco de nossa milit\u00e2ncia em ressaltar a heroica resist\u00eancia do povo palestino independente da multiplicidade de tend\u00eancias que comp\u00f5e o cen\u00e1rio das organiza\u00e7\u00f5es da chamada resist\u00eancia palestina.<\/p>\n<p>Sendo assim, as iniciativas de solidariedade ao povo palestino v\u00eam constituindo em todo o mundo um amplo campo de den\u00fancia contra o governo de ultradireita de Bejamin Nethanyahun, bem como a pol\u00edtica de Estado que promove a usurpa\u00e7\u00e3o de terras palestinas e o apartheid social imposto, os massacres constantes e a viola\u00e7\u00e3o de tratados internacionais e dos mais elementares direitos humanos. Mesmo com nuances diversas, movimentos como o Boicote, Desinvestimento e San\u00e7\u00f5es (BDS), que foi criado em 2005 por uma coliga\u00e7\u00e3o de grupos da sociedade civil palestina, t\u00eam provocado efeitos econ\u00f4micos e pol\u00edticos a diversas empresas que financiam o Estado de Israel e as pol\u00edticas de Nethanyahun.<\/p>\n<p>\u00c9 importante destacar a repercuss\u00e3o na m\u00eddia internacional sobre a manifesta\u00e7\u00e3o do Governo Sul-Africano junto \u00e0 Corte Internacional de Justi\u00e7a em Haia, acusando o Estado de Israel de descumprir os protocolos internacionais de Guerra, acusando-o de pr\u00e1tica de genoc\u00eddio, levou Israel ao banco dos r\u00e9us pela primeira vez na Hist\u00f3ria, em seu longo percurso de massacres e viola\u00e7\u00f5es de direitos. Todo o conjunto de a\u00e7\u00f5es articuladas e variadas, inclusive as manifesta\u00e7\u00f5es de chefes de Estado, de cl\u00e9rigos de religi\u00f5es diversas, celebridades do mundo das artes e esportistas, dentre outros, tem aumentado a exposi\u00e7\u00e3o das contradi\u00e7\u00f5es e dos crimes do Governo sionista de Israel e seu consecutivo isolamento no cen\u00e1rio internacional. Esse deve ser um dos principais elementos que devemos explorar constantemente em nossas manifesta\u00e7\u00f5es p\u00fablicas.<\/p>\n<p>Nesse contexto, o fortalecimento dos Comit\u00eas de Solidariedade a Palestina \u00e9 algo imprescind\u00edvel por parte de todas as organiza\u00e7\u00f5es que possuem o compromisso com a causa palestina e com a necess\u00e1ria emancipa\u00e7\u00e3o do povo palestino do jugo do colonialismo de Israel. E isso deve estar associado ao necess\u00e1rio debate sobre o que representa a crise do capitalismo em sua atualidade e seus desdobramentos internacionais, que podem se manifestar atrav\u00e9s dos conflitos e guerras regionais, interven\u00e7\u00f5es imperialistas na desestrutura\u00e7\u00e3o de governos locais, genoc\u00eddios como o que ocorre na Palestina e em pa\u00edses em guerra no continente africano, por exemplo.<\/p>\n<p>Evidentemente esse debate sobre a conjuntura em crise deve se desdobrar tamb\u00e9m sobre nosso contexto pol\u00edtico recente, sobre os atores pol\u00edticos regionais e suas ramifica\u00e7\u00f5es com a extrema direita internacional, a correla\u00e7\u00e3o de for\u00e7as e a intensidade do grau de mobiliza\u00e7\u00e3o e rea\u00e7\u00e3o dos aliados do sionismo em suas vari\u00e1veis vertentes, os poss\u00edveis cen\u00e1rios e a potencialidade de nossas for\u00e7as.<\/p>\n<p>Um bom exemplo desse processo descrito acima s\u00e3o as sucessivas investidas da Confedera\u00e7\u00e3o Israelita do Brasil (CONIB) contra o jornalista Breno Altman em rela\u00e7\u00e3o a sua campanha de den\u00fancias sobre os crimes do governo sionista de Bejamin Nethanyahun e mais recentemente as investidas do presidente da C\u00e2mera dos Deputados Arthur Lira, do PP de Alagoas, que solicitou no conselho de \u00e9tica da C\u00e2mara um pedido de cassa\u00e7\u00e3o do mandato do deputado federal Glauber Braga do PSOL-RJ, apenas por ter promovido uma audi\u00eancia em solidariedade ao povo palestino.<\/p>\n<p>A quest\u00e3o da solidariedade internacional n\u00e3o pode estar desassociada do necess\u00e1rio debate sobre a conjuntura em crise e seus desdobramentos pol\u00edticos, econ\u00f4micos e ideol\u00f3gicos sobre a classe trabalhadora tanto no n\u00edvel internacional quanto no Brasil. Al\u00e9m de atuamos tamb\u00e9m na desconstru\u00e7\u00e3o das fal\u00e1cias que tentam justificar o massacre palestino, combater os preconceitos contra a popula\u00e7\u00e3o palestina, alimentados principalmente pela m\u00eddia burguesa, esse processo deve tamb\u00e9m ser a express\u00e3o da justa exig\u00eancia ao Governo Lula de romper os acordos institucionais entre Brasil e Israel. Al\u00e9m das palavras de efeito, o Governo Lula at\u00e9 aqui apenas fez gestos diplom\u00e1ticos em apoio ao processo do governo sul-africano contra Israel em Haia e considera\u00e7\u00f5es pelo cessar-fogo imediato. Mas mesmo ap\u00f3s o pronunciamento de Lula no encontro da Confedera\u00e7\u00e3o Africana em Adis Abeba, em fevereiro desse ano, o governo brasileiro mant\u00e9m os acordos militares firmados em 2019 ainda no Governo Bolsonaro. A C\u00e2mara dos Deputados ampliou esses acordos com a aprova\u00e7\u00e3o, em 19\/10\/2023 (dez dias ap\u00f3s os in\u00edcios das incurs\u00f5es mais recentes de Israel \u00e0 Faixa de Gaza), do Projeto de Lei 554\/21 que, entre outras coisas, amplia as a\u00e7\u00f5es de intelig\u00eancia e o uso de tecnologia de informa\u00e7\u00e3o.<\/p>\n<p>Os Comit\u00eas de Solidariedade t\u00eam tido um papel decisivo nas mobiliza\u00e7\u00f5es de massa em defesa do povo palestino e na demonstra\u00e7\u00e3o p\u00fablica de nosso rep\u00fadio ao massacre palestino, ao sionismo e seus aliados e \u00e0 exig\u00eancia da ruptura dos acordos institucionais (militares, cient\u00edficos-tecnol\u00f3gicos, comerciais, entre outros) entre o Estado brasileiro e o Estado israelense. Al\u00e9m disso, os Comit\u00eas tamb\u00e9m se tornaram um importante espa\u00e7o de debate e forma\u00e7\u00e3o pol\u00edtica que enfatiza o contraponto ideol\u00f3gico \u00e0s narrativas conservadoras defensoras do chamado \u201cdireito de defesa\u201d do Estado de Israel, que servem como argumentos falaciosos junto ao senso comum para justificar a pr\u00e1tica do apartheid social e o genoc\u00eddio em curso.<\/p>\n<p>E por fim t\u00eam representado sobretudo um significativo potencial de unidade de a\u00e7\u00e3o, fruto do esfor\u00e7o que muitas organiza\u00e7\u00f5es pol\u00edticas tem procurado desempenhar para que os Comit\u00eas se mantenham amplos em sua capacidade de aglutina\u00e7\u00e3o de todos(as) aqueles(as) que se revoltam com os crimes cometidos em Gaza, que queiram ajudar a disputar cora\u00e7\u00f5es e mentes junto \u00e0 sociedade brasileira denunciando os crimes do governo israelense e a import\u00e2ncia da nossa aten\u00e7\u00e3o e mobiliza\u00e7\u00e3o solid\u00e1ria. Esse tem sido o foco dos comit\u00eas e \u00e9 a justa medida daquilo que nos unifica e fortalece nosso compromisso internacionalista contra o flagelo da barb\u00e1rie capitalista nesse contexto.<\/p>\n<p>A milit\u00e2ncia em torno da solidariedade ao povo palestino poder\u00e1, por sua vez, efetivar poss\u00edveis di\u00e1logos e unidade de a\u00e7\u00e3o no campo dos movimentos sociais, que v\u00eam empreendendo conjuntamente campanhas de rua contra o genoc\u00eddio e apartheid social promovidos na Palestina. Essa unidade de a\u00e7\u00e3o poder\u00e1, a partir da evid\u00eancia das an\u00e1lises sobre a conjuntura internacional, associar as contradi\u00e7\u00f5es em curso no panorama nacional, como express\u00f5es de um mesmo processo conjuntural, adaptando os cen\u00e1rios locais e as circunst\u00e2ncias de determinados processos pol\u00edticos \u00e0 necessidade de tamb\u00e9m empreendermos lutas conjuntas em outros espa\u00e7os espec\u00edficos que fortale\u00e7am a rea\u00e7\u00e3o da classe trabalhadora e da juventude ao neoliberalismo e ao neofascismo.<\/p>\n<p><strong>Os poss\u00edveis cen\u00e1rios<\/strong><\/p>\n<p>A resist\u00eancia institucional do Governo Nethanyahu em ceder aos apelos diplom\u00e1ticos de diversos pa\u00edses e at\u00e9 mesmo \u00e0 resolu\u00e7\u00e3o do Conselho de Seguran\u00e7a da ONU por um cessar-fogo imediato, tem demonstrado o quanto o governo israelense est\u00e1 disposto a continuar o genoc\u00eddio em curso e o quanto o lobby sionista est\u00e1 disposto a sustentar esse massacre \u00e0 guisa de qualquer posicionamento dos organismos multilaterais e dos chefes de Estado.<br \/>\nO pre\u00e7o pol\u00edtico de dobrar a aposta em aumentar as a\u00e7\u00f5es militares contra civis palestinos em Gaza, destruindo hospitais, massacrando pessoas fam\u00e9licas, que buscavam acesso aos sacos de farinha despejados de avi\u00f5es no litoral de Gaza e, mais recentemente, o assassinato de sete agentes da ONG World Central Kitchen (WCK) que prestavam aux\u00edlio humanit\u00e1rio aos palestinos, tem aumentado a repulsa mundial aos ataques israelenses, expondo as atrocidades da coliga\u00e7\u00e3o de ultradireita que governa o pa\u00eds.<\/p>\n<p>Essa exposi\u00e7\u00e3o mundial, por sua vez, tem alimentado velhos preconceitos antissemitas contra o povo judeu de modo geral, atingindo tamb\u00e9m parte da comunidade israelense que n\u00e3o apoia o sionismo como regime de governo e tampouco o genoc\u00eddio em curso em Gaza e os massacres na Cisjord\u00e2nia ocupada. Essa situa\u00e7\u00e3o tem elevado tamb\u00e9m as press\u00f5es internas em Israel pela queda do governo de Netanyahu que, antes do recrudescimento dos ataques sobre a popula\u00e7\u00e3o palestina, vinha sofrendo processos judiciais por acusa\u00e7\u00f5es de corrup\u00e7\u00e3o. J\u00e1 foram contabilizadas, por exemplo, nos \u00faltimos meses, dezenas de manifesta\u00e7\u00f5es de rua em Tel Aviv e outras cidades promovida por israelenses exigindo a queda do governo.<\/p>\n<p>\u00c9 poss\u00edvel um cen\u00e1rio de aumento de press\u00f5es vindas das grandes pot\u00eancias capitalistas \u2013 fiadoras dos governos israelenses, pol\u00edtica e financeiramente por muitos anos &#8211; pela suspens\u00e3o das incurs\u00f5es militares em Gaza, mas isso \u00e9 uma possibilidade que n\u00e3o necessariamente resultar\u00e1 em um cessar-fogo imediato, tampouco na suspens\u00e3o de viola\u00e7\u00f5es e muito menos significa o fim eminente do sionismo como regime de governo. Mesmo que Netanyahu venha a cair nos pr\u00f3ximos meses, isso n\u00e3o significa necessariamente uma mudan\u00e7a radical nos rumos da pol\u00edtica de estado de Israel em rela\u00e7\u00e3o \u00e0s ocupa\u00e7\u00f5es sionistas em terras palestinas, tampouco a liberta\u00e7\u00e3o dos mais de 3000 presos pol\u00edticos palestinos, enclausurados nas masmorras israelenses. At\u00e9 porque j\u00e1 assistimos a composi\u00e7\u00f5es partid\u00e1rias que assumiram o governo israelense e que n\u00e3o defendiam em seus programas de governo certas pr\u00e1ticas sionistas, mas mantiveram de forma latente o colonialismo, a repress\u00e3o e a arbitrariedade na Palestina ocupada.<\/p>\n<p>A possibilidade mais prov\u00e1vel, tendo em vista as recentes declara\u00e7\u00f5es do Ministro da Defesa, \u00e9 a de que o Governo israelense n\u00e3o pretende recuar e jamais suspender seu intento de destruir a Faixa de Gaza por completo e isso fica ainda mais evidente com o cerco \u00e0 cidade de Rafah ao sul de Gaza, \u00faltimo ref\u00fagio de centenas de milhares de palestinos que perderam absolutamente tudo ao norte de Gaza. Essa amea\u00e7a eminente de uma carnificina ainda mais sangrenta e desumana com os poss\u00edveis ataques em Rafah n\u00e3o pode ser desconsiderada pela moment\u00e2nea retirada das tropas sionistas da cidade de Khan Yunis e o crescente isolamento internacional do governo israelense.<\/p>\n<p>Uma prova de quanto o sionismo est\u00e1 disposto a alimentar a instabilidade regional como elemento para se auto-justificar internamente, disputar a opini\u00e3o p\u00fablica israelense e o apoio internacional foi o recente atentado terrorista promovido pelas For\u00e7as de Defesa Israelense, com o apoio log\u00edstico da Mossad (Ag\u00eancia de Intelig\u00eancia e Opera\u00e7\u00f5es Especiais israelense) \u00e0 embaixada da Rep\u00fablica do Ir\u00e3 em Damasco na S\u00edria, no \u00faltimo dia 02 de abril, deixando 13 pessoas mortas e dezenas feridas. Isso tudo nos imp\u00f5e a consci\u00eancia da possibilidade de que as incurs\u00f5es militares de Israel na Faixa de Gaza ainda est\u00e3o longe de acabar &#8211; mesmo com todo o desgaste pol\u00edtico e militar de Israel &#8211; assim como \u00e9 poss\u00edvel que haja uma escalada ainda maior de ataques milicianos na Cisjord\u00e2nia ocupada e outros atos de terrorismo de Estado contra pa\u00edses \u00e1rabes. Esses atos de terrorismo de Estado funcionam como t\u00e1ticas de provoca\u00e7\u00e3o pol\u00edtica para ampliar a instabilidade regional e justificar assim novos ataques militares, procurando retirar, dessa forma, os holofotes dos desgastes e das rea\u00e7\u00f5es contr\u00e1rias que o governo sionista de Benjamin Netanyahu vem acumulando.<\/p>\n<p>Desta forma se faz necess\u00e1rio ainda mais empenho, compromisso e diversifica\u00e7\u00e3o nas a\u00e7\u00f5es de massa que os Comit\u00eas de Solidariedade \u00e0 Palestina devem desempenhar, no sentido de ampliar a den\u00fancia sobre o genoc\u00eddio em curso e aumentar a press\u00e3o pol\u00edtica sobre o governo Lula, para que se rompam todas as rela\u00e7\u00f5es institucionais entre os dois pa\u00edses como forma de aumentar a press\u00e3o internacional contra o holocausto vivenciado pelo povo palestino.<\/p>\n<p>A resist\u00eancia palestina a d\u00e9cadas de humilha\u00e7\u00e3o, usurpa\u00e7\u00e3o criminosa de seu territ\u00f3rio, massacres e todas as formas de desrespeito e tentativa de subjuga\u00e7\u00e3o \u00e9 com certeza um dos maiores exemplos hist\u00f3ricos de resili\u00eancia moral e persist\u00eancia pol\u00edtica de um povo que n\u00e3o se deixa sujeitar pela for\u00e7a invasora, n\u00e3o se curva ao jugo do colonialismo e que mant\u00e9m viva a chama da rebeldia e da esperan\u00e7a daqueles que lutam pelo direito de viverem livres e com dignidade em suas terras. Por tudo isso \u00e9 fundamental o fortalecimento dos Comit\u00eas de Solidariedade \u00e0 Palestina, sua amplia\u00e7\u00e3o em todo o pa\u00eds e a possibilidade de constru\u00e7\u00e3o de espa\u00e7os comuns onde possamos trocar experi\u00eancias, informa\u00e7\u00f5es, avalia\u00e7\u00f5es e a promo\u00e7\u00e3o de campanhas unificadas que possam ampliar nossa atua\u00e7\u00e3o junto \u00e0 popula\u00e7\u00e3o brasileira e aumentar nossa for\u00e7a pol\u00edtica em defesa do povo palestino nos somando a esse amplo movimento internacional de solidariedade.<\/p>\n<p>\u00c9 a esse povo de luta, assim como a tantos outros povos que travaram lutas de liberta\u00e7\u00e3o nacional contra o jugo da domina\u00e7\u00e3o estrangeira \u00e9 que rendemos nossa homenagem e a total e incondicional solidariedade, que deve ser um instrumento de conscientiza\u00e7\u00e3o de nosso povo sobre a import\u00e2ncia da resist\u00eancia ao autoritarismo e a tudo aquilo que nos oprime, nos explora e tenta nos destruir como classe.<\/p>\n<p>Em tempo, ao fechar a reda\u00e7\u00e3o desse texto, tomei ci\u00eancia de que o combatente da Frente Popular para a Liberta\u00e7\u00e3o da Palestina (FPLP), Walid Daqqa, 62 anos, que estava preso desde 1986 e estava com seu nome cotado em uma lista de liberta\u00e7\u00e3o de presos firmada h\u00e1 mais de um ano entre o governo israelense e a Autoridade Nacional Palestina, por motivos de gravidade nas condi\u00e7\u00f5es de sa\u00fade, faleceu neste domingo, dia 07 de abril, devido ao abandono da administra\u00e7\u00e3o prisional e \u00e0 falta de assist\u00eancia m\u00e9dica necess\u00e1ria ao quadro de agravamento de seu estado cl\u00ednico, que foi se deteriorando ao longo dos anos, submetido aos maus tratos e torturas diversas.<br \/>\nAo longo de seus 38 anos de pris\u00e3o, Daqqa produziu dezenas de livros, estudos e artigos sobre a Resist\u00eancia Palestina e as atrocidades \u00e0s quais os presos pol\u00edticos eram submetidos nas pris\u00f5es israelenses.<\/p>\n<p>Camarada Walid Daqqa Presente!<br \/>\nAgora e Sempre!<\/p>\n<p><strong>Palestina Livre do Rio ao Mar!<\/strong><\/p>\n<p>F\u00e1bio Bezerra \u00e9 professor de Filosofia, membro do CC do PCB e do Comit\u00ea Mineiro de Solidariedade ao Povo Palestino<\/p>\n","protected":false},"excerpt":{"rendered":"<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/31556\"> <\/a>","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[181,65,9,75,146,255,10,78],"tags":[225],"class_list":["post-31556","post","type-post","status-publish","format-standard","hentry","category-asia","category-c78-internacional","category-s10-internacional","category-c88-internacionalismo","category-internacionalismo","category-israel","category-s19-opiniao","category-c91-solidariedade-a-palestina","tag-4a"],"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p659gw-8cY","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/31556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=31556"}],"version-history":[{"count":1,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/31556\/revisions"}],"predecessor-version":[{"id":31558,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/31556\/revisions\/31558"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=31556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=31556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=31556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}