{"id":33196,"date":"2025-10-03T15:36:43","date_gmt":"2025-10-03T18:36:43","guid":{"rendered":"https:\/\/pcb.org.br\/portal2\/?p=33196"},"modified":"2025-10-03T16:24:34","modified_gmt":"2025-10-03T19:24:34","slug":"declaracao-do-partido-comunista-de-israel-3","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/33196","title":{"rendered":"Declara\u00e7\u00e3o do Partido Comunista de Israel"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"33197\" data-permalink=\"https:\/\/pcb.org.br\/portal2\/33196\/attachment\/1000074348\" data-orig-file=\"https:\/\/i0.wp.com\/pcb.org.br\/portal2\/wp-content\/uploads\/2025\/10\/1000074348.png?fit=1280%2C1216&amp;ssl=1\" data-orig-size=\"1280,1216\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1000074348\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/pcb.org.br\/portal2\/wp-content\/uploads\/2025\/10\/1000074348.png?fit=747%2C710&amp;ssl=1\" class=\"alignnone wp-image-33197 size-medium\" src=\"https:\/\/i0.wp.com\/pcb.org.br\/portal2\/wp-content\/uploads\/2025\/10\/1000074348.png?resize=300%2C285&#038;ssl=1\" alt=\"\" width=\"300\" height=\"285\" srcset=\"https:\/\/i0.wp.com\/pcb.org.br\/portal2\/wp-content\/uploads\/2025\/10\/1000074348.png?resize=300%2C285&amp;ssl=1 300w, https:\/\/i0.wp.com\/pcb.org.br\/portal2\/wp-content\/uploads\/2025\/10\/1000074348.png?resize=900%2C855&amp;ssl=1 900w, https:\/\/i0.wp.com\/pcb.org.br\/portal2\/wp-content\/uploads\/2025\/10\/1000074348.png?resize=768%2C730&amp;ssl=1 768w, https:\/\/i0.wp.com\/pcb.org.br\/portal2\/wp-content\/uploads\/2025\/10\/1000074348.png?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><!--more--><\/p>\n<p>O Partido Comunista de Israel (CPI) e o Hadash exigem urgentemente o fim imediato da guerra genocida contra o povo palestino<\/p>\n<p>Isso inclui interromper a destrui\u00e7\u00e3o da Faixa de Gaza \u2014 suas cidades, vilas e campos de refugiados \u2014, bem como findar a anexa\u00e7\u00e3o, a expans\u00e3o de assentamentos e as deporta\u00e7\u00f5es for\u00e7adas na Cisjord\u00e2nia ocupada. Cada minuto que passa deste conflito em curso resulta em mais massacres e deslocamentos, que devem cessar sem demora.<\/p>\n<p>O chamado &#8220;plano Trump&#8221; para p\u00f4r fim \u00e0 guerra em Gaza \u00e9 uma iniciativa perigosa, liderada pelos EUA e coordenada com o agressor. Est\u00e1 repleto de armadilhas pol\u00edticas e n\u00e3o apresenta um cronograma claro para a retirada de Gaza, revelando seu verdadeiro objetivo: fortalecer e prolongar a ocupa\u00e7\u00e3o. Este plano sequestra a soberania pol\u00edtica palestina, amea\u00e7ando estender as a\u00e7\u00f5es de ocupa\u00e7\u00e3o para al\u00e9m de Gaza, a todos os territ\u00f3rios palestinos, especialmente a Cisjord\u00e2nia. Desconsidera os crimes di\u00e1rios cometidos pela ocupa\u00e7\u00e3o e suas mil\u00edcias, obstruindo o caminho rumo a um Estado palestino \u2014 um direito reconhecido por 80% dos pa\u00edses do mundo, habitados por 90% da popula\u00e7\u00e3o mundial.<\/p>\n<p>O plano prev\u00ea a imposi\u00e7\u00e3o de uma administra\u00e7\u00e3o civil e pol\u00edtica sobre Gaza, liderada por figuras alinhadas \u00e0 ocupa\u00e7\u00e3o, como o pr\u00f3prio Trump e Tony Blair, conhecidos agentes dos interesses imperialistas na regi\u00e3o. O atual governo de direita dos colonos em Israel lidera esta guerra com quase nenhuma oposi\u00e7\u00e3o parlamentar, avan\u00e7ando implacavelmente com sua agenda destrutiva. Nesse contexto, o PCI, o Hadash e seus aliados mant\u00eam-se firmes na oposi\u00e7\u00e3o, resistindo corajosamente \u00e0 guerra genocida contra o povo palestino e a todas as formas de opress\u00e3o enfrentadas pelos palestinos em Israel e pelas for\u00e7as democr\u00e1ticas judaicas.<\/p>\n<p>Neste momento cr\u00edtico, a maior prioridade \u00e9 o fim imediato da guerra, da fome e da deporta\u00e7\u00e3o. A ajuda humanit\u00e1ria deve fluir sem obst\u00e1culos, e os prisioneiros de ambos os lados devem ser libertados imediatamente como parte de um acordo de paz abrangente para p\u00f4r fim a este conflito.<\/p>\n<p>Este momento perigoso exige uma posi\u00e7\u00e3o palestina unida, inabal\u00e1vel diante dos planos concebidos para minar seu direito \u00e0 autogovernan\u00e7a, \u00e0 autodetermina\u00e7\u00e3o e ao estabelecimento de um Estado palestino independente. Apesar das amea\u00e7as constantes, acreditamos firmemente na derrota inevit\u00e1vel da ocupa\u00e7\u00e3o e no triunfo final da justa causa do povo palestino.<\/p>\n<p>Haifa, 1\u00ba de outubro de 2025<\/p>\n","protected":false},"excerpt":{"rendered":"<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/33196\"> <\/a>","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[233],"class_list":["post-33196","post","type-post","status-publish","format-standard","hentry","category-geral","tag-6a"],"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p659gw-8Dq","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/33196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=33196"}],"version-history":[{"count":1,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/33196\/revisions"}],"predecessor-version":[{"id":33198,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/33196\/revisions\/33198"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=33196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=33196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=33196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}