{"id":3878,"date":"2012-11-20T22:10:58","date_gmt":"2012-11-20T22:10:58","guid":{"rendered":"http:\/\/pcb.org.br\/portal2\/?p=3878"},"modified":"2012-11-20T22:10:58","modified_gmt":"2012-11-20T22:10:58","slug":"ato-de-solidariedade-com-o-povo-colombiano","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/3878","title":{"rendered":"ATO DE SOLIDARIEDADE COM O POVO COLOMBIANO"},"content":{"rendered":"\n<p style=\"text-align: right;\">Che<\/p>\n<p>Representantes de diversas organiza\u00e7\u00f5es sociais, partidos pol\u00edticos, movimentos populares e pessoas brasileiras e colombianas num ato de solidariedade com o povo colombiano e sua luta pela paz, se reuniram o passado 7 de Novembro frente do Consulado de Col\u00f4mbia na cidade de S\u00e3o Paulo. Com o firme prop\u00f3sito de entregar o Manifesto em solidariedade a Piedad C\u00f3rdoba e \u00e0 Marcha Patri\u00f3tica, assinado por um amplo grupo de for\u00e7as sociais, pol\u00edticas e culturais do Brasil, o qual tem como principal consigna respaldar a busca de uma solu\u00e7\u00e3o pol\u00edtica ao conflito e se solidarizar com o povo colombiano em sua luta por ampliar a democracia e conquistar garantias pol\u00edticas e sociais.<\/p>\n<p>Infelizmente esse dia n\u00e3o foi poss\u00edvel o atendimento por parte do Consulado, no entanto, se persistiu no prop\u00f3sito e o dia 9 de Novembro uma comiss\u00e3o composta por brasileiros e colombianos foram atendidos pelo c\u00f4nsul de Col\u00f4mbia em S\u00e3o Paulo, Edwin Ostos Alfonso\u00a0e mais dois funcion\u00e1rios diplom\u00e1ticos do consulado.\u00a0 Neste espa\u00e7o se fez leitura do manifesto e se exorto ao governo colombiano a garantir a participa\u00e7\u00e3o da oposi\u00e7\u00e3o pol\u00edtica. Resalto se parte do manifesto que diz:<\/p>\n<p>\u201cAfirmamos com clareza que se devem respeitar e apoiar todos os esfor\u00e7os democratizadores e participativos que permitam consolidar Am\u00e9rica Latina como um territ\u00f3rio de paz. Diante do exposto, exortamos o governo colombiano a restabelecer os direitos pol\u00edticos da l\u00edder Piedad C\u00f3rdoba; que se garanta a vida de todos e todas integrantes do movimento Marcha Patri\u00f3tica e se lhe outorguem as condi\u00e7\u00f5es necess\u00e1rias para o exerc\u00edcio da oposi\u00e7\u00e3o pol\u00edtica. Comprometemo-nos a estar atenciosos para evitar qualquer atentado contra os direitos \u00e0 vida e a participa\u00e7\u00e3o deste movimento pol\u00edtico e da sociedade colombiana em geral\u201d.<\/p>\n<p>Este ato foi sem duvida uma mostra de solidariedade do povo brasileiro e suas diversas organiza\u00e7\u00f5es sociais, a solidariedade se fez palp\u00e1vel transcendendo a ret\u00f3rica e derrubando as barreiras com as que historicamente nos tentam dividir, com este ato acrescentamos o grito pelo fim das injusti\u00e7as, da persecu\u00e7\u00e3o ao pensamento cr\u00edtico na Col\u00f4mbia; grito pela vida, a democracia e a paz com justi\u00e7a social em procura de um continente americano unido, democr\u00e1tico, justo e soberano.<\/p>\n<p>Agenda Col\u00f4mbia &#8211; Brasil<\/p>\n","protected":false},"excerpt":{"rendered":"\n\n\nPCB\n\n\n\n\n\n\n\n\n\u201cA solidariedade \u00e9 a ternura dos povos\u201d\n<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/3878\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[34],"tags":[],"class_list":["post-3878","post","type-post","status-publish","format-standard","hentry","category-c39-colombia"],"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p659gw-10y","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/3878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=3878"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/3878\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=3878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=3878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=3878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}