{"id":3892,"date":"2012-11-22T17:41:23","date_gmt":"2012-11-22T17:41:23","guid":{"rendered":"http:\/\/pcb.org.br\/portal2\/?p=3892"},"modified":"2012-11-22T17:41:23","modified_gmt":"2012-11-22T17:41:23","slug":"salve-o-dia-da-consciencia-negra","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/3892","title":{"rendered":"Salve o Dia da Consci\u00eancia Negra!"},"content":{"rendered":"\n<p>O comprometimento de nosso partido para com as lutas pela valoriza\u00e7\u00e3o do negro brasileiro vem de longa data. J\u00e1 em julho de 1930 denunci\u00e1vamos a persist\u00eancia de elementos de escravid\u00e3o na situa\u00e7\u00e3o real experimentada pelos negros do pa\u00eds, n\u00e3o obstante a t\u00e3o propalada Aboli\u00e7\u00e3o da Escravatura. Neste mesmo ano, nas elei\u00e7\u00f5es presidenciais, apresentamos ao povo a candidatura de Minervino de Oliveira (foto), militante de nosso partido, que se tornou ent\u00e3o o primeiro negro e o primeiro oper\u00e1rio a disputar a presid\u00eancia da rep\u00fablica.<\/p>\n<p>Em nossa Primeira Confer\u00eancia Nacional de julho de 1934, realizada na mesma \u00e9poca em que se iniciava a propaga\u00e7\u00e3o da tese da \u201cdemocracia racial brasileira\u201d, denunci\u00e1vamos o racismo das classes dominantes e nos compromet\u00edamos a apoiar todas as lutas pela igualdade de direitos econ\u00f4micos, pol\u00edticos e sociais de negros e \u00edndios.<\/p>\n<p>Ainda em meados da d\u00e9cada de 30, o intelectual comunista baiano Edison Carneiro iniciava uma vasta e significativa obra de investiga\u00e7\u00e3o e resgate da cultura afro-brasileira, tornando-se um dos pioneiros em tal campo de estudos e uma refer\u00eancia fundamental at\u00e9 os dias de hoje. Este mesmo Edison Carneiro, com o apoio de outros intelectuais comunistas como Jorge Amado e Aydano do Couto Ferraz, criava, no ano de 1937, a Uni\u00e3o de Seitas Afro-Brasileiras, a primeira entidade criada no pa\u00eds com o objetivo de proteger e cultivar os valores e as tradi\u00e7\u00f5es religiosas de matriz africana.<\/p>\n<p>Na d\u00e9cada de 1940, o PCB solidificou seu engajamento na luta contra o racismo e em defesa da cultura afro-brasileira. Sob sua legenda elegeu-se, em 1945, Claudino Jos\u00e9 da Silva, primeiro negro a exercer mandato parlamentar e primeiro constituinte negro da hist\u00f3ria do Brasil. Durante os trabalhos da Assembl\u00e9ia Nacional Constituinte de 1946, coube ao escritor e deputado comunista Jorge Amado a elabora\u00e7\u00e3o do projeto da primeira lei federal que estabeleceu a liberdade para a pr\u00e1tica das religi\u00f5es afro-brasileiras. Este per\u00edodo registra tamb\u00e9m a cria\u00e7\u00e3o do Teatro Experimental do Negro, que tem como um de seus principais expoentes o ator, poeta e teatr\u00f3logo comunista Francisco Solano Trindade, que marcaria com sua atividade intensa a arte popular brasileira das d\u00e9cadas seguintes. Alguns anos mais tarde, apareceram os primeiros trabalhos de Cl\u00f3vis Moura, ent\u00e3o vinculado ao PCB, cuja produ\u00e7\u00e3o aportaria uma importante contribui\u00e7\u00e3o aos estudos hist\u00f3ricos e sociol\u00f3gicos sobre o negro no Brasil.<\/p>\n<p>Se no passado n\u00f3s comunistas estivemos presentes em praticamente todos os momentos relevantes da trajet\u00f3ria do povo negro brasileiro, no presente continuamos a apoiar e nos envolver com essas lutas. Apoiamos as reivindica\u00e7\u00f5es imediatas e conquistas parciais do movimento negro como a titula\u00e7\u00e3o das terras das comunidades remanescentes de quilombos e o Estatuto da Igualdade Racial. No entanto, compreendemos que nenhuma destas conquistas estar\u00e1 assegurada no futuro enquanto perdurarem: a) o esvaziamento e sucateamento das universidades p\u00fablicas, a privatiza\u00e7\u00e3o e a mercantiliza\u00e7\u00e3o do ensino; b) o controle do Estado pelos grandes propriet\u00e1rios fundi\u00e1rios e a subordina\u00e7\u00e3o da pol\u00edtica agr\u00e1ria do governo aos interesses do agro-neg\u00f3cio; c) a hegemonia dos interesses do grande capital nacional e internacional no interior da sociedade brasileira e a subordina\u00e7\u00e3o das necessidades do povo \u00e0 l\u00f3gica da acumula\u00e7\u00e3o capitalista.<\/p>\n<p>Para que as atuais conquistas sejam mantidas e aprofundadas e para que novas sejam alcan\u00e7adas \u00e9 essencial que as lutas do povo negro, sem prescindir de sua especificidade, estejam combinadas \u00e0s lutas gerais do povo e dos trabalhadores brasileiros. \u00c9 necess\u00e1rio somar esfor\u00e7os aos movimentos em defesa de uma universidade p\u00fablica gratuita e de qualidade, voltada para a resolu\u00e7\u00e3o dos problemas nacionais e para a promo\u00e7\u00e3o social das classes populares, apoiar as a\u00e7\u00f5es contra o monop\u00f3lio da propriedade da terra pelos grupos latifundi\u00e1rios e por uma reforma agr\u00e1ria ampla e radical, mobilizar-se enfim, por um poder pol\u00edtico que seja a encarna\u00e7\u00e3o da vontade de negros e negras, trabalhadores das cidades e dos campos, pequenos propriet\u00e1rios urbanos e rurais, artistas e intelectuais avan\u00e7ados.<\/p>\n<p><strong>Salve o Dia da Consci\u00eancia Negra!<\/strong><\/p>\n<p>Leia mais:\u00a0<a href=\"http:\/\/www.pcb-baixadasantista.net\/news\/sauda%c3%a7%c3%a3o-ao-povo-negro\/?utm_source=copy&amp;utm_medium=paste&amp;utm_campaign=copypaste&amp;utm_content=http%3A%2F%2Fwww.pcb-baixadasantista.net%2Fnews%2Fsauda%25c3%25a7%25c3%25a3o-ao-povo-negro%2F\" target=\"_blank\"><\/a><a href=\"http:\/\/www.pcb-baixadasantista.net\/news\/sauda%c3%a7%c3%a3o-ao-povo-negro\/\" target=\"_blank\">http:\/\/www.pcb-baixadasantista.net\/news\/sauda%c3%a7%c3%a3o-ao-povo-negro\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"\n\n\nPCB\n\n\n\n\n\n\n\n\nFelipe Queiroz\n<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/3892\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[46],"tags":[],"class_list":["post-3892","post","type-post","status-publish","format-standard","hentry","category-c56-memoria"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-10M","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/3892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=3892"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/3892\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=3892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=3892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=3892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}