{"id":4071,"date":"2012-12-22T00:05:38","date_gmt":"2012-12-22T00:05:38","guid":{"rendered":"http:\/\/pcb.org.br\/portal2\/?p=4071"},"modified":"2012-12-22T00:05:38","modified_gmt":"2012-12-22T00:05:38","slug":"90-anos-do-pcb-e-sua-historia-de-luta-em-goias","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/4071","title":{"rendered":"90 ANOS DO PCB E SUA HIST\u00d3RIA DE LUTA EM GOI\u00c1S"},"content":{"rendered":"\n<p>Ferreira Gullar, nas comemora\u00e7\u00f5es dos 60 anos do PCB, escreve de forma po\u00e9tica e certeira: \u201cO PCB n\u00e3o se tornou o maior partido do Ocidente, nem mesmo do Brasil. Mas quem contar a hist\u00f3ria de nosso povo e seus her\u00f3is tem que falar dele. Ou estar\u00e1 mentindo.\u201d<\/p>\n<p>Fundado em 25 de mar\u00e7o de 1922, o Partido Comunista Brasileiro (PCB) est\u00e1 completando 90 anos de exist\u00eancia. 90 anos carregados de erros e acertos na luta pela Revolu\u00e7\u00e3o Socialista.<\/p>\n<p>A nossa hist\u00f3ria, \u00e9 a hist\u00f3ria da Classe Trabalhadora, que na d\u00e9cada de 20 v\u00ea como necess\u00e1ria a constru\u00e7\u00e3o de um instrumento pol\u00edtico capaz de conduzir os trabalhadores para al\u00e9m das reinvindica\u00e7\u00f5es econ\u00f4micas e pontuais. Esta necessidade, n\u00e3o s\u00f3 se tornou real, mas foi alvo da cassada incessante da burguesia: ficamos mais da metade da nossa exist\u00eancia de forma clandestina. Nos anos 30 e 40, nos consolidamos enquanto alternativa \u00e0 ordem vigente, dando conta de criar uma cultura socialista no pais. Com a divulga\u00e7\u00e3o do Manifesto Comunista\u00a0e da distribui\u00e7\u00e3o do jornal\u00a0A Classe Oper\u00e1ria, difundimos as teses do marxismo-leninismo. Em 35, fizemos uma insurrei\u00e7\u00e3o armada, que foi duramente reprimida. Nas d\u00e9cadas de 50 e 60, nos iludimos com a burguesia nacional, compondo alian\u00e7as que mais tarde se reverteu num refluxo significativo para os comunistas e trabalhadores: a ditadura empresarial-militar.<\/p>\n<p>Com a crise na URSS nas d\u00e9cadas de 70 e 80, grupos majorit\u00e1rios no PCB levam a incessantes cis\u00f5es. As duas principais delas foram a de 1962, criando o PCdoB e a de 1992, criando o PPS. Rompimentos reformistas estes, que causaram graves sequelas nos comunistas.<\/p>\n<p>Sabendo da necessidade de reorganizar o instrumento revolucion\u00e1rio dos trabalhadores e acima de tudo, a tarefa militante de construir o socialismo, o PCB se reorganiza em todo o Pais. Reorganiza-se n\u00e3o numa perspectiva reformista, eleitoreira ou com concilia\u00e7\u00e3o de classes. Mas se reorganiza em bases revolucion\u00e1rias, apontando como \u00fanica sa\u00edda para por fim as mazelas da humanidade a constitui\u00e7\u00e3o da sociedade comunista. Mantemos nossa tradi\u00e7\u00e3o marxista-leninista, com a qual nos conduz em \u201can\u00e1lises concretas da realidade concreta\u201d como diria nosso Camarada Prestes.<\/p>\n<p>Em Goi\u00e1s, al\u00e9m das comemora\u00e7\u00f5es dos 90 anos do PCB, festejamos tamb\u00e9m os 12 anos de reorganiza\u00e7\u00e3o do Partido Comunista Brasileiro em Goi\u00e1s. Fruto deste recente momento hist\u00f3rico em que vive o PCB estamos recrutando militantes em solos goianos que lutam cotidianamente contra os patr\u00f5es. Dos anos 30 e 40, quando da primeira organiza\u00e7\u00e3o do PCB em Goi\u00e1s no eixo-urbano Goiandira e Catal\u00e3o, por influencia da cria\u00e7\u00e3o da ANL (Alian\u00e7a Nacional Libertadora), fizemos parte da hist\u00f3ria pol\u00edtica do Estado de Goi\u00e1s com:<\/p>\n<p>&#8211; a funda\u00e7\u00e3o do ent\u00e3o maior sindicato de trabalhadores em Goi\u00e1s, o Sindicato dos Trabalhadores da Constru\u00e7\u00e3o Civil de An\u00e1polis na d\u00e9cada de 40;<\/p>\n<p>&#8211; as lutas pela Reforma Agr\u00e1ria culminando na organiza\u00e7\u00e3o de resist\u00eancia de Trombas e Formoso (1950 a 1964) e a cria\u00e7\u00e3o da ULTAB (Uni\u00e3o dos Lavradores e Trabalhadores Agr\u00edcolas do Brasil) com os Camaradas Jos\u00e9 Porf\u00edrio, Geraldo Tib\u00farcio, Jos\u00e9 Sobrinho;<\/p>\n<p>&#8211; a edi\u00e7\u00e3o do Jornal \u201cA Voz Camponesa\u201d instrumento de contra-hegemonia e forma\u00e7\u00e3o dos trabalhadores do campo em Goi\u00e1s, dirigida por Jos\u00e9 Basilio;<\/p>\n<p>&#8211; a organiza\u00e7\u00e3o da Uni\u00e3o da Juventude Comunista por Tabajara Santana, organizando a juventude nas escolas e posteriormente a UJC enraizada na UFG nas d\u00e9cadas de 50 e 60;<\/p>\n<p>&#8211; a luta pela redemocratiza\u00e7\u00e3o do pais, tendo a frente os Camarada Horiestes Gomes, Carlos, Seu Alaor, Davi, Sergio, Basileu Pires, Bernardo Elis, que constru\u00edram ferramentas de propaganda, agita\u00e7\u00e3o e forma\u00e7\u00e3o aos trabalhadores como o CEB (Centro de Estudos Brasileiros, instalado na UFG e destru\u00eddo pelos militares), CEFEG (Centro de Estudos Filos\u00f3ficos e Econ\u00f4micos e de Goi\u00e1s) e o Instituto Cultural Brasil-URSS, principalmente nas d\u00e9cadas de 70.<\/p>\n<p>Estes foram momentos que n\u00e3o s\u00f3 configurou o per\u00edodo nacionalmente e regionalmente, mas que mostra o potencial de organiza\u00e7\u00e3o da Classe Trabalhadora, que diferentemente do que vem se publicando, n\u00e3o se perdeu.<\/p>\n<p>Em nossos tempos, o PCB em Goi\u00e1s est\u00e1 inserido nas lutas cotidianos da juventude e dos trabalhadores. As greves no campo da educa\u00e7\u00e3o, a milit\u00e2ncia estudantil na UFG e UEG, entre os trabalhadores do transporte coletivo, a luta pela moradia, s\u00e3o exemplos de que a luta pelo socialismo, na perspectiva do comunismo n\u00e3o morreu. Como escreve Gonzaguinha: \u201cSe muito vale o j\u00e1 feito, Mais vale o que ser\u00e1\u201d.<\/p>\n<p>Dire\u00e7\u00e3o Estadual do PCB em Goi\u00e1s.<\/p>\n","protected":false},"excerpt":{"rendered":"\n\n\nPCB\n\n\n\n\n\n\n\n\n<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/4071\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[46],"tags":[],"class_list":["post-4071","post","type-post","status-publish","format-standard","hentry","category-c56-memoria"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-13F","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/4071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=4071"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/4071\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=4071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=4071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=4071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}