{"id":490,"date":"2010-05-24T21:58:55","date_gmt":"2010-05-24T21:58:55","guid":{"rendered":"http:\/\/pcb.org.br\/portal2\/?p=490"},"modified":"2010-05-24T21:58:55","modified_gmt":"2010-05-24T21:58:55","slug":"pcpe-converter-a-jornada-de-8-de-junho-em-uma-reclamacao-generalizada-de-greve-geral","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/490","title":{"rendered":"PCPE: CONVERTER A JORNADA DE 8 DE JUNHO EM UMA RECLAMA\u00c7\u00c3O GENERALIZADA DE GREVE GERAL"},"content":{"rendered":"\n<p><strong>CONVOCAT\u00d3RIA DO COMIT\u00ca EXECUTIVO DO PCPE PARA CONVERTER A JORNADA DE 8 DE JUNHO EM UMA RECLAMA\u00c7\u00c3O GENERALIZADA DE GREVE GERAL CONTRA AS POL\u00cdTICAS DO GOVERNO E CONTRA O CAPITALISMO<\/strong><\/p>\n<p>O Comit\u00ea Executivo do PCPE chama toda a classe trabalhadora para converter a jornada de greve, convocada pelos sindicatos do funcionalismo p\u00fablico, do dia 8 de junho, numa grande jornada de luta contra a gest\u00e3o que o governo realiza frente a crise capitalista, cujas consequ\u00eancias recaem sobre o povo trabalhador.<\/p>\n<p>Por\u00e9m, as medidas tomadas pelo governo requerem uma resposta mais contundente por parte das organiza\u00e7\u00f5es trabalhistas e populares. N\u00e3o \u00e9 somente o governo quem tem responsabilidade nesta situa\u00e7\u00e3o. \u00c9 o projeto imperialista da UE quem est\u00e1 por tr\u00e1s de toda esta estrat\u00e9gia da oligarquia. \u00c9 do projeto da UE que compartilham todas as for\u00e7as do arco parlamentar espanhol.<\/p>\n<p>N\u00e3o s\u00e3o somente as mencionadas medidas que afetam diretamente os trabalhadores e as trabalhadoras. Os banqueiros e o patronato aplaudem tais medidas, j\u00e1 que favorecem seus interesses diretos e que v\u00e3o na linha da contra-reforma trabalhista que o governo anuncia como iminente, mostrando, mais uma vez, que o peso mais brutal da crise capitalista ur\u00e1 recair sobre os trabalhadores e trabalhadoras.<\/p>\n<p>O Comit\u00ea Executivo do PCPE convida o conjunto da classe trabalhadora para somar-se a esta jornada de greve do dia 8 de junho. Os comit\u00eas de empresas de todos os centros de trabalho, assim como os sindicatos setoriais, devem discutir esta situa\u00e7\u00e3o e participar desse dia, de suas mobiliza\u00e7\u00f5es, impondo, na pr\u00e1tica, a din\u00e2mica da greve geral. O objetivo deve ser o de ampliar, o m\u00e1ximo poss\u00edvel, esta jornada de luta.<\/p>\n<p>O Comit\u00ea Executivo do PCPE conclama toda a classe trabalhadora para somar-se \u00e0s manifesta\u00e7\u00f5es que se realizar\u00e3o no dia 8 de junho, para tratar de que estas sejam as mais massivas poss\u00edvel e, para que nelas, o clamor da convocat\u00f3ria da greve geral se imponha \u2013 no menor prazo poss\u00edvel \u2013 sobre as dire\u00e7\u00f5es sindicais que pretendam parar esta convocat\u00f3ria de luta geral.<\/p>\n<p>O Comit\u00ea Executivo do PCPE conclama as for\u00e7as revolucion\u00e1rias e populares para constituir uma grande frente unit\u00e1ria contra a crise capitalista, colocando a convocat\u00f3ria de uma greve geral contra este governo, contra a UE, e contra o capitalismo, como eixo de seu trabalho pol\u00edtico imediato.<\/p>\n<p>O Comit\u00ea Executivo do PCPE chama toda a classe trabalhadora para fazer da jornada de 8 de junho o in\u00edcio da resposta trabalhadora contra a oligarquia e seus governos. Um ponto de inflex\u00e3o necess\u00e1rio para que sejam os interesses trabalhadores e populares que protagonizem as pol\u00edticas para enfrentas a crise capitalista geral.<\/p>\n<p align=\"justify\">Tradu\u00e7\u00e3o: Maria Fernanda M. Scelza<\/p>\n","protected":false},"excerpt":{"rendered":"\n\n\nCr\u00e9dito: PCPE\n\n\n\n\nMadrid, 16 de maio de 2010.\n<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/490\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[71],"tags":[],"class_list":["post-490","post","type-post","status-publish","format-standard","hentry","category-c84-solidariedade"],"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p659gw-7U","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=490"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/490\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=490"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=490"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}