{"id":5014,"date":"2013-06-25T20:03:44","date_gmt":"2013-06-25T20:03:44","guid":{"rendered":"http:\/\/pcb.org.br\/portal2\/?p=5014"},"modified":"2013-06-25T20:03:44","modified_gmt":"2013-06-25T20:03:44","slug":"nao-e-so-por-vinte-centavos-e-pela-desmilitarizacao-das-policias-pelo-fim-da-violencia-policial","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/5014","title":{"rendered":"N\u00e3o \u00e9 s\u00f3 por vinte centavos, \u00e9 pela desmilitariza\u00e7\u00e3o das pol\u00edcias, pelo fim da viol\u00eancia policial!"},"content":{"rendered":"\n<p>As a\u00e7\u00f5es violentas e arbitr\u00e1rias das pol\u00edcias nas favelas e periferias do Brasil sistematicamente denunciadas pela Justi\u00e7a Global est\u00e3o sendo postas em pr\u00e1tica tamb\u00e9m nos protestos pela redu\u00e7\u00e3o da passagem. A pol\u00edcia que reprime as manifesta\u00e7\u00f5es \u00e9 a mesma que executa pessoas nas favelas e periferias e a mesma que implanta nos morros as Unidades de Pol\u00edcia Pacificadora (UPP&#8217;s).<\/p>\n<p>A viol\u00eancia policial \u00e9 certamente um dos principais problemas a ser enfrentado pelo Brasil. A persist\u00eancia da tortura, o encarceramento massivo de pessoas e, principalmente, as execu\u00e7\u00f5es extrajudiciais cometidas sistematicamente por agentes do estado conformam um quadro preocupante em rela\u00e7\u00e3o \u00e0 seguran\u00e7a p\u00fablica e \u00e0 garantia da cidadania b\u00e1sica, em especial para a popula\u00e7\u00e3o negra e pobre. A desmilitariza\u00e7\u00e3o das pol\u00edcias \u00e9 um passo fundamental para a reforma estrutural das pol\u00edcias em nosso pa\u00eds, e constitui-se um novo paradigma no trato da seguran\u00e7a p\u00fablica.<\/p>\n<p>No protesto realizado na \u00faltima quinta-feira, dia 20, no Rio de Janeiro, Cavalaria, Caveir\u00f5es, balas de borracha e bombas de g\u00e1s lacrimog\u00eaneo foram usados para dispersar manifestantes. De armas nas m\u00e3os, os pol\u00edcias do Batalh\u00e3o de Choque fizeram uma ca\u00e7a pela regi\u00e3o central da cidade, logo ap\u00f3s a dispers\u00e3o da manifesta\u00e7\u00e3o da frente da prefeitura. Os pr\u00e9dios da faculdade de Direito e do Instituto de Ci\u00eancias Sociais e Filosofia da UFRJ foram cercados. Mais de 2 mil bombas foram usadas na opera\u00e7\u00e3o, at\u00e9 contra o Hospital Municipal Souza Aguiar. Cerca de 64 pessoas ficaram feridas.<\/p>\n<p>Essa a\u00e7\u00e3o da Pol\u00edcia do Governador S\u00e9rgio Cabral corrobora o que as organiza\u00e7\u00f5es de direitos humanos h\u00e1 muito tempo denunciam. As Pol\u00edcias Militares s\u00e3o preparadas para confrontos b\u00e9licos e para lidar com o \u201cinimigo\u201d, os PMs n\u00e3o est\u00e3o aptos para a\u00e7\u00f5es junto \u00e0 popula\u00e7\u00e3o. S\u00e3o treinados para a guerra.<\/p>\n<p><strong>A periferia nunca dormiu<\/strong><\/p>\n<p>O secret\u00e1rio de Seguran\u00e7a P\u00fablica do Rio de Janeiro, Mariano Beltrame avisa que se for necess\u00e1rio usar\u00e1 as for\u00e7as do ex\u00e9rcito nos protestos do Rio. H\u00e1 cinco anos, no dia 14 de junho de 2008, David Wilson Flor\u00eancio da Silva, 24 anos; Wellington Gonzaga da Costa Ferreira, 19 anos; e Marcos Paulo Rodrigues Campos, 17 anos, moradores do Morro da Provid\u00eancia foram assassinados, ap\u00f3s terem sido espancados, presos e entregues por 11 militares do Ex\u00e9rcito \u00e0 traficantes do Morro da Mineira.<\/p>\n<p><strong>Na favela a bala n\u00e3o \u00e9 de borracha<\/strong><\/p>\n<p>Policiais da Rota mataram tr\u00eas pessoas na madrugada de s\u00e1bado, dia 22, em supostos tiroteios na favela da Funer\u00e1ria, na Vila Maria, Zona Norte de S\u00e3o Paulo, horas depois de um PM ter sido baleado durante um protesto na regi\u00e3o.<\/p>\n<p><strong>Toda arma mata<\/strong><\/p>\n<p>O uso indiscriminado de armamento \u201cn\u00e3o letal\u201d nos atos j\u00e1 levaram a um \u00f3bito. Em Bel\u00e9m, a gari Cleonice Vieira de Moraes, de 51 anos, passou mal ap\u00f3s a explos\u00e3o de uma bomba de efeito moral. Hipertensa, a gari acabou morrendo.<\/p>\n<p>Em Manguinhos, favela com interven\u00e7\u00e3o militar, situada na Zona Norte do Rio, o menino Mateus Cas\u00e9, 17 anos, morreu ap\u00f3s ser atingido por uma arma de eletrochoque.<\/p>\n<p><strong>Grupos de Exterm\u00ednio<\/strong><\/p>\n<p>Na Bahia \u00e9 not\u00f3rio o envolvimento de policiais militares em um forte esquema de execu\u00e7\u00e3o sum\u00e1ria e extrajudicial. Em 2008 o jovem artista circense Ricardo Matos, foi executado na comunidade do Bate Facho, no bairro Boca do Rio, em Salvador. Policiais Militares foram denunciados pelo Minist\u00e9rio P\u00fablico e ainda hoje respondem a processo judicial que apura as responsabilidades sobre a execu\u00e7\u00e3o desse jovem negro. Em 10 de mar\u00e7o deste ano, seu irm\u00e3o, \u00canio Matos, tamb\u00e9m foi executado. A execu\u00e7\u00e3o de Ricardo e \u00canio s\u00e3o lamentavelmente casos emblem\u00e1ticos da sistem\u00e1tica de exterm\u00ednio dos jovens negros de nossas periferias.<\/p>\n<p><strong>N\u00e3o \u00e9 a Gr\u00e9cia nem a Turquia<\/strong><\/p>\n<p>A pol\u00edcia brasileira \u00e9 uma das mais violentas do mundo, mas ao inv\u00e9s da cria\u00e7\u00e3o massiva de pol\u00edticas para redu\u00e7\u00e3o da viol\u00eancia, percebe-se uma inten\u00e7\u00e3o em fortalecer a institui\u00e7\u00e3o. No final do ano passado, o Brasil negou a recomenda\u00e7\u00e3o feita pela ONU no processo de Revis\u00e3o Peri\u00f3dica Universal para extinguir a pol\u00edcia militar. E mais, o Governo do Estado do Rio prev\u00ea concurso para a PMRJ com 6 mil novas vagas.<\/p>\n<p><em>Justi\u00e7a Global<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"\nNota da Justi\u00e7a Global\n<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/5014\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[119],"tags":[],"class_list":["post-5014","post","type-post","status-publish","format-standard","hentry","category-c132-passe-livre"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-1iS","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/5014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=5014"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/5014\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=5014"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=5014"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=5014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}