{"id":5166,"date":"2013-07-30T23:43:43","date_gmt":"2013-07-30T23:43:43","guid":{"rendered":"http:\/\/pcb.org.br\/portal2\/?p=5166"},"modified":"2013-07-30T23:43:43","modified_gmt":"2013-07-30T23:43:43","slug":"brasil-o-capitalismo-extractivo-e-o-grande-salto-para-tras","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/5166","title":{"rendered":"Brasil: O capitalismo extractivo e o grande salto para tr\u00e1s"},"content":{"rendered":"\n<p>come\u00e7aram a verificar-se a seguir ao golpe de 1964 e aceleraram-se ap\u00f3s o retorno da pol\u00edtica eleitoral nos meados da d\u00e9cada de 1980. A elei\u00e7\u00e3o de pol\u00edticos neoliberais, especialmente com a elei\u00e7\u00e3o do regime Cardoso em meados da d\u00e9cada de 1990, teve um impacto devastador sobre sectores estrat\u00e9gicos da economia nacional: a privatiza\u00e7\u00e3o generalizada foi acompanhada pela desnacionaliza\u00e7\u00e3o dos altos comandos da economia e a desregulamenta\u00e7\u00e3o maci\u00e7a de mercados de capitais\u00a0<strong>[1]<\/strong> . O regime Cardoso preparou o cen\u00e1rio para o fluxo maci\u00e7o de capital estrangeiro nos sectores agro-mineral, financeiro, seguros e imobili\u00e1rio. A ascens\u00e3o das taxas de juro, como exigido pelo FMI, o Banco Mundial e o mercado especulativo imobili\u00e1rio elevaram os custos da produ\u00e7\u00e3o industrial. A redu\u00e7\u00e3o de tarifas de Cardoso acabou com subs\u00eddios \u00e0 ind\u00fastria e abriu a porta a importa\u00e7\u00f5es industriais. Estas pol\u00edticas neoliberais levaram ao decl\u00ednio relativo e absoluto da produ\u00e7\u00e3o industrial <strong>[2]<\/strong> .<\/p>\n<p>\u00a0<\/p>\n<p>A vit\u00f3ria presidencial do auto-intitulado &#8220;Partido dos Trabalhadores&#8221;, em 2002, aprofundou e expandiu o &#8220;grande retrocesso&#8221; promovido pelos seus antecessores neoliberais. O Brasil reverteu para tornar-se um exportador prim\u00e1rio de\u00a0<em>commodities, <\/em>como soja, gado, ferro e min\u00e9rios que se multiplicaram, as exporta\u00e7\u00f5es de material de transporte e manufacturas declinaram\u00a0<strong>[3]<\/strong> . O Brasil tornou-se uma dos principais exportadores de commodities extractivas do mundo. A depend\u00eancia do Brasil das exporta\u00e7\u00f5es de commodities foi ajudada e compensada pela entrada maci\u00e7a e a penetra\u00e7\u00e3o de corpora\u00e7\u00f5es imperiais multinacionais e de fluxos de financeiros por bancos al\u00e9m-mar. Os mercados al\u00e9m-mar e os bancos estrangeiros tornaram-se a for\u00e7a condutora do crescimento extractivo e da morte industrial.<\/p>\n<p>Para ter um melhor entendimento da &#8220;grande revers\u00e3o&#8221; do Brasil de uma din\u00e2mica nacionalista-industrializante para uma vulner\u00e1vel depend\u00eancia imperial conduzida pela extrac\u00e7\u00e3o agro-mineral, precisamos resumidamente rever a economia pol\u00edtica do Brasil ao longo dos \u00faltimos cinquenta anos a fim de identificar os &#8220;pontos de viragem&#8221; decisivos e a centralidade da pol\u00edtica e da luta de classe.<\/p>\n<p><strong>Modelo militar: Moderniza\u00e7\u00e3o a partir de cima <\/strong><\/p>\n<p>Sob a ditadura militar (1964-1984) a pol\u00edtica econ\u00f3mica era baseada numa estrat\u00e9gia h\u00edbrida enfatizando uma tr\u00edplice alian\u00e7a do estado, do capital estrangeiro e do capital privado nacional\u00a0<strong>[4]<\/strong> centrada primariamente em exporta\u00e7\u00f5es industriais e secundariamente e <em>commodities <\/em>agr\u00edcolas (especialmente produtos tradicionais como o caf\u00e9).<\/p>\n<p>Os militares rejeitaram o modelo nacionalista-populista baseado em ind\u00fastrias do estado e cooperativas camponesas do deposto presidente Goulart e puseram em vigor uma alian\u00e7a de capitalistas industriais e agroneg\u00f3cio. A cavalgar uma onda de mercados globais em expans\u00e3o e beneficiando da repress\u00e3o do trabalho, a compress\u00e3o de sal\u00e1rios, subs\u00eddios abrangentes e pol\u00edticas proteccionistas, a economia cresceu a dois d\u00edgitos desde o fim da d\u00e9cada de 1960 at\u00e9 meados da de 1970, o chamado &#8220;Milagre brasileiro&#8221;\u00a0<strong>[5]<\/strong> . Os militares, se bem que afastando quaisquer amea\u00e7as de nacionaliza\u00e7\u00f5es, puseram em vigor um certo n\u00famero de regras de &#8220;conte\u00fado nacional&#8221; e ampliaram a dimens\u00e3o e \u00e2mbito da classe trabalhadora urbana, especialmente na ind\u00fastria automotiva. Isto levou ao crescimento dos sindicatos de trabalhadores metal\u00fargicos e posteriormente do Partido dos Trabalhadores. O &#8220;modelo exportador&#8221; baseado na ind\u00fastria leve e pesada, de produtores estrangeiros e internos, tinha base regional (Sudeste). A estrat\u00e9gia de moderniza\u00e7\u00e3o aumentou desigualdades e integrou os capitalistas &#8220;nacionais&#8221; a multinacionais imperiais. Isto preparou o terreno para o in\u00edcio das lutas anti-ditatoriais e o retorno da democracia. Partidos neoliberais ganharam hegemonia com a viragem para pol\u00edticas eleitorais.<\/p>\n<p><strong>Pol\u00edticas eleitorais, a ascens\u00e3o de neoliberalismo e a ascend\u00eancia do capitalismo extractivo <\/strong><\/p>\n<p>A oposi\u00e7\u00e3o eleitoral que sucedeu aos regimes militares esteve inicialmente polarizada entre uma elite liberal, adepta do livre mercado agro-mineral e aliada a multinacionais imperiais e, por outro lado, um bloco nacionalista de trabalhadores, camponeses, trabalhadores rurais e classe m\u00e9dia baixa. Trabalhadores militantes constitu\u00edam a CUT, camponeses sem terra o MST e ambos juntaram-se \u00e0 classe m\u00e9dia para constituir o PT.\u00a0<strong>[6]<\/strong><\/p>\n<p>A primeira d\u00e9cada de pol\u00edtica eleitoral, 1984-94, foi caracterizada pelo puxa e empurra entre o capitalismo estatista residual herdado do regime militar anterior e a emergente burguesia do &#8220;livre mercado&#8221; liberal. As crises de d\u00edvida, hiper-infla\u00e7\u00e3o, corrup\u00e7\u00e3o sist\u00e9mica maci\u00e7a, o impedimento do presidente Collor e a estagna\u00e7\u00e3o econ\u00f3mica enfraqueceram gravemente os sectores capitalistas estatais e levaram \u00e0 ascend\u00eancia de uma alian\u00e7a do capital agro-mineral e financeiro, tanto de capitalistas estrangeiros como locais, ligada a mercados al\u00e9m-mar. Esta coliga\u00e7\u00e3o retr\u00f3grada encontrou o seu l\u00edder politico e o caminho do poder com a elei\u00e7\u00e3o de Fernando Henrique Cardoso, um antigo acad\u00e9mico de esquerda que se converteu em fan\u00e1tico do mercado livre.<\/p>\n<p>A elei\u00e7\u00e3o de Cardoso levou a uma ruptura decisiva com as pol\u00edticas nacionais estatistas dos sessenta anos anteriores. As pol\u00edticas de Cardoso deram um impulso decisivo \u00e0 desnacionaliza\u00e7\u00e3o e privatiza\u00e7\u00e3o da economia, elementos essenciais na reconfigura\u00e7\u00e3o da economia do Brasil, e \u00e0 ascend\u00eancia do capital extractivo\u00a0<strong>[7]<\/strong> . De acordo com quase todos os indicadores, as pol\u00edticas ultra-liberais de Cardoso levaram a um precipitado grande salto para tr\u00e1s, concentrando rendimento e terra, e aumentando a propriedade estrangeiro de sectores estrat\u00e9gicos. A &#8220;reforma&#8221; da economia de Cardoso a expensas do trabalho industrial, da propriedade p\u00fablica, dos trabalhadores sem terra provocou greves generalizadas e ocupa\u00e7\u00f5es de terra <strong>[8]<\/strong> . A &#8220;economia extractiva&#8221;, especialmente a abertura de sectores lucrativos na agricultura, minera\u00e7\u00e3o e energia, ganhou espa\u00e7o a expensas das for\u00e7as produtivas: a posi\u00e7\u00e3o relativa da manufactura, tecnologia e servi\u00e7os avan\u00e7ados declinou. Em particular, os ganhos do trabalho como um todo declinaram como percentagem do PNB <strong>[9]<\/strong> .<\/p>\n<p>A taxa de crescimento m\u00e9dio da ind\u00fastria declinou para uns magros 1,4%. O emprego no sector industrial caiu em 26%, o desemprego subiu para mais de 18,4%, o &#8220;sector informal&#8221; subiu de 52,5% em 1980 para 56,1% em 1995\u00a0<strong>[10]<\/strong> .<\/p>\n<p>A privatiza\u00e7\u00e3o de empresas p\u00fablicas como a Telebr\u00e1s, firma gigante e lucrativa de telecomunica\u00e7\u00f5es, levou ao despedimento maci\u00e7o de trabalhadores e \u00e0 subcontrata\u00e7\u00e3o de trabalho com sal\u00e1rios mais baixos e sem benef\u00edcios sociais. Sob Cardoso, o Brasil tinha as mais altas taxas de desigualdade (coeficiente de Gini) entre todos os pa\u00edses do mundo.<\/p>\n<p>Cardoso utilizou subs\u00eddios do estado para promover o capital estrangeiro, especialmente nos sectores da exporta\u00e7\u00e3o agr\u00e1ria e mineral, enquanto pequenos e m\u00e9dios agricultores ansiavam por cr\u00e9dito. O seu programa de desregulamenta\u00e7\u00e3o financeira levou \u00e0 especula\u00e7\u00e3o com divisas, lucros maci\u00e7os e inesperados para bancos da Wall Street quando o regime elevou as taxas de juro em mais de 50%\u00a0<strong>[11]<\/strong> . A bancarrota de agricultores levou ao seu despojamento pelos capitalistas agro-exportadores. A concentra\u00e7\u00e3o de terra assumiu uma viragem decisiva quando 7% dos grandes propriet\u00e1rios que possu\u00edam fazendas de mais de 2000 hectares aumentaram a dimens\u00e3o das suas terras de 39,5% para 43% das terras agr\u00edcolas brasileiras <strong>[12]<\/strong> .<\/p>\n<p>Durante os oito anos de Cardoso no governo (1994-2001) houve um tsunami de investimento estrangeiro: mais de US$50 mil milh\u00f5es entraram no pa\u00eds s\u00f3 nos primeiros cinco anos \u2013 dez vezes o total dos 15 anos anteriores\u00a0<strong>[13]<\/strong> . Companhias agro-minerais de propriedade estrangeiras entre as principais companhias estrangeiras (em 1997) representavam mais de um ter\u00e7o e continuavam a crescer. Entre 1996-1998 multinacionais estrangeiras adquiriram oito grandes firmas de alimentos, minera\u00e7\u00e3o e produ\u00e7\u00e3o met\u00e1lica <strong>[14]<\/strong> .<\/p>\n<p>As pol\u00edticas neoliberais de Cardoso abriram a porta amplamente para a tomada de ind\u00fastrias cr\u00edticas e sectores banc\u00e1rios pelo capital estrangeiro. No entanto, foram os presidentes do &#8220;Partido dos Trabalhadores&#8221; que vieram a seguir, Lula da Silva e Rousseff, que completaram o Grande Salto para Tr\u00e1s da economia brasileira ao se voltarem decisivamente para o capital extractivo como a for\u00e7a condutora da economia.<\/p>\n<p><strong>Do neoliberalismo ao capital extractivo <\/strong><\/p>\n<p>As privatiza\u00e7\u00f5es de Cardoso foram apoiadas e aprofundadas pelo regime Lula. A ultrajante privatiza\u00e7\u00e3o de Cardoso da mineradora Vale do Rio Doce por uma frac\u00e7\u00e3o do seu valor foi defendida por Lula; o mesmo se passou com a privatiza\u00e7\u00e3o de facto da companhia petrol\u00edfera estatal Petrobr\u00e1s. Lula abra\u00e7ou as pol\u00edticas monet\u00e1rias restritivas, acordos de excedente or\u00e7amental com o FMI e seguiu as prescri\u00e7\u00f5es or\u00e7amentais dos directores do FMI\u00a0<strong>[15]<\/strong> .<\/p>\n<p>O regime Lula (2003-2011) adoptou as pol\u00edticas neoliberais de Cardoso como um guia para promover a reconfigura\u00e7\u00e3o da economia do Brasil em benef\u00edcio do capital estrangeiro e interno, agora assente no sector prim\u00e1rio e de exporta\u00e7\u00e3o de mat\u00e9rias-primas. Em 2005 o Brasil exportou US$55,3 mil milh\u00f5es em mat\u00e9rias-primas e US$44,2 mil milh\u00f5es em bens manufacturados; em 2011 o Brasil triplicou suas exporta\u00e7\u00f5es de mat\u00e9rias-primas para US$162,2 mil milh\u00f5es enquanto suas exporta\u00e7\u00f5es de manufacturas aumentaram para uns meros US$60,3 mil milh\u00f5es\u00a0<strong>[16]<\/strong> .<\/p>\n<p>Por outras palavras, a diferen\u00e7a entre o valor das exporta\u00e7\u00f5es de mat\u00e9rias-primas e de manufacturas aumentou de US$13 mil milh\u00f5es para mais de US$100 mil milh\u00f5es nos \u00faltimos cinco anos do regime Lula. A desindustrializa\u00e7\u00e3o relativa da economia, o desequil\u00edbrio crescente entre o sector extractivo dominante e o sector manufactureiro ilustra a revers\u00e3o do Brasil para o seu &#8220;estilo colonial de desenvolvimento&#8221;.<\/p>\n<p><strong>O capitalismo agro-mineral, o estado e o povo <\/strong><\/p>\n<p>O sector exportador do Brasil beneficiou-se enormemente com a ascens\u00e3o dos pre\u00e7os das\u00a0<em>commodities <\/em>. O principal benefici\u00e1rio foi o sector exportador agro-mineral. Mas o custo para a ind\u00fastria, transporte p\u00fablico, condi\u00e7\u00f5es de vida, investiga\u00e7\u00e3o e desenvolvimento e educa\u00e7\u00e3o foi enorme. As exporta\u00e7\u00f5es agro-minerais proporcionarem grandes receitas para o estado mas tamb\u00e9m extrairam-lhe grandes subs\u00eddios, benef\u00edcios fiscais e lucros.<\/p>\n<p>A economia industrial do Brasil foi afectada desfavoravelmente pelo boom da\u00a0<em>commodities <\/em>devido \u00e0 ascens\u00e3o no valor da sua divisa, o real, em 40% entre 2010-2012, a qual aumentou o pre\u00e7os das exporta\u00e7\u00f5es de manufacturas e diminuiu a competitividade dos produtos manufacturados<strong>[17]<\/strong> . As pol\u00edticas de &#8220;mercado livre&#8221; tamb\u00e9m facilitaram a entrada de bens manufacturados mais baratos da \u00c1sia, particularmente da China. Enquanto as exporta\u00e7\u00f5es prim\u00e1rias para a China deram um salto, o sector manufactureiro do Brasil, particularmente bens de consumo como t\u00eaxteis e cal\u00e7ados, declinou entre 2005 e 2010 em mais de 10% <strong>[18]<\/strong> .<\/p>\n<p>Sob os regimes Lula-Rousseff, a extrema depend\u00eancia de um n\u00famero limitado de\u00a0<em>commodities <\/em>levou a um decl\u00ednio agudo nas for\u00e7as produtivas, medido pelos investimentos em inova\u00e7\u00f5es tecnol\u00f3gicas, especialmente aqueles relacionados com a ind\u00fastria\u00a0<strong>[19]<\/strong> . Al\u00e9m disso, o Brasil tornou-se mais dependente do que nunca de um \u00fanico mercado. De 2000 para 2010 a importa\u00e7\u00f5es chinesas de soja \u2013 a principal exporta\u00e7\u00e3o agr\u00edcola \u2013 representaram 40% das exporta\u00e7\u00f5es do Brasil; as importa\u00e7\u00f5es chinesas de ferro \u2013 a exporta\u00e7\u00e3o mineira chave \u2013 constituem mais de um ter\u00e7o do total das exporta\u00e7\u00f5es daquele sector. A China tamb\u00e9m importa cerca de 10% das exporta\u00e7\u00f5es brasileiras de petr\u00f3leo, carne, celulose e papel <strong>[20]<\/strong>. Sob os regimes Lula e Rousseff, o Brasil reverteu para uma economia quase mono-cultural dependente de um mercado muito limitado. Em consequ\u00eancia, o arrefecimento da economia da China levou como era de prever a um decl\u00ednio no crescimento do Brasil para menos de 2% de 2011 para 2013 <strong>[21]<\/strong> .<\/p>\n<p><strong>Brasil: Para\u00edso econ\u00f3mico do capital financeiro <\/strong><\/p>\n<p>Sob as pol\u00edticas de mercado livre do Partido dos Trabalhadores, o capital financeiro entrou a jorros no Brasil, como nunca antes. O investimento directo estrangeiro saltou de cerca de US$16 mil milh\u00f5es em 2002, durante o \u00faltimo ano do regime Cardoso, para mais de US$48 mil milh\u00f5es no \u00faltimo ano do governo de Lula\u00a0<strong>[22]<\/strong> . A carteira de investimento \u2013 na maior parte de tipo especulativo \u2013 subiu de US$5 mil milh\u00f5es negativo em 2002 para US$67 mil milh\u00f5es em 2010. Entradas l\u00edquidas de investimento directo estrangeiro (IDE) e investimentos de carteira totalizaram US$400 mil milh\u00f5es durante 2007-2011, a comparar com os US$79 mil milh\u00f5es durante o per\u00edodo anterior de cinco anos <strong>[23]<\/strong> . Investimentos de carteira em t\u00edtulos de altos juros retornaram entre 8% e 15%, o triplo e o qu\u00e1druplo das taxas na Am\u00e9rica do Norte e Europa. Lula e Dilma s\u00e3o presidentes poster da Wall Street.<\/p>\n<p>De acordo com os indicadores econ\u00f3micos mais importantes, as pol\u00edticas dos regimes Lula-Dilma foram as mais lucrativas para o capital estrangeiro al\u00e9m-mar e os investidores nos sectores agro-minerais prim\u00e1rios na hist\u00f3ria recente do Brasil.<\/p>\n<p><strong>O modelo agro-mineral e o ambiente <\/strong><\/p>\n<p>Apesar da sua ret\u00f3rica pol\u00edtica em favor da fam\u00edlia agricultora, os regimes Lula-Dilva t\u00eam estado entre os maiores promotores do agro-neg\u00f3cio na hist\u00f3ria pol\u00edtica brasileira. A maior fatia de recursos do estado foi concedida \u00e0 agricultura, finan\u00e7as e grandes propriet\u00e1rios rurais. De acordo com um estudo, em 2008\/2009 pequenos propriet\u00e1rios receberam cerca de US$6,35 mil milh\u00f5es, ao passo que o agro-neg\u00f3cio e grandes propriet\u00e1rios rurais receberam US$31,9 mil milh\u00f5es em financiamento e cr\u00e9dito\u00a0<strong>[24]<\/strong> . Menos de 4% dos recursos do governo e de investiga\u00e7\u00e3o foi destinada \u00e0 agricultura familiar e explora\u00e7\u00f5es agro-ecol\u00f3gicas.<\/p>\n<p>Sob Lula, a destrui\u00e7\u00e3o das florestas tropicais verificou-se a um ritmo acelerado. Entre 2002 e 2008 a vegeta\u00e7\u00e3o da regi\u00e3o do\u00a0Cerrado foi reduzida em 7,5% ou mais de 8,5 milh\u00f5es de hectares, principalmente por corpora\u00e7\u00f5es do agro-neg\u00f3cio\u00a0<strong>[25]<\/strong> . O Cerrado brasileiro \u00e9 uma das regi\u00f5es de savana mais biologicamente ricas do mundo, concentrando-se na regi\u00e3o centro-leste do pa\u00eds. De acordo com um estudo, 69% da terra de propriedade de corpora\u00e7\u00f5es estrangeiras est\u00e1 concentrada no Cerrado do Brasil <strong>[26]<\/strong> . Entre 1995 e 2005 a fatia de capital estrangeiro no sector cereal\u00edfero agro-industrial saltou de 16% para 57%. O capital estrangeiro capitalizou com as pol\u00edticas neoliberais sob Cardoso, Lula e Dilma deslocando-se para o sector do agro-combust\u00edvel (etanol), controlando cerca de 22% das companhias brasileiras de cana-de-a\u00e7\u00facar e etanol <strong>[27]<\/strong>\u2013 e rapidamente invadindo a floresta amaz\u00f3nica.<\/p>\n<p>Entre Maio de 2000 e Agosto de 2005, gra\u00e7as \u00e0 expans\u00e3o do sector exportador, o Brasil perdeu 132 mil quil\u00f3metros quadrados de floresta devido \u00e0 expans\u00e3o de grandes propriet\u00e1rios de terra e multinacionais dedicados \u00e0 cria\u00e7\u00e3o de gado, soja e madeira\u00a0<strong>[28]<\/strong> . Entre 2003 e 2012, mais de 137 mil quil\u00f3metros quadrados foram desflorestados, crime ajudado por multibilion\u00e1rios investimentos do governo em infraestrutura, incentivos fiscais e subs\u00eddios.<\/p>\n<p>Em 2008 o dano \u00e0 floresta tropical amaz\u00f3nica aumentou 67%. Sob press\u00e3o de ind\u00edgenas, camponeses, trabalhadores rurais sem terra e movimentos ecol\u00f3gicos o governo entrou em ac\u00e7\u00e3o para restringir a desfloresta\u00e7\u00e3o. Ela declinou de um pico de 27.772 quil\u00f3metros quadrados em 2004 (o segundo, apenas inferior ao de 1995, sob Cardoso, com 29.059 km2) para 4.656 km2 em 2012\u00a0<strong>[29]<\/strong> .<\/p>\n<p>A cria\u00e7\u00e3o de gado \u00e9 a principal causa da desfloresta\u00e7\u00e3o na Amaz\u00f3nia brasileira. Estimativas atribuem mais de 40% a grandes capitalistas e corpora\u00e7\u00f5es multinacionais de processamento de carne\u00a0<strong>[30]<\/strong> . Os principais investimentos em infraestrutura dos regimes Lula-Dilma, principalmente estradas, haviam aberto anteriormente terras florestais inacess\u00edveis a empresas corporativas de gado. Sob Lula e Dilma, a agricultura comercial, especialmente a soja, tornou-se o segundo maior contribuidor para a desfloresta\u00e7\u00e3o da Amaz\u00f3nia.<\/p>\n<p>Acompanhando a degrada\u00e7\u00e3o do ambiente natural, a expans\u00e3o do agro-neg\u00f3cio foi acompanhada pelo despojamento, assass\u00ednio e escraviza\u00e7\u00e3o de povos ind\u00edgenas. A Comiss\u00e3o Pastoral da Terra, da Igreja Cat\u00f3lica, informou que em 2004 a viol\u00eancia latifundi\u00e1ria atingiu o seu mais alto n\u00edvel em pelo menos 20 anos \u2013 o segundo ano do mandato de Lula. Os conflitos subiram de 1.801 em 2004, quando em 2003 foram 1.690 e em 2002 foram 925\u00a0<strong>[31]<\/strong> .<\/p>\n<p>Segundo o governo, corpora\u00e7\u00f5es de gado e soja exploram pelo menos 25 mil brasileiros (principalmente \u00edndios despojados da sua terra e camponeses sem terra) sob &#8220;condi\u00e7\u00f5es an\u00e1logas \u00e0 escravid\u00e3o&#8221;. As principais ONGs afirmam que o n\u00famero verdadeiro poderia ser dez vezes superior \u00e0quele. Mais de 183 fazendas foram inspeccionadas em 2005 libertando 4.133 escravizados\u00a0<strong>[32]<\/strong> .<\/p>\n<p><strong>Minera\u00e7\u00e3o: A fraude da &#8220;privatiza\u00e7\u00e3o&#8221; da Vale, agora poluidora n\u00famero um <\/strong><\/p>\n<p>Cerca de 25% das exporta\u00e7\u00f5es do Brasil s\u00e3o constitu\u00eddas por produtos minerais \u2013 o que destaca a crescente centralidade do capital extractivo na economia. O min\u00e9rio de ferro \u00e9 o min\u00e9rio de maior import\u00e2ncia, representando 78% do total das exporta\u00e7\u00f5es mineiras. Em 2008, o ferro representou US$16,5 dos rendimentos da ind\u00fastria, num total de US$22,5 mil milh\u00f5es\u00a0<strong>[33]<\/strong> . A vasta maioria das exporta\u00e7\u00f5es de ferro est\u00e1 dependente de um \u00fanico mercado \u2013 a China. Quando o crescimento da China diminui, a procura declina e a vulnerabilidade econ\u00f3mica do Brasil aumenta.<\/p>\n<p>Uma firma, privatizada durante a presid\u00eancia Cardoso, a Vale, atrav\u00e9s de aquisi\u00e7\u00f5es e fus\u00f5es controla quase 100% da produ\u00e7\u00e3o das minas de ferro do Brasil\u00a0<strong>[34]<\/strong> . Em 1997 a Vale foi vendida pelo estado neoliberal por US$3,14 mil milh\u00f5es, uma pequena frac\u00e7\u00e3o do seu valor. Ao longo da d\u00e9cada seguinte ela concentrou seus investimentos na minera\u00e7\u00e3o, estabelecendo uma rede global de minas em mais de uma d\u00fazia de pa\u00edses na Am\u00e9rica do Norte e do Sul, Austr\u00e1lia, \u00c1frica e \u00c1sia. O regime Lula-Dilma desempenhou um papel importante para facilitar a domin\u00e2ncia da Vale no sector mineiro e o crescimento exponencial do seu valor. O valor l\u00edquido da Vale hoje \u00e9 de mais de US$100 mil milh\u00f5es mas ela paga uma das mais baixas taxas de imposto do mundo, apesar de ser a segunda maior companhia mineira do mundo, o maior produtor de min\u00e9rio de ferro e o segundo maior de n\u00edquel. Os royalties m\u00e1ximos sobre a riqueza mineral subiram de 2% para 4% em 2013 <strong>[35]<\/strong> . Por outras palavras, durante a d\u00e9cada do governo &#8220;progressista&#8221; de Lula e Dilma, a taxa fiscal era um sexto daquela da conservadora Austr\u00e1lia, que mant\u00e9m uma taxa de 12%.<\/p>\n<p>A Vale tem utilizado os seus enormes lucros para diversificar opera\u00e7\u00f5es mineiras e actividades relacionadas. Ela liquidou neg\u00f3cios como o a\u00e7o e a celulose vendendo-os por US$2,9 mil milh\u00f5es \u2013 aproximadamente o pre\u00e7o pago por todo o complexo mineral. Em vez disso concentrou-se na compra de minas de ferro de competidores e literalmente na monopoliza\u00e7\u00e3o da produ\u00e7\u00e3o. A Vale expandiu-se no mangan\u00eas, n\u00edquel, cobre, carv\u00e3o, potassa, caulim, bauxita; comprou ferrovias, portos, terminais de contentores, navios e pelo menos oito centrais hidroel\u00e9ctricas; dois ter\u00e7os das suas centrais hidroel\u00e9ctricas foram constru\u00eddas durante o regime Lula\u00a0<strong>[36]<\/strong> .<\/p>\n<p>Em suma, o capitalismo floresceu durante o regime Lula com lucros recorde no sector extractivo, perigo extremo para o ambiente e deslocamento maci\u00e7o de povos ind\u00edgenas e produtores em pequena escala. A experi\u00eancia mineira da Vale sublinha as poderosas continuidades estruturais entre o regime neoliberal de Cardoso e o de Lula: o primeiro privatizou a Vale a pre\u00e7o de saldo, o \u00faltimo promoveu a Vale como o produtor e exportador monopolista dominante de ferro, ignorando totalmente a concentra\u00e7\u00e3o de riqueza, lucros e poderes do capital extractivo.<\/p>\n<p>Em compara\u00e7\u00e3o com o crescimento geom\u00e9trico dos lucros de monop\u00f3lio do sector extractivo, os miser\u00e1veis dois d\u00f3lares por dia de Lula e Dilma, dados como subs\u00eddio para reduzir a pobreza, dificilmente permitem classificar este regime como &#8220;progressista&#8221; ou de &#8220;centro-esquerda&#8221;.<\/p>\n<p>Se bem que Lula e Dilma estejam embevecidos com o crescimento do &#8220;campe\u00e3o mineiro&#8221; do Brasil (a Vale), outros n\u00e3o est\u00e3o. Em 2002, a Public Eye, um grupo de direitos humanos e ambientais, deu \u00e0 Vale um &#8220;pr\u00e9mio&#8221; como a pior corpora\u00e7\u00e3o do mundo: &#8220;A Vale Corporation actua com o maior desrespeito pelo ambiente e direitos humanos no mundo&#8221;\u00a0<strong>[37]<\/strong> . Os cr\u00edticos citaram a constru\u00e7\u00e3o da barragem de Belo Monte, da Vale, no meio da floresta tropical amaz\u00f3nica como tendo &#8220;consequ\u00eancias devastadoras para regi\u00f5es com biodiversidade \u00fanica e tribos ind\u00edgenas&#8221; <strong>[38]<\/strong> .<\/p>\n<p>O sector mineiro \u00e9 capital intensivo, gera poucos empregos e acrescenta pouco valor \u00e0s suas exporta\u00e7\u00f5es. Ele tem degradado a \u00e1gua, a terra e o ar; afectado desfavoravelmente comunidades locais, despojado comunidades \u00edndias e criado uma economia de altos e baixos.<\/p>\n<p>Com o acentuado arrefecimento da economia chinesa, especialmente o seu sector manufactureiro em 2012-14, os pre\u00e7os do ferro e do cobre ca\u00edram. As receitas de exporta\u00e7\u00e3o do Brasil declinaram, minando o crescimento geral. \u00c9 especialmente importante que a canaliza\u00e7\u00e3o de recursos para infraestruturas destinadas aos sectores agro-minerais resultou no esgotamento de fundos para hospitais, escolas e transporte urbano \u2013 os quais est\u00e3o de deprimidos e proporcionam um servi\u00e7o fraco a milh\u00f5es de trabalhadores urbanos.<\/p>\n<p><strong>O fim do &#8220;mega ciclo&#8221; extractivo e a ascens\u00e3o de protestos em massa <\/strong><\/p>\n<p>O modelo de orienta\u00e7\u00e3o extractiva do Brasil entrou num per\u00edodo de decl\u00ednio e estagna\u00e7\u00e3o em 2012-2013 quando a procura mundial \u2013 especialmente na \u00c1sia \u2013 declinou, sobretudo na China\u00a0<strong>[39]<\/strong> . O crescimento flutuou em torno dos 2%, mal acompanhando o crescimento populacional. A classe baseada neste modelo de crescimento, especialmente o estrato reduzido de investidores estrangeiros de carteira, minera\u00e7\u00e3o monopolista e grandes corpora\u00e7\u00f5es do agro-neg\u00f3cio, os quais controlam e arrecadam a maior parte das receitas e lucros, limitou os &#8220;efeitos gotejamento&#8221; <em>(&#8220;trickle down effects&#8221;) <\/em>que os regimes Lula-Dilma promoveram como a sua &#8220;transforma\u00e7\u00e3o social&#8221;. Se bem que alguns programas inovadores tenham sido iniciados, o acompanhamento e a qualidade dos servi\u00e7os realmente deteriorou-se.<\/p>\n<p>O n\u00famero de leitos para pacientes em hospitais declinou de 3,3 por 1000 brasileiros em 1993 para 1,9 em 2009, o segundo mais baixo da OCDE<strong>[40]<\/strong> . As admiss\u00f5es em hospitais financiados pelo sector p\u00fablico caiu e as longas esperas e baixa qualidade s\u00e3o end\u00e9micos.<\/p>\n<p>O gasto federal no sistema de sa\u00fade tem ca\u00eddo desde 2003, quando ajustado \u00e0 infla\u00e7\u00e3o, segundo o estudo da OCDE. A despesa p\u00fablica em sa\u00fade \u00e9 baixa<strong>[41]<\/strong>. \u00a0A polarizaza\u00e7\u00e3o de classe inerente ao modelo extractivo agro-mineral estende-se \u00e0s despesas do governo, impostos, transportes e infraestrutura: financiamento maci\u00e7o para rodovias, barragens, centrais hidroel\u00e9ctricas para o capital extractivo, contra gastos inadequados e em decl\u00ednio para transportes p\u00fablicos, sa\u00fade p\u00fablica e educa\u00e7\u00e3o.<\/p>\n<p align=\"justify\">\u00a0<\/p>\n<p>As ra\u00edzes mais profundas das manifesta\u00e7\u00f5es de massa de 2013 est\u00e3o localizadas na pol\u00edtica de classe de um estado corporativo. Os regimes Cardoso e Lula-Dilma, ao longo das \u00faltimas duas d\u00e9cadas, seguiram uma agenda elitista e conservadora, amortecida pela pol\u00edtica clientelista e paternalista que neutralizou a oposi\u00e7\u00e3o em massa durante um per\u00edodo de tempo extenso, at\u00e9 que a rebeli\u00e3o em massa e os protestos \u00e0 escala nacional desmascararam a fachada &#8220;progressista&#8221;.<\/p>\n<p>Publicistas de esquerda e sabich\u00f5es conservadores que saudaram Lula como um &#8220;progressista pragm\u00e1tico&#8221; ignoraram o facto de que durante o seu primeiro mandato o apoio do estado \u00e0 elite do agro-neg\u00f3cio foi sete vezes maior do que a oferecida aos agricultores familiares que representavam aproximadamente 90% da for\u00e7a de trabalho rural e proporcionavam a maior parte dos alimentos para consumo local. Durante o segundo mandato de Lula, o apoio financeiro do Minist\u00e9rio da Agricultura ao agro-neg\u00f3cio durante a safra 2008\/09 foi seis vezes maior do que os fundos concedidos ao programa de redu\u00e7\u00e3o da pobreza de Lula, o altamente propagandeado programa &#8220;Bolsa Fam\u00edlia&#8221;\u00a0<strong>[42]<\/strong> . Ortodoxia econ\u00f3mica e demagogia populista n\u00e3o s\u00e3o substitutos de mudan\u00e7as estruturais substantivas, envolvendo uma reforma agr\u00e1ria ampla que abranja 4 milh\u00f5es de trabalhadores rurais sem terra, assim como uma renacionaliza\u00e7\u00e3o de empresas extractivas estrat\u00e9gicas como a Vale a fim de financiar agricultura sustent\u00e1vel e preservar a floresta tropical.<\/p>\n<p>Ao inv\u00e9s disso, Lula e Dilma saltaram em for\u00e7a para o boom do etanol: &#8220;a\u00e7\u00facar, a\u00e7\u00facar por toda a parte&#8221; mas sem nunca perguntar, &#8220;Que bolsos enchem?&#8221; A crescente rigidez estrutural do Brasil, sua transforma\u00e7\u00e3o numa economia capitalista extractiva, potenciou e ampliou o \u00e2mbito da corrup\u00e7\u00e3o. A competi\u00e7\u00e3o por contratos mineiros, concess\u00f5es de terra e projectos gigantes de infraestrutura encoraja as elites dos neg\u00f3cios agro-minerais a pagarem ao &#8220;partido no poder&#8221; a fim de assegurar vantagens competitivas. Isto se verificou particularmente com o &#8220;Partido dos Trabalhadores&#8221; cuja lideran\u00e7a executiva (destitu\u00edda de trabalhadores) era composta de profissionais em ascens\u00e3o, aspirando a posi\u00e7\u00f5es na classe da elite que encarava os subornos nos neg\u00f3cios para o seu &#8220;capital inicial&#8221; como uma esp\u00e9cie de &#8220;acumula\u00e7\u00e3o inicial atrav\u00e9s da corrup\u00e7\u00e3o&#8221;.<\/p>\n<p>O boom das\u00a0<em>commodities, <\/em>durante quase uma d\u00e9cada, encobriu as contradi\u00e7\u00f5es de classe e a extrema vulnerabilidade de uma economia extractiva dependente de exporta\u00e7\u00f5es de bens prim\u00e1rios para mercados limitados. As pol\u00edticas neoliberais adaptadas \u00e0 promo\u00e7\u00e3o de exporta\u00e7\u00f5es de\u00a0<em>commodities <\/em>levaram ao influxo dos bens manufacturados e enfraqueceram a posi\u00e7\u00e3o do sector industrial. Em consequ\u00eancia, os esfor\u00e7os de Dilma para renovar a economia produtiva a fim de compensar o decl\u00ednio das receitas de\u00a0<em>commodities <\/em>n\u00e3o funcionaram: estagfla\u00e7\u00e3o, excedentes or\u00e7ament\u00e1rios em decl\u00ednio e enfraquecimento da balan\u00e7a comercial praguejaram a sua administra\u00e7\u00e3o precisamente quando a massa de trabalhadores e da classe m\u00e9dia est\u00e3o a pedir uma redistribui\u00e7\u00e3o de recursos em grande escala, de subs\u00eddios ao sector privado para investimentos em servi\u00e7os p\u00fablicos.<\/p>\n<p>As fortunas politicas de Rousseff e do seu mentor, Lula, foram constru\u00eddas sobre os fr\u00e1geis fundamentos do modelo extractivo. Eles falharam em reconhecer os limites do seu modelo, muito menos em formular uma estrat\u00e9gia alternativa. Uma colcha de retalhos de propostas, reformas pol\u00edticas, ret\u00f3rica anti-corrup\u00e7\u00e3o face aos protestos de milh\u00f5es de pessoas que se estendem a todas as grandes e pequenas cidades do pa\u00eds n\u00e3o resolve o problema b\u00e1sico de desafiar a concentra\u00e7\u00e3o de riqueza, propriedade e poder de classe da elite agro-mineral e financeira. As suas aliadas multinacionais controlam as alavancas do poder pol\u00edtico, com e sem corrup\u00e7\u00e3o e bloqueiam quaisquer reformas significativas.<\/p>\n<p>A era do &#8220;Populismo Wall Street&#8221; de Lula est\u00e1 acabada. A ideia de que altas receitas provenientes das ind\u00fastrias extractivas podem comprar lealdades populares atrav\u00e9s do consumismo, financiado pelo cr\u00e9dito f\u00e1cil, est\u00e1 ultrapassada. Os investidores da Wall Street j\u00e1 n\u00e3o louvam mais os BRICs como um novo mercado din\u00e2mico. Como \u00e9 previs\u00edvel eles est\u00e3o a transferir seus investimentos para actividades mais lucrativas em novas regi\u00f5es. Quando a carteira de investimentos declina e a economia estagna, o capital extractivo intensifica sua press\u00e3o dentro da Amaz\u00f3nia e com terr\u00edvel pre\u00e7o por parte da popula\u00e7\u00e3o ind\u00edgena e a floresta tropical.<\/p>\n<p>O ano de 2012 foi um dos piores para os povos ind\u00edgenas. Segundo o Conselho Indigenista Mission\u00e1rio, filiado \u00e0 Igreja Cat\u00f3lica, o n\u00famero de incidentes violentos contra as comunidades \u00edndias aumentou 237%\u00a0<strong>[43]<\/strong> . O regime Rousseff deu aos \u00edndios o menor n\u00famero de t\u00edtulos legais \u00e0 terra do que qualquer presidente desde o retorno da democracia (sete t\u00edtulos). A esta taxa, o estado brasileiro levar\u00e1 um s\u00e9culo para titular os pedidos de terra das comunidades \u00edndias. Ao mesmo tempo, em 2012, 62 territ\u00f3rios \u00edndios foram invadidos por latifundi\u00e1rios, mineiros e madeireiros, 47% mais do que em 2011 <strong>[44]<\/strong> . A maior amea\u00e7a de despojamento vem de projectos como a mega barragem de\u00a0Belo Monte e centrais hidroel\u00e9ctricas gigantes promovidas pelo regime Rousseff. Quando a economia agro-mineral vacila, as comunidades \u00edndias est\u00e3o a ser esmagadas (&#8220;genoc\u00eddio silencioso&#8221;) a fim de intensificar o crescimento agro-mineral.<\/p>\n<p>Os maiores benefici\u00e1rios da economia extractiva do Brasil s\u00e3o os principais\u00a0<em>traders <\/em>de\u00a0<em>commodities <\/em>do mundo os quais, \u00e0 escala mundial, embolsaram US$250 mil milh\u00f5es ao longo do per\u00edodo 2003-2013, ultrapassando os lucros das maiores firmas da Wall Street e cinco das maiores companhias automobil\u00edsticas. Em meados de 2000, alguns\u00a0<em>traders <\/em>desfrutaram retornos de 50 a 60 por cento. Mesmo em 2013 eles estavam numa m\u00e9dia de 20-30% (\u00a0<em>Financial Times <\/em>, 4\/15\/13, p. 1). Especuladores de\u00a0<em>commodities <\/em>ganharam mais de 10 vezes o que foi gasto com os pobres. Estes especuladores lucram com flutua\u00e7\u00f5es de pre\u00e7os entre localiza\u00e7\u00f5es, com oportunidades de arbitragem proporcionadas pela abund\u00e2ncia de discrep\u00e2ncias de pre\u00e7os entre regi\u00f5es. Traders monopolistas eliminaram competidores e os impostos baixos (5-15%) aumentaram a sua mega riqueza. Os maiores benefici\u00e1rios do modelo extractivista Lula-Dilma, ultrapassando mesmo os gigantes agro-minerais, s\u00e3o os vinte maiores<em>traders <\/em>-especuladores de\u00a0<em>commodities. <\/em><\/p>\n<p><strong>Capital extractivo, colonialismo interno e o decl\u00ednio a luta de classe <\/strong><\/p>\n<p>A luta de classe, especialmente sua express\u00e3o em greves conduzidas por sindicatos e trabalhadores rurais localizados em acampamentos que lan\u00e7am ocupa\u00e7\u00f5es de terras, declinou drasticamente ao longo do \u00faltimo quarto de s\u00e9culo. O Brasil durante o per\u00edodo que se seguiu \u00e0 ditadura militar (1989) foi um l\u00edder mundial em greves, com 4000 em 1989. Com o retorno da pol\u00edtica eleitoral e a incorpora\u00e7\u00e3o e legaliza\u00e7\u00e3o dos sindicatos, especialmente na estrutura de negocia\u00e7\u00f5es colectivas tripartidas, as greves declinaram para uma m\u00e9dia de 500 durante a d\u00e9cada de 1990. Com o advento do regime Lula (2003-2010) as greves declinaram ainda mais, para 300-400 por ano\u00a0<strong>[45]<\/strong> . As duas maiores centrais sindicais, CUT e For\u00e7a Sindical, aliadas ao regime Lula, tornaram-se adjuntas virtuais do Minist\u00e9rio do Trabalho: sindicalistas asseguravam posi\u00e7\u00f5es no governo e as organiza\u00e7\u00f5es recebiam grandes subs\u00eddios do estado, ostensivamente para treino e educa\u00e7\u00e3o do trabalhador. Com o boom das <em>commodities <\/em>e a ascens\u00e3o das receitas do estado e rendimentos de exporta\u00e7\u00f5es, os governos formularam uma estrat\u00e9gia do gotejamento, aumentando o sal\u00e1rio m\u00ednimo e lan\u00e7ando novos programas anti-pobreza. Nas zonas rurais, o MST continuava a pedir uma reforma agr\u00e1ria e empenhado em ocupa\u00e7\u00f5es de terras mas a sua posi\u00e7\u00e3o de apoiar criticamente o Partido dos Trabalhadores em troca de subs\u00eddios sociais levou a um decl\u00ednio agudo nos acampamentos a partir dos quais lan\u00e7ar ocupa\u00e7\u00f5es de terras<strong>[46]<\/strong>.<\/p>\n<p align=\"justify\">O decl\u00ednio da luta de classe e a coopta\u00e7\u00e3o dos movimentos de massa estabelecidos coincidiram com a intensifica\u00e7\u00e3o da explora\u00e7\u00e3o capitalista extractiva do interior do pa\u00eds e o violento despojamento das comunidades ind\u00edgenas. Por outras palavras, a explora\u00e7\u00e3o acrescida do &#8220;interior&#8221; pelo capital agro-mineral facilitou a concentra\u00e7\u00e3o de riqueza nos grandes centros urbanos e nas \u00e1reas rurais estabelecidas, levando \u00e0 coopta\u00e7\u00e3o de sindicatos e movimentos rurais. Portanto, apesar de algumas declara\u00e7\u00f5es ret\u00f3ricas e protestos simb\u00f3licos, o capital agro-mineral encontrou pouca solidariedade organizada entre o trabalho urbano e os \u00edndios despojados e trabalhadores rurais escravizados na Amaz\u00f3nia &#8220;arrasada&#8221;. Lula e Dilma desempenharam um papel chave na neutraliza\u00e7\u00e3o de qualquer frente unida nacional contra as depreda\u00e7\u00f5es do capital agro-mineral.<\/p>\n<p align=\"justify\">\u00a0<\/p>\n<p>A degenera\u00e7\u00e3o das principais confedera\u00e7\u00f5es trabalhistas \u00e9 vis\u00edvel n\u00e3o s\u00f3 com a sua presen\u00e7a no governo e com a aus\u00eancia de greves como tamb\u00e9m na organiza\u00e7\u00e3o dos com\u00edcios anuais de trabalhadores no 1\u00ba de Maio. Os mais recentes virtualmente n\u00e3o inclu\u00edram qualquer conte\u00fado pol\u00edtico. H\u00e1 espect\u00e1culos de m\u00fasica, temperados com sorteios oferecendo autom\u00f3veis e outras formas de entretenimento consumista, financiados e patrocinados por grandes bancos privados e multinacionais\u00a0<strong>[47]<\/strong> . Esta rela\u00e7\u00e3o entre a cidade e a Amaz\u00f3nia lembra com efeito uma esp\u00e9cie de colonialismo interno, no qual o capital extractivo subornou uma aristocracia do trabalho como aliado c\u00famplice para a sua pilhagem das comunidades do interior.<\/p>\n<p><strong>Conclus\u00e3o: Com movimentos de massa, o modelo extractivista est\u00e1 sob s\u00edtio <\/strong><\/p>\n<p>Se a CUT e a For\u00e7a Sindical est\u00e3o cooptadas, o MST est\u00e1 enfraquecido e as classes de baixo rendimento receberam aumentos monet\u00e1rios, como e por que movimentos de massa sem precedentes emergiram em simult\u00e2neo numa centena de grandes cidades e outras menores por todo o pa\u00eds?<\/p>\n<p>O contraste entre os novos movimentos de massa e os sindicatos foi evidente na sua capacidade para mobilizar apoio durante os dias de protesto de Junho-Julho\/2013: os primeiros mobilizaram 2 milh\u00f5es, os \u00faltimos 100 mil.<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/resistir.info\/petras\/imagens\/desflorestacao_amazonia.jpg?w=747\" border=\"0\" alt=\"Manifesta\u00e7\u00e3o em S. Paulo.\" align=\"right\" \/>O que precisa ser esclarecido \u00e9 a diferen\u00e7a entre os pequenos grupos locais de estudantes (\u00a0<a href=\"http:\/\/pt.wikipedia.org\/wiki\/Movimento_Passe_Livre\" target=\"_blank\">Movimento Passe Livre<\/a> , MPL) que detonaram os movimentos de massa com base num aumento em tarifas de autocarros e os gastos fara\u00f3nicos do estado com a Copa do Mundo (campeonato de futebol) e as Olimp\u00edadas e os movimentos de massa espont\u00e2neos que questionaram as pol\u00edticas or\u00e7amentais do estado e as prioridades na sua totalidade.<\/p>\n<p>Muitos apologistas dos regimes Lula-Dilma aceitam sem questionamento as verbas or\u00e7amentais atribu\u00eddas a projectos sociais e de infraestrutura, quando de facto apenas uma frac\u00e7\u00e3o \u00e9 realmente gasta na medida em que s\u00e3o roubadas por administradores corruptos. Exemplo: entre 2008-12 foram destinados R$6,5 mil milh\u00f5es para transporte p\u00fablicos nas cidades principais mas s\u00f3 17% foi realmente gasto (\u00a0<em>Veja,<\/em>17\/07\/2013). Segundo a ONG &#8220;Contas Abertas&#8221;, ao longo de um per\u00edodo de dez anos o Brasil gastou mais de R$160 mil milh\u00f5es em obras p\u00fablicas que n\u00e3o est\u00e3o conclu\u00eddas, nunca deixaram a prancheta de desenho ou foram roubadas por respons\u00e1veis corruptos. Um dos mais not\u00f3rios casos de corrup\u00e7\u00e3o e m\u00e1 administra\u00e7\u00e3o \u00e9 a constru\u00e7\u00e3o de 12 quil\u00f3metros de metro em Salvador, com a condi\u00e7\u00e3o estabelecida de que seria completado em 40 meses ao custo de R$307 milh\u00f5es. Treze anos depois (2000-13) as despesas aumentaram para cerca 1000 milh\u00f5es de reais e escassos 6 km foram completados. Seis locomotoras e 24 vag\u00f5es comprados por 100 milh\u00f5es de reais decompuseram-se e a garantia dos fabricantes expirou (\u00a0<em>Veja, <\/em>17\/07\/2013). O projecto foi paralisado por ac\u00e7\u00f5es de sobrefactura\u00e7\u00e3o corrupta envolvendo administradores federais, estaduais e municipais. Enquanto isso, 200 mil passageiros s\u00e3o for\u00e7ados a viajar diariamente em transportes coletivos decr\u00e9pitos.<\/p>\n<p>A corrup\u00e7\u00e3o profunda que infecta toda a administra\u00e7\u00e3o Lula-Dilma conduziu a um vasto fosso entre os apregoados feitos do regime e a deteriorada experi\u00eancia di\u00e1ria da grande maioria do povo brasileiro. O mesmo fosso existe em rela\u00e7\u00e3o \u00e0s despesas para preservar a floresta tropical amaz\u00f3nica, as terras dos \u00edndios e para financiar os programas anti-pobreza: administradores corruptos do PT desviam fundos para financiar suas campanhas eleitorais ao inv\u00e9s de reduzir a destrui\u00e7\u00e3o ambiental e reduzir a pobreza.<\/p>\n<p>Se a riqueza do boom no modelo extractivo agro-mineral &#8220;filtrou-se&#8221; para o resto da economia e elevou sal\u00e1rios, isso fez-se de um modo muito irregular, desigual e distorcido. A grande riqueza concentrada no topo encontrou express\u00e3o numa esp\u00e9cie de novo sistema casta-classe no qual transporte privado \u2013 helic\u00f3pteros e heliportos \u2013 cl\u00ednicas privadas, escolas privadas, \u00e1reas de recrea\u00e7\u00e3o privadas, ex\u00e9rcitos de seguran\u00e7a privada para os ricos e abastados foram financiados por subs\u00eddios promovidos pelo estado. Em contraste, as massas experimentaram um agudo decl\u00ednio relativo e absoluto em servi\u00e7os p\u00fablicos nas pr\u00f3prias experi\u00eancias essenciais da vida.<\/p>\n<p align=\"justify\">A ascens\u00e3o no sal\u00e1rio m\u00ednimo n\u00e3o compensada por 10 horas de espera em apinhadas salas p\u00fablicas de emerg\u00eancia, transportes irregulares e sobrelotados, amea\u00e7as pessoais di\u00e1rias e inseguran\u00e7a (50 mil homic\u00eddios). Pais que recebem a esmola anti-pobreza enviam seus filhos para escola decadentes onde professores mal pagos correm de uma escola para outra mal atendendo suas classes e proporcionando um fraco aprendizado. A maior indignidade para aqueles que recebem esmolas de subsist\u00eancia foi dizerem-lhes que, nesta sociedade de classe-casta, eles eram &#8220;classe m\u00e9dia&#8221;; que faziam parte da imensa transforma\u00e7\u00e3o social que retirou 40 milh\u00f5es da pobreza, quando se arrastavam para suas casas com horas de tr\u00e1fego, retornando de empregos cujo sal\u00e1rio mensal pagava uma partida de t\u00e9nis num clube de campo da classe alta. A economia extractiva agro-mineral acentuou todas as desigualdades s\u00f3cio-econ\u00f3micas do Brasil e o regime Lula-Dilma acentuou esta diferen\u00e7a pela eleva\u00e7\u00e3o das expectativas, ao afirmar o seu cumprimento e a seguir ignorar os impactos sociais reais na vida di\u00e1ria. As verbas or\u00e7amentais em grande escala do governo para transporte p\u00fablico e promessas de projectos para novas linhas de metro e comboio foram adiadas durante d\u00e9cadas pela corrup\u00e7\u00e3o em grande escala e a longo prazo. Os milhares de milh\u00f5es gastos ao longo de anos renderam resultados m\u00ednimos \u2013 uns poucos quil\u00f3metros completados. O resultado \u00e9 que o fosso entre as projec\u00e7\u00f5es optimistas do regime e a frustra\u00e7\u00e3o das massas aumentou amplamente. O fosso entre a promessa populista e o aprofundamento da clivagem entre classes sociais n\u00e3o ser\u00e1 encoberto por sorteios sindicais e almo\u00e7os VIP. Especialmente para toda uma gera\u00e7\u00e3o de jovens trabalhadores que n\u00e3o est\u00e3o presos \u00e0s antigas mem\u00f3rias do Lula &#8220;metal\u00fargico&#8221; um quarto de s\u00e9culo antes. A CUT, a FS, o Partido dos Trabalhadores s\u00e3o irrelevantes ou s\u00e3o percebidos como parte do sistema de corrup\u00e7\u00e3o, estagna\u00e7\u00e3o social e privil\u00e9gio. A caracter\u00edstica mais gritante da nova onda de protesto de classe \u00e9 a divis\u00e3o geracional e organizacional: trabalhadores metal\u00fargicos mais velhos ausentes, jovens trabalhadores n\u00e3o organizados dos servi\u00e7os presentes.<\/p>\n<p align=\"justify\">Organiza\u00e7\u00f5es locais e espont\u00e2neas substituem os sindicatos cooptados.<\/p>\n<p>O local de confronta\u00e7\u00e3o \u00e9 a rua \u2013 n\u00e3o o lugar de trabalho. As reivindica\u00e7\u00f5es transcendem sal\u00e1rios monet\u00e1rios \u2013 as quest\u00f5es em causa s\u00e3o o sal\u00e1rio social, padr\u00f5es de vida, or\u00e7amentos nacionais. Em \u00faltima an\u00e1lise os novos movimentos sociais levantam a quest\u00e3o das prioridades de classe nacionais. O regime est\u00e1 a remover centenas de milhares de residentes em favelas \u2013 um expurgo social \u2013 para construir complexos desportivos e acomoda\u00e7\u00f5es de luxo. As quest\u00f5es sociais permeiam os movimentos de massa. A sua independ\u00eancia organizativa e autonomia sublinham o mais profundo desafio a todo o modelo extractivista neoliberal; muito embora nenhuma organiza\u00e7\u00e3o ou lideran\u00e7a nacional tenha emergido para elaborar uma alternativa. Mas a luta continua. Os mecanismos tradicionais de coopta\u00e7\u00e3o fracassam porque n\u00e3o h\u00e1 l\u00edderes identific\u00e1veis para subornar. O regime, a enfrentar o decl\u00ednio dos mercados de exporta\u00e7\u00f5es e dos pre\u00e7os das\u00a0<em>commodities, <\/em>e profundamente comprometido com investimentos n\u00e3o produtivos de muitos milhares de milh\u00f5es de d\u00f3lares nos jogos, tem poucas op\u00e7\u00f5es. O PT perdeu h\u00e1 muito a sua vanguarda anti-sist\u00e9mica. Seus pol\u00edticos est\u00e3o ligados a e financiados por bancos e elites agro-minerais. Os l\u00edderes sindicais protegem seus feudos, os descontos mensais autom\u00e1ticos dos sal\u00e1rios e suas verbas oficiais. Os movimentos de massa das cidades, tal como as comunidades \u00edndias da Amaz\u00f3nia, ter\u00e3o de encontrar novos instrumentos pol\u00edticos. Mas ao tomarem o caminho da &#8220;ac\u00e7\u00e3o directa&#8221; eles deram o primeiro grande passo.<\/p>\n<p>[1] James Petras and Henry Veltmeyer Cardoso&#8217;s Brazil: A land for Sale (Lanham, Maryland: Rowman and Littlefield 2003\/Chapter 2.<\/p>\n<p>[2] ibid Chapter 1.<\/p>\n<p>[3] James Petras, Brasil e Lula \u2013 Ano Zero (Blumenau: EdiFurb 2005) Chapter 1.<\/p>\n<p>[4] Peter Evans, Dependent Development: The Alliance of Multinational State and Local Capital in Brazil (Princeton NJ : Princeton University Press 1979).<\/p>\n<p>[5] Jose Serra &#8220;The Brazilian Economic Miracle&#8221; in James Petras Latin America from Dependence to Revolution (New York: John Wiley 1973) pp. 100 \u2013 140.<\/p>\n<p>[6] Brasil e Lula op cit. Ch. 1<\/p>\n<p>[7] Cardoso&#8217;s Brazil Ch. 5<\/p>\n<p>[8] ibid, Ch.3 and 6<\/p>\n<p>[9] ibid, Table A.12, p. 126<\/p>\n<p>[10]iIbid, Ch. 3.<\/p>\n<p>[11] ibid, Ch. 1, 2.<\/p>\n<p>[12] ibid, Ch. 5<\/p>\n<p>[13] ibid, Ch. 2.<\/p>\n<p>[14] ibid, Table A. 6.<\/p>\n<p>[15] Brasil e Lula, Ch. 1.<\/p>\n<p>[16] Brazil Exports by Product Section (USD)\u00a0<a href=\"http:\/\/www.indexmundi.com\/trade\/exports\/Brazil\" target=\"_blank\">www.INDEXMUNDI.com\/trade\/exports\/Brazil<\/a><\/p>\n<p>[17] Peter Kingstone &#8220;Brazil &#8216;s Reliance on Commodity Exports threatens its Medium and Long Term Growth Prospects&#8221;\u00a0<a href=\"http:\/\/www.americasquarterly.or\/icingstone\" target=\"_blank\">www.americasquarterly.or\/icingstone<\/a> .<\/p>\n<p>[18] Brazil Exports op cit.<\/p>\n<p>[19] Kingstone op cit.<\/p>\n<p>[20] Kingstone op cit. World Bank Yearbook 2011.<\/p>\n<p>[21]\u00a0<em>Financial Times, <\/em>3\/26\/13, p. 7.<\/p>\n<p>[22] Brazil&#8217;s Surging Foreign Investment: A Blessing or Curse? VSITC Executive Briefing on Trade Oct. 2012.<\/p>\n<p>[23] ibid<\/p>\n<p>[24]\u00a0<a href=\"http:\/\/rainforestsmongabay.com\" target=\"_blank\">rainforests:mongabay.com\/amazon_destruction<\/a><\/p>\n<p>[25] Ibid.<\/p>\n<p>[26] Bernard Mancano Fernandes and Elizabeth Alice Clements &#8220;Land Grabbing, Agribusiness and the Peasantry in Brazil and Mozambique &#8221; Agrarian South (April 2013).<\/p>\n<p>[27] Rainforests op cit.<\/p>\n<p>[28] Rainforests op cit.<\/p>\n<p>[29] Rainforests op cit.<\/p>\n<p>[30] ibid<\/p>\n<p>[31] Jose Manual Rambla &#8220;La agonia de los pueblos indigenas, buera de la agenda reivindicativa de Brasil&#8221;<a href=\"http:\/\/rebellion.org\/notice\" target=\"_blank\">rebellion.org\/notice<\/a>, 5\/7\/13.<\/p>\n<p>[32] Rainforests ibid p. 8<\/p>\n<p>[33] Brazil Mining,\u00a0<a href=\"http:\/\/www.e-mj.com\/index.php\/reatures\/850-Brazil-,mining\" target=\"_blank\">www.e-mj.com\/index.php\/reatures\/850-Brazil-,mining<\/a> .<\/p>\n<p>[34] Wikipedia Vale,\u00a0<a href=\"http:\/\/en.wilkipedia.org\/wiki\/vale_miningcompany\" target=\"_blank\">en.wilkipedia.org\/wiki\/vale_miningcompany<\/a> .<\/p>\n<p>[35]\u00a0<em>The Economist, <\/em>June 2, 2013.<\/p>\n<p>[36] Wikipedia, p. 9.<\/p>\n<p>[37]\u00a0<em>Guardian, <\/em>Jan. 27, 2012.<\/p>\n<p>[38] ibid<\/p>\n<p>[39]\u00a0<em>Financial Times, <\/em>July 13, 2013, p. 9.<\/p>\n<p>[40]\u00a0<em>Financial Times, <\/em>July 1, 2013.<\/p>\n<p>[41] ibid<\/p>\n<p>[42] Rainforest op cit.<\/p>\n<p>[43] ibid<\/p>\n<p>[44] ibid<\/p>\n<p>[45] Raul Zibechi, &#8220;El fin del consenso lulista&#8221; rebellion 7\/7\/13<\/p>\n<p>[46] Ibid.<\/p>\n<p>[47] Ibid.<\/p>\n<p><strong>O original encontra-se em\u00a0<a href=\"http:\/\/petras.lahaine.org\/?p=1945\" target=\"_blank\">http:\/\/petras.lahaine.org\/?p=1945<\/a> <\/strong><\/p>\n<p><strong>Este artigo encontra-se em\u00a0<a href=\"http:\/\/resistir.info\/\" target=\"_blank\">http:\/\/resistir.info\/<\/a> .<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"\npor James Petras\nO Brasil testemunhou um dos mais gritantes retrocessos s\u00f3cio-econ\u00f3micos da moderna hist\u00f3ria mundial:\u00a0 de uma din\u00e2mica nacionalista de industrializa\u00e7\u00e3o para uma economia exportadora prim\u00e1ria. Entre meados da d\u00e9cada de 1930 e meados da d\u00e9cada de 1980, o Brasil cresceu a uma taxa m\u00e9dia de cerca de 10% no seu sector manufactureiro, em grande medida com base em pol\u00edticas intervencionistas do estado, subs\u00eddios, protec\u00e7\u00e3o e regula\u00e7\u00e3o do crescimento de empresas p\u00fablicas nacionais e privadas. Mudan\u00e7as no &#8220;equil\u00edbrio&#8221; entre o capital nacional e estrangeiro (imperial)\n<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/5166\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[54],"tags":[],"class_list":["post-5166","post","type-post","status-publish","format-standard","hentry","category-c65-lulismo"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-1lk","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/5166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=5166"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/5166\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=5166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=5166"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=5166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}