{"id":5580,"date":"2013-10-18T12:57:54","date_gmt":"2013-10-18T12:57:54","guid":{"rendered":"http:\/\/pcb.org.br\/portal2\/?p=5580"},"modified":"2013-10-18T12:57:54","modified_gmt":"2013-10-18T12:57:54","slug":"bomba-proibida-usada-na-cinelandia","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/5580","title":{"rendered":"Bomba proibida usada na Cinel\u00e2ndia"},"content":{"rendered":"\n<p>Cinel\u00e2ndia, 07-10-2013. Na ocupa\u00e7\u00e3o da C\u00e2mara, esclarecimentos sobre a bomba proibida, filmado tamb\u00e9m pelos Ninjas.<\/p>\n<p>Segundo o Jornal Zona de Conflito M\u00eddia Independente &#8220;Bombas de g\u00e1s Rubber Ball GL 309 , atiradas hoje pela PM, foram encaminhadas para advogados. Essas bombas s\u00e3o proibidas pela ONU por conterem 20% a mais de g\u00e1s do que o permitido. S\u00e3o consideradas armas qu\u00edmicas letais. O Brasil as exporta para Israel e Turquia, mas nunca eram usadas aqui.Ser\u00e3o encaminhadas para a Comiss\u00e3o de Direitos Humanos da ONU.&#8221;<\/p>\n<p>Conforme Cris Brasil, sobre os sintomas:<\/p>\n<p>Os sintomas desse g\u00e1s azul e sinais est\u00e3o directamente relacionados com a dose de cianeto, a via de exposi\u00e7\u00e3o e o tipo de composto.<\/p>\n<p>Os sais de cianeto s\u00e3o c\u00e1usticos e pode ocorrer sensa\u00e7\u00e3o de queima\u00e7\u00e3o na l\u00edngua e inflama\u00e7\u00e3o da mucosa g\u00e1strica ap\u00f3s a ingest\u00e3o. Em casos de inala\u00e7\u00e3o pode ocorrer irrita\u00e7\u00e3o nasal.<\/p>\n<p>Os cianetos podem cheirar a am\u00eandoas amargas, o que pode ser uma pista, mas caso n\u00e3o se detecte o odor de uma subst\u00e2ncia, n\u00e3o significa que n\u00e3o tenha cianetos, porque 40 a 60% da popula\u00e7\u00e3o n\u00e3o consegue detectar o odor, sendo esta anosmia determinada geneticamente .<\/p>\n<p>Os sintomas propriamente ditos come\u00e7am poucos minutos ap\u00f3s a ingest\u00e3o de sais de cianeto. A exposi\u00e7\u00e3o aguda afecta o sistema nervoso central inicialmente estimulando-o e depois deprimindo-o e os sintomas s\u00e3o dependentes da concentra\u00e7\u00e3o administrada. Concentra\u00e7\u00f5es baixas de cianetos podem produzir sintomas e sinais n\u00e3o espec\u00edficos como: dor de cabe\u00e7a, agita\u00e7\u00e3o, n\u00e1useas, desmaios, v\u00f3mitos, confus\u00e3o e incontin\u00eancia. Exposi\u00e7\u00e3o a concentra\u00e7\u00f5es mais elevadas pode provocar hipertens\u00e3o seguida de hipotens\u00e3o, taquicardia seguida de bradicardia, dispneia, descoordena\u00e7\u00e3o de movimentos, convuls\u00f5es, cianose, coma e disfun\u00e7\u00e3o card\u00edaca ou respirat\u00f3ria que pode ser fatal. Estes sintomas s\u00e3o na sua maioria resultado da hip\u00f3xia tecidular que se instala ap\u00f3s a intoxica\u00e7\u00e3o por cianeto.<\/p>\n<p>A ingest\u00e3o cr\u00f3nica de pequenas doses pode ocorrer por ingest\u00e3o de plantas ricas em glicos\u00eddeos cianog\u00e9nicos, como por exemplo a mandioca mal processada, muitas vezes associada a uma dieta com poucas prote\u00ednas e por isso deficiente em enxofre que ajuda a destoxificar o veneno. Nestes casos, o resultado pode ser uma neuropatia denominada at\u00e1xica tropical uma vez que estas situa\u00e7\u00f5es s\u00e3o mais comuns nos tr\u00f3picos, onde a mandioca \u00e9 uma das plantas mais utilizadas na alimenta\u00e7\u00e3o. A neuropatia at\u00e1xica tropical \u00e9 uma doen\u00e7a do sistema nervoso que torna a pessoa inst\u00e1vel e descoordenada.<\/p>\n<p>O envenenamento grave por cianeto, especialmente durante per\u00edodos de fome est\u00e1 associado com o konzo, uma paralisia irrevers\u00edvel e debilitante e em alguns casos com a morte. Em certas \u00e1reas a incid\u00eancia de neuropatia at\u00e1xica tropical e konzo podem chegar aos 3%.<\/p>\n<p>Os cianetos causam tamb\u00e9m insufici\u00eancia da produ\u00e7\u00e3o de hormonas da tir\u00f3ide porque quando h\u00e1 ingest\u00e3o de cianeto ocorre destoxifica\u00e7\u00e3o por convers\u00e3o do cianeto em tiocianatoque \u00e9 uma subst\u00e2ncia que inibe a capta\u00e7\u00e3o de iodo pela gl\u00e2ndula tir\u00f3ide, impedindo-a de produzir T3 e T4 e provocando o seu aumento (b\u00f3cio).<\/p>\n<p>A ambilopia associada ao tabaco e a neuropatia perif\u00e9rica associada \u00e0 amigdalina s\u00e3o outras condi\u00e7\u00f5es provocadas pela intoxica\u00e7\u00e3o cr\u00f3nica por cianetos. 08\/10\/2013<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=1JBZq6NVbFo\" target=\"_blank\">https:\/\/www.youtube.com\/watch?v=1JBZq6NVbFo<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"  \n<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/5580\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[88],"tags":[],"class_list":["post-5580","post","type-post","status-publish","format-standard","hentry","category-c101-criminalizacao"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-1s0","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/5580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=5580"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/5580\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=5580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=5580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=5580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}