{"id":5700,"date":"2013-12-03T15:54:26","date_gmt":"2013-12-03T15:54:26","guid":{"rendered":"http:\/\/pcb.org.br\/portal2\/?p=5700"},"modified":"2017-08-25T00:59:16","modified_gmt":"2017-08-25T03:59:16","slug":"o-narcotrafico-uma-caixa-de-pandora","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/5700","title":{"rendered":"O NARCOTR\u00c1FICO, UMA CAIXA DE PANDORA"},"content":{"rendered":"\n<p>Sobre o flagelo do narcotr\u00e1fico, permitam-nos fazer as seguintes considera\u00e7\u00f5es:<\/p>\n<p><strong id=\"docs-internal-guid-10ab80fc-b92d-ebd1-bc09-a2e25b7975ec\"><\/strong><\/p>\n<p>Esse n\u00e3o \u00e9 um problema exclusivo da Col\u00f4mbia, mas um problema internacional, cuja solu\u00e7\u00e3o deve comprometer o conjunto das na\u00e7\u00f5es.<\/p>\n<p>A folha da coca, atrav\u00e9s dos s\u00e9culos, tem sido utilizada para mitigar a fome, a sede, o cansa\u00e7o, como digestivo e relaxante, estando determinado pela ci\u00eancia que tem propriedades nutricionais e medicinais.<\/p>\n<p>Outra coisa \u00e9 a coca\u00edna, que, ainda que tenha sido utilizada como anest\u00e9sico, desafortunadamente \u00e9 derivada de um estupefaciente de generalizado uso aditivo e nocivo, que gera hoje um grave problema de sa\u00fade p\u00fablica mundial.<\/p>\n<p>Se concordamos que coca e coca\u00edna n\u00e3o s\u00e3o a mesma coisa, resulta il\u00f3gico que, para acabar com o problema do narcotr\u00e1fico, se deva ent\u00e3o erradicar uma planta que pode propiciar benef\u00edcios \u00e0 humanidade. O rigor da repress\u00e3o e das medidas punitivas contra a criminalidade que se desenvolve nos processos de produ\u00e7\u00e3o, comercializa\u00e7\u00e3o e consumo das chamadas drogas il\u00edcitas, derivadas do processamento da folha de coca ou de outras plantas, n\u00e3o deve recair sobre os n\u00f3s mais fracos dessa corrente, que s\u00e3o os consumidores e os agricultores, mas sobre os benefici\u00e1rios principais do neg\u00f3cio ilegal, que s\u00e3o os mercados financeiros mundiais.<\/p>\n<p>Podemos dizer que o narcotr\u00e1fico, lamentavelmente, permeia todo o tecido social colombiano, incluindo o Estado. H\u00e1 duas d\u00e9cadas, Joe Toff, ent\u00e3o diretor da DEA (departamento de repress\u00e3o ao narcotr\u00e1fico dos EUA) para a Col\u00f4mbia, afirmou que a Col\u00f4mbia era uma narcodemocracia.<\/p>\n<p>O fen\u00f4meno n\u00e3o \u00e9 exclusivo do nosso pa\u00eds. Hoje em dia, se reconhece que os lucros do narcotr\u00e1fico e de outras atividades ilegais contaminaram todos os c\u00edrculos financeiros da economia mundial.<\/p>\n<p>Dentro desse contexto, as FARC-EP n\u00e3o s\u00f3 expressaram sua preocupa\u00e7\u00e3o, como tamb\u00e9m tra\u00e7aram pol\u00edticas que podem contribuir para criar solu\u00e7\u00f5es. H\u00e1 20 anos, a VIII Confer\u00eancia Nacional dos Guerrilheiros apresentou no ponto 10 de sua plataforma para a reconstru\u00e7\u00e3o e a reconcilia\u00e7\u00e3o nacional:<\/p>\n<p>&#8220;Solu\u00e7\u00e3o do fen\u00f4meno de produ\u00e7\u00e3o, comercializa\u00e7\u00e3o e consumo de narc\u00f3ticos e alucin\u00f3genos, entendido sobretudo como um grave problema social que n\u00e3o pode ser tratado pela via militar, mas requer acordos com a participa\u00e7\u00e3o da comunidade nacional e internacional e o compromisso das grandes pot\u00eancias como principais fontes da demanda mundial de drogas&#8221;.<\/p>\n<p>Dentro da mesma perspectiva, o pleno do Estado Maior Central das FARC-EP, em mar\u00e7o de 2000, determinou que:<\/p>\n<p>&#8220;Como o governo estadunidense alega que sua criminosa a\u00e7\u00e3o contra o povo colombiano \u00e9 a exist\u00eancia do narcotr\u00e1fico, o exortamos a legalizar o consumo de narc\u00f3ticos. Assim, se suprimem na raiz as altas rendas produzidas pela ilegalidade desse com\u00e9rcio, assim se controla o consumo, se atende clinicamente aos toxicodependentes e se liquida definitivamente esse c\u00e2ncer. Para grandes enfermidades, grandes rem\u00e9dios&#8221;.<\/p>\n<p>No desenvolvimento pr\u00e1tico dessas ideias, no marco dos Di\u00e1logos de Paz de Cagu\u00e1n, o comandante em chefe das FARC, Manuel Marulanda V\u00e9lez, apresentou um plano para, em acordo com as comunidades, implementar mecanismos de substitui\u00e7\u00e3o de cultivos de uso il\u00edcito. Tratava-se de um experimento-piloto para ser desenvolvido no munic\u00edpio de Cartagena del Chair\u00e1 (Departamento de Caquet\u00e1), complementado com uma iniciativa de desenvolvimento social que melhoraria as condi\u00e7\u00f5es de vida dos habitantes dessa regi\u00e3o, e se articularia com a reforma agr\u00e1ria rural integral que requer o pa\u00eds.<\/p>\n<p>Nossas posi\u00e7\u00f5es frente ao assunto de que trata o terceiro ponto da discuss\u00e3o dos Di\u00e1logos de Havana tem sido historicamente claras, mas aspiramos enriquec\u00ea-las com as propostas e pontos de vista expressados nos f\u00f3runs que a mesa convocou sobre o tema, e que a respeito podem seguir aportando as comunidades afetadas e todos os que quiserem ajudar a resolver esse problema, que \u00e9 usado como desculpa para o intervencionismo de pot\u00eancias estrangeiras no conflito interno colombiano.<\/p>\n<p>No estudo de cultivos e narcotr\u00e1fico, temos que come\u00e7ar pelo princ\u00edpio: Quando se iniciou o \u201cneg\u00f3cio\u201d? Quando foi a semeadura? Como foi a hist\u00f3ria da bonan\u00e7a dos bar\u00f5es da coca e da maconha na Col\u00f4mbia? Quem foram os que enriqueceram? Onde est\u00e3o? Quando se iniciou a planta\u00e7\u00e3o da coca e da papoula? Quando surge a &#8220;janela sinistra&#8221; do Banco da Rep\u00fablica? Que presidente a permitiu? Quem foi beneficiado? Quais foram os montantes, de onde vieram e de quem, quando da Anistia de Turbay Ayala? Quem se beneficiou? Onde est\u00e3o essas pessoas?<\/p>\n<p>Tais documentos n\u00e3o s\u00e3o reservados. O segredo n\u00e3o os ampara.<\/p>\n<p>Nessa \u00e9poca, quais bancos tinham sucursais no Panam\u00e1 e em outros para\u00edsos fiscais? Quais bancos tiveram dificuldades nessas sucursais (especialmente as panamenhas), e sobre quais bancos reca\u00edram investiga\u00e7\u00f5es nacionais e estadunidenses? Quais eram os seus donos e o que fazem hoje?<\/p>\n<p>O que sabem as autoridades sobre as opera\u00e7\u00f5es realizadas por bancos de Medell\u00edn e Cali para lavar dinheiro de neg\u00f3cios sujos dos dois carteis do narcotr\u00e1fico de ambas as cidades? Existe alguma conclus\u00e3o das autoridades judiciais em torno da alian\u00e7a do governo de C\u00e9sar Gaviria com o cartel de Cali, dos paramilitares para perseguir Pablo Escobar? Perguntaram sobre o financiamento do cartel de Cali para o funcionamento do Bloco de Busca no seu in\u00edcio?<\/p>\n<p>Que investiga\u00e7\u00f5es e que condena\u00e7\u00f5es existem relacionadas com a for\u00e7a p\u00fablica e sua vincula\u00e7\u00e3o com o narcotr\u00e1fico?<\/p>\n<p>Quem foi foi o diretor da avia\u00e7\u00e3o civil que autorizou a m\u00e1fia na utiliza\u00e7\u00e3o de pistas clandestinas nas selvas do Yar\u00ed para a opera\u00e7\u00e3o de recep\u00e7\u00e3o de pasta de coca do Peru, reabastecimento de combust\u00edvel e a decolagem de aeronaves carregadas de coca\u00edna para os Estados Unidos? A que fam\u00edlia pertencia o helic\u00f3ptero Hughes interceptado pelas autoridades na opera\u00e7\u00e3o contra o laborat\u00f3rio de &#8220;Tranquilandia&#8221;, o maior complexo de produ\u00e7\u00e3o de coca\u00edna do mundo?<\/p>\n<p>Quem foi o presidente que exonerou da dire\u00e7\u00e3o da pol\u00edcia de Magdalena o coronel Pardo Garc\u00eda por se negar a suspender os operativos antidrogas contra o chefe paramilitar Hern\u00e1n Giraldo, na Sierra Nevada de Santa Marta? Como surgiu e incidiu na vida pol\u00edtica nacional o chamado cartel das tr\u00eas letras, o DAS (Departamento Administrativo de Seguran\u00e7a)?<\/p>\n<p>Por que n\u00e3o investigar e tornar p\u00fablicas as den\u00fancias do informante dessa institui\u00e7\u00e3o, Rafael Garc\u00eda, um de seus art\u00edfices confessos? \u00c9 poss\u00edvel que toda essa trama funcionasse sem a participa\u00e7\u00e3o do Estado e de suas For\u00e7as Armadas em um dos pa\u00edses mais militarizados do mundo? Desde a bonan\u00e7a &#8220;marimbera&#8221; at\u00e9 hoje, quantos presidentes, parlamentares, governadores e prefeitos foram eleitos com o dinheiro \u201cquente\u201d dos carteis da droga?<\/p>\n<p>Como se explica que anualmente a lavagem de dinheiro fa\u00e7a ingressar na economia colombiana pelo menos 16 bilh\u00f5es de pesos, o que representa 3 pontos do Produto Interno Bruto? Tem algo a ver com o que os bancos colombianos ganharam? Ou seja, 4,5 bilh\u00f5es at\u00e9 julho de 2013?<\/p>\n<p>Por que os chefes mafiosos da distribui\u00e7\u00e3o da droga nos Estados Unidos, que s\u00e3o os que ficam com a maior parte do neg\u00f3cio, n\u00e3o s\u00e3o presos?<\/p>\n<p>Todas essas inquietudes nos fazem pensar que o narcotr\u00e1fico \u00e9 um problema complexo cuja solu\u00e7\u00e3o requer a participa\u00e7\u00e3o da comunidade internacional.<\/p>\n<p>DELEGA\u00c7\u00c3O DE PAZ DAS FARC-EP<\/p>\n<p>Fonte: <a href=\"http:\/\/pazfarc-ep.org\/\">http:\/\/pazfarc-ep.org\/<\/a><\/p>\n<p><strong><a href=\"http:\/\/pazfarc-ep.org\/\"><\/a><\/strong><\/p>\n<p>Tradu\u00e7\u00e3o: PCB Partido Comunista Brasileiro<\/p>\n","protected":false},"excerpt":{"rendered":"\nHavana, Cuba, sede dos di\u00e1logos de paz, 28 de novembro de 2013\n<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/5700\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[7],"tags":[],"class_list":["post-5700","post","type-post","status-publish","format-standard","hentry","category-s8-brasil"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-1tW","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/5700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=5700"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/5700\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=5700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=5700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=5700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}