{"id":5767,"date":"2013-12-28T04:23:26","date_gmt":"2013-12-28T04:23:26","guid":{"rendered":"http:\/\/pcb.org.br\/portal2\/?p=5767"},"modified":"2017-08-25T00:48:45","modified_gmt":"2017-08-25T03:48:45","slug":"mandela-morreu-por-que-esconder-a-verdade-sobre-o-apartheid","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/5767","title":{"rendered":"Mandela morreu. Por que esconder a verdade sobre o Apartheid?"},"content":{"rendered":"\n<p>Talvez o imp\u00e9rio n\u00e3o acreditasse que nosso povo honraria sua palavra quando, nos dias incertos do s\u00e9culo passado, afirmamos que caso a URSS desparecesse, Cuba continuaria lutando.<\/p>\n<p>A Segunda Guerra Mundial come\u00e7ou quando, em 1\u00b0\u00a0de setembro de 1939, o nazi-fascismo invadiu a Pol\u00f4nia e caiu como um raio sobre o heroico povo da URSS, que contribuiu com 27 milh\u00f5es de vidas para preservar a humanidade daquela brutal matan\u00e7a que colocou fim \u00e0 vida de mais de 50 milh\u00f5es de pessoas.<\/p>\n<p>A guerra \u00e9, por outro lado, a \u00fanica atividade ao longo da hist\u00f3ria que o g\u00eanero humano nunca foi capaz de evitar; o que levou Einstein a responder que n\u00e3o sabia como seria a Terceira Guerra Mundial, por\u00e9m a Quarta seria com paus e pedras.<\/p>\n<p>Somados os meios dispon\u00edveis, as duas mais poderosas pot\u00eancias, Estados Unidos e R\u00fassia, disp\u00f5em de mais de 20.000 \u2013 vinte mil \u2013 ogivas nucleares. A humanidade deve saber que, tr\u00eas dias depois da ascens\u00e3o de John F. Kennedy \u00e0 presid\u00eancia de seu pa\u00eds, em 20 de janeiro de 1961, um bombardeio B-52 dos Estados Unidos, em voo de rotina, que transportava duas bombas at\u00f4micas com uma capacidade destrutiva 260 vezes superior \u00e0 utilizada em Hiroshima, sofreu um acidente que precipitou o aparato na terra. Em tais casos, equipamentos autom\u00e1ticos sofisticados aplicam mecanismos que impedem o estouro das bombas. A primeira caiu na terra sem risco algum; a segunda, dos 4 mecanismos, tr\u00eas falharam, e o quarto, em estado cr\u00edtico, funcionou; por puro azar, a bomba n\u00e3o estourou.<\/p>\n<p>Nenhum acontecimento presente ou passado, que eu recorde ou tenha ouvido mencionar, como a morte de Mandela, impactou a opini\u00e3o p\u00fablica mundial; e n\u00e3o por suas riquezas, mas pela qualidade humana e a nobreza de seus sentimentos e ideias.<\/p>\n<p>Ao longo da hist\u00f3ria, at\u00e9\u00a0apenas um s\u00e9culo e meio e antes das m\u00e1quinas e rob\u00f4s, a um custo m\u00ednimo de energia, se ocuparam de nossas modestas tarefas, n\u00e3o existiam nenhum dos fen\u00f4menos que hoje comovem a humanidade e regem inexoravelmente cada uma das pessoas: homens ou mulheres, crian\u00e7as e idosos, jovens e adultos, agricultores e oper\u00e1rios, manuais ou intelectuais. A tend\u00eancia dominante \u00e9 a de instalar-se nas cidades, onde a cria\u00e7\u00e3o de empregos, transporte e condi\u00e7\u00f5es elementares de vida, demandam enormes investimentos em detrimento da produ\u00e7\u00e3o aliment\u00edcia e outras formas de vida mais razo\u00e1veis.<\/p>\n<p>Tr\u00eas pot\u00eancias colocaram artefatos na Lua de nosso planeta. No mesmo dia em que Nelson Mandela, envolto na bandeira de sua p\u00e1tria, foi enterrado no p\u00e1tio da humilde casa onde nasceu h\u00e1 95 anos, um artefato sofisticado da Rep\u00fablica Popular da China era posto no espa\u00e7o iluminado de nossa Lua. A coincid\u00eancia de ambos os fatos foi absolutamente casual.<\/p>\n<p>Milh\u00f5es de cientistas investigam mat\u00e9rias e radia\u00e7\u00f5es na Terra e no espa\u00e7o; por eles se conhece que o Tit\u00e3, uma das luas de Saturno, acumulou 40 \u2013 quarenta \u2013 vezes mais petr\u00f3leo que o existente em nosso planeta quando come\u00e7ou a explora\u00e7\u00e3o deste h\u00e1 apenas 125 anos, e ao ritmo atual de consumo, durar\u00e1 apenas um s\u00e9culo mais.<\/p>\n<p>Os fraternais sentimentos de irmandade profunda entre o povo cubano e a p\u00e1tria de Nelson Mandela nasceram de um fato que nem sequer foi mencionado, e do qual n\u00e3o t\u00ednhamos falado uma palavra ao longo de muitos anos; Mandela, porque era um ap\u00f3stolo da paz e n\u00e3o desejava prejudicar ningu\u00e9m. Cuba, porque jamais realizou a\u00e7\u00e3o alguma em busca de gl\u00f3ria ou prest\u00edgio.<\/p>\n<p>Quando a Revolu\u00e7\u00e3o triunfou em Cuba fomos solid\u00e1rios com as col\u00f4nias portuguesas na \u00c1frica, desde os primeiros anos; os Movimentos de Liberta\u00e7\u00e3o nesse continente punham em xeque o colonialismo e o imperialismo, depois da Segunda Guerra Mundial e a liberta\u00e7\u00e3o da Rep\u00fablica Popular da China \u2013 o pa\u00eds mais povoado do mundo \u2013, ap\u00f3s o triunfo glorioso da Revolu\u00e7\u00e3o Socialista Russa.<\/p>\n<p>As revolu\u00e7\u00f5es sociais assombravam os alicerces da velha ordem. A popula\u00e7\u00e3o do planeta, em 1960, alcan\u00e7avam o n\u00famero de 3 bilh\u00f5es de habitantes. Da mesma forma, cresceu o poder das grandes empresas transnacionais, quase todas nas m\u00e3os dos Estados Unidos, cuja moeda, apoiada no monop\u00f3lio do ouro e na ind\u00fastria intacta pela dist\u00e2ncia das frentes de batalha, se fez dona da economia mundial. Richard Nixon aboliu, unilateralmente, o respaldo de sua moeda em ouro. Assim, as empresas de seu pa\u00eds apoderaram-se dos principais recursos e mat\u00e9rias primas do planeta que adquiriram com pap\u00e9is.<\/p>\n<p>At\u00e9\u00a0aqui n\u00e3o existe nada que n\u00e3o se conhe\u00e7a.<\/p>\n<p>Por\u00e9m, por que se pretende esconder que o regime do Apartheid, que tanto fez sofrer a \u00c1frica e indignou a imensa maioria das na\u00e7\u00f5es do mundo, era fruto da Europa colonial e foi convertido em pot\u00eancia nuclear pelos Estados Unidos e Israel, o qual Cuba, um pa\u00eds que apoiava as col\u00f4nias portuguesas na \u00c1frica que lutavam por sua independ\u00eancia, condenou abertamente?<\/p>\n<p>Nosso povo, que foi sido cedido pela Espanha aos Estados Unidos ap\u00f3s a heroica luta de mais de 30 anos, nunca se resignou ao regime escravista imposto durante quase 500 anos.<\/p>\n<p>Da Nam\u00edbia, ocupada pela \u00c1frica do Sul, em 1975, partiram as tropas racistas apoiadas por tanques r\u00e1pidos com canh\u00f5es de 90 mil\u00edmetros, que penetraram mais de mil quil\u00f4metros at\u00e9 as proximidades de Luanda. No local, encontrava-se um Batalh\u00e3o de Tropas Especiais cubanas \u2013 enviadas por ar \u2013 e v\u00e1rias tripula\u00e7\u00f5es, tamb\u00e9m cubanas, com tanques sovi\u00e9ticos, que as contiveram. Isso ocorreu em novembro de 1975, 13 anos antes da Batalha de Cuito Cuanavale.<\/p>\n<p>J\u00e1\u00a0disse que n\u00e3o fizemos nada em busca de prest\u00edgio ou benef\u00edcio. Por\u00e9m, \u00e9 um fato muito real que Mandela foi um homem \u00edntegro, revolucion\u00e1rio profundo e radicalmente socialista que, com grande estoicismo, suportou 27 anos de encarceramento solit\u00e1rio. Eu n\u00e3o deixava de admirar sua honradez, sua mod\u00e9stia e seu enorme m\u00e9rito.<\/p>\n<p>Cuba cumpria seus deveres internacionalistas rigorosamente. Defendia pontos chaves e, anualmente, treinava milhares de combatentes angolanos para o manejo das armas. A URSS fornecia o armamento. No entanto, naquela \u00e9poca, n\u00e3o compartilh\u00e1vamos da ideia do principal assessor dos fornecedores dos equipamentos militares. Milhares de angolanos jovens e saud\u00e1veis ingressavam constantemente as unidades de seu incipiente ex\u00e9rcito. O principal assessor n\u00e3o era, no entanto, um Zh\u00fakov, Rokossovski, Malinovsky ou muitos outros que levaram \u00e0 gl\u00f3ria a estrat\u00e9gia militar sovi\u00e9tica. Sua ideia obsessiva era enviar brigadas angolanas com as melhores armas ao territ\u00f3rio, onde, supostamente, residia o governo tribal de Savimbi, um mercen\u00e1rio a servi\u00e7o dos Estados Unidos e da \u00c1frica do Sul. Era como enviar as for\u00e7as que combatiam em Stalingrado \u00e0 fronteira da Espanha falangista, que havia enviado mais de cem mil soldados pata lutarem contra a URSS. Nesse ano, estava sendo produzida uma opera\u00e7\u00e3o desse tipo.<\/p>\n<p>O inimigo avan\u00e7ava por depois das for\u00e7as de v\u00e1rias brigadas angolanas, golpeadas nas proximidades do objetivo para onde eram enviadas, a 1.500 quil\u00f4metros aproximadamente de Luanda. Dali, vinham perseguidas pelas for\u00e7as sul-africanas em dire\u00e7\u00e3o a Cuito Cuanavale, antiga base militar da OTAN, a uns 100 quil\u00f4metros da primeira Brigada de Tanques cubana.<\/p>\n<p>Nesse instante cr\u00edtico, o Presidente da Angola solicitou o apoio das tropas cubanas. O Chefe de nossas for\u00e7as no Sul, General Leopoldo Cintra Fr\u00edas, nos comunicou a solicita\u00e7\u00e3o, algo que soava ser habitual. Nossa resposta firme foi que prestar\u00edamos esse apoio se todas as for\u00e7as e equipamentos angolanos dessa frente se subordinassem ao comando cubano no Sul da Angola. Todo o mundo compreendia que nossa solicita\u00e7\u00e3o era um requisito para converter a antiga base no campo ideal para golpear as for\u00e7as racistas da \u00c1frica do Sul.<\/p>\n<p>Em menos de 24 horas chegou de Angola a resposta positiva.<\/p>\n<p>Decidiu-se o envio imediato de uma Brigada de Tanques cubana para esse ponto. V\u00e1rias mais estavam na mesma linha para o Oeste. O obst\u00e1culo principal era a lama e a umidade da terra na \u00e9poca da chuva, fazendo que verific\u00e1ssemos metro a metro contra as minas terrestres. Igualmente foi enviado a Cuito o pessoal para operar os tanques sem tripula\u00e7\u00e3o e os canh\u00f5es que precisavam delas.<\/p>\n<p>A base estava separada do territ\u00f3rio que se situa \u00e0 Leste pelo caudaloso e r\u00e1pido rio Cuito, sobre o qual se sustentava uma s\u00f3lida ponte. O ex\u00e9rcito racista a atacava desesperadamente; um avi\u00e3o teleguiado repleto de explosivos conseguiu atingir a ponte e inutiliz\u00e1-la. Os tanques angolanos em retirada que podiam mover-se cruzaram a ponte num ponto mais ao Norte. Os que n\u00e3o estavam em condi\u00e7\u00f5es adequadas foram enterrados, com suas armas apontando para Leste; uma densa faixa de minas terrestres e antitanques converteram a linha numa mortal armadilha no outro lado do rio. Quando as for\u00e7as racistas reiniciaram o avan\u00e7o e chocaram contra aquela muralha, todas as pe\u00e7as de artilharia e os tanques das brigadas revolucion\u00e1rias disparavam a partir de seus pontos de localiza\u00e7\u00e3o na zona de Cuito.<\/p>\n<p>Um papel especial foi reservado para os ca\u00e7as Mig-23 que, em velocidade pr\u00f3xima a mil quil\u00f4metros por hora e a 100 \u2013 cem \u2013 metros de altura, eram capazes de distinguir se o pessoal da artilharia era negro ou branco, e disparavam incessantemente contra eles.<\/p>\n<p>Quando o inimigo desgastado e imobilizado iniciou a retirada, as for\u00e7as revolucion\u00e1rias se prepararam para os combates finais.<\/p>\n<p>Numerosas brigadas angolanas e cubanas se moveram em ritmo r\u00e1pido e com dist\u00e2ncia adequada para o Oeste, onde estavam as \u00fanicas vias amplas por onde os sul-africanos sempre iniciavam suas a\u00e7\u00f5es contra Angola. O aeroporto, no entanto, estava a aproximadamente 300 \u2013 trezentos \u2013 quil\u00f4metros da fronteira com a Nam\u00edbia, totalmente ocupada pelo ex\u00e9rcito do Apartheid.<\/p>\n<p>Enquanto as tropas se reorganizavam e reequipavam, decidiu-se com toda urg\u00eancia construir uma pista de aterrissagem para os Mig-23. Nossos pilotos estavam utilizando os equipamentos a\u00e9reos entregues pela URSS a Angola, cujos pilotos n\u00e3o possu\u00edam o tempo necess\u00e1rio para sua adequada instru\u00e7\u00e3o. V\u00e1rios equipamentos a\u00e9reos estavam prejudicados por baixas que, \u00e0s vezes, eram ocasionadas por nossos pr\u00f3prios artilheiros ou operadores de meios antia\u00e9reos. Todavia, os sul-africanos ocupavam uma parte da estrada principal que conduz da borda do planalto angolano at\u00e9 a Nam\u00edbia. Nas pontes sobre o caudaloso rio Cunene, entre o Sul da Angola e o Norte da Nam\u00edbia, na \u00e9poca, come\u00e7aram os joguinhos de disparos com canh\u00f5es de 140 mil\u00edmetros, que dava a seus proj\u00e9teis um alcance pr\u00f3ximo a 40 quil\u00f4metros. O problema principal radicava no fato de que os racistas sul-africanos possu\u00edam, segundo nossos c\u00e1lculos, entre 10 e 12 armas nucleares. Tinham realizado testes inclusive nos mares ou nas \u00e1reas congeladas do Sul. O presidente Ronald Reagan o tinha autorizado tais testes e, entre os equipamentos entregues por Israel, estava o dispositivo necess\u00e1rio para fazer estourar a carga nuclear. Nossa resposta foi organizar pessoal em grupos de combate de n\u00e3o mais de 1.000 \u2013 mil \u2013 homens, que deviam marchar de noite numa ampla extens\u00e3o de terreno e dotados de carros de combate antia\u00e9reos.<\/p>\n<p>As armas nucleares da \u00c1frica do Sul, segundo informes fidedignos, n\u00e3o poderiam ser carregadas por avi\u00f5es Mirage, necessitavam bombardeios pesados tipo Canberra. Por\u00e9m, em qualquer caso, a defesa antia\u00e9rea de nossas for\u00e7as dispunha de numerosos tipos de foguetes que podiam golpear e destruir objetivos a\u00e9reos at\u00e9 dezenas de quil\u00f4metros de nossas tropas. Al\u00e9m disso, uma barragem de 80 milh\u00f5es de metros c\u00fabicos de \u00e1gua situada em territ\u00f3rio angolano tinha sido ocupada e minada por combatentes cubanos e angolanos. O estouro daquela represa teria sido equivalente a v\u00e1rias armas nucleares.<\/p>\n<p>N\u00e3o obstante, uma hidrel\u00e9trica que usava as fontes correntes do rio Cunene, antes de chegar \u00e0 fronteira com a Nam\u00edbia, estava sendo utilizada por um destacamento do ex\u00e9rcito sul-africano.<\/p>\n<p>Quando no novo teatro de opera\u00e7\u00f5es os racistas come\u00e7aram a disparar os canh\u00f5es de 140 mil\u00edmetros, os Mig-23 golpearam fortemente aquele destacamento de soldados brancos e os sobreviventes abandonaram o lugar deixando, inclusive, alguns grupos cr\u00edticos contra seu pr\u00f3prio comando. Tal era a situa\u00e7\u00e3o quando as for\u00e7as cubanas e angolanas avan\u00e7avam para a linha inimiga.<\/p>\n<p>Soube que Katiuska Blanco, autora de v\u00e1rios relatos hist\u00f3ricos, junto a outros jornalistas e rep\u00f3rteres, estava l\u00e1. A situa\u00e7\u00e3o era tensa, mas ningu\u00e9m perdeu a calma.<\/p>\n<p>Foi ent\u00e3o que chegaram not\u00edcias de que o inimigo estava disposto a negociar. Conquistou-se o fim da aventura imperialista e racista num continente que em 30 anos teria uma popula\u00e7\u00e3o superior \u00e0 da China e \u00cdndia juntas.<\/p>\n<p>O papel da delega\u00e7\u00e3o de Cuba, por conta do falecimento de nosso amigo e irm\u00e3o Nelson Mandela, ser\u00e1 inesquec\u00edvel.<\/p>\n<p>Felicito o companheiro Ra\u00fal por seu brilhante desempenho e, em especial, pela firmeza e dignidade quando, com um gesto am\u00e1vel, por\u00e9m firme, saudou o chefe do governo dos Estados Unidos e lhe disse, em ingl\u00eas:\u00a0\u201cSenhor Presidente, eu sou Castro\u201d.<\/p>\n<p>Quando minha pr\u00f3pria sa\u00fade p\u00f4s limite a minha capacidade f\u00edsica, n\u00e3o vacilei um minuto em expressar meu crit\u00e9rio sobre quem, em meu ju\u00edzo, poderia assumir a responsabilidade. Uma vida \u00e9 um minuto na hist\u00f3ria dos povos e penso que quem assume hoje tal responsabilidade requer a experi\u00eancia e autoridade necess\u00e1ria para optar ante um n\u00famero crescente, quase infinito, de variantes.<\/p>\n<p>O imperialismo sempre reservar\u00e1\u00a0v\u00e1rias cartas para dobrar nossa ilha, ainda que tenha que despovo\u00e1-la, privando-a de homens e mulheres jovens, oferecendo-lhe migalhas de bens e recursos naturais que saqueia do mundo.<\/p>\n<p>Que falem agora os porta-vozes do imp\u00e9rio sobre como e porque surgiu o Apartheid.<\/p>\n<p>Fidel Castro Ruz<\/p>\n<p>18 de dezembro de 2013.<\/p>\n<p>8 e 35 p.m.<\/p>\n<p>Fonte: <a href=\"http:\/\/www.cubadebate.cu\/fidel-castro-ruz\/2013\/12\/19\/articulo-de-fidel-mandela-ha-muerto-por-que-ocultar-la-verdad-sobre-el-apartheid\/\" target=\"_blank\">http:\/\/www.cubadebate.cu\/fidel-castro-ruz\/2013\/12\/19\/articulo-de-fidel-mandela-ha-muerto-por-que-ocultar-la-verdad-sobre-el-apartheid\/<\/a><\/p>\n<p>Tradu\u00e7\u00e3o: Partido Comunista Brasileiro (PCB)<\/p>\n","protected":false},"excerpt":{"rendered":"\nFidel Castro\n<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/5767\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[9],"tags":[],"class_list":["post-5767","post","type-post","status-publish","format-standard","hentry","category-s10-internacional"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-1v1","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/5767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=5767"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/5767\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=5767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=5767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=5767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}