{"id":5868,"date":"2014-02-06T18:50:57","date_gmt":"2014-02-06T18:50:57","guid":{"rendered":"http:\/\/pcb.org.br\/portal2\/?p=5868"},"modified":"2014-02-06T18:50:57","modified_gmt":"2014-02-06T18:50:57","slug":"frente-as-ameacas-aos-dirigentes-sociais-e-prisoes","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/5868","title":{"rendered":"Frente \u00e0s amea\u00e7as aos dirigentes sociais e pris\u00f5es"},"content":{"rendered":"\n<p>Escrito por <a href=\"http:\/\/www.pazfarc-ep.org\/index.php\/noticias-comunicados-documentos-farc-ep\/delegacion-de-paz-farc-ep\/autor\/213-delegaci%C3%B3n-de-paz-farc-ep.html\">Delega\u00e7\u00e3o de Paz FARC-EP<\/a><\/p>\n<p>Havana, Cuba, sede dos di\u00e1logos de paz, 5 de fevereiro de 2014<\/p>\n<p>Em defesa da paz<\/p>\n<p>De maneira for\u00e7ada e lament\u00e1vel, temos que nos referir novamente, de Havana, \u00e0s m\u00e1s not\u00edcias oriundas da Col\u00f4mbia, que se tornaram cotidianas no desenvolvimento da vida nacional e que impactam negativamente sobre o processo de paz.<\/p>\n<p>At\u00e9 agora, temos posto todo nosso empenho e otimismo para levar adiante dois acordos parciais que abririam caminho para a justi\u00e7a social e para a democracia real. Um \u00e9 o referente ao hist\u00f3rico problema da propriedade e uso da terra, e o outro, referente \u00e0 Participa\u00e7\u00e3o pol\u00edtica cidad\u00e3, os quais de uma forma ou outra semeiam esperan\u00e7as de reconcilia\u00e7\u00e3o. Por\u00e9m, frente \u00e0 terr\u00edvel realidade dos assassinatos de reclamantes da terra, a repress\u00e3o contra aqueles que clamam pela concretiza\u00e7\u00e3o da reforma agr\u00e1ria, a persegui\u00e7\u00e3o e as pris\u00f5es amparadas em normas draconianas de seguran\u00e7a cidad\u00e3; a admiss\u00e3o descarada da interven\u00e7\u00e3o da CIA no conflito interno; enfim, frente \u00e0 m\u00e3o tenebrosa do imp\u00e9rio, frente \u00e0 guerra suja e ao terrorismo de Estado que n\u00e3o cessam, nos perguntamos se \u00e9 poss\u00edvel continuar confiando na certeza de encontrar a paz ap\u00f3s a assinatura de um acordo final.<\/p>\n<p>As amea\u00e7as contra a UP, contra a Marcha Patri\u00f3tica (que desde o ano passado j\u00e1 soma 30 integrantes assassinados), contra a Mesa de Interlocu\u00e7\u00e3o Agr\u00e1ria (MIA), contra juristas e ativistas defensores dos direitos humanos, contra Gustavo Petro, Iv\u00e1n Cepeda, contra dirigentes de tradi\u00e7\u00e3o popular como Piedad C\u00f3rdoba, Jaime Caicedo, Carlos Lozano, A\u00edda Abella, C\u00e9sar Pach\u00f3n, David Fl\u00f3rez, Andr\u00e9s Gil\u2026 entre outras dezenas de l\u00edderes pol\u00edticos e sociais, s\u00e3o a reedi\u00e7\u00e3o da Guerra de Baixa Intensidade e da velha Doutrina de Seguran\u00e7a Nacional em geral que, durante d\u00e9cadas, protagonizam o militarismo na Col\u00f4mbia.<\/p>\n<p>Uma institucionalidade que funciona de maneira corrupta (com a manipula\u00e7\u00e3o dolosa do tesouro p\u00fablico) dentro da qual, todos os dias eclodem esc\u00e2ndalos de imoralidade e deslealdade, de rapina clientelista e de interesses grupais e pessoais, n\u00e3o consegue gerar confian\u00e7a para depositar nela os destinos do pa\u00eds. Quem espia quem? Quem manda assassinar quem e por qu\u00ea? Resqu\u00edcios? \u00c1guias Negras? Paramilitarismo? Os velhos instrumentos da guerra suja, os esquadr\u00f5es da morte atuando.<\/p>\n<p>Parece que a governabilidade entrou em crise, que o caos abra\u00e7a o regime em seu conjunto.<\/p>\n<p>Apesar de tudo, nossa disposi\u00e7\u00e3o de encontrar os pontos de entendimento que levem \u00e0 solu\u00e7\u00e3o dos profundos problemas sociais e ponham fim \u00e0s causas da guerra, todavia espera uma atitude sensata em contrapartida, que a impede com indol\u00eancia e abusos contra o povo e suas organiza\u00e7\u00f5es sociais e pol\u00edticas. O governo de Juan Manuel Santos deve estabelecer uma posi\u00e7\u00e3o clara de compromisso com a solu\u00e7\u00e3o pol\u00edtica e social, entendendo que a via mais conveniente para tra\u00e7armos o futuro est\u00e1 na mobiliza\u00e7\u00e3o do pa\u00eds, na interven\u00e7\u00e3o do soberano, o que obriga, sem mais demoras, a convocar a Assembleia Nacional Constituinte pela Paz.<\/p>\n<p>A CELAC conclamou fazer do continente uma zona de paz, manifestando com a assinatura de quase todos os presidentes de Nossa Am\u00e9rica, seu respaldo ao processo de di\u00e1logos entre o governo da Col\u00f4mbia e as FARC-EP, em Havana. De nossa parte, estamos dispostos a lutarmos por esta causa humanit\u00e1ria e altru\u00edsta. Por isso, ante o perigo em que se encontra esta nova tentativa de reconcilia\u00e7\u00e3o, chamamos a que toda a cidadania, em cada parte da p\u00e1tria atue com todas suas potencialidades, em defesa e salva\u00e7\u00e3o do processo de paz.<\/p>\n<p>DELEGA\u00c7\u00c3O DE PAZ DAS FARC-EP<\/p>\n<p>Fonte: <a href=\"http:\/\/www.pazfarc-ep.org\/index.php\/noticias-comunicados-documentos-farc-ep\/delegacion-de-paz-farc-ep\/autor\/213-delegaci%C3%B3n-de-paz-farc-ep.html\">http:\/\/www.pazfarc-ep.org\/<\/a><\/p>\n<p>Tradu\u00e7\u00e3o: Partido Comunista Brasileiro (PCB)<\/p>\n<p>Na foto: Da esquerda para a direita: Comandantes Pablo Catatumbo, Iv\u00e1n M\u00e1rquez e Jes\u00fas Santrich<\/p>\n","protected":false},"excerpt":{"rendered":" \nQuarta-feira, 05 de fevereiro de 2014 00:00\n<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/5868\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[34],"tags":[],"class_list":["post-5868","post","type-post","status-publish","format-standard","hentry","category-c39-colombia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-1wE","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/5868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=5868"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/5868\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=5868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=5868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=5868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}